{"id":63801,"date":"2024-05-20T21:00:22","date_gmt":"2024-05-20T21:00:22","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc6442-2022\/"},"modified":"2024-05-20T21:00:22","modified_gmt":"2024-05-20T21:00:22","slug":"stc6442-2022","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc6442-2022\/","title":{"rendered":"STC6442 2022"},"content":{"rendered":"<p>STC6442-2022<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>Magistrado &nbsp;Ponente &nbsp;<\/p>\n<p>STC6442-2022 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n.\u00b0 25000-22-13-000-2022-00121-01 &nbsp;<\/p>\n<p>(Aprobado &nbsp;en sesi\u00f3n de veinticinco de mayo de dos mil veintid\u00f3s) &nbsp;<\/p>\n<p>Bogot\u00e1 &nbsp;D.C., veinticinco (25) de mayo de dos mil veintid\u00f3s (2022). &nbsp;<\/p>\n<p>La &nbsp;Corte decide la impugnaci\u00f3n interpuesta frente a la &nbsp;sentencia &nbsp;proferida por &nbsp;la Sala Civil-Familia del Tribunal Superior del Distrito Judicial de &nbsp;Cundinamarca el 19 de abril de 2022, con la cual neg\u00f3 el &nbsp;amparo promovido por la sociedad Mu\u00f1oz Hermanos F&amp;N &nbsp;Compa\u00f1\u00eda S.A.S. contra &nbsp;el Juzgado Civil del Circuito de Chocont\u00e1 y el Juzgado Civil &nbsp;Municipal de la misma ciudad. &nbsp;Al tr\u00e1mite se vincul\u00f3 a los intervinientes en el &nbsp;proceso ejecutivo de radicado 2021-00134-00. &nbsp;<\/p>\n<p>I. &nbsp;ANTECEDENTES &nbsp;<\/p>\n<p>1. &nbsp;La promotora, por medio de apoderado judicial, reclam\u00f3 la &nbsp;protecci\u00f3n constitucional de su derecho fundamental al debido &nbsp;proceso, presuntamente vulnerado por las autoridades acusadas. &nbsp;<\/p>\n<p>2. &nbsp;Narr\u00f3 que interpuso demanda ejecutiva en contra de Almacenes &nbsp;\u00c9xito S.A. con el fin de que se librara \u00abmandamiento &nbsp;de pago [\u2026] por la suma de [\u2026] $14.023.208 por concepto &nbsp;de saldo insoluto sobre el canon de arrendamiento del mes de &nbsp;noviembre de 2018 [\u2026] $20.978.616, por concepto del saldo &nbsp;insoluto sobre [los c\u00e1nones] de arrendamiento de [\u2026] &nbsp;diciembre de 2018 [\u2026] y enero de [\u2026] 2019\u00bb. &nbsp;Adem\u00e1s, se condene al pago de los intereses moratorios &nbsp;causados por el incumplimiento de las sumas acordadas en el contrato &nbsp;de arrendamiento de local comercial suscrito entre las partes1. &nbsp;En ese orden, el Juzgado Civil Municipal de Chocont\u00e1, -el 19 &nbsp;de noviembre de 2020- orden\u00f3 librar mandamiento de pago2. &nbsp;Frente a ello, el extremo pasivo contest\u00f3 y, propuso &nbsp;\u00abexcepciones &nbsp;de m\u00e9rito\u00bb3. &nbsp;<\/p>\n<p>2.2. &nbsp;El Juzgado Civil del Circuito de Chocont\u00e1 -con resoluci\u00f3n &nbsp;del 27 de septiembre de 2021- decidi\u00f3 \u00abconfirmar &nbsp;en su integridad la sentencia proferida en audiencia de 13 de julio &nbsp;de 2021 (sic) proferida por el Juzgado Civil Municipal de Chocont\u00e1\u00bb5. &nbsp;<\/p>\n<p>2.3. &nbsp;As\u00ed &nbsp;las cosas, la promotora, &nbsp;por v\u00eda de tutela, consider\u00f3 que los juzgados de &nbsp;instancia \u00abno &nbsp;cumplieron con la obligaci\u00f3n de valorar de manera conjunta la &nbsp;prueba allegada al proceso y con sustento en manifestaciones &nbsp;parciales, tanto en el interrogatorio de parte, como en las &nbsp;testimoniales recaudadas, [\u2026] raz\u00f3n que consideraron &nbsp;suficiente para concluir que los pagos hechos por la parte demandada &nbsp;satisfac\u00edan plenamente la obligaci\u00f3n\u00bb. Adem\u00e1s, &nbsp;adujo que no \u00abse &nbsp;comprende, &nbsp;la raz\u00f3n por la cual, se desestima una prueba documental que &nbsp;la misma parte demandante afirma que el contrato de arrendamiento se &nbsp;ci\u00f1e al clausulado pactado el 11 de junio de 2013, y de manera &nbsp;expresa en la carta de terminaci\u00f3n, hace alusi\u00f3n a la &nbsp;cl\u00e1usula cuarta referente al t\u00e9rmino de duraci\u00f3n, &nbsp;de lo que se concluye el desconocimiento de la supuesta &nbsp;modificaci\u00f3n\u00bb. &nbsp;<\/p>\n<p>3. &nbsp;Inst\u00f3, &nbsp;conforme a lo relatado, que se ordene \u00abdejar &nbsp;sin efecto las decisiones y se proceda a efectuar la valoraci\u00f3n &nbsp;conjunta de la prueba en los t\u00e9rminos que ordena la &nbsp;jurisprudencia y la ley procesal vigente\u00bb. &nbsp;<\/p>\n<p>II. &nbsp;LAS RESPUESTAS RECIBIDAS &nbsp;<\/p>\n<p>1. &nbsp;El Juzgado Civil Municipal de Chocont\u00e1, manifest\u00f3 que &nbsp;\u00ablas &nbsp;decisiones controvertidas [\u2026] se resolvieron con la debida &nbsp;argumentaci\u00f3n f\u00e1ctica y jur\u00eddica, con valoraci\u00f3n &nbsp;probatoria razonada sin que de ellas se pueda derivar [una] presunta &nbsp;vulneraci\u00f3n [\u2026]\u00bb. &nbsp;<\/p>\n<p>2. &nbsp;El Despacho Civil del Circuito de Chocont\u00e1, indic\u00f3 que &nbsp;la determinaci\u00f3n proferida \u2013el 27 de septiembre de 2021 &nbsp;\u00abest\u00e1 &nbsp;debidamente fundamentada y por tanto, [\u2026] no vulner\u00f3 &nbsp;derecho fundamental alguno de la accionante [\u2026]\u00bb. &nbsp;<\/p>\n<p>III. &nbsp;LA SENTENCIA IMPUGNADA &nbsp;<\/p>\n<p>La &nbsp;Sala constitucional a &nbsp;quo &nbsp;deneg\u00f3 el &nbsp;amparo, al considerar que de lo estimado por \u00ablos &nbsp;juzgados civil municipal y civil circuito de Chocont\u00e1, [\u2026] &nbsp;no se advierte capricho o arbitrariedad que deba ser sometido a &nbsp;control constitucional, pues el estudio del proceso permiti\u00f3 a &nbsp;los jueces de conocimiento considerar que deb\u00edan prosperar las &nbsp;excepciones planteadas por la parte ejecutada, dado que en efecto las &nbsp;partes hab\u00edan modificado el contrato de arrendamiento &nbsp;presentado como t\u00edtulo ejecutivo, conclusi\u00f3n a la que &nbsp;llegaron los juzgadores luego de analizar el material probatorio &nbsp;[\u2026]\u00bb. &nbsp;<\/p>\n<p>IV. &nbsp;LA IMPUGNACI\u00d3N &nbsp;<\/p>\n<p>La &nbsp;accionante indic\u00f3 que lo resuelto en primera instancia resulta &nbsp;apartado de la realidad pues, \u00ablo &nbsp;pretendido [\u2026] es precisamente que se revise la incidencia de &nbsp;la valoraci\u00f3n probatoria hecha de manera parcial en la que no &nbsp;se tuvieron en cuenta todos los elementos que arrojaba la realidad &nbsp;procesal, espec\u00edficamente se tuvo en cuenta que la &nbsp;modificaci\u00f3n del contrato de arrendamiento lo fue &nbsp;estrictamente con el valor del canon de arrendamiento, desestimando &nbsp;que con la misma prueba se estableci\u00f3 una modificaci\u00f3n &nbsp;del plazo [\u2026]\u00bb. &nbsp;<\/p>\n<p>V. &nbsp;CONSIDERACIONES &nbsp;<\/p>\n<p>1. &nbsp;En el sub &nbsp;examine, &nbsp;corresponde a la Sala establecer si las autoridades cuestionadas &nbsp;vulneraron el derecho fundamental alegado por la tutelante. Ello &nbsp;pues, estim\u00f3 que no se realiz\u00f3 una valoraci\u00f3n &nbsp;completa de los medios de convicci\u00f3n decretados y practicados &nbsp;al interior de la causa ejecutiva. &nbsp;<\/p>\n<p>2. &nbsp;Sobre &nbsp;el particular, se observa que la &nbsp;autoridad acusada -con providencia del 27 de septiembre de 2021- &nbsp;expres\u00f3 los motivos por los cuales resolvi\u00f3 confirmar &nbsp;la decisi\u00f3n de primer grado. Para ello, comenz\u00f3 &nbsp;por indicar la regulaci\u00f3n comercial que rige el contrato de &nbsp;arrendamiento \u2013renovaci\u00f3n, desahucio, indemnizaci\u00f3n &nbsp;al arrendatario, subarriendo y cesi\u00f3n- y la definici\u00f3n &nbsp;que para este estructura el C\u00f3digo Civil. Por lo anterior, &nbsp;expuso que tanto en el \u00abcontrato &nbsp;de arrendamiento civil como comercial\u00bb, &nbsp;no es exigible ninguna formalidad adicional \u00abal &nbsp;mero acuerdo de voluntades entre arrendador y arrendatario, &nbsp;igualmente lo ser\u00e1 aquellas modificaciones que sobre esos &nbsp;elementos esenciales y tambi\u00e9n accesorios las partes &nbsp;acuerden\u00bb. Por &nbsp;tanto, resalt\u00f3 que las partes &nbsp;\u00abtienen libertad probatoria para acreditar la existencia de &nbsp;aquellos elementos esenciales -y accesorios- del contrato de &nbsp;arrendamiento, as\u00ed como para probar las modificaciones que en &nbsp;el curso del tiempo -recu\u00e9rdese que el contrato de &nbsp;arrendamiento es adem\u00e1s de tracto sucesivo- se acuerden\u00bb. &nbsp;<\/p>\n<p>2.1. &nbsp;En relaci\u00f3n con el material probatorio practicado al interior &nbsp;de la causa, indic\u00f3 que las partes concuerdan \u00abque &nbsp;para el mes de mayo de 2018 \u2013previo al vencimiento del t\u00e9rmino &nbsp;de duraci\u00f3n del contrato de arrendamiento inicial-, se &nbsp;efectuaron conversaciones entre el representante legal de la &nbsp;[demandante] y Norberto Rodr\u00edguez Rodr\u00edguez \u2013Analista &nbsp;costos de ocupaci\u00f3n de la Direcci\u00f3n Servicios Gesti\u00f3n &nbsp;de Activos-\u00bb, de &nbsp;lo que acordaron &nbsp;\u00abque el contrato se renovar\u00eda por 5 cinco a\u00f1os &nbsp;m\u00e1s, que el canon de arrendamiento durante los meses de julio &nbsp;de 2018 hasta junio de 2019 ser\u00eda por $11.300.000, de julio de &nbsp;2019 hasta junio de 2020 lo ser\u00eda por $9.200.000 y para el &nbsp;tercer a\u00f1o luego de la renovaci\u00f3n, esto es el de junio &nbsp;de 2020 a julio de 2021 se revisar\u00edan las condiciones de &nbsp;acuerdo al comportamiento de ventas y resultados del almac\u00e9n\u00bb. &nbsp;Al &nbsp;respecto, rese\u00f1\u00f3 que lo descrito result\u00f3 el &nbsp;aspecto b\u00e1sico en el que se fund\u00f3 la apelaci\u00f3n, &nbsp;ya que \u00ab[\u2026] &nbsp;la modificaci\u00f3n en cuesti\u00f3n y del modo en c\u00f3mo &nbsp;fue interpretada por el a quo se tratar\u00eda de una novaci\u00f3n\u00bb. &nbsp;Frente &nbsp;a ello, y con fundamento en el art\u00edculo 1687 del C\u00f3digo &nbsp;Civil y precedente de esta Sala, estim\u00f3 que \u00abno &nbsp;cabe duda que [\u2026] Almacenes \u00c9xito S.A., como &nbsp;arrendatario y la sociedad demandante como arrendadora, en las &nbsp;negociaciones que tuvieron lugar en el mes de mayo de 2018 no hubo &nbsp;novaci\u00f3n alguna como lo consider\u00f3 el a quo y como &nbsp;err\u00f3neamente lo pretende hacer valer el apelante\u00bb. &nbsp;<\/p>\n<p>2.2. &nbsp;Para explicar lo descrito, resalt\u00f3 que el representante legal &nbsp;de la actora reconoci\u00f3 \u00aben &nbsp;su interrogatorio, que el objeto de aquella reuni\u00f3n con [\u2026] &nbsp;Norberto Rodr\u00edguez, no era otro que la ampliaci\u00f3n del &nbsp;plazo o renovaci\u00f3n por 5 a\u00f1os del contrato de &nbsp;arrendamiento inicialmente suscrito por los contratantes\u00bb. &nbsp;Adem\u00e1s, indic\u00f3 que el recurrente refiri\u00f3 que \u00abno &nbsp;pod\u00eda darse valor a aquellas negociaciones ni tenerlas como un &nbsp;verdadero acuerdo modificatorio de las condiciones del contrato &nbsp;inicial, pues en todo caso Norberto Rodr\u00edguez Rodr\u00edguez &nbsp;no era ni es representante legal de la demandada\u00bb. En &nbsp;el punto, especific\u00f3 lo decidido por el juez de primer grado, &nbsp;quien anot\u00f3 que la persona citada actu\u00f3 como &nbsp;\u00abrepresentante aparente en los t\u00e9rminos del art\u00edculo &nbsp;842 del C\u00f3digo de Comercio\u00bb. &nbsp;<\/p>\n<p>2.3. &nbsp;Por otra parte, examin\u00f3 lo mencionado por la gestora, &nbsp;referente a que Rodriguez Rodr\u00edguez \u00aby &nbsp;Pedro Arias son [testigos] sospechosos \u2013como quiera que son &nbsp;empleados de la demandada-\u00bb. &nbsp;De cara a ello, fundado en el art\u00edculo 211 y la jurisprudencia &nbsp;de esta Sala, analiz\u00f3 que del dicho de ambos \u00abtestigos, &nbsp;no se evidencia \u00e1nimo alguno de favorecer deliberadamente a la &nbsp;parte demandada o por perjudicar a la demandante. Por el contrario, &nbsp;sus declaraciones son coincidentes con las dem\u00e1s pruebas aqu\u00ed &nbsp;recaudadas, especialmente con el interrogatorio de parte rendido por &nbsp;el representante legal de [la demandante]\u00bb. &nbsp;Ello se ratific\u00f3 en \u00abel &nbsp;correo electr\u00f3nico de 24 de mayo de 2018 [\u2026], y que fue &nbsp;remitido [a las cuentas electr\u00f3nicas de la demandante], &nbsp;donde se relacionaron los acuerdos suscritos entre ambas partes. Por &nbsp;lo tanto, concluy\u00f3 que \u00abhabr\u00e1 &nbsp;de darse credibilidad a las declaraciones de los testigos Norberto &nbsp;Rodriguez y Pedro Arias y que, por tanto, la tacha de sospecha &nbsp;formulada [\u2026] no tiene vocaci\u00f3n de prosperidad\u00bb. &nbsp;<\/p>\n<p>2.4. &nbsp;Ahora, en referencia con la representaci\u00f3n aparente &nbsp;considerada por el juez a &nbsp;quo, &nbsp;anot\u00f3 que se \u00abencuentra &nbsp;acreditado que en efecto Norberto Rodr\u00edguez Rodr\u00edguez, &nbsp;aunque no ostentaba \u2013ni ostenta en la actualidad- la calidad de &nbsp;representante legal de la sociedad demandada, \u00e9l al interior &nbsp;de la compa\u00f1\u00eda se encarga de la administraci\u00f3n &nbsp;de los contratos de arrendamiento sin necesidad de solicitar &nbsp;autorizaci\u00f3n alguna a otros directivos de Almacenes \u00c9xito &nbsp;S.A., ni mucho menos a su representante legal\u00bb6. &nbsp;Adem\u00e1s, discurri\u00f3 que \u00abaunque &nbsp;convenientemente en su declaraci\u00f3n el representante legal de &nbsp;la demandante, se\u00f1ala que el convenio verbalmente con Norberto &nbsp;Rodr\u00edguez no es v\u00e1lido por cuanto no era el &nbsp;representante legal de Almacenes \u00c9xito S.A., porque no se &nbsp;hab\u00eda elevado por escrito, sin embargo, aqu\u00ed ha quedado &nbsp;acreditado que Norberto Rodr\u00edguez s\u00ed ten\u00eda la &nbsp;capacidad de negociar las condiciones y\/o modificaciones del contrato &nbsp;inicial y que en efecto existi\u00f3 un acuerdo de voluntades entre &nbsp;las partes en cuanto a la renovaci\u00f3n del plazo por 5 a\u00f1os &nbsp;m\u00e1s y en modificar el valor del canon de arrendamiento, &nbsp;haciendo falta \u00fanicamente la \u201cformalizaci\u00f3n\u201d &nbsp;del aquel acuerdo elev\u00e1ndolo a escrito a trav\u00e9s de &nbsp;\u201cotrosi\u201d\u00bb. &nbsp;Aunque, ello tampoco es determinante, dado que \u00abno &nbsp;es un contrato solemne\u00bb. &nbsp;<\/p>\n<p>2.5. &nbsp;Tocante con la \u00abinasistencia &nbsp;del representante legal de la sociedad demandada a la audiencia &nbsp;concentrada programada por el a quo y desarrollada el 13 de julio de &nbsp;2021, trae como consecuencia la confesi\u00f3n ficta en los &nbsp;t\u00e9rminos del art\u00edculo 372 del C.G.P. de los hechos &nbsp;susceptibles de confesi\u00f3n contenidos en la demanda\u00bb, &nbsp;destac\u00f3 que dicha confesi\u00f3n es \u00abde &nbsp;tipo legal y por ende admite prueba en contrario\u00bb. &nbsp;Particularmente, se consider\u00f3 \u00absusceptible &nbsp;de confesi\u00f3n el [\u2026] hecho 7\u00b0 en el que se refiere &nbsp;que, la demandada incumpli\u00f3 su obligaci\u00f3n de pagar el &nbsp;canon de arrendamiento completo a partir del mes de julio de 2018 y &nbsp;hasta el mes de octubre de ese mismo a\u00f1o, y el hecho 9\u00b0 &nbsp;que refiere que para el 2019 -fecha de entrega del inmueble\u2013 el &nbsp;canon de arrendamiento ascend\u00eda a [\u2026] $20.978.616\u00bb. &nbsp;Al &nbsp;respecto, estim\u00f3 que \u00ab[\u2026] &nbsp;se encuentra del todo desvirtuada, pues de acuerdo a las pruebas [\u2026] &nbsp;valoradas, se tiene que para aquellos meses las partes modificaron &nbsp;verbalmente entre otras el valor del canon de arrendamiento, que en &nbsp;virtud de aquel acuerdo la demandante expidi\u00f3 las facturas &nbsp;Nos. 2237 &nbsp;-julio 2018-, 2260 -agosto 2018-, 2286 -septiembre 2018- y 2309 &nbsp;-octubre 2018-, cada una por la suma $11.300.000 (aportadas por la &nbsp;demandada y obrantes a r\u00f3tulo 009) y que aquellas fueron &nbsp;debidamente canceladas -as\u00ed incluso lo confes\u00f3 el &nbsp;demandante en su interrogatorio-\u00bb. De &nbsp;cara a los dem\u00e1s hechos, advirti\u00f3 que \u00abcuentan &nbsp;con prueba documental aportada por el mismo demandante \u2013como la &nbsp;suscripci\u00f3n del contrato en el 2013, la destinaci\u00f3n del &nbsp;local comercial, el otros\u00ed del a\u00f1o 2015, la terminaci\u00f3n &nbsp;del contrato, y la fecha de entrega- y as\u00ed los tuvo por &nbsp;probados el a quo\u00bb. &nbsp;<\/p>\n<p>3. &nbsp;De lo transcrito, esta Sala -en su calidad de juez constitucional- &nbsp;advierte que la acci\u00f3n no tiene vocaci\u00f3n de &nbsp;prosperidad. Y, por tanto, la providencia impugnada deber\u00e1 &nbsp;confirmarse. En efecto, con independencia de que se compartan o no &nbsp;todas las conclusiones del Juzgado atacado, para esta Corporaci\u00f3n, &nbsp;la decisi\u00f3n cuestionada no podr\u00eda recibirse como &nbsp;irrazonable. &nbsp;Ello &nbsp;pues, fue proferida por el juzgador natural, sirvi\u00e9ndose de un &nbsp;an\u00e1lisis normativo del tema y de una valoraci\u00f3n &nbsp;razonable &nbsp;de &nbsp;los medios de convicci\u00f3n aportados (documentales y &nbsp;testimonios). &nbsp;<\/p>\n<p>3.1. &nbsp;Para esta Sala Civil, el juez constitucional no es el llamado a &nbsp;intervenir a manera de autoridad de instancia para establecer cu\u00e1les &nbsp;de los planteamientos expuestos resultan ser los m\u00e1s &nbsp;acertados. Y, &nbsp;tampoco, para ordenar una determinada apreciaci\u00f3n o valoraci\u00f3n &nbsp;de los elementos demostrativos obrantes en el expediente. &nbsp;En &nbsp;el punto, es necesario destacar que el juez de tutela s\u00f3lo &nbsp;interviene en la \u00abesfera &nbsp;probatoria\u00bb, &nbsp;cuando el \u00aberror &nbsp;en el juicio valorativo\u00bb &nbsp;sea ostensible, flagrante, manifiesto y con incidencia directa en la &nbsp;decisi\u00f3n, cuya ocurrencia no se advierte en el sub &nbsp;examine, &nbsp;pues no se observa un juicio il\u00f3gico o contraevidente del &nbsp;material probatorio7. &nbsp;<\/p>\n<p>3.2. &nbsp;En una palabra, esta Sala ha sostenido reiteradamente8 &nbsp;que el juez constitucional, en principio, no se ocupa de la &nbsp;valoraci\u00f3n y apreciaci\u00f3n de las probanzas, pues, se &nbsp;insiste, ello ata\u00f1e al juez natural -con su respectiva &nbsp;independencia-9. &nbsp;<\/p>\n<p>5. &nbsp;Por &nbsp;lo considerado, se confirmar\u00e1 el fallo impugnado. &nbsp;<\/p>\n<p>VI. &nbsp;DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Sala de Casaci\u00f3n Civil de la &nbsp;Corte Suprema de Justicia, administrando justicia en nombre de la &nbsp;Rep\u00fablica y por autoridad de la ley, CONFIRMA &nbsp;la sentencia de fecha, contenido y procedencia puntualizados en la &nbsp;motivaci\u00f3n que antecede. &nbsp;<\/p>\n<p>Comun\u00edquese &nbsp;esta providencia a los interesados en la forma prevista por el &nbsp;art\u00edculo 30 del Decreto 2591 de 1991. Oportunamente, rem\u00edtase &nbsp;el expediente a la Corte Constitucional para su eventual revisi\u00f3n. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>Presidente &nbsp;de Sala &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>(Ausencia &nbsp;Justificada) &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>1\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Folios &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2 a 7 del archivo PDF \u00ab0001 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Demanda Anexos\u00bb. &nbsp;<\/p>\n<p>2\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Archivo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;PDF \u00ab0007 Mandamiento\u00bb. &nbsp;<\/p>\n<p>3\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Folios 3 a 13 Archivo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;PDF \u00ab0009Contestacion\u00bb. &nbsp;<\/p>\n<p>4\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Archivo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;PDF \u00ab0032ActaAudiencia\u00bb. &nbsp;<\/p>\n<p>5\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Archivo PDF \u00ab0045 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Sentencia 2021-134 Ejecutivo, Confirma\u00bb. &nbsp;<\/p>\n<p>6\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Tocante &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;con la figura de la representaci\u00f3n aparente, se destac\u00f3 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;la sentencia SC11815-2016 de la Sala Civil de la Corte Suprema de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Justicia. &nbsp;<\/p>\n<p>7\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Esto es, en el caso concreto, no se advierte ni defecto f\u00e1ctico &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;en su dimensi\u00f3n positiva (CC T 916 -2008), ni defecto f\u00e1ctico &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;en su dimensi\u00f3n negativa (por un lado, CC sentencias C-548 de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;1997, C-874 de 2003 y C- 102 de 2005, por otro, CC T 949-003 y CC T &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;264-2009). &nbsp;<\/p>\n<p>8\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;CSJ STC 12201-2021, CSJ STC 11453-2021, CSJ STC 1218-2021, CSJ STC &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;9218-2021, CSJ STC2870-2021, CSJ STC 1551-2021, CSJ STC 492-2021, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;CSJ STC 6617-2021, CSJ STC 5632-2021, CSJ STC 11453-2021, CSJ STC &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;10575-2021, CSJ STC 8446-2021, CSJ STC 8187-2021, &nbsp;CSJ STC &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;7607-2021, CSJ STC 7609-2021, CSJ STC 7076-2021, CSJ STC 6617-2021, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;CSJ STC 6529-2021, CSJ STC 6398-2021, &nbsp;CSJ STC 6402-2021, CSJ STC &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2870-2021, CSJ STC &nbsp;11365-2020, CSJ STC 071-2021, CSJ STC 3903-2021, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;CSJ STC 942-2021, &nbsp;CSJ STC 7663-2020, CSJ STC 7483-2020, CSJ STC &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;7520-2021, CSJ STC 5668-2021, CSJ STC 5379-2021, CSJ STC &nbsp;3980-2021, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;CSJ STC 10673-2021, CSJ STC 1453-2021, CSJ STC &nbsp;10575-2021. &nbsp;<\/p>\n<p>9\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Al &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;respecto, \u00abel &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;campo en donde fluye la independencia del juez con mayor vigor es en &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;cuanto a la valoraci\u00f3n de las pruebas. Ello por cuanto el &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;administrador de justicia es quien puede apreciar y valorar, de la &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;manera m\u00e1s certera, el material probatorio que obra dentro de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;un proceso, inspir\u00e1ndose en los principios cient\u00edficos &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;de la sana cr\u00edtica; por lo tanto, a juicio de la Corte, la &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;regla general de que la figura de la v\u00eda de hecho solamente &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;puede tener una aplicaci\u00f3n en situaciones extremas debe ser &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;manejada con un criterio restrictivo (&#8230;) de forma que s\u00f3lo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;es factible fundar una acci\u00f3n de tutela, cuando se observa en &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;el caso concreto, que de manera manifiesta el operador jur\u00eddico &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;ejecuta un juicio irrazonable o arbitrario sobre la valoraci\u00f3n &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;probatoria por fuera de las reglas b\u00e1sicas de realizaci\u00f3n, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;pr\u00e1ctica y apreciaci\u00f3n, las cuales se reflejan en la &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;correspondiente providencia. El error en el juicio valorativo, ha &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;dicho esta Corte, debe ser de tal entidad que debe ser ostensible, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;flagrante, manifiesto y el mismo debe poseer una incidencia directa &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;en la decisi\u00f3n\u00bb (CSJ &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;STC, 7065-2019, 5 jun., rad. 2019-01590-00, reiterada en &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;STC8884-2020, 22 oct., rad. 2020-02553-00, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;STC 2462-2021, 12 de marzo de 2021, entre otras). &nbsp;<\/p>\n<p>10\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Sobre &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;el particular, la Sala ha sostenido, de un lado, que \u00abel &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;juez de tutela no es el llamado a intervenir a manera de \u00e1rbitro &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;para determinar cu\u00e1les de los planteamientos valorativos y &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;hermen\u00e9uticas del juzgador, o de las partes, resultan ser los &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;m\u00e1s acertados, y menos acometer, bajo ese pretexto, como lo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;pretende la actora, la revisi\u00f3n oficiosa del asunto, como si &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;fuese uno de instancia\u00bb &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;(CSJ &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;STC.7 mar. 2008, Rad. 2007-00514-01 Reiterada en CSJ STC 4454. 15 de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;jul. 2020); &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;y, de otro, que \u00abla &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;adversidad de la decisi\u00f3n no es por s\u00ed misma &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;fundamento que le allane el camino al vencido para perseverar en sus &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;discrepancias frente a lo resuelto por el juez natural\u00bb &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;(CSJ &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;STC 28 mar. 2012, Rad. 00022-01, CSJ STC 3446- 2020, reiterada en &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;STC2462-2021, 12 de marzo de 2021). &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC6442-2022 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; FRANCISCO &nbsp;TERNERA BARRIOS &nbsp; Magistrado &nbsp;Ponente &nbsp; STC6442-2022 &nbsp; Radicaci\u00f3n &nbsp;n.\u00b0 25000-22-13-000-2022-00121-01 &nbsp; (Aprobado &nbsp;en sesi\u00f3n de veinticinco de mayo de dos mil veintid\u00f3s) &nbsp; Bogot\u00e1 &nbsp;D.C., veinticinco (25) de mayo de dos mil veintid\u00f3s (2022). &nbsp; La &nbsp;Corte decide la impugnaci\u00f3n interpuesta frente a la &nbsp;sentencia &nbsp;proferida por &nbsp;la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-63801","post","type-post","status-publish","format-standard","hentry","category-mayo-2022"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=63801"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63801\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=63801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=63801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=63801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}