{"id":67576,"date":"2024-05-20T21:00:58","date_gmt":"2024-05-20T21:00:58","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/ac4633-2022-2022-03295-00\/"},"modified":"2024-05-20T21:00:58","modified_gmt":"2024-05-20T21:00:58","slug":"ac4633-2022-2022-03295-00","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/ac4633-2022-2022-03295-00\/","title":{"rendered":"AC 4633 2022"},"content":{"rendered":"<p>AC4633-2022 (2022-03295-00)<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>AC4633-2022 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n. &nbsp;11001-02-03-000-2022-03295-00 &nbsp;<\/p>\n<p>Bogot\u00e1 &nbsp;D.C., once (11) de octubre de dos mil veintid\u00f3s (2022). &nbsp;<\/p>\n<p>Se resuelve el &nbsp;conflicto de competencia suscitado entre los Juzgados Veintiuno Civil &nbsp;Municipal de Bogot\u00e1 D.C., y Octavo Civil Municipal de Pereira &nbsp;(Risaralda), &nbsp;con ocasi\u00f3n del conocimiento de la demanda ejecutiva promovida &nbsp;por la sociedad AECSA S.A., contra Carlos Andr\u00e9s Espitia &nbsp;Arag\u00f3n. &nbsp;<\/p>\n<p>I. &nbsp; &nbsp; &nbsp; &nbsp;ANTECEDENTES &nbsp;<\/p>\n<p>1.- &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;La &nbsp;parte actora solicit\u00f3 librar mandamiento de pago respecto del &nbsp;pagar\u00e9 n.\u00b0 6023638, por la suma de $40\u00b4453.376.oo &nbsp;como capital insoluto de la obligaci\u00f3n, &nbsp;junto con los &nbsp;intereses moratorios causados a partir de su fecha de exigibilidad. &nbsp;<\/p>\n<p>En cuanto a la &nbsp;competencia, indic\u00f3 que le correspond\u00eda al Juzgado de &nbsp;esta ciudad, \u00abpor &nbsp;la cuant\u00eda citada y el lugar de cumplimiento de las &nbsp;obligaciones, conforme al numeral 4 del [a]rt\u00edculo 28 del &nbsp;[C.G.P.] &nbsp;(\u2026)\u00bb.&nbsp; &nbsp;<\/p>\n<p>2.- &nbsp; &nbsp; &nbsp; &nbsp;El &nbsp;escrito inicial se asign\u00f3 al Juzgado Veintiuno &nbsp;Civil Municipal de Bogot\u00e1 D.C., quien &nbsp;mediante providencia calendada el 29 &nbsp;de julio de 2022, rechaz\u00f3 la demanda por falta de competencia &nbsp;territorial, &nbsp;tras argumentar que el convocado &nbsp;tiene como domicilio la ciudad de Pereira &nbsp;(Risaralda); &nbsp;por lo tanto, de conformidad con lo previsto en el numeral 1\u00b0 del &nbsp;art\u00edculo 28 del C\u00f3digo General del Proceso, los jueces &nbsp;de esa localidad son los competentes para conocer de la acci\u00f3n &nbsp;instaurada. &nbsp;<\/p>\n<p>De &nbsp;otro lado, asegur\u00f3 que el numeral 3\u00b0 del art\u00edculo &nbsp;en cita no es aplicable a este caso, toda vez que dicho precepto se &nbsp;refiere \u00fanicamente controversias relacionadas con contratos, &nbsp;m\u00e1s no a t\u00edtulos valores. De suerte que al allegarse &nbsp;como base de recaudo un pagar\u00e9, el mentado canon no resulta &nbsp;procedente. &nbsp;<\/p>\n<p>3.- &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Cumplidos &nbsp;los tr\u00e1mites pertinentes, el expediente se remiti\u00f3 al &nbsp;Juzgado &nbsp;Octavo &nbsp;Civil Municipal de Pereira, el cual, en &nbsp;auto del 1\u00ba de septiembre de 2022, resolvi\u00f3 no avocar &nbsp;conocimiento del asunto y, en consecuencia, promovi\u00f3 el &nbsp;conflicto negativo. &nbsp;<\/p>\n<p>Para sustentar su &nbsp;aserto, explic\u00f3 que del &nbsp;cartular aportado se desprende con claridad que el lugar de &nbsp;cumplimiento de la obligaci\u00f3n es la ciudad de Bogot\u00e1, &nbsp;por lo que, evidentemente, la parte actora hizo uso de la atribuci\u00f3n &nbsp;conferida por el art\u00edculo 28 del C.G.P., ante la existencia de &nbsp;dos fueros concurrentes, el general de que trata el numeral 1\u00ba &nbsp;ejusdem, &nbsp;y &nbsp;el especial para los negocios jur\u00eddicos o que involucren &nbsp;t\u00edtulos ejecutivos del numeral 3\u00ba \u00eddem, &nbsp;optando &nbsp;por el segundo para el tr\u00e1mite de la ejecuci\u00f3n a su &nbsp;favor; por ende, el juzgador primigenio no debi\u00f3 rehusar la &nbsp;competencia. &nbsp;<\/p>\n<p>4.- &nbsp; &nbsp; &nbsp; &nbsp;As\u00ed &nbsp;las cosas, se pasa a resolver lo que corresponda previas las &nbsp;siguientes, &nbsp;<\/p>\n<p>II. &nbsp; &nbsp; &nbsp; &nbsp;CONSIDERACIONES &nbsp;<\/p>\n<p>1.- &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Como &nbsp;el conflicto planteado involucra dos juzgados de diferente distrito &nbsp;judicial, Bogot\u00e1 y Pereira, el superior funcional com\u00fan &nbsp;a ambos es esta Sala de la Corte, quien es la competente para &nbsp;resolverlo, de conformidad con lo estipulado en los art\u00edculos &nbsp;139 del C\u00f3digo General del Proceso y 16 de la Ley 270 de 1996, &nbsp;modificado por el art\u00edculo 7 de la Ley 1285 de 2009. &nbsp;<\/p>\n<p>2.- &nbsp; &nbsp; &nbsp; &nbsp;De &nbsp;las pautas de competencia territorial consagradas por el art\u00edculo &nbsp;28 del C\u00f3digo General del Proceso, el numeral 1\u00ba &nbsp;constituye la regla general, cual es que \u00ab[e]n &nbsp;los &nbsp;procesos contenciosos, salvo disposici\u00f3n legal en contrario, &nbsp;es &nbsp;competente el juez del domicilio del demandado &nbsp;(\u2026)\u00bb &nbsp;(se &nbsp;subraya).&nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>Sin embargo, &nbsp;cuando se trata de \u00abprocesos &nbsp;originados en un negocio jur\u00eddico o que involucren &nbsp;t\u00edtulos ejecutivos es tambi\u00e9n competente el juez del &nbsp;lugar de cumplimiento de cualquiera de las obligaciones. &nbsp;La estipulaci\u00f3n de domicilio contractual para efectos &nbsp;judiciales se tendr\u00e1 por no escrita\u00bb &nbsp;(num. 3 \u00eddem, &nbsp;subraya externa).&nbsp; &nbsp;<\/p>\n<p>Por lo tanto, ante &nbsp;esas dos opciones (de &nbsp;id\u00e9ntica jerarqu\u00eda) &nbsp;le corresponde a la parte actora elegir el factor que determine la &nbsp;competencia jurisdiccional, mismo que, una vez escogido por el &nbsp;interesado, lo torna inmodificable frente al juez que conoce el &nbsp;escrito introductorio (AC2738, 5 may. 2016, rad. 2016-00873-00, &nbsp;reiterado en AC5781-2021).&nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>Entonces, para &nbsp;fijar la competencia en demandas nacidas de un negocio jur\u00eddico &nbsp;o que comprendan t\u00edtulos ejecutivos [o valores], existen dos &nbsp;fueros concurrentes, el general del domicilio de la parte convocada y &nbsp;el del cumplimiento de cualquiera de las obligaciones. As\u00ed las &nbsp;cosas, teniendo en cuenta que ninguno prevalece sobre el otro, la &nbsp;potestad de elecci\u00f3n recae exclusivamente en el actor y no &nbsp;puede ser desconocida por el servidor judicial ante quien se promueva &nbsp;la acci\u00f3n. &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>Sobre este punto, &nbsp;la Corporaci\u00f3n ha explicado que el demandante, con fundamento &nbsp;en los actos jur\u00eddicos de \u00abalcance &nbsp;bilateral o en un t\u00edtulo ejecutivo tiene la opci\u00f3n de &nbsp;accionar, &nbsp;[ad libitum], &nbsp;en uno u otro lugar, o sea, en el domicilio de la contraparte o donde &nbsp;el pacto objeto de discusi\u00f3n o t\u00edtulo de ejecuci\u00f3n &nbsp;deb\u00eda cumplirse; pero, ins\u00edstese, ello queda, en &nbsp;principio, a la determinaci\u00f3n expresa de su promotor\u00bb &nbsp;(AC4412, &nbsp;13 jul. 2016, rad. 2016-01858-00, reiterado en AC5781-2021).&nbsp; &nbsp;<\/p>\n<p>3.- &nbsp; &nbsp; &nbsp; &nbsp;En &nbsp;el caso en estudio, la &nbsp;sociedad AECSA &nbsp;S.A. &nbsp;acudi\u00f3 ab &nbsp;initio &nbsp;ante los jueces de Bogot\u00e1 D.C., bajo la consideraci\u00f3n &nbsp;de ser all\u00ed el lugar de \u00abcumplimiento &nbsp;de las obligaciones\u00bb, &nbsp;con fundamento en la prorrogativa contenida en el numeral 3\u00ba del &nbsp;art\u00edculo 28 del C\u00f3digo General del Proceso. &nbsp;<\/p>\n<p>Siendo as\u00ed, &nbsp;nuevamente se destaca que, en este evento, la facultad de escoger &nbsp;entre los fueros general y especial (num. 1\u00ba y 3\u00ba, art. 28 &nbsp;del C.G.P.), se reserva a quien impetra la acci\u00f3n, por lo que &nbsp;esta Corporaci\u00f3n se encuentra compelida a respetar la &nbsp;determinaci\u00f3n que en tal sentido adopt\u00f3 la sociedad &nbsp;ejecutante que, en este caso particular, opt\u00f3 por el lugar de &nbsp;cumplimiento de la obligaci\u00f3n; es decir, Bogot\u00e1. &nbsp;<\/p>\n<p>4.- &nbsp; &nbsp; &nbsp; &nbsp;Finalmente, &nbsp;no es de recibo el argumento esgrimido por la juzgadora primigenia, &nbsp;al sostener que el numeral 3\u00b0 del art\u00edculo 28 del C\u00f3digo &nbsp;General del Proceso no es aplicable a los t\u00edtulos valores sino &nbsp;\u00fanicamente a los contratos, pues como ya lo ha explicado en &nbsp;innumerables oportunidades esta Corte, la norma procede frente a toda &nbsp;clase de negocios jur\u00eddicos, as\u00ed como de t\u00edtulos &nbsp;ejecutivos o valores. &nbsp;<\/p>\n<p>Sobre el &nbsp;particular, en reciente pronunciamiento de similares contornos se &nbsp;indic\u00f3: &nbsp;<\/p>\n<p>En &nbsp;adici\u00f3n, de destacar que esta &nbsp;regla legal alude no s\u00f3lo a los procesos originados en &nbsp;negocios jur\u00eddicos -de los cuales s\u00ed es fiel reflejo el &nbsp;otorgamiento de t\u00edtulos-valores-, &nbsp;sino tambi\u00e9n a los t\u00edtulos ejecutivos, que constituyen &nbsp;el g\u00e9nero al paso que los t\u00edtulos-valores bien podr\u00edan &nbsp;denominarse como una especie, en &nbsp;la medida en que todo t\u00edtulo valor es t\u00edtulo ejecutivo. &nbsp;<\/p>\n<p>Por &nbsp;ende, es &nbsp;inadmisible el argumento del estrado judicial de la capital de la &nbsp;rep\u00fablica al pretender apartarse del conocimiento del asunto, &nbsp;porque si bien el domicilio del ejecutado se encuentra en &nbsp;Barranquilla, el &nbsp;lugar donde deb\u00eda realizarse el pago del mutuo es la ciudad de &nbsp;Bogot\u00e1, seg\u00fan se desprende del tenor literal del pagar\u00e9 &nbsp;suscrito, y ante la existencia de fueros concurrentes, el convocante &nbsp;escogi\u00f3 incoar su libelo ejecutivo ante los jueces del lugar &nbsp;pactado para el cumplimiento de la obligaci\u00f3n plasmada en ese &nbsp;instrumento cartular. &nbsp;(AC2594, &nbsp;21 jun. 2022, rad. 2022-01982-00) (resaltado ajeno al texto).&nbsp; &nbsp;<\/p>\n<p>5.- &nbsp; &nbsp; &nbsp; &nbsp;De &nbsp;conformidad con lo anterior, la competencia queda establecida en el &nbsp;Juzgado Veintiuno &nbsp;Civil Municipal de Bogot\u00e1 D.C., quien ser\u00e1 el encargado &nbsp;de conocer y tramitar la acci\u00f3n ejecutiva presentada. &nbsp;<\/p>\n<p>III. DECISI\u00d3N &nbsp;<\/p>\n<p>En m\u00e9rito &nbsp;de lo expuesto, la Corte Suprema de Justicia, Sala de Casaci\u00f3n &nbsp;Civil, &nbsp;<\/p>\n<p>RESUELVE: &nbsp;<\/p>\n<p>PRIMERO: &nbsp; &nbsp; &nbsp; &nbsp;Declarar &nbsp;que &nbsp;el Juzgado &nbsp;Veintiuno Civil Municipal de Bogot\u00e1 D.C., &nbsp;es &nbsp;el competente para conocer el asunto. &nbsp;<\/p>\n<p>SEGUNDO: &nbsp; &nbsp; &nbsp; &nbsp;Remitir &nbsp;el expediente a la se\u00f1alada autoridad judicial, para que &nbsp;avoque el conocimiento e &nbsp;imparta el tr\u00e1mite correspondiente. &nbsp;<\/p>\n<p>TERCERO: &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Comunicar &nbsp;esta decisi\u00f3n al Juzgado Octavo &nbsp;Civil Municipal de Pereira, &nbsp;as\u00ed &nbsp;como a la promotora del tr\u00e1mite. &nbsp;<\/p>\n<p>Notif\u00edquese &nbsp;y C\u00famplase, &nbsp;<\/p>\n<p>MARTHA PATRICIA &nbsp;GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Magistrada &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>AC4633-2022 (2022-03295-00) &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; AC4633-2022 &nbsp; Radicaci\u00f3n &nbsp;n. &nbsp;11001-02-03-000-2022-03295-00 &nbsp; Bogot\u00e1 &nbsp;D.C., once (11) de octubre de dos mil veintid\u00f3s (2022). &nbsp; Se resuelve el &nbsp;conflicto de competencia suscitado entre los Juzgados Veintiuno Civil &nbsp;Municipal de Bogot\u00e1 D.C., y Octavo Civil Municipal de Pereira &nbsp;(Risaralda), &nbsp;con ocasi\u00f3n del conocimiento de la demanda ejecutiva [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54],"tags":[],"class_list":["post-67576","post","type-post","status-publish","format-standard","hentry","category-octubre-2022"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/67576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=67576"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/67576\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=67576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=67576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=67576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}