{"id":68363,"date":"2024-05-20T21:00:26","date_gmt":"2024-05-20T21:00:26","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/ac5091-2022-2022-03500-00\/"},"modified":"2024-05-20T21:00:26","modified_gmt":"2024-05-20T21:00:26","slug":"ac5091-2022-2022-03500-00","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/ac5091-2022-2022-03500-00\/","title":{"rendered":"AC 5091 2022"},"content":{"rendered":"<p>AC5091-2022 (2022-03500-00)<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>AC5091-2022 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n.\u00b0 11001-02-03-000-2022-03500-00 &nbsp;<\/p>\n<p>Bogot\u00e1 &nbsp;D.C., diez (10) de noviembre de dos mil veintid\u00f3s (2022). &nbsp;<\/p>\n<p>Se &nbsp;decide el conflicto de competencia suscitado entre los Juzgados &nbsp;Sesenta y Cinco Civil Municipal de Bogot\u00e1 y el Primero Civil &nbsp;Municipal de Zipaquir\u00e1, atinente al conocimiento de la demanda &nbsp;declarativa interpuesta por Coltanques S.A.S contra Juan Arturo &nbsp;Torres Lara. &nbsp;<\/p>\n<p>I. &nbsp;ANTECEDENTES &nbsp;<\/p>\n<p>1. En &nbsp;escrito presentado ante el \u00abJUEZ &nbsp;CIVIL MUNICIPAL DE PEQUE\u00d1AS CAUSAS Y COMPETENCIA M\u00daLTIPLE &nbsp;DE BOGOT\u00c1 D.C. (REPARTO)\u00bb, &nbsp;la parte actora reclam\u00f3 de la jurisdicci\u00f3n, entre &nbsp;otras, que se declare que entre las partes existi\u00f3 un contrato &nbsp;de transporte y \u00abque &nbsp;se declare que [el demandado] (\u2026) es solidariamente &nbsp;responsable por el faltante de la mercanc\u00eda, como consecuencia &nbsp;del saqueo presentado en ejecuci\u00f3n de la operaci\u00f3n de &nbsp;transporte realizada (\u2026)\u00bb. &nbsp;Indic\u00f3 que la competencia le concern\u00eda a dicha &nbsp;autoridad judicial, \u00aben &nbsp;virtud de la materia y el asunto de la cuant\u00eda de las &nbsp;pretensiones\u00bb1. &nbsp;<\/p>\n<p>2. El &nbsp;Juzgado Sesenta &nbsp;y Cinco Civil Municipal de Bogot\u00e1 -con &nbsp;prove\u00eddo del 10 de agosto de 2022-, rehus\u00f3 la &nbsp;competencia asignada. Para ello, argument\u00f3 que: &nbsp;<\/p>\n<p>As\u00ed &nbsp;las cosas, como del texto de la demanda y del manifiesto de carga de &nbsp;01\/02\/2020, se advierte que el demandado JUAN ARTURO TORRES LARA, &nbsp;poseedor\/propietario\/tenedor y conductor del veh\u00edculo de &nbsp;placas SRM-523 y Tr\u00e1iler R13128, en el que se ejecut\u00f3 &nbsp;la operaci\u00f3n de transporte, se advierte que tiene su domicilio &nbsp;y\/o lugar de residencia en la ciudad de Zipaquir\u00e1 (Cund), &nbsp;claro es que la competencia por raz\u00f3n del territorio radica en &nbsp;los Jueces Civiles Municipales y\/o Juzgados de Peque\u00f1as Causas &nbsp;y Competencia M\u00faltiple de la citada ciudad, no ante los jueces &nbsp;de Bogot\u00e1. (\u2026) De igual manera, ha de se\u00f1alarse &nbsp;que si bien de conformidad con el numeral 3 del art\u00edculo 28 &nbsp;del CGP, trat\u00e1ndose de procesos originados en un negocio &nbsp;jur\u00eddico o que involucren t\u00edtulos ejecutivos, tambi\u00e9n &nbsp;es competente el juez del lugar del cumplimiento de cualquiera de las &nbsp;obligaciones, tambi\u00e9n lo es que en los textos de los &nbsp;documentos base de la acci\u00f3n no se estipul\u00f3 la ciudad &nbsp;de Bogot\u00e1 como lugar de cumplimiento de la obligaci\u00f3n2. &nbsp;<\/p>\n<p>3. &nbsp;Cumplidos los tr\u00e1mites necesarios, el expediente fue entregado &nbsp;al Despacho Primero Civil Municipal de Zipaquir\u00e1. No obstante, &nbsp;con auto del 19 de septiembre siguiente, manifest\u00f3 que no le &nbsp;correspond\u00eda asumir el conocimiento del asunto. Y promovi\u00f3 &nbsp;el conflicto de competencia que ocupa la atenci\u00f3n de la Corte. &nbsp;Para el efecto, sostuvo que: &nbsp;<\/p>\n<p>(\u2026) &nbsp;este Despacho se abstiene de asumir el conocimiento del comentado &nbsp;proceso, al no compartir los argumentos esbozados por el Juzgado de &nbsp;la capital de la Rep\u00fablica, en virtud de que est\u00e1 &nbsp;confundiendo los conceptos de lugar de residencia y domicilio, &nbsp;situaci\u00f3n que ya la Corte Suprema de Justicia de tiempo &nbsp;inmemorable tiene por decantado. (\u2026) Luego como en anteriores &nbsp;oportunidades lo ha dicho el m\u00e1ximo \u00f3rgano de la &nbsp;jurisdicci\u00f3n ordinaria, si se detecta una incongruencia entre &nbsp;los documentos aportados y el contenido del libelo, lo procedente es &nbsp;dictar auto de inadmisi\u00f3n de la demanda a fin de clarificar la &nbsp;situaci\u00f3n y no partir de supuestos err\u00f3neos como lo es &nbsp;asumir de facto que el domicilio del demandado es distinto al &nbsp;manifestado por el actor en el cuerpo de la demanda3. &nbsp;<\/p>\n<p>4. &nbsp;As\u00ed las cosas, de &nbsp;conformidad al canon &nbsp;139 del C\u00f3digo General del Proceso, se entra a desatar el &nbsp;conflicto propuesto con base en las siguientes, &nbsp;<\/p>\n<p>II. &nbsp;CONSIDERACIONES &nbsp;<\/p>\n<p>1. &nbsp;Corresponde &nbsp;a esta Sala resolver el conflicto negativo suscitado entre los &nbsp;Juzgados de distinto distrito judicial -Bogot\u00e1 y &nbsp;Cundinamarca-, de acuerdo con los art\u00edculos 139 ibidem y 16 de &nbsp;la Ley 270 de 1996, modificado por el 7\u00ba de su par 1285 de 2009. &nbsp;<\/p>\n<p>2. &nbsp;Para &nbsp;la determinaci\u00f3n de la competencia, debe precisarse que la &nbsp;selecci\u00f3n del juez, a quien le corresponde asumir el &nbsp;conocimiento de una causa litigiosa, surge como el resultado de la &nbsp;conjugaci\u00f3n de algunas circunstancias o aspectos subjetivos u &nbsp;objetivos, vinculados, verbigracia, &nbsp;a la persona involucrada, al sitio en donde el accionado tiene su &nbsp;domicilio, al lugar en donde acontecieron los hechos, la cuant\u00eda &nbsp;o naturaleza del asunto, etc. &nbsp;<\/p>\n<p>Por &nbsp;supuesto, se destaca que es el demandante quien cuenta con el &nbsp;beneficio de escoger entre esas posibilidades el fallador que debe &nbsp;pronunciarse sobre el asunto, sin que a este le sea posible alterar &nbsp;tal decisi\u00f3n. As\u00ed lo ha manifestado la Sala, &nbsp;entendiendo que el interesado con fundamento en actos jur\u00eddicos &nbsp;de &nbsp;<\/p>\n<p>(\u2026) &nbsp;alcance bilateral o en un t\u00edtulo ejecutivo tiene la opci\u00f3n &nbsp;de accionar, ad libitum, en uno u otro lugar, o sea, en el domicilio &nbsp;de la contraparte o donde el pacto objeto de discusi\u00f3n o &nbsp;t\u00edtulo de ejecuci\u00f3n deb\u00eda cumplirse; pero, &nbsp;ins\u00edstase, ello &nbsp;queda, en principio, a la determinaci\u00f3n expresa de su &nbsp;promotor. &nbsp;(Se &nbsp;subraya) (AC4412, 13 de julio de 2016, rad. 2016-01858-00; reiterado &nbsp;en AC4020, 24 sept. 2018, rad. 2018-02392-00 y AC3159-2022, 21 jul. &nbsp;2022, rad. 2022-01776-00). &nbsp;<\/p>\n<p>4. &nbsp;Bajo los anteriores lineamientos y en aras de desatar el presente &nbsp;asunto, es del caso resaltar lo que viene. &nbsp;<\/p>\n<p>4.1. &nbsp;En primer lugar, se advierte que el escrito genitor est\u00e1 &nbsp;dirigido al \u00abJUEZ &nbsp;CIVIL MUNICIPAL DE PEQUE\u00d1AS CAUSAS Y COMPETENCIA M\u00daLTIPLE &nbsp;DE BOGOT\u00c1 D.C. (REPARTO)\u00bb, &nbsp;en raz\u00f3n &nbsp;a \u00abla &nbsp;materia y el asunto de la cuant\u00eda de las pretensiones (&#8230;)\u00bb, &nbsp;seg\u00fan lo afirmado en el ac\u00e1pite de competencia. Sin &nbsp;embargo, dicha escogencia no cumple con los criterios de competencia &nbsp;establecidos en el adjetivo procesal civil. Ello por cuanto, la parte &nbsp;demandante omiti\u00f3 dichas reglas de competencia para realizar &nbsp;la designaci\u00f3n del juez que conocer\u00eda de la causa &nbsp;-numerales 1\u00ba y 3\u00ba del art\u00edculo 28 del C\u00f3digo &nbsp;General del Proceso-. &nbsp;<\/p>\n<p>4.2. &nbsp;En ese orden, no aparece en la demanda la manifestaci\u00f3n &nbsp;expresa de la parte actora frente al fallador que debe pronunciarse &nbsp;sobre el asunto. En consecuencia, le correspond\u00eda al Juzgado &nbsp;Sesenta &nbsp;y Cinco Civil Municipal de Bogot\u00e1, D.C., &nbsp;previo a declararse incompetente y con miras a desentra\u00f1ar &nbsp;dicho aspecto, acudir al mecanismo expedito de la &nbsp;inadmisi\u00f3n de la demanda. &nbsp;Ello, a fin de requerir a la promotora para que realice una selecci\u00f3n &nbsp;del factor de atribuci\u00f3n y, de este modo dilucidar toda &nbsp;incertidumbre que sobre el asunto surgi\u00f3. &nbsp;<\/p>\n<p>4.3. &nbsp;En consonancia con lo anterior, deviene que dicha autoridad rehus\u00f3 &nbsp;su conocimiento para conocer del asunto de manera prematura, al no &nbsp;contar con los elementos de juicio suficientes que permitieran &nbsp;esclarecer la situaci\u00f3n anotada. As\u00ed lo ha aseverado &nbsp;esta Corporaci\u00f3n en casos similares, frente a los cuales se ha &nbsp;dicho que: \u00ab(&#8230;) &nbsp;el receptor no puede salirse de los elementos delimitantes expuestos &nbsp;expl\u00edcita o impl\u00edcitamente en la demanda; adem\u00e1s, &nbsp;de no estar clara su determinaci\u00f3n, esta\u0301 en la &nbsp;obligaci\u00f3n de requerir las precisiones necesarias para su &nbsp;esclarecimiento, de manera que se evite su repulsi\u00f3n sobre una &nbsp;base inexistente, propiciando un conflicto antes de tiempo\u00bb &nbsp;(CSJ &nbsp;AC1943-2019, reiterado en AC1251-2022). &nbsp;<\/p>\n<p>4.4. &nbsp;Por otra parte, corresponde recordar al precitado juzgador que, en &nbsp;m\u00faltiples ocasiones la Corte ha dicho que el lugar de &nbsp;domicilio y el destino para notificaciones no pueden confundirse, &nbsp;\u00ab(\u2026) &nbsp;toda vez que uno y otro dato satisfacen exigencias diferentes, pues &nbsp;mientras el primero hace alusi\u00f3n al asiento general de los &nbsp;negocios del convocado a juicio, el segundo \u2013que no siempre &nbsp;coincide con el anterior- se refiere al sitio donde con mayor &nbsp;facilidad se le puede conseguir para efectos de su notificaci\u00f3n &nbsp;personal\u00bb (CSJ, &nbsp;AC3771-2017, reiterado en CSJ, AC1263-2021). &nbsp;<\/p>\n<p>5. &nbsp;Por las razones antedichas, y con relaci\u00f3n a la manera &nbsp;precipitada en que actu\u00f3 el operador con asiento en Bogot\u00e1, &nbsp;se ordenar\u00e1 remitir las presentes diligencias a ese despacho, &nbsp;a fin de que proceda conforme a lo indicado en esta providencia. &nbsp;<\/p>\n<p>III. &nbsp;DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, el suscrito Magistrado de la Sala de &nbsp;Casaci\u00f3n Civil de la Corte Suprema de Justicia, &nbsp;<\/p>\n<p>RESUELVE &nbsp;<\/p>\n<p>PRIMERO: &nbsp;Declarar &nbsp;que el conflicto de competencia planteado es prematuro. &nbsp;<\/p>\n<p>SEGUNDO: &nbsp;Ordenar &nbsp;la devoluci\u00f3n del expediente al Juzgado &nbsp;Sesenta &nbsp;y Cinco Civil Municipal de Bogot\u00e1, D.C. -transitoriamente &nbsp;Juzgado Cuarenta y Siete de Peque\u00f1as Causas y Competencia &nbsp;M\u00faltiple-, &nbsp;para que proceda de conformidad con las consideraciones expuestas. &nbsp;<\/p>\n<p>TERCERO: &nbsp;Comunicar &nbsp;lo decidido al Despacho Primero &nbsp;Civil Municipal de Zipaquir\u00e1, &nbsp;acompa\u00f1\u00e1ndole copia de este prove\u00eddo. &nbsp;<\/p>\n<p>NOT\u00cdFIQUESE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>1\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Archivo \u201c16. DEMANDA21062022_161301\u201d del expediente &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;digital. &nbsp;<\/p>\n<p>2\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Archivo \u201c18. 2022-780 Rechaza demanda por competencia &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;territorial Zipaquir\u00e1\u201d del expediente digital. &nbsp;<\/p>\n<p>3\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Archivo \u201c18. 2022-780 Rechaza demanda x competenc territorial &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Zipaquira\u0301\u201d del expediente digital. &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>AC5091-2022 (2022-03500-00) &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; AC5091-2022 &nbsp; Radicaci\u00f3n &nbsp;n.\u00b0 11001-02-03-000-2022-03500-00 &nbsp; Bogot\u00e1 &nbsp;D.C., diez (10) de noviembre de dos mil veintid\u00f3s (2022). &nbsp; Se &nbsp;decide el conflicto de competencia suscitado entre los Juzgados &nbsp;Sesenta y Cinco Civil Municipal de Bogot\u00e1 y el Primero Civil &nbsp;Municipal de Zipaquir\u00e1, atinente al conocimiento de la demanda &nbsp;declarativa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-68363","post","type-post","status-publish","format-standard","hentry","category-noviembre-2022"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/68363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=68363"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/68363\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=68363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=68363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=68363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}