{"id":68535,"date":"2024-05-20T21:00:30","date_gmt":"2024-05-20T21:00:30","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/atc1720-2022\/"},"modified":"2024-05-20T21:00:30","modified_gmt":"2024-05-20T21:00:30","slug":"atc1720-2022","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/atc1720-2022\/","title":{"rendered":"ATC1720 2022"},"content":{"rendered":"<p>ATC1720-2022<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>ATC1720-2022 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00b0. &nbsp;11001-22-03-000-2022-02193-01 &nbsp; &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D.C., dieciocho (18) de noviembre de dos mil veintid\u00f3s (2022). &nbsp;<\/p>\n<p>Ser\u00eda &nbsp;del caso resolver &nbsp;la impugnaci\u00f3n interpuesta frente a la sentencia proferida el &nbsp;19 de octubre de 2022 por la Sala Civil del Tribunal Superior del &nbsp;Distrito Judicial de Bogot\u00e1, que neg\u00f3 el amparo &nbsp;formulado por Juan Manuel Falla Rodr\u00edguez en representaci\u00f3n &nbsp;de Yesid Fernando Acosta Bustos1 &nbsp;contra el Juzgado Catorce Civil del Circuito de esta ciudad, si &nbsp;no fuera porque en el devenir de la primera instancia se incurri\u00f3 &nbsp;en una causal de nulidad que afecta lo actuado, seg\u00fan se &nbsp;examina. &nbsp;<\/p>\n<p>1. En efecto, &nbsp;se observa que se omiti\u00f3 la notificaci\u00f3n a Seguros de &nbsp;Vida Alfa S.A., cuya vinculaci\u00f3n se orden\u00f3 en el auto &nbsp;admisorio de la tutela y a quien le asiste un leg\u00edtimo inter\u00e9s &nbsp;en los resultados de este asunto, pues funge como accionada en el &nbsp;proceso verbal formulado por Yesid Fernando Acosta Bustos de radicado &nbsp;2019-00841, frente al cual se pretende que se conceda la apelaci\u00f3n &nbsp;interpuesta contra la sentencia de primera instancia, que fue &nbsp;favorable a los intereses de aquella. &nbsp;<\/p>\n<p>Lo &nbsp;anterior, por cuanto el auto admisorio de la tutela, el fallo emitido &nbsp;por el a &nbsp;quo &nbsp;constitucional y el auto que concede la impugnaci\u00f3n fueron &nbsp;notificados a dicha sociedad a trav\u00e9s del correo electr\u00f3nico &nbsp;servicioalcliente@segurosalfa.com, &nbsp;no obstante, la direcci\u00f3n de notificaciones judiciales &nbsp;registrada en el certificado de existencia y representaci\u00f3n &nbsp;legal anexo al expediente es servicioalcliente@segurosalfa.com.co. &nbsp;<\/p>\n<p>Y, aunque se &nbsp;enter\u00f3 del asunto a quien fungi\u00f3 como su abogado en el &nbsp;juicio rebatido, se &nbsp;precisa que la &nbsp;notificaci\u00f3n a los interesados se debe efectuar de manera &nbsp;directa, sin que sea v\u00e1lida la comunicaci\u00f3n a trav\u00e9s &nbsp;de su apoderado judicial, pues, como lo sostuvo la Sala en asunto &nbsp;similar: &nbsp;<\/p>\n<p>\u2026la &nbsp;no vinculaci\u00f3n de (XXX), quien acumul\u00f3 un libelo de &nbsp;cobro compulsivo en el curso del procedimiento que motiva el reclamo &nbsp;constitucional, pero no se le enter\u00f3 personalmente de su &nbsp;existencia, sino que se le comunic\u00f3 a su mandataria, con quien &nbsp;no se satisfacen a cabalidad las garant\u00edas al presente &nbsp;procedimiento excepcional. &nbsp;<\/p>\n<p>Frente al &nbsp;punto, la Corte explic\u00f3 en asunto semejante que \u2018[a]s\u00ed, &nbsp;es claro, como ya se dijera, que lo decidido en la presente acci\u00f3n &nbsp;tambi\u00e9n incumbe a las referidas demandantes\u2026, sin que, &nbsp;a su vez, hubiesen sido enteradas, como era del caso, de esa &nbsp;tramitaci\u00f3n, gener\u00e1ndose el vicio expuesto, toda vez &nbsp;que la notificaci\u00f3n efectuada se surti\u00f3 con el &nbsp;apoderado\u2026, quien funge como su representante judicial en el &nbsp;litigio que origina esta actuaci\u00f3n de amparo y que al efecto &nbsp;actu\u00f3 en el presente asunto conforme se observa a folios 338 a &nbsp;340 del cuaderno uno, enteramiento que no releva materializar la &nbsp;notificaci\u00f3n que origin\u00f3 la deficiencia apuntada, &nbsp;puesto que el actuar del aludido abogado no suple el debido &nbsp;conocimiento del tr\u00e1mite constitucional que hab\u00eda de &nbsp;proveerse directamente con aquellas, am\u00e9n que omiti\u00f3 &nbsp;aportar el mandato correspondiente para que pudiera actuar en dicha &nbsp;calidad\u2019 (auto &nbsp;del 4 de mayo de 2012, rad. 2012-00102-01) (CSJ ATC, 14 feb. 2013, &nbsp;rad. 2012-00973-01; reiterado, entre muchos otros, en CSJ &nbsp;ATC750-2015. &nbsp;<\/p>\n<p>2. Al respecto, &nbsp;debe tenerse en cuenta que el debido proceso constituye un conjunto &nbsp;de garant\u00edas fundamentales, entre las que se destaca la &nbsp;posibilidad de enfrentar en igualdad de condiciones los cargos, &nbsp;cuestionamientos o condenas reclamadas en sede judicial. Para ello, &nbsp;resulta indispensable concurrir al proceso y contar la posibilidad de &nbsp;aducir pruebas y controvertir las allegadas por la parte contraria, &nbsp;principios consagrados en el art\u00edculo 29 de la Constituci\u00f3n &nbsp;Pol\u00edtica, lo cual no escapa a la acci\u00f3n de tutela, dado &nbsp;que, pese a ser un tr\u00e1mite caracterizado por la brevedad y &nbsp;sumariedad, no es ajeno a las reglas del referido derecho &nbsp;fundamental, &nbsp;tal &nbsp;y como disponen los art\u00edculos 16 del Decreto 2591 de 1991, &nbsp;2.2.3.1.1.3. y 2.2.3.1.1.4. del Decreto 1069 de 2015. &nbsp;<\/p>\n<p>3. As\u00ed las &nbsp;cosas, la circunstancia que viene de advertirse desemboca en la &nbsp;causal de nulidad reglada en el numeral 8\u00ba del art\u00edculo &nbsp;133 C\u00f3digo General del Proceso, preceptiva que resulta &nbsp;aplicable a la presente acci\u00f3n constitucional en virtud de lo &nbsp;dispuesto por el art\u00edculo 2.2.3.1.1.3. del Decreto 1069 de &nbsp;2015 y, por tanto, se impone declarar la invalidez de todo lo actuado &nbsp;con posterioridad al auto que avoc\u00f3 el conocimiento del &nbsp;asunto, para que el a-quo &nbsp;constitucional &nbsp;cumpla con la formalidad omitida y notifique, en debida forma, a &nbsp;Seguros de Vida Alfa S.A., a la direcci\u00f3n &nbsp;de notificaciones judiciales registrada en el certificado de &nbsp;existencia y representaci\u00f3n legal que reposa en el expediente. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>1. Declarar &nbsp;la nulidad de lo actuado en la tutela rese\u00f1ada, &nbsp;con posterioridad al auto &nbsp;admisorio, sin &nbsp;perjuicio de la validez de las pruebas en los t\u00e9rminos del &nbsp;inciso 2\u00ba del art\u00edculo 138 del C\u00f3digo General del &nbsp;Proceso. &nbsp;<\/p>\n<p>2. &nbsp;Disponer &nbsp;que por Secretar\u00eda se devuelva el expediente a la a &nbsp;quo constitucional, &nbsp;para que notifique &nbsp;el &nbsp;auto admisorio de la tutela, &nbsp;en debida forma, a Seguros de Vida Alfa S.A., a la direcci\u00f3n &nbsp;de notificaciones judiciales registrada en el certificado de &nbsp;existencia y representaci\u00f3n legal que reposa en el expediente &nbsp;y rehaga la actuaci\u00f3n surtida. &nbsp;Of\u00edciese. &nbsp;<\/p>\n<p>3. Ordenar &nbsp;notificar esta decisi\u00f3n a los interesados, en la forma &nbsp;prescrita en el art\u00edculo 16 del Decreto 2591 de 1991. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>1\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Documento. Pdf05AutoAdmisorio. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Requiri\u00f3 a Juan Manuel Falla Rodr\u00edguez para que &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;ratificara si actuaba en causa propia, o acreditada la calidad de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;mandatario judicial de alguna de las partes en el proceso censurado, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;lo cual acredit\u00f3 en correo electr\u00f3nico allegado el 18 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;de octubre de 2022 -10:28- Documentos. Pdf 19 y 20 expediente &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;digital. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>ATC1720-2022 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; ATC1720-2022 &nbsp; Radicaci\u00f3n &nbsp;n\u00b0. &nbsp;11001-22-03-000-2022-02193-01 &nbsp; &nbsp; Bogot\u00e1, &nbsp;D.C., dieciocho (18) de noviembre de dos mil veintid\u00f3s (2022). &nbsp; Ser\u00eda &nbsp;del caso resolver &nbsp;la impugnaci\u00f3n interpuesta frente a la sentencia proferida el &nbsp;19 de octubre de 2022 por la Sala Civil del Tribunal Superior del &nbsp;Distrito Judicial de Bogot\u00e1, que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-68535","post","type-post","status-publish","format-standard","hentry","category-noviembre-2022"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/68535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=68535"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/68535\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=68535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=68535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=68535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}