{"id":68539,"date":"2024-05-20T21:00:30","date_gmt":"2024-05-20T21:00:30","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/atc1729-2022\/"},"modified":"2024-05-20T21:00:30","modified_gmt":"2024-05-20T21:00:30","slug":"atc1729-2022","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/atc1729-2022\/","title":{"rendered":"ATC1729 2022"},"content":{"rendered":"<p>ATC1729-2022<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>AROLDO WILSON &nbsp;QUIROZ MONSALVO &nbsp;<\/p>\n<p>Magistrado ponente &nbsp;<\/p>\n<p>ATC1729-2022 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n.\u00b0 11001-02-03-000-2022-04099-00 &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D.C., veintitr\u00e9s (23) de noviembre de dos mil veintid\u00f3s &nbsp;(2022). &nbsp;<\/p>\n<p>Se decide el &nbsp;conflicto negativo de competencia que se suscit\u00f3 entre los &nbsp;Juzgados Primero Promiscuo Municipal de Cajic\u00e1 y 16 Civil &nbsp;Municipal de Bogot\u00e1, ya que ambos despachos judiciales &nbsp;rehusaron conocer de la petici\u00f3n de amparo que formul\u00f3 &nbsp;Nevardo de Jes\u00fas Cardona Pemberty contra el Banco Popular. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>1. A la primera de &nbsp;las mencionadas agencias judiciales le fue repartida la acci\u00f3n &nbsp;de tutela atr\u00e1s referida, autoridad que, a trav\u00e9s de &nbsp;auto de 21 de noviembre de los corrientes, se declar\u00f3 &nbsp;incompetente para conocerla, en la medida en que \u00abel &nbsp;lugar en donde eventualmente puede estar [ocurriendo] la presunta &nbsp;violaci\u00f3n o amenaza\u2026, que motiv\u00f3 la presentaci\u00f3n &nbsp;de esta acci\u00f3n es la ciudad de Bogot\u00e1, D.C., ya que la &nbsp;sede principal de la entidad financiera accionada, y lugar de &nbsp;atenci\u00f3n de los derechos de petici\u00f3n que sirven como &nbsp;antecedente y base de esta acci\u00f3n es la ciudad capital del &nbsp;pa\u00eds\u00bb. &nbsp;<\/p>\n<p>2. Por su parte, &nbsp;el Juzgado 16 Civil Municipal de Bogot\u00e1, a quien fue asignado &nbsp;el asunto, plante\u00f3 conflicto negativo de competencia, al &nbsp;considerar que \u00abadem\u00e1s &nbsp;de tener su domicilio el accionante en [Cajic\u00e1], escogi\u00f3 &nbsp;a prevenci\u00f3n, el conocimiento de esas autoridades judiciales &nbsp;para que resolvieran su tutela, competencia acorde con el Decreto 333 &nbsp;de 2021\u00bb. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>1. No hay duda de &nbsp;que en esta Corporaci\u00f3n radica la competencia para dirimir el &nbsp;referido conflicto, al tenor del art\u00edculo 18 de la Ley 270 de &nbsp;1996, en concordancia con el art\u00edculo 139 del C\u00f3digo &nbsp;General del Proceso, habida consideraci\u00f3n de que los despachos &nbsp;enfrentados pertenecen a diferentes distritos judiciales. &nbsp;<\/p>\n<p>2. En &nbsp;el sub &nbsp;lite se &nbsp;advierte que la controversia planteada va dirigida a determinar qu\u00e9 &nbsp;estrado debe conocer la queja constitucional del actor contra el &nbsp;Banco Popular, &nbsp;destacando que aquel considera vulnerados sus derechos fundamentales &nbsp;con ocasi\u00f3n del actuar de ese ente, toda vez que, seg\u00fan &nbsp;\u00e9l, no ha respondido debidamente las peticiones que elev\u00f3 &nbsp;con miras a recuperar el dinero que fue \u00absustra\u00eddo &nbsp;il\u00edcitamente\u00bb &nbsp;de &nbsp;su cuenta bancaria. &nbsp;<\/p>\n<p>2.1. &nbsp; &nbsp; &nbsp; &nbsp;El art\u00edculo &nbsp;2.2.3.1.2.1 del decreto 1069 de 2015, modificado por el canon primero &nbsp;del decreto 333 de 2021, &nbsp;establece &nbsp;que \u00ab[p]ara &nbsp;los efectos previstos en el art\u00edculo 37 del Decreto 2591 de &nbsp;1991, conocer\u00e1n de la acci\u00f3n de tutela, a prevenci\u00f3n, &nbsp;los jueces con jurisdicci\u00f3n donde ocurriere la violaci\u00f3n &nbsp;o la amenaza que motivare la presentaci\u00f3n de la solicitud o &nbsp;donde se produjeren sus efectos\u00bb, &nbsp;siendo el principal objetivo de la anterior disposici\u00f3n &nbsp;facilitar al afectado en sus derechos fundamentales la elecci\u00f3n &nbsp;del juez que deba resolver sobre la protecci\u00f3n constitucional &nbsp;deprecada, de tal suerte que la competencia por el factor territorial &nbsp;est\u00e1 instituida a prevenci\u00f3n por el sitio en que, seg\u00fan &nbsp;las afirmaciones de la demanda, ocurren los hechos denunciados o &nbsp;produce sus efectos la acci\u00f3n u omisi\u00f3n generatriz del &nbsp;agravio, cualquiera de los cuales, por lo general, puede coincidir &nbsp;con el de domicilio o el de residencia de la parte accionante, seg\u00fan &nbsp;sea el caso. &nbsp;<\/p>\n<p>2.2. &nbsp; &nbsp; &nbsp; &nbsp;Asimismo, el &nbsp;numeral primero de la citada norma (art\u00edculo &nbsp;2.2.3.1.2.1, decreto 1069 de 2015) &nbsp;indica que \u00ab[l]as &nbsp;acciones de tutela que se interpongan contra cualquier autoridad, &nbsp;organismo o entidad p\u00fablica del orden departamental, distrital &nbsp;o municipal y contra particulares ser\u00e1n repartidas, para su &nbsp;conocimiento en primera instancia, a los Jueces Municipales\u00bb. &nbsp;<\/p>\n<p>2.3. &nbsp; &nbsp; &nbsp; &nbsp;En &nbsp;el caso bajo examen, la parte actora eligi\u00f3 a los jueces de &nbsp;Cajic\u00e1 para radicar el libelo contentivo de su solicitud de &nbsp;amparo, raz\u00f3n por la cual debe entenderse que precisamente en &nbsp;dicha localidad es que han tenido lugar los efectos de la vulneraci\u00f3n &nbsp;que alega frente a sus garant\u00edas fundamentales, habida cuenta &nbsp;que es ese sitio donde dicho extremo se desenvuelve, pues en \u00e9ste &nbsp;radica su domicilio, conforme se desprende de lo informado en la &nbsp;demanda de tutela; de lo que se deduce que en esa ciudad se ha &nbsp;materializado la presunta conculcaci\u00f3n de tales derechos, de &nbsp;donde, por lo explicado, corresponde al Juzgado Primero Promiscuo &nbsp;Municipal de Cajic\u00e1 el conocimiento de esta tutela. &nbsp;<\/p>\n<p>3. Luego, el &nbsp;despacho al cual inicialmente correspondi\u00f3 por reparto la &nbsp;demanda es el competente para conocerla, ya que, it\u00e9rese, \u00e9sta &nbsp;puede instaurarse en cualquiera de los lugares donde adquiera &nbsp;materialidad o irradie efectos la actuaci\u00f3n u omisi\u00f3n &nbsp;criticada. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>Por lo expuesto, &nbsp;se resuelve: &nbsp;<\/p>\n<p>Primero. &nbsp; &nbsp; &nbsp; &nbsp;Declarar &nbsp;que el competente para conocer de la presente acci\u00f3n de tutela &nbsp;es el Juzgado &nbsp;Primero Promiscuo Municipal de Cajic\u00e1, &nbsp;al cual se habr\u00e1 de remitirse el expediente. &nbsp;<\/p>\n<p>Segundo. &nbsp; &nbsp; &nbsp; &nbsp;Comunicar &nbsp;esta decisi\u00f3n al interesado y a los despachos involucrados. &nbsp;<\/p>\n<p>AROLDO WILSON &nbsp;QUIROZ MONSALVO &nbsp;<\/p>\n<p>Magistrado &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>ATC1729-2022 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; AROLDO WILSON &nbsp;QUIROZ MONSALVO &nbsp; Magistrado ponente &nbsp; ATC1729-2022 &nbsp; Radicaci\u00f3n &nbsp;n.\u00b0 11001-02-03-000-2022-04099-00 &nbsp; Bogot\u00e1, &nbsp;D.C., veintitr\u00e9s (23) de noviembre de dos mil veintid\u00f3s &nbsp;(2022). &nbsp; Se decide el &nbsp;conflicto negativo de competencia que se suscit\u00f3 entre los &nbsp;Juzgados Primero Promiscuo Municipal de Cajic\u00e1 y 16 Civil &nbsp;Municipal de Bogot\u00e1, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-68539","post","type-post","status-publish","format-standard","hentry","category-noviembre-2022"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/68539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=68539"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/68539\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=68539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=68539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=68539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}