{"id":68635,"date":"2024-05-20T21:00:32","date_gmt":"2024-05-20T21:00:32","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc14767-2022\/"},"modified":"2024-05-20T21:00:32","modified_gmt":"2024-05-20T21:00:32","slug":"stc14767-2022","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc14767-2022\/","title":{"rendered":"STC14767 2022"},"content":{"rendered":"<p>STC14767-2022<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>Magistrada &nbsp;ponente &nbsp;<\/p>\n<p>STC14767-2022 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00ba 11001-02-03-000-2022-03675-00 &nbsp;<\/p>\n<p>(Aprobado &nbsp;en Sala de dos de noviembre de dos mil veintid\u00f3s) &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D.C., tres (3) de noviembre de dos mil veintid\u00f3s (2022). &nbsp;<\/p>\n<p>Se &nbsp;resuelve la acci\u00f3n de tutela que Enrique Ardila Franco le &nbsp;instaur\u00f3 a la Sala Civil Familia del Tribunal Superior del &nbsp;Distrito Judicial y al Juzgado Primero Civil del Circuito &nbsp;Especializado en Restituci\u00f3n de Tierras, ambos de Bucaramanga. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>1.- &nbsp;El libelista, actuando en nombre propio, reclam\u00f3 la protecci\u00f3n &nbsp;de los derechos al \u00abdebido &nbsp;proceso, acceso a la administraci\u00f3n de justicia, tutela &nbsp;judicial efectiva, buen nombre, libertad y patrimonio\u00bb &nbsp;para que, &nbsp;<\/p>\n<p>i) &nbsp;Se ordene al juzgado accionado dejar sin efecto la decisi\u00f3n &nbsp;contenida en el prove\u00eddo de 7 de septiembre de 2022 y en su &nbsp;lugar reconozca el cumplimiento de la sentencia. &nbsp;<\/p>\n<p>ii) &nbsp;En virtud del cumplimiento del fallo judicial se inaplique o &nbsp;inejecute las sanciones impuestas al suscrito mediante providencia de &nbsp;23 de marzo de 2021 y que impuso al suscrito cinco d\u00edas de &nbsp;arresto y multa equivalente a tres s.m.l.m.v. y la compulsa de copias &nbsp;ante la Procuradur\u00eda General de la Naci\u00f3n y la Fiscal\u00eda &nbsp;General de la Naci\u00f3n. &nbsp;<\/p>\n<p>iv) &nbsp;Conminar al juzgado a que acate y aplique los precedentes &nbsp;jurisprudenciales frente a la procedencia del levantamiento o &nbsp;inaplicaci\u00f3n de la sanci\u00f3n, previa acreditaci\u00f3n &nbsp;del cumplimiento de la orden, con base en la naturaleza persuasiva &nbsp;del incidente de desacato y a verificar la responsabilidad objetiva y &nbsp;subjetiva de los funcionarios en el cumplimiento de las \u00f3rdenes &nbsp;judiciales que desconocen o contrar\u00edan t\u00e1citamente el &nbsp;procedimiento administrativo reglado como ocurri\u00f3 en el caso &nbsp;particular en donde el juzgado accionado pretende la omisi\u00f3n &nbsp;del proceso de reconocimiento y pago de la medida de indemnizaci\u00f3n &nbsp;administrativa reglamentado por la Resoluci\u00f3n 01049 de 2019\u00bb. &nbsp;<\/p>\n<p>En &nbsp;compendio adujo &nbsp;que el Juzgado Primero Civil del Circuito Especializado en &nbsp;Restituci\u00f3n de Tierras de Bucaramanga concedi\u00f3 el &nbsp;auxilio rogado por Flor Alba Alvarado S\u00e1nchez en &nbsp;representaci\u00f3n de Juan Bautista Alvarado Romero, en el &nbsp;resguardo que promovi\u00f3 contra la Unidad para la Atenci\u00f3n &nbsp;y Reparaci\u00f3n Integral a las Victimas \u2013 UARIV y, por &nbsp;consiguiente, orden\u00f3 a esta, que \u00aben &nbsp;el t\u00e9rmino improrrogable de 48 horas siguientes a la &nbsp;notificaci\u00f3n del presente fallo, si a\u00fan no lo ha hecho, &nbsp;levante la suspensi\u00f3n del tr\u00e1mite de indemnizaci\u00f3n &nbsp;administrativa respecto del accionante y contin\u00fae con el &nbsp;correspondiente procedimiento de manera prioritaria atendiendo su &nbsp;avanzada edad y estado de salud, adoptando una decisi\u00f3n de &nbsp;fondo sin exceder los plazos m\u00e1ximos establecidos para ello\u00bb &nbsp;(10 sep. 2020), decisi\u00f3n que el superior confirm\u00f3 (21 &nbsp;oct.). &nbsp;<\/p>\n<p>Posteriormente, &nbsp;se inici\u00f3 en su contra, en calidad de \u00abDirector &nbsp;de Reparaci\u00f3n\u00bb &nbsp;de la citada Unidad, incidente de desacato, en el que se le impuso &nbsp;\u00abarresto &nbsp;que fue conmutado a multa de cinco salarios m\u00ednimos legales &nbsp;mensuales vigentes; multa por un valor de 3 salarios m\u00ednimos &nbsp;legales mensuales vigentes y la compulsa de copias ante la &nbsp;Procuradur\u00eda General de la Naci\u00f3n y la Fiscal\u00eda &nbsp;General de la Naci\u00f3n\u00bb &nbsp;(23 mar.2021), determinaci\u00f3n ratificada &nbsp;en &nbsp;grado jurisdiccional de consulta (26 mar.). &nbsp;<\/p>\n<p>Asegur\u00f3 &nbsp;que en atenci\u00f3n al cumplimento del mandato superlativo, &nbsp;solicit\u00f3 la inaplicaci\u00f3n de la sanci\u00f3n, &nbsp;empero, &nbsp;el &nbsp;juez &nbsp;de conocimiento la neg\u00f3, aduciendo que \u00abno &nbsp;pod\u00eda predicarse v\u00e1lidamente el cumplimiento de la &nbsp;orden de tutela porque nunca observ\u00f3 el t\u00e9rmino de las &nbsp;48 horas que se le otorg\u00f3 ni basta que con que a la final y &nbsp;luego casi de un a\u00f1o se haya entregado la indemnizaci\u00f3n &nbsp;administrativa al accionante\u00bb, pues &nbsp;previo a ello \u00abmantuvo &nbsp;la indebida exigencia de documentos adicionales, lo que era &nbsp;violatorio de derechos fundamentales al imponer cargas &nbsp;desproporcionadas a una persona que pertenece a la poblaci\u00f3n &nbsp;desplazada, teniendo que esperar largos meses para al fin lograr &nbsp;obtener su reparaci\u00f3n monetaria\u00bb &nbsp;(22 abr. 2022), pretensi\u00f3n que pese a ser reiterada se mantuvo &nbsp;(7 sep.). &nbsp;<\/p>\n<p>En &nbsp;su opini\u00f3n con los \u00faltimos pronunciamientos se &nbsp;afectaron sus prerrogativas esenciales, en tanto \u00abincurri\u00f3 &nbsp;en indebida motivaci\u00f3n, defecto f\u00e1ctico y &nbsp;desconocimiento del precedente\u00bb, &nbsp;ya que \u00abno &nbsp;tuvo en cuenta las explicaciones que dio en distintas oportunidades &nbsp;en relaci\u00f3n a que no se pod\u00eda ordenar el pago inmediato &nbsp;de la indemnizaci\u00f3n, sino que para dar cumplimiento deb\u00eda &nbsp;adelantar el debido proceso administrativo gestado en la Resoluci\u00f3n &nbsp;01049 de 2019 que regula lo relacionado para la entrega de la &nbsp;indemnizaci\u00f3n administrativa a las v\u00edctimas del &nbsp;conflicto armado\u00bb. &nbsp;<\/p>\n<p>Sostuvo &nbsp;que \u00abse &nbsp;desconoci\u00f3 que no hubo negligencia o desidia de su parte y que &nbsp;la finalidad del incidente de desacato es lograr el cumplimiento &nbsp;efectivo de la orden de tutela lo cual ya sucedi\u00f3, por tanto, &nbsp;es claro que la sanci\u00f3n se mantendr\u00e1 hasta cuando la &nbsp;sentencia se cumpla, por lo que se entiende que acatada la misma y &nbsp;las sanciones no se han hecho efectivas, deben levantarse las mismas &nbsp;por carencia de objeto\u00bb. &nbsp;<\/p>\n<p>2.- &nbsp;El Juzgado Primero Civil del Circuito Especializado en Restituci\u00f3n &nbsp;de Tierras de Bucaramanga defendi\u00f3 &nbsp;la legalidad de su proceder y alleg\u00f3 copia del paginario. &nbsp;<\/p>\n<p>La &nbsp;Unidad &nbsp;de Restituci\u00f3n de Tierras pidi\u00f3 su desvinculaci\u00f3n &nbsp;por falta de legitimaci\u00f3n en la causa por pasiva. &nbsp;<\/p>\n<p>La &nbsp;Unidad para la Atenci\u00f3n y Reparaci\u00f3n Integral a las &nbsp;Victimas \u2013 UARIV &#8211; manifest\u00f3 que se debe \u00abaceptar &nbsp;las pretensiones del accionante, por haberse demostrado la &nbsp;procedencia de la acci\u00f3n de tutela ante la ocurrencia de una &nbsp;v\u00eda de hecho por parte de los operadores judiciales &nbsp;accionados\u00bb. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>1.- &nbsp; &nbsp; &nbsp; &nbsp;La &nbsp;Sala ha reiterado la impertinencia de la &nbsp;\u00abacci\u00f3n de tutela\u00bb &nbsp;para cuestionar resoluciones proferidas en el curso de un \u00abincidente &nbsp;de desacato\u00bb, &nbsp;toda vez que en esos tr\u00e1mites &nbsp;<\/p>\n<p>no &nbsp;se considera procedente ning\u00fan otro instrumento diferente de &nbsp;reestudio, incluida como es natural la acci\u00f3n de tutela, &nbsp;porque se convertir\u00eda en un mecanismo llamado a minar las &nbsp;determinaciones tomadas en desarrollo de un tr\u00e1mite de &nbsp;indiscutido raigambre constitucional (\u2026). Es evidente que la &nbsp;real intenci\u00f3n del legislador, en relaci\u00f3n con el &nbsp;incidente de desacato, era que se regulara a s\u00ed mismo, a &nbsp;trav\u00e9s de la decisi\u00f3n incidental y su eventual consulta &nbsp;cuando se impusiere sanci\u00f3n, con total autonom\u00eda y sin &nbsp;injerencia de \u00f3rganos externos, aun de nivel constitucional, &nbsp;que puedan interferir en sus decisiones &nbsp;(STC9955-2020). &nbsp;<\/p>\n<p>Se ha &nbsp;dicho, entonces de tiempo atr\u00e1s, que \u00absi &nbsp;hoy es pac\u00edfico que, contra lo sentenciado en tutela, no es &nbsp;dable acci\u00f3n -ex novo- de naturaleza semejante, menos &nbsp;proceder\u00eda esta acci\u00f3n extraordinaria en punto a las &nbsp;providencias que se pronuncien en la etapa derivada del &nbsp;incumplimiento de la parte resolutiva que se denuncie (incidente de &nbsp;desacato)\u00bb &nbsp;CSJ, STC1985-2020 reiterada en STC365-2021. &nbsp;<\/p>\n<p>Sin &nbsp;embargo, tambi\u00e9n se ha establecido que, de manera excepcional, &nbsp;este mecanismo resulta viable cuando en el diligenciamiento del &nbsp;\u00abdesacato\u00bb &nbsp;se ha desconocido de manera flagrante la garant\u00eda &nbsp;constitucional al debido proceso de los intervinientes, por lo que, &nbsp;<\/p>\n<p>en &nbsp;el evento en que durante el curso del incidente se advierta &nbsp;desconocimiento del derecho al debido proceso y como consecuencia de &nbsp;ello se constituya una v\u00eda de hecho, es perfectamente &nbsp;admisible que quien considere vulnerado su derecho acuda a la acci\u00f3n &nbsp;de tutela en procura de obtener protecci\u00f3n constitucional. &nbsp;Ser\u00e1 el juez de tutela, entonces, el que entre a valorar si en &nbsp;el caso concreto se configuran los presupuestos para la procedencia &nbsp;de la acci\u00f3n contra providencias judiciales y si se configura &nbsp;o no una v\u00eda de hecho &nbsp;(\u00edd.). &nbsp;<\/p>\n<p>2.- &nbsp;Bajo &nbsp;los anteriores lineamientos, no cabe duda que, si bien en principio &nbsp;no resultar\u00eda procedente la ayuda aqu\u00ed requerida, por &nbsp;estar dirigida contra los autos de 22 de abril y 7 de septiembre de &nbsp;2022, que negaron la \u00absolicitud &nbsp;de inaplicaci\u00f3n, inejecuci\u00f3n y\/o levantamiento de la &nbsp;sanci\u00f3n\u00bb, &nbsp;por haber sido dictados en un \u00abincidente &nbsp;de desacato\u00bb, &nbsp;lo cierto es que los argumentos all\u00ed expuestos son arbitrarios &nbsp;y, por ende, conculcan la garant\u00eda superior al \u00abdebido &nbsp;proceso\u00bb &nbsp;de Enrique Ardila Franco, incurri\u00e9ndose as\u00ed en \u00abcausal &nbsp;de procedencia\u00bb &nbsp;de la gurda. &nbsp;<\/p>\n<p>Se &nbsp;arriba a la anterior conclusi\u00f3n, porque despu\u00e9s del &nbsp;prove\u00eddo de 23 de marzo de 2021, mediante el cual se sancion\u00f3 &nbsp;por \u00abdesacato\u00bb &nbsp;al gestor, \u00e9ste aport\u00f3 varios documentos para acreditar &nbsp;el acatamiento de las \u00f3rdenes que le fueron impartidas; luego &nbsp;entonces, en virtud del art\u00edculo 27 del Decreto 2591 de 1991, &nbsp;el Juzgado Primero Civil del Circuito Especializado en Restituci\u00f3n &nbsp;de Tierras de Bucaramanga estaba en la obligaci\u00f3n de estudiar &nbsp;y definir de fondo la pertinencia de mantener dicho castigo, en la &nbsp;medida que, no solo la norma en cita prev\u00e9 que \u00e9ste &nbsp;debe perdurar \u00fanicamente hasta que se verifique el &nbsp;cumplimiento del fallo, &nbsp;sino que no puede aceptarse lo esbozado en torno a que, \u00absi &nbsp;bien lo que en \u00faltimas buscaba el accionante era que se le &nbsp;reconociera y pagara la indemnizaci\u00f3n administrativa, ello no &nbsp;se pretend\u00eda que se hiciera excediendo los plazos establecidos &nbsp;para ello\u00bb. &nbsp;<\/p>\n<p>Al &nbsp;respecto, t\u00e9ngase &nbsp;en cuenta que, de vieja data se ha insistido en que, &nbsp;aunque entre los objetivos del \u00abincidente &nbsp;de desacato\u00bb &nbsp;est\u00e1 el de \u00absancionar &nbsp;el incumplimiento del fallo de tutela\u00bb, &nbsp;su prop\u00f3sito final no es otro que la observancia efectiva de &nbsp;la \u00aborden &nbsp;constitucional\u00bb &nbsp;pendiente de ser ejecutada y, por tanto, la custodia de los \u00abderechos &nbsp;fundamentales\u00bb &nbsp;con ella salvaguardados; de ah\u00ed que, &nbsp;<\/p>\n<p>cuando &nbsp;se observa el cabal cumplimiento de la orden de tutela, as\u00ed &nbsp;sea extempor\u00e1neamente e incluso despu\u00e9s de decidida la &nbsp;consulta, &nbsp;la Corte ha prohijado la tesis de &nbsp;que es del caso levantar las sanciones respectivas (\u2026) \u2018pues &nbsp;el fin perseguido con el tr\u00e1mite del desacato ya se cumpli\u00f3. &nbsp;(\u2026) Cabe acotar, que la Corte Constitucional sobre el tema ha &nbsp;precisado que \u2018(\u2026) se puede deducir que la finalidad del &nbsp;incidente de desacato no es la imposici\u00f3n de la sanci\u00f3n &nbsp;en s\u00ed misma, sino la sanci\u00f3n como una de las formas de &nbsp;b\u00fasqueda del cumplimiento de la sentencia &nbsp;(CSJ &nbsp;STC1985-2020, &nbsp;reiterada en STC12116-2022). &nbsp;<\/p>\n<p>De igual forma, en &nbsp;sentencia SU-034 de 2018 la Corte Constitucional, record\u00f3 que &nbsp;<\/p>\n<p>(\u2026) si bien una de &nbsp;las consecuencias derivadas de este tr\u00e1mite incidental, es la &nbsp;imposici\u00f3n de sanciones por la desobediencia frente a la &nbsp;sentencia, su &nbsp;aut\u00e9ntico prop\u00f3sito es lograr el cumplimiento efectivo &nbsp;de la orden de tutela pendiente de ser ejecutada; &nbsp;de suerte que no se persigue reprender al renuente por el peso de la &nbsp;sanci\u00f3n en s\u00ed misma, sino que \u00e9sta debe &nbsp;entenderse como una forma para inducir que aquel encauce su conducta &nbsp;hacia el cumplimiento, &nbsp;a trav\u00e9s de una medida de reconvenci\u00f3n cuyo objetivo no &nbsp;es otro que auspiciar la eficacia de la acci\u00f3n impetrada y, &nbsp;con ella, la reivindicaci\u00f3n de los derechos quebrantados. &nbsp;<\/p>\n<p>En consecuencia, cuando &nbsp;en el curso del incidente &nbsp;de desacato el &nbsp;accionado se persuade a cumplir la orden de tutela, &nbsp;no hay lugar &nbsp;a la imposici\u00f3n y\/o &nbsp;aplicaci\u00f3n de la sanci\u00f3n: &nbsp;\u2018La imposici\u00f3n o no de una sanci\u00f3n dentro del &nbsp;incidente puede implicar que el accionado se persuada o no del &nbsp;cumplimiento de una sentencia. En efecto, en caso de que se inicie el &nbsp;incidente de desacato y el accionado, reconociendo que se ha &nbsp;desacatado lo ordenado por el juez de tutela, quiera evitar la &nbsp;sanci\u00f3n, deber\u00e1 acatar la sentencia. En &nbsp;caso de que se haya adelantado el tr\u00e1mite y resuelto sancionar &nbsp;por desacato, para que la sanci\u00f3n no se haga efectiva, el &nbsp;renuente a cumplir podr\u00e1 evitar ser sancionado acatando\u2019 &nbsp;(\u2026). &nbsp;(Negritas ajenas al texto original. &nbsp;<\/p>\n<p>Y &nbsp;no se olvide que all\u00ed mismo, tambi\u00e9n se advirti\u00f3 &nbsp;que la &nbsp;\u00abpretermisi\u00f3n &nbsp;del estudio sobre la responsabilidad subjetiva [conlleva] un &nbsp;desconocimiento del precedente jurisprudencial sobre la finalidad del &nbsp;incidente de desacato\u00bb, &nbsp;capaz de desnaturalizar las \u00absanciones\u00bb &nbsp;que el art\u00edculo 52 del Decreto 2591 de 1991 consagra como &nbsp;\u00abmecanismos &nbsp;llamados a propiciar la salvaguarda dispensada en los fallos de &nbsp;tutela\u00bb, &nbsp;por lo que seg\u00fan se\u00f1al\u00f3, &nbsp;<\/p>\n<p>(\u2026) &nbsp;mal [se puede] negar el levantamiento de las sanciones con argumentos &nbsp;como que las mismas se encontraban en firme y que el desacato es un &nbsp;dispositivo para castigar al renuente, pues ello &nbsp;desconoce la doctrina desarrollada de forma pac\u00edfica por esta &nbsp;Corte en cuanto a que el prop\u00f3sito perseguido por la sanci\u00f3n &nbsp;es conminar al obligado como medio para garantizar el goce efectivo &nbsp;del derecho tutelado mediante sentencia, mas no sancionar por &nbsp;sancionar. &nbsp;<\/p>\n<p>Bajo &nbsp;esa \u00f3ptica, ante las solicitudes de inaplicaci\u00f3n de las &nbsp;sanciones, el Juzgado (\u2026) estaba llamado a incorporar en su &nbsp;razonamiento la jurisprudencia consolidada por esta Corte y aplicar &nbsp;el mandato constitucional de prevalencia de lo sustancial &nbsp;(que en este caso ser\u00eda la constataci\u00f3n de las acciones &nbsp;positivas orientadas al cumplimiento), para &nbsp;con base en ello reconsiderar si se justificaba mantener las medidas &nbsp;coercitivas impuestas &nbsp;(Destaca &nbsp;la Sala). &nbsp;<\/p>\n<p>En &nbsp;estas condiciones, si el incidentado atendi\u00f3 as\u00ed sea &nbsp;extempor\u00e1neamente el \u00abfallo &nbsp;de tutela\u00bb &nbsp;y con ello se superaron las circunstancias que propiciaron el debate &nbsp;supralegal, para esta Corporaci\u00f3n es incuestionable la &nbsp;vulneraci\u00f3n que suponen los \u00abargumentos\u00bb &nbsp;del juzgador para desestimar la \u00absolicitud &nbsp;de inaplicaci\u00f3n de la sanci\u00f3n por cumplimiento\u00bb &nbsp;elevada por el quejoso, sin analizar las pautas que sobre la materia &nbsp;ha sentado la jurisprudencia de esta Corte y la Constitucional. &nbsp;<\/p>\n<p>3.- &nbsp;As\u00ed las cosas, se abre paso el ruego instado, para que la sede &nbsp;acusada eval\u00fae de nuevo los requerimientos del pretensor a la &nbsp;luz de los principios aqu\u00ed resaltados y todos aquellos que &nbsp;resulten consecuentes. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, en Sala &nbsp;de Casaci\u00f3n Civil, administrando justicia en nombre de la &nbsp;Rep\u00fablica de Colombia y por autoridad de la Constituci\u00f3n, &nbsp;CONCEDE &nbsp;el amparo instado por Enrique Ardila Franco. &nbsp;<\/p>\n<p>En &nbsp;consecuencia, se deja &nbsp;sin &nbsp;valor y efecto el interlocutorio de 7 de septiembre de 2022 que el &nbsp;Juzgado &nbsp;Primero Civil del Circuito Especializado en Restituci\u00f3n de &nbsp;Tierras de Bucaramanga &nbsp;emiti\u00f3 en el incidente de &nbsp;desacato n\u00b0 &nbsp;68001312100120200010700, &nbsp;y se ORDENA &nbsp;a este que, en el t\u00e9rmino de diez (10) d\u00edas siguientes &nbsp;a la notificaci\u00f3n de esta determinaci\u00f3n, resuelva &nbsp;nuevamente la \u00absolicitud &nbsp;de inaplicaci\u00f3n &nbsp;de la sanci\u00f3n\u00bb &nbsp;formulada por &nbsp;Enrique &nbsp;Ardila Franco, &nbsp;con fundamento en los preceptos legales y las directrices &nbsp;jurisprudenciales aqu\u00ed rese\u00f1adas y las dem\u00e1s que &nbsp;sean aplicables al caso particular. &nbsp;<\/p>\n<p>Comun\u00edquese &nbsp;por el medio m\u00e1s expedito y, en caso de no ser impugnado este &nbsp;fallo, rem\u00edtase el expediente a la Corte Constitucional para &nbsp;su eventual revisi\u00f3n. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>Presidenta &nbsp;de Sala &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>AUSENCIA &nbsp;JUSTIFICADA &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC14767-2022 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp; Magistrada &nbsp;ponente &nbsp; STC14767-2022 &nbsp; Radicaci\u00f3n &nbsp;n\u00ba 11001-02-03-000-2022-03675-00 &nbsp; (Aprobado &nbsp;en Sala de dos de noviembre de dos mil veintid\u00f3s) &nbsp; Bogot\u00e1, &nbsp;D.C., tres (3) de noviembre de dos mil veintid\u00f3s (2022). &nbsp; Se &nbsp;resuelve la acci\u00f3n de tutela que Enrique Ardila Franco le &nbsp;instaur\u00f3 a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-68635","post","type-post","status-publish","format-standard","hentry","category-noviembre-2022"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/68635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=68635"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/68635\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=68635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=68635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=68635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}