{"id":70419,"date":"2024-05-20T22:42:00","date_gmt":"2024-05-20T22:42:00","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/ac356-2023-2023-00477-00\/"},"modified":"2024-05-20T22:42:00","modified_gmt":"2024-05-20T22:42:00","slug":"ac356-2023-2023-00477-00","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/ac356-2023-2023-00477-00\/","title":{"rendered":"AC 356 2023"},"content":{"rendered":"<p>AC356-2023 (2023-00477-00)<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>AC356-2023 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n.\u00ba 11001-02-03-000-2023-00477-00 &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D.C., veintid\u00f3s (22) de febrero &nbsp;de dos mil veintitr\u00e9s (2023). &nbsp;<\/p>\n<p>En &nbsp;cuanto al \u00abconflicto &nbsp;de competencia\u00bb &nbsp;suscitado entre los Juzgados Primero Civil Municipal y Veintid\u00f3s &nbsp;Administrativo, ambos de Medell\u00edn, con motivo de la demanda &nbsp;ejecutiva que promovi\u00f3 \u00abLa &nbsp;Naci\u00f3n \u2013 Ministerio de Educaci\u00f3n \u2013 Fondo &nbsp;Nacional de Prestaciones Sociales del Magisterio\u00bb &nbsp;contra Irma Stella Molina Valencia, observa &nbsp;la Corte que carece de la aptitud legal para tramitar el asunto, &nbsp;seg\u00fan pasar\u00e1 a exponerse. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>Conforme &nbsp;al art\u00edculo 18 de la Ley 270 de 1996, a las Salas &nbsp;Especializadas de la Corte Suprema de Justicia corresponde el &nbsp;conocimiento de \u00ablos &nbsp;conflictos de competencia que se susciten entre &nbsp;autoridades de la jurisdicci\u00f3n ordinaria &nbsp;que &nbsp;tengan distinta especialidad jurisdiccional y que pertenezcan a &nbsp;distintos distritos\u00bb. &nbsp;<\/p>\n<p>Por &nbsp;su parte, el art\u00edculo 241 de la Constituci\u00f3n Pol\u00edtica &nbsp;(modificado por el canon 14 del acto legislativo 2 de 2015), dispone &nbsp;que la Corte Constitucional es la encargada de \u00abdirimir &nbsp;los conflictos de competencia que ocurran entre &nbsp;las distintas jurisdicciones\u00bb; &nbsp;precepto cuya aplicaci\u00f3n hab\u00eda entendido postergada &nbsp;dicha Corporaci\u00f3n, hasta tanto la Sala Jurisdiccional &nbsp;Disciplinaria del Consejo Superior de la Judicatura cesara &nbsp;definitivamente en el ejercicio de sus funciones (auto 278 de 2015), &nbsp;lo cual ocurri\u00f3 el 13 de enero de 2021, con la posesi\u00f3n &nbsp;de los Magistrados que integran la Comisi\u00f3n Nacional de &nbsp;Disciplina Judicial. &nbsp;<\/p>\n<p>As\u00ed &nbsp;las cosas, y dado que la disputa de la que viene habl\u00e1ndose &nbsp;involucr\u00f3 no solamente a un estrado de la jurisdicci\u00f3n &nbsp;ordinaria (en su especialidad civil), sino tambi\u00e9n a un &nbsp;despacho judicial que pertenece a la jurisdicci\u00f3n contencioso &nbsp;administrativa, es forzoso colegir que su resoluci\u00f3n compete a &nbsp;la Corte Constitucional, a quien se ordenar\u00e1 remitir las &nbsp;presentes diligencias. &nbsp;<\/p>\n<p>Conforme &nbsp;con ello, el suscrito Magistrado de la &nbsp;Corte Suprema de Justicia, Sala de Casaci\u00f3n Civil, &nbsp;<\/p>\n<p>RESUELVE &nbsp;<\/p>\n<p>PRIMERO. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;DECLARAR la &nbsp;falta de competencia de esta Corporaci\u00f3n para resolver el &nbsp;conflicto suscitado entre los Juzgados Primero Civil Municipal y &nbsp;Veintid\u00f3s Administrativo, ambos de Medell\u00edn. &nbsp;<\/p>\n<p>SEGUNDO. &nbsp; &nbsp; &nbsp; &nbsp;REMITIR &nbsp;las &nbsp;diligencias a &nbsp;la Corte Constitucional, para que resuelva el asunto. &nbsp;<\/p>\n<p>TERCERO. &nbsp;COMUNICAR esta &nbsp;determinaci\u00f3n a los despachos judiciales involucrados. &nbsp;<\/p>\n<p>Notif\u00edquese &nbsp;y c\u00famplase. &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>AC356-2023 (2023-00477-00) &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; AC356-2023 &nbsp; Radicaci\u00f3n &nbsp;n.\u00ba 11001-02-03-000-2023-00477-00 &nbsp; Bogot\u00e1, &nbsp;D.C., veintid\u00f3s (22) de febrero &nbsp;de dos mil veintitr\u00e9s (2023). &nbsp; En &nbsp;cuanto al \u00abconflicto &nbsp;de competencia\u00bb &nbsp;suscitado entre los Juzgados Primero Civil Municipal y Veintid\u00f3s &nbsp;Administrativo, ambos de Medell\u00edn, con motivo de la demanda &nbsp;ejecutiva que promovi\u00f3 \u00abLa &nbsp;Naci\u00f3n \u2013 Ministerio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-70419","post","type-post","status-publish","format-standard","hentry","category-febrero-2023"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=70419"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70419\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=70419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=70419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=70419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}