{"id":70433,"date":"2024-05-20T22:42:02","date_gmt":"2024-05-20T22:42:02","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/ac381-2023-2023-00097-00\/"},"modified":"2024-05-20T22:42:02","modified_gmt":"2024-05-20T22:42:02","slug":"ac381-2023-2023-00097-00","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/ac381-2023-2023-00097-00\/","title":{"rendered":"AC 381 2023"},"content":{"rendered":"<p>AC381-2023 (2023-00097-00)<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>AC381-2023 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n.\u00b0 11001-02-03-000-2023-00097-00 &nbsp;<\/p>\n<p>Bogot\u00e1 &nbsp;D.C., veintitr\u00e9s (23) de febrero de dos mil veintitr\u00e9s &nbsp;(2023). &nbsp;<\/p>\n<p>Se &nbsp;decide el conflicto de competencia que surgi\u00f3 entre el Juzgado &nbsp;Tercero Civil Municipal de Florencia y el Despacho Segundo Civil &nbsp;Municipal de Neiva, atinente al conocimiento de la demanda de &nbsp;sucesi\u00f3n promovida por Amelia Marroqu\u00edn Manjarrez. &nbsp;<\/p>\n<p>I. &nbsp;ANTECEDENTES &nbsp;<\/p>\n<p>1. En &nbsp;la demanda dirigida al \u00abJUEZ &nbsp;DE FAMILIA DE FLORENCIA=REPARTO=\u00bb, &nbsp;la &nbsp;parte actora reclam\u00f3 de la jurisdicci\u00f3n que se declare &nbsp;\u00ababierto &nbsp;y radicado en su juzgado el proceso de sucesi\u00f3n de las &nbsp;causantes MARIA JOSEFA MANJARRES SILVA, CELSA VIRGINIA MANJARRES &nbsp;SILVA Y EFEGENIA MANJARRES SILVA\u00bb. &nbsp;Indic\u00f3 &nbsp;que la competencia le concern\u00eda a dicha autoridad judicial, &nbsp;\u00abpor ser &nbsp;el \u00faltimo lugar de residencia y domicilio de la causante MARIA &nbsp;JOSEFA MANJARRES SILVA\u00bb1. &nbsp;<\/p>\n<p>2. &nbsp;Repartida la demanda, el Juzgado &nbsp;Primero de Familia de Florencia -con prove\u00eddo del 21 de junio &nbsp;de 2022- resolvi\u00f3 rechazarla de plano por la cuant\u00eda &nbsp;del asunto2. &nbsp;Y remiti\u00f3 el expediente. &nbsp;<\/p>\n<p>3. &nbsp;El Juzgado Tercero Civil Municipal de Florencia -con auto del 1\u00ba &nbsp;de agosto de 2022- tambi\u00e9n rechaz\u00f3 la demanda por falta &nbsp;de competencia. Manifest\u00f3 que: &nbsp;<\/p>\n<p>En el caso que &nbsp;nos ocupa, debemos tener en cuenta que adem\u00e1s de la causante &nbsp;MARIA JOSEFA &nbsp;MANJARRES SILVA, &nbsp;las otras dos causantes CELSA &nbsp;VIRGINIA MANJARRES SILVA y &nbsp;EFEGENIA &nbsp;MANJARRES SILVA, &nbsp;que pretende el apoderado se abra juicio de sucesi\u00f3n en &nbsp;acumulaci\u00f3n de sucesiones y por econom\u00eda procesal, &nbsp;seg\u00fan informaci\u00f3n del apoderado ten\u00edan su &nbsp;domicilio en la ciudad de Neiva H, adem\u00e1s que el \u00fanico &nbsp;activo objeto de partici\u00f3n corresponde a un bien inmueble que &nbsp;se encuentra ubicado en el municipio de Neiva Huila, por lo que para &nbsp;este Despacho le es aplicable el segundo enunciado del art\u00edculo &nbsp;correspondiente al asiento principal de sus negocios, por cuanto como &nbsp;se indic\u00f3, dos de las causantes tuvieron su \u00faltimo &nbsp;domicilio en la referida ciudad, y bien inmueble igualmente se &nbsp;encuentra ubicado en dicha ciudad. Circunstancia esta que conlleva a &nbsp;determinar qu\u00e9 este Juzgado carece de competencia de conocer &nbsp;del presente proceso, por lo que ordenara\u0301 su remisi\u00f3n &nbsp;ante el Juez Civil Municipal reparto de la ciudad de Neiva Huila, el &nbsp;cual se llevara\u0301 a cabo a trav\u00e9s del Centro de Servicio &nbsp;de los Juzgados Civiles y de Familia de la ciudad.3 &nbsp;<\/p>\n<p>4. &nbsp;Inconforme con dicha decisi\u00f3n, la parte actora present\u00f3 &nbsp;recurso de reposici\u00f3n4. &nbsp;Sin embargo, el juez resolvi\u00f3 mantener su postura5. &nbsp;<\/p>\n<p>\u2026resulta &nbsp;patente la determinaci\u00f3n arbitraria de la competencia &nbsp;territorial se\u00f1alada por el juzgado remitente del presente &nbsp;proceso, pues acertadamente el apoderado actor desde la presentaci\u00f3n &nbsp;de la demanda ha sido claro en precisar que son varios los causantes, &nbsp;con diferentes domicilios, por tanto, a su elecci\u00f3n escogi\u00f3 &nbsp;el de la se\u00f1ora MARIA &nbsp;JOSEFA MANJARRES SILVA, &nbsp;quien si bien falleci\u00f3 el 05 de enero de 2020 en la ciudad de &nbsp;Ibagu\u00e9 &#8211; Tolima, su \u00faltimo domicilio estaba fijado en &nbsp;la ciudad de Florencia, Caquet\u00e1, de quien adem\u00e1s &nbsp;precisa, en el recurso de reposici\u00f3n, que dicha persona era la &nbsp;causante principal, por manera que al rechazarse la demanda, se hizo &nbsp;por la referida autoridad judicial una lectura distorsionada de la &nbsp;regla de competencia territorial prevista en el numeral 12 del &nbsp;art\u00edculo 28 del CGP, toda vez que debi\u00f3 desde el &nbsp;principio radicarse la competencia en cabeza del juez de Florencia &nbsp;Caquet\u00e1, y en \u00faltimas, ante la existencia de varios &nbsp;causantes con diferentes domicilios y por tanto varios jueces &nbsp;competentes por factor territorial, resultaba viable la elecci\u00f3n &nbsp;de cualquiera de ellos como tambi\u00e9n lo advirti\u00f3 el &nbsp;apoderado actor6. &nbsp;<\/p>\n<p>6. &nbsp;As\u00ed las cosas, conforme al canon 139 del C\u00f3digo General &nbsp;del Proceso, se entra a desatar el conflicto propuesto con base en &nbsp;las siguientes, &nbsp;<\/p>\n<p>II. &nbsp;CONSIDERACIONES &nbsp;<\/p>\n<p>1. &nbsp;Corresponde &nbsp;a esta Sala resolver el conflicto negativo suscitado entre los &nbsp;Juzgados de distinto distrito judicial -Florencia y Neiva-, de &nbsp;acuerdo con los art\u00edculos 139 ibidem y 16 de la Ley 270 de &nbsp;1996, modificado por el 7\u00ba de su par 1285 de 2009. &nbsp;<\/p>\n<p>2. &nbsp;Para &nbsp;la determinaci\u00f3n de la competencia, debe precisarse que la &nbsp;selecci\u00f3n del juez, a quien le corresponde asumir el &nbsp;conocimiento de una causa litigiosa, surge como el resultado de la &nbsp;conjugaci\u00f3n de algunas circunstancias o aspectos subjetivos u &nbsp;objetivos, vinculados, verbigracia, a la persona involucrada, al &nbsp;sitio en donde el accionado tiene su domicilio, al lugar en donde &nbsp;acontecieron los hechos, la cuant\u00eda o naturaleza del asunto, &nbsp;etc. &nbsp;Por supuesto, en ciertas ocasiones, aunque algunos de esos factores &nbsp;se entremezclan y se vuelven concurrentes, prevalecen unos sobre &nbsp;otros, puesto que el legislador determina la potestad e indica de &nbsp;manera precisa el funcionario que, con exclusi\u00f3n de cualquier &nbsp;otro, est\u00e1 llamado a encarar el debate. &nbsp;<\/p>\n<p>3. &nbsp;Trat\u00e1ndose de juicios sucesorios, el &nbsp;numeral 12 del art\u00edculo 28 del C\u00f3digo General del &nbsp;Proceso establece como regla especial de competencia que el llamado a &nbsp;conocer de la controversia es el \u00abjuez &nbsp;del \u00faltimo &nbsp;domicilio del difunto en el territorio nacional, &nbsp;y en caso de que a su muerte hubiere tenido varios, el que &nbsp;corresponda al &nbsp;asiento principal de sus negocios\u00bb &nbsp;(Se &nbsp;subraya). &nbsp;<\/p>\n<p>4. De &nbsp;ese modo, el &nbsp;asunto que origina la atenci\u00f3n de la Corte concierne a un &nbsp;proceso de sucesi\u00f3n intestada promovido por Amelia Marroqu\u00edn &nbsp;Manjarrez, a fin de que se declare abierta la sucesi\u00f3n de &nbsp;Mar\u00eda Josefa Manjarrez Silva, Celsa Virginia Manjarrez Silva y &nbsp;Eugenia Manjarrez Silva. Por tanto, es de analizar lo que viene. &nbsp;<\/p>\n<p>4.1. &nbsp;El escrito genitor fue presentado ante el \u00abJUEZ &nbsp;DE FAMILIA DE FLORENCIA =REPARTO=\u00bb, &nbsp;pues en dicha ciudad tuvo su \u00faltimo domicilio una de las &nbsp;causantes -Mar\u00eda Josefa Manjarrez Silva-. &nbsp;<\/p>\n<p>4.2. &nbsp;As\u00ed las cosas, no le asist\u00eda raz\u00f3n al juez que &nbsp;conoci\u00f3 de entrada el litigio para rehusar el conocimiento del &nbsp;proceso. Ello pues, en la demanda -hechos y ac\u00e1pite de la &nbsp;competencia- se afirm\u00f3 que Mar\u00eda Josefa Manjarrez Silva &nbsp;tuvo su \u00faltimo domicilio en la ciudad Florencia, Caquet\u00e1. &nbsp;Ahora, si bien en el proceso se pretende tambi\u00e9n la apertura &nbsp;de las sucesiones de Celsa Virginia Manjarrez Silva y Eugenia &nbsp;Manjarrez Silva, lo cierto es que la facultad de escogencia estaba en &nbsp;cabeza de la demandante, la cual eligi\u00f3 amparada en el numeral &nbsp;12 del art\u00edculo 28 del estatuto procesal. &nbsp;<\/p>\n<p>5. &nbsp;Por estas razones, se remitir\u00e1 la demanda al Juzgado &nbsp;Tercero Civil Municipal de Florencia, a quien le corresponde &nbsp;continuar con el conocimiento de la acci\u00f3n emprendida. &nbsp;<\/p>\n<p>III. &nbsp;DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, el suscrito Magistrado de la Sala de &nbsp;Casaci\u00f3n Civil de la Corte Suprema de Justicia, &nbsp;<\/p>\n<p>RESUELVE &nbsp;<\/p>\n<p>PRIMERO: &nbsp;Declarar &nbsp;que el competente para conocer del proceso de la referencia es el &nbsp;Juzgado &nbsp;Tercero Civil Municipal de Florencia. &nbsp;<\/p>\n<p>SEGUNDO: &nbsp;Comunicar &nbsp;lo decidido al Juzgado Segundo &nbsp;Civil Municipal de Neiva. &nbsp;<\/p>\n<p>TERCERO: &nbsp;Por &nbsp;secretaria, remitir &nbsp;el expediente a la c\u00e9lula judicial referida en el numeral &nbsp;primero de esta decisi\u00f3n. Librar los oficios correspondientes &nbsp;y dejar las constancias del caso. &nbsp;<\/p>\n<p>NOT\u00cdFIQUESE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>1\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Folio &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;1-5, archivo \u201c0001DemandaAnexos.pdf\u201d del expediente &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;digital.&nbsp; &nbsp;<\/p>\n<p>2\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Folio &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;22, ibidem. &nbsp;<\/p>\n<p>3\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Archivo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;\u201c0002AutoRechazaPorCompetencia.pdf\u201d del expediente &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;digital.&nbsp; &nbsp;<\/p>\n<p>4\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Folio &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;25, archivo \u201c0001DemandaAnexos.pdf\u201d del expediente &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;digital.&nbsp; &nbsp;<\/p>\n<p>5\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Archivo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;\u201c0003AutoResuelveRecurso.pdf\u201d del expediente digital. &nbsp;<\/p>\n<p>6\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Archivo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;\u201c0005AutoPrononeConflictoFactorTerritorial.pdf\u201d del &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;expediente digital. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>AC381-2023 (2023-00097-00) &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; AC381-2023 &nbsp; Radicaci\u00f3n &nbsp;n.\u00b0 11001-02-03-000-2023-00097-00 &nbsp; Bogot\u00e1 &nbsp;D.C., veintitr\u00e9s (23) de febrero de dos mil veintitr\u00e9s &nbsp;(2023). &nbsp; Se &nbsp;decide el conflicto de competencia que surgi\u00f3 entre el Juzgado &nbsp;Tercero Civil Municipal de Florencia y el Despacho Segundo Civil &nbsp;Municipal de Neiva, atinente al conocimiento de la demanda de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-70433","post","type-post","status-publish","format-standard","hentry","category-febrero-2023"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=70433"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70433\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=70433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=70433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=70433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}