{"id":70492,"date":"2024-05-20T22:42:02","date_gmt":"2024-05-20T22:42:02","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/atc092-2023\/"},"modified":"2024-05-20T22:42:02","modified_gmt":"2024-05-20T22:42:02","slug":"atc092-2023","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/atc092-2023\/","title":{"rendered":"ATC092 2023"},"content":{"rendered":"<p>ATC092-2023<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>Magistrado &nbsp;ponente &nbsp;<\/p>\n<p>ATC092-2023 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00b0 &nbsp;05001-22-03-000-2022-00670-01 &nbsp;<\/p>\n<p>(Aprobado &nbsp;en sesi\u00f3n de tres (03) de febrero de dos mil veintitr\u00e9s) &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D. C., tres (03) de febrero de dos mil veintitr\u00e9s (2023). &nbsp;<\/p>\n<p>Se &nbsp;decide la consulta del auto de 30 de enero de 2023, por medio del &nbsp;cual la Sala Civil del Tribunal Superior del Distrito Judicial de &nbsp;Medell\u00edn resolvi\u00f3 el incidente de desacato formulado &nbsp;por \u00c1lvaro Eduardo y Andr\u00e9s Felipe Arenas Villegas &nbsp;contra el Juzgado Octavo Civil del Circuito de la misma ciudad. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>1. Mediante &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;fallo proferido el 28 de noviembre de 2022, la Sala de Familia del &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Tribunal Superior del Distrito Judicial de Medell\u00edn (rad. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;05-2022-00670-01) ampar\u00f3 el derecho fundamental al debido &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;proceso de los prenombrados, ordenando al estrado accionado aqu\u00ed &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;sancionado que dentro del proceso de restituci\u00f3n de inmueble &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;arrendado tramitado por aquellos contra Fernando Enrique Rodr\u00edguez &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Gonz\u00e1lez y Mar\u00eda Pilar Rodr\u00edguez Acosta &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;(05001-40-03-021-2015-00436-04), emita nueva sentencia de segunda &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;instancia, porque no analiz\u00f3 \u00abel &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;hecho de que uno de los contratantes arrendatario hubiese suscrito &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;el documento denominado \u201cotro s\u00ed\u201d al contrato de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;arrendamiento. Igualmente adjunto que no hab\u00eda prueba de la &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;compraventa del local comercial a favor de los accionantes, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;soslayando que a folio 27 del cuaderno principal milita la escritura &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;p\u00fablica 3879 otorgada el 15 de diciembre de 2010 en la &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Notar\u00eda Diecisiete de Medell\u00edn, relativa a dicho acto &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;jur\u00eddico; guard\u00f3 silencio respecto de los correos &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;electr\u00f3nicos entre los contratantes, as\u00ed como frente a &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;las declaraciones de partes y terceros\u00bb, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;pese a que, puntualiz\u00f3, esas pruebas \u00abresultaban &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;\u00fatiles para el buen suceso de las pretensiones\u00bb. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>2. \u00c1lvaro &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Eduardo y Andr\u00e9s Felipe Arenas Villegas radicaron &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;ante el a-quo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;constitucional &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;escrito en el que indicaron que en el nuevo fallo emitido por el &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;estrado accionado el 6 de diciembre de 2022 \u00abno &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;cumpli\u00f3 con la sentencia de amparo (\u2026) incurriendo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;nuevamente en defecto f\u00e1ctico al no valorar concienzudamente &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;las pruebas aportadas al proceso, negando nuevamente nuestras &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;pretensiones\u00bb, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;porque \u00abomite &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;tener en cuenta que el vinculado y demandado Enrique Rodr\u00edguez &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;y Mar\u00eda Pilar, si conocieron y consintieron la cesi\u00f3n &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;del contrato de arrendamiento con los suscrito, tal como se &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;evidencia en los correos electr\u00f3nicos provenientes del &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;demandado admitiendo la cesi\u00f3n y reconoci\u00e9ndonos como &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;actuales arrendadores. Peso a ello, el Juzgado Octavo Civil del &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Circuito tozudamente se niega a valorar estas pruebas documentales &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;que dan fe del comportamiento negocial y contractual que revalidad &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;la existencia del contrato de arrendamiento entre nosotros los &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;arrendadores y los demandados\u00bb &nbsp;<\/p>\n<p>Agregaron, &nbsp;\u00abobs\u00e9rvese &nbsp;como el juzgado accionado insiste en no practicar y valorar las &nbsp;pruebas de forma juiciosa, por lo que se sigue incurriendo en el &nbsp;defecto f\u00e1ctico negativo, al no indicar porque \u00e9stos &nbsp;documentos no demuestran la aceptaci\u00f3n t\u00e1cita de la &nbsp;cesi\u00f3n del contrato de arrendamiento, donde evidentemente &nbsp;estos demuestran la aceptaci\u00f3n t\u00e1cita de la cesi\u00f3n &nbsp;del contrato de arrendamiento, donde evidentemente estos demuestran y &nbsp;dan fe de la vigencia del contrato de arrendamiento entre nosotros &nbsp;como arrendadores y propietarios del establecimiento de comercio y &nbsp;local comercial y los demandados como arrendatarios\u00bb. &nbsp;<\/p>\n<p>3. &nbsp;El Tribunal, por medio de auto de 17 de enero de los corrientes, &nbsp;requiri\u00f3 a Carlos Arturo Higuita, titular del Juzgado Octavo &nbsp;Civil del Circuito de Medell\u00edn, con el fin de que informe &nbsp;sobre el cumplimiento del prenotado fallo de tutela. &nbsp;<\/p>\n<p>4. &nbsp;El prenombrado funcionario manifest\u00f3 que, para cumplir la &nbsp;orden constitucional dict\u00f3 sentencia el 6 de diciembre pasado, &nbsp;donde acat\u00f3 lo dispuesto en el fallo de tutela, porque realiz\u00f3 &nbsp;la valoraci\u00f3n integral de la prueba, sin que la orden &nbsp;incluyera el acceder a las pretensiones, por lo cual no incurri\u00f3 &nbsp;en el desacato del que se le acusa. &nbsp;<\/p>\n<p>5. &nbsp;El 19 de enero de 2023 se dispuso tramitar el incidente conforme a lo &nbsp;reglado en el Decreto 2591 de 1991, contra Carlos Arturo Guerra &nbsp;Higuita, como Juez Octavo Civil del Circuito de Medell\u00edn, &nbsp;surtiendo el traslado de rigor; t\u00e9rmino dentro del cual el &nbsp;funcionario insisti\u00f3 en que obedeci\u00f3 lo ordenado por la &nbsp;Colegiatura, porque en la nueva decisi\u00f3n de fondo abord\u00f3 &nbsp;el estudio de la escritura p\u00fablica de compraventa del local &nbsp;comercial y los correos electr\u00f3nicos, medios que, a su juicio &nbsp;\u00abno &nbsp;ten\u00edan la aptitud para varias la decisi\u00f3n inicial y as\u00ed &nbsp;se consign\u00f3\u00bb, &nbsp;sin que, reafirm\u00f3, se le haya impuesto el sentido de la &nbsp;determinaci\u00f3n a emitir. &nbsp;<\/p>\n<p>6. &nbsp; &nbsp; &nbsp; &nbsp;El &nbsp;24 de enero siguiente se decretaron como pruebas las documentales &nbsp;aportadas por los accionantes y el accionado, de las cuales se corri\u00f3 &nbsp;traslado. &nbsp;<\/p>\n<p>7. &nbsp; &nbsp; &nbsp; &nbsp;El &nbsp;d\u00eda 27 de los mismos mes y a\u00f1o, se notific\u00f3 la &nbsp;decisi\u00f3n tomada por esta Sala el d\u00eda 25 anterior, con &nbsp;que confirm\u00f3 el amparo concedido en la sentencia de tutela de &nbsp;primera instancia, prove\u00eddo que en sus consideraciones &nbsp;especific\u00f3 que en la nueva decisi\u00f3n que se le orden\u00f3 &nbsp;proferir al Juzgado Octavo Civil del Circuito de Medell\u00edn, &nbsp;deb\u00eda tenerse en cuenta al analizar las pruebas que, &nbsp;<\/p>\n<p>si &nbsp;bien se pact\u00f3 en el contrato de arrendamiento que su cesi\u00f3n &nbsp;tendr\u00eda como consecuencia darlo por terminado \u00abipso &nbsp;facto\u00bb, lo cierto es que las pruebas que los accionantes &nbsp;reclamaron analizar en su apelaci\u00f3n, apuntan a demostrar que &nbsp;el acuerdo de voluntades continu\u00f3 ejecut\u00e1ndose, ya que &nbsp;buscan dar cuenta del reconocimiento a ellos como arrendadores debido &nbsp;a varios mensajes de correo electr\u00f3nico, testimonios, &nbsp;la &nbsp;continuaci\u00f3n hasta cierto momento del pago de los c\u00e1nones &nbsp;de arrendamiento etc., todo lo cual amerita una valoraci\u00f3n por &nbsp;parte del juzgador del caso. &nbsp;<\/p>\n<p>3.2.1. &nbsp; &nbsp; &nbsp; &nbsp;Deber\u00e1 &nbsp;sopesarse en ese estudio que, aun cuando en principio, pudiera &nbsp;tenerse por v\u00e1lido el pacto inicial de prohibici\u00f3n de &nbsp;cesi\u00f3n del contrato tanto para el arrendador como para los &nbsp;arrendatarios, se pas\u00f3 por alto que el \u00abotros\u00ed\u00bb &nbsp;con que se efectu\u00f3 esa disposici\u00f3n de derechos fue &nbsp;suscrito por uno de \u00e9stos, particularidad de indudable &nbsp;trascendencia para el caso, porque esa manifestaci\u00f3n de &nbsp;voluntad del arrendatario puede interpretarse como una modificaci\u00f3n &nbsp;a la estipulaci\u00f3n prohibitiva inicial, revoc\u00e1ndola al &nbsp;expresamente consentirse en la cesi\u00f3n. &nbsp;<\/p>\n<p>Esa &nbsp;anuencia del arrendatario suscribiente vincular\u00eda a su &nbsp;coarrendataria, pese a que ciertamente \u00e9sta no plasm\u00f3 &nbsp;su r\u00fabrica en el documento, debido a la solidaridad que cobija &nbsp;a los deudores en aplicaci\u00f3n del art\u00edculo 825 del &nbsp;C\u00f3digo de Comercio. &nbsp;<\/p>\n<p>3.2.2. &nbsp; &nbsp; &nbsp; &nbsp;De &nbsp;otro lado, siempre dependiendo de lo que arroje el an\u00e1lisis &nbsp;conjunto de las pruebas, bien pudiera interpretarse la comentada &nbsp;cl\u00e1usula del contrato de arrendamiento, al tamiz de la &nbsp;conducta reiterada de las partes al ejecutarlo luego de la cesi\u00f3n, &nbsp;pues no se olvide que seg\u00fan la regla hermen\u00e9utica del &nbsp;art\u00edculo 1618 del C\u00f3digo Civil, aplicable al caso por &nbsp;la remisi\u00f3n del art\u00edculo 822 del C\u00f3digo de &nbsp;Comercio, \u00abconocida claramente la intenci\u00f3n de los &nbsp;contratantes, debe estarse a ella m\u00e1s que a lo literal de las &nbsp;palabras\u00bb, lo que traducido al caso particular, se enfatiza, &nbsp;seg\u00fan lo que arroje el an\u00e1lisis de las pruebas, dar\u00eda &nbsp;para evidenciar que la real intenci\u00f3n de las partes no fue dar &nbsp;por terminado el contrato como consecuencia de su cesi\u00f3n, sino &nbsp;continuar ejecut\u00e1ndolo con el cambio de arrendadores. &nbsp;<\/p>\n<p>Es &nbsp;m\u00e1s, de acreditarse esa ejecuci\u00f3n reiterada del &nbsp;contrato por las partes, cuando menos hasta que se dio el &nbsp;incumplimiento alegado como motivo para su terminaci\u00f3n, bien &nbsp;pudiera tenerse por renunciada la cl\u00e1usula de prohibici\u00f3n &nbsp;de cesi\u00f3n que all\u00ed se incluy\u00f3, como una renuncia &nbsp;leg\u00edtima al derecho que de all\u00ed dimana. &nbsp;<\/p>\n<p>3.2.3. &nbsp; &nbsp; &nbsp; &nbsp;As\u00ed &nbsp;mismo, no puede pasarse por alto que, si como alegan los demandantes, &nbsp;inmediatamente se efectu\u00f3 la cesi\u00f3n, los arrendatarios &nbsp;continuaron ejecutando el contrato de arrendamiento teni\u00e9ndolos &nbsp;a ellos como nuevos arrendadores, no resultar\u00eda aceptable que &nbsp;llegue a buen suceso la excepci\u00f3n esgrimida por aquellos &nbsp;durante el proceso, con que pretenden desconocer sus propios actos, &nbsp;derivando de tal actuar un provecho injustificado, pues ello &nbsp;implicar\u00eda omitir el principio \u00abvenire contra factum &nbsp;propium non valet\u00bb. &nbsp;<\/p>\n<p>8. &nbsp; &nbsp; &nbsp; &nbsp;El &nbsp;Tribunal constitucional de primera instancia, con providencia de 30 &nbsp;de enero pasado, sancion\u00f3 por desacato al \u00abdoctor &nbsp;Carlos Arturo Guerra Higuita, titular del Juzgado Octavo Civil del &nbsp;Circuito de Medell\u00edn\u00bb,en &nbsp;consecuencia le impuso \u00abmulta &nbsp;equivalente a un (1) salario m\u00ednimo legal mensual vigente a &nbsp;favor del Tesoro Nacional\u00bb, &nbsp;de &nbsp;conformidad con los art\u00edculos 52 y 53 del Decreto 2591 de &nbsp;1991. &nbsp;<\/p>\n<p>Para &nbsp;arribar a tal conclusi\u00f3n el a &nbsp;quo, tras &nbsp;destacar la orden que imparti\u00f3, consider\u00f3 que, \u00ab\u2026a &nbsp;trav\u00e9s de la sentencia proferida el 6 de diciembre de 2022, el &nbsp;juzgado accionado no satisfizo la orden de emitir una nueva decisi\u00f3n &nbsp;en la que valorase como le fue indicado las pruebas aducidas por la &nbsp;parte demandante y recurrente en el proceso radicado 050014003 021 &nbsp;2015 00436 01. Y as\u00ed se aprecia porque el juez de conocimiento &nbsp;no expuso razonadamente el m\u00e9rito que correspond\u00eda a &nbsp;cada prueba, solo se limit\u00f3 a descartar, sin an\u00e1lisis y &nbsp;rigor alguno, los elementos de juicio cuya valoraci\u00f3n se &nbsp;orden\u00f3 en la sentencia de tutela que se estima desacatada, con &nbsp;lo cual pretermiti\u00f3 no solo la orden de tutela, sino tambi\u00e9n &nbsp;las pautas descritas en el art\u00edculo 176 del CGP\u00bb. &nbsp;<\/p>\n<p>Asimismo, &nbsp;refiri\u00f3 luego de citar apartes del prove\u00eddo emitido por &nbsp;el juzgador sancionado que, a juicio de \u00e9ste, \u00abel &nbsp;contrato de arrendamiento allegado por los demandantes-tutelantes &nbsp;perdi\u00f3 vigencia al estar prohibida la cesi\u00f3n del mismo &nbsp;y, a partir de all\u00ed, desech\u00f3 sin valoraci\u00f3n &nbsp;jur\u00eddica alguna: el \u201cotro s\u00ed\u201d, la prueba de &nbsp;adquisici\u00f3n del dominio por parte de los actores, el cruce de &nbsp;correos electr\u00f3nicos entre las partes relativos a la &nbsp;continuaci\u00f3n del contrato, y las declaraciones de aquellas y &nbsp;terceros, estas \u00faltimas ni siquiera fueron mencionadas en la &nbsp;nueva decisi\u00f3n\u00bb. &nbsp;<\/p>\n<p>Para &nbsp;el Tribunal, tal proceder se apart\u00f3 de la orden de tutela \u00abal &nbsp;soslayar que en aquella se le conmin\u00f3 a realizar una &nbsp;valoraci\u00f3n concienzuda de las pruebas. La sentencia que emiti\u00f3 &nbsp;el despacho cognoscente no responde a la pregunta de por qu\u00e9 &nbsp;las declaraciones de las partes y de terceros; el comportamiento &nbsp;contractual de las partes, evidenciado en el cruce de correos &nbsp;electr\u00f3nicos; la suscripci\u00f3n del \u201cotro s\u00ed\u201d &nbsp;por uno de los arrendatarios solidarios; as\u00ed como los dem\u00e1s &nbsp;elementos de persuasi\u00f3n cuyo estudio es obligatorio, no son &nbsp;suficientes para deducir la modificaci\u00f3n de la cl\u00e1usula &nbsp;que prohib\u00eda la cesi\u00f3n del contrato, y por lo mismo la &nbsp;plena vigencia de este. En definitiva, sobre ese particular ninguna &nbsp;explicaci\u00f3n ofreci\u00f3 el juez de la causa\u00bb. &nbsp;<\/p>\n<p>9. &nbsp;El expediente se remiti\u00f3 a esta Corte para que fuera &nbsp;consultada la decisi\u00f3n adoptada. &nbsp;<\/p>\n<p>Ante &nbsp;esta sede el funcionario sancionado alleg\u00f3 escrito donde pidi\u00f3 &nbsp;la revocatoria de la decisi\u00f3n en su contra, porque \u00abjam\u00e1s &nbsp;ha sido ni ser\u00e1 [su] &nbsp;intenci\u00f3n &nbsp;desacatar ninguna orden judicial, y menos de [sus] &nbsp;superiores en sede de tutela\u00bb, &nbsp;por lo cual afirm\u00f3 que emitir\u00e1 la sentencia que le fue &nbsp;ordenada, aunque para el cometido presenta la dificultad de que el &nbsp;fallo con el cual pretendi\u00f3 acatar la orden se encuentra &nbsp;ejecutoriado, sin que en el auto sancionatorio se haya dejado sin &nbsp;efecto, particularidad frente a la cual pidi\u00f3 un &nbsp;pronunciamiento por parte de la Corte. &nbsp;<\/p>\n<p>De &nbsp;otro lado sostuvo que el Tribunal no valor\u00f3 el aspecto &nbsp;subjetivo del desacato, sino \u00fanicamente el objetivo, sin &nbsp;observar que si se analizaron las pruebas tal como se le orden\u00f3. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>1. Al tenor del &nbsp;inciso segundo del art\u00edculo 52 del Decreto 2591 de 1991, \u00abla &nbsp;sanci\u00f3n por desacato ser\u00e1 impuesta por el mismo juez\u00bb &nbsp;que profiri\u00f3 la orden, mediante tr\u00e1mite incidental; \u00aben &nbsp;raz\u00f3n a lo cual no existe duda de que la competencia para &nbsp;resolver el incidente propuesto est\u00e1 radicada en cabeza del &nbsp;mismo juzgador o sentenciador que resolvi\u00f3 la tutela a favor &nbsp;de su promotor, salvedad hecha de las \u00f3rdenes de protecci\u00f3n &nbsp;impartidas con ocasi\u00f3n de la impugnaci\u00f3n formulada &nbsp;contra el fallo denegatorio del amparo, porque en tal caso, la &nbsp;resoluci\u00f3n de la actuaci\u00f3n incidental corresponde al &nbsp;juzgador de la primera instancia\u00bb &nbsp;(ATC, &nbsp;13 jun. 2012, rad. &nbsp;2011-02468-04). &nbsp;<\/p>\n<p>2. Es menester &nbsp;indicar que el fallo emitido en el \u00e1mbito de la acci\u00f3n &nbsp;de tutela \u00abno &nbsp;s\u00f3lo goza de la fuerza vinculante propia de toda decisi\u00f3n &nbsp;judicial, sino que, al encontrar fundamento directo en la Carta &nbsp;Pol\u00edtica y estar consagrada aqu\u00e9lla de modo espec\u00edfico &nbsp;para la guarda y protecci\u00f3n de los derechos fundamentales de &nbsp;rango constitucional, se reclama la aplicaci\u00f3n urgente e &nbsp;integral de lo ordenado, comprometiendo a partir de su notificaci\u00f3n, &nbsp;la responsabilidad del sujeto pasivo de ese mandato judicial, por lo &nbsp;que est\u00e1 obligado a su cumplimiento\u00bb &nbsp;(\u00eddem). &nbsp;<\/p>\n<p>Igualmente, &nbsp;por su especial connotaci\u00f3n, al juez que conoce del desacato &nbsp;no le es permitido analizar nuevamente los t\u00f3picos que fueron &nbsp;objeto de debate en el tr\u00e1mite constitucional, pues de &nbsp;aceptarse tal proceder revivir\u00eda una controversia concluida. &nbsp;Es por ello que \u00ab\u2026 &nbsp;su actuaci\u00f3n se encuentre delimitada por la parte resolutiva &nbsp;de la decisi\u00f3n que se acusa incumplida, limitaci\u00f3n con &nbsp;la que, entonces, le corresponde constatar los aspectos relacionados &nbsp;con el destinatario de la orden de protecci\u00f3n, su contenido y &nbsp;el t\u00e9rmino otorgado para su cumplimiento\u00bb &nbsp;(\u00eddem). &nbsp;<\/p>\n<p>3. &nbsp;Con &nbsp;base en las anteriores premisas, para establecer si en el caso sub &nbsp;examine &nbsp;el convocado atendi\u00f3 la orden constitucional y comoquiera que &nbsp;el alcance &nbsp;de la protecci\u00f3n brindada constituye la base para ello, es &nbsp;preciso remitirse a la sentencia que otorg\u00f3 el amparo. &nbsp;<\/p>\n<p>4. &nbsp;En &nbsp;esa decisi\u00f3n fue ordenado al Juzgado Octavo Civil del Circuito &nbsp;de Medell\u00edn, como qued\u00f3 dicho, que en &nbsp;el t\u00e9rmino de 48 horas a partir de la notificaci\u00f3n de &nbsp;ese fallo, \u00abteniendo &nbsp;en cuenta lo aqu\u00ed dilucidado, emita nuevamente una decisi\u00f3n &nbsp;que resuelva la segunda instancia en el asunto mencionado\u00bb. &nbsp;<\/p>\n<p>Donde &nbsp;el fundamento de la orden consisti\u00f3 en que, &nbsp;<\/p>\n<p>\u2026la &nbsp;lectura al fallo de segundo grado se concluye que el funcionario &nbsp;decisor omiti\u00f3 apreciar en conjunto las pruebas, limit\u00e1ndose &nbsp;solo a expresar que el contrato de arrendamiento hab\u00eda perdido &nbsp;vigencia dada la cl\u00e1usula s\u00e9ptima del mismo, en la que &nbsp;se prescribi\u00f3 \u00ab[s]e proh\u00edbe la cesi\u00f3n o el &nbsp;subarriendo, parcial o total, del contrato de arrendamiento. La &nbsp;violaci\u00f3n de esta obligaci\u00f3n da lugar a la terminaci\u00f3n &nbsp;del contrato de arrendamiento ipso facto\u00bb, sin merecerle ning\u00fan &nbsp;an\u00e1lisis el hecho de que uno de los contratantes arrendatario &nbsp;hubiese suscrito el documento denominado \u201cotro s\u00ed\u201d &nbsp;al contrato de arrendamiento. Igualmente, adujo que no hab\u00eda &nbsp;prueba de la compraventa del local comercial a favor de los &nbsp;accionantes, soslayando que a folio 27 del cuaderno principal milita &nbsp;la escritura p\u00fablica 3.879 otorgada el 15 de diciembre de 2010 &nbsp;en la Notar\u00eda Diecisiete de Medell\u00edn, relativa a dicho &nbsp;acto jur\u00eddico; guard\u00f3 silencio respecto a los correos &nbsp;electr\u00f3nicos entre los contratantes, as\u00ed como frente a &nbsp;las declaraciones de partes y terceros. En tal sentido, la omisi\u00f3n &nbsp;antedicha impidi\u00f3 que el juzgado analizara si esos elementos &nbsp;de persuasi\u00f3n resultaban \u00fatiles para el buen suceso de &nbsp;las pretensiones, al tiempo que olvid\u00f3 la regla instituida en &nbsp;el art\u00edculo 176 del CGP. &nbsp;<\/p>\n<p>5. &nbsp;A partir de lo dispuesto en el mencionado fallo constitucional es que &nbsp;esta Corte debe cotejar si la persona destinataria de ese mandato se &nbsp;sujet\u00f3 a sus lineamientos, pues de encontrar una respuesta &nbsp;negativa, &nbsp;como es apenas natural deber\u00e1 &nbsp;accederse a &nbsp;la aspiraci\u00f3n de los promotores del presente incidente. &nbsp;<\/p>\n<p>Para &nbsp;el cometido, se observa que, en la decisi\u00f3n emitida a &nbsp;instancias de la orden constitucional, el estrado accionado &nbsp;nuevamente confirm\u00f3 la decisi\u00f3n con se negaron las &nbsp;pretensiones de la demanda, y en punto al reexamen probatorio &nbsp;ordenado consider\u00f3 que, &nbsp;<\/p>\n<p>Realizada &nbsp;una valoraci\u00f3n probatoria en conjunto, como fue ordenado, se &nbsp;llega a colegir que la apelaci\u00f3n no tiene vocaci\u00f3n de &nbsp;prosperidad y que lo que se impone es la confirmaci\u00f3n de la &nbsp;sentencia de primera instancia, pues como se ha dicho, el contrato de &nbsp;arrendamiento perdi\u00f3 vigencia al estar prohibida la cesi\u00f3n, &nbsp;sin que el afirmado \u201cotro s\u00ed\u201d tenga la aptitud &nbsp;legal para derruir tal prohibici\u00f3n; como tampoco la tiene la &nbsp;escritura p\u00fablica 3.879 otorgada el 15 de diciembre de 2010 en &nbsp;la Notar\u00eda Diecisiete de Medell\u00edn de la compraventa del &nbsp;local comercial a favor de los accionantes, que se dice visible a &nbsp;folio 27 del cuaderno principal, relativa a dicho acto jur\u00eddico &nbsp;por medio de la cual se dice que los demandantes adquirieron, en &nbsp;tanto, se repite, la cesi\u00f3n estaba prohibida contractualmente. &nbsp;Recu\u00e9rdese que el contrato inicial dada de agosto 23 de 2002, &nbsp;y la cesi\u00f3n a trav\u00e9s de \u201cotro s\u00ed\u201d es &nbsp;de enero de 2011. &nbsp;<\/p>\n<p>Es &nbsp;que, si demandantes a pesar del haber adquirido el bien, &nbsp;establecimiento de comercio, al proceso no allegaron tal escritura &nbsp;p\u00fablica como t\u00edtulo o base de la restituci\u00f3n, &nbsp;sino que aportaron el tantas veces mencionado \u201cotro s\u00ed\u201d, &nbsp;que, como se dijo, no deja sin efecto la prohibici\u00f3n &nbsp;convenida. V\u00e9ase que, aunque as\u00ed fuera, que los &nbsp;arrendadores hubiesen vendido el establecimiento de comercio y esto &nbsp;incluyera el contrato de arrendamiento, la prohibici\u00f3n &nbsp;persistir\u00eda en los t\u00e9rminos pactados, tal y como se &nbsp;dijo en primera y segunda instancia. &nbsp;<\/p>\n<p>Como &nbsp;anexo, se present\u00f3 el contrato de arrendamiento de local &nbsp;comercial suscrito entre los se\u00f1ores JANETH ESQUENAZI, cuyo &nbsp;apoderado general es el se\u00f1or ROBERTO ESQUENAZI, y un \u201cOTRO &nbsp;S\u00cd\u201d a dicho contrato, de fecha enero 11 de 2011 que &nbsp;contiene la cesi\u00f3n que de dicho contrato hizo el arrendador a &nbsp;los ahora demandantes; documento firmado por el codemandado ENRIQUE &nbsp;RODRIGUEZ, pero no por la co-demandada MARIA PILAR RODR\u00cdGUEZ &nbsp;ACOSTA. &nbsp;<\/p>\n<p>Finalmente, &nbsp;lo dicho sirve de sustento para decir que los correos electr\u00f3nicos &nbsp;habidos entre las partes, que a juicio del apelante y ahora tutelante &nbsp;evidencian la aceptaci\u00f3n de la cesi\u00f3n por parte de los &nbsp;demandados, tampoco son prueba apta y suficiente para avalar el que &nbsp;se revoque la decisi\u00f3n de primera instancia, dado que, se &nbsp;reitera, la cesi\u00f3n estaba prohibida. Todo lo anterior lleva a &nbsp;que, nuevamente y cumpliendo con lo ordenado por el Superior, se &nbsp;desestime la apelaci\u00f3n y se confirme la sentencia de primera &nbsp;instancia. &nbsp;<\/p>\n<p>6. &nbsp; &nbsp; &nbsp; &nbsp;Analizadas &nbsp;las anteriores consideraciones se observa que, si bien incluyen un &nbsp;an\u00e1lisis probatorio, el mismo no acompasa con el rigor y &nbsp;alcance que exigi\u00f3 el Tribunal a &nbsp;quo &nbsp;en su decisi\u00f3n, sin embargo, tambi\u00e9n es cierto que la &nbsp;Colegiatura no fue muy precisa al respecto, de ah\u00ed que esta &nbsp;Sala, al resolver la impugnaci\u00f3n, brind\u00f3 par\u00e1metros &nbsp;m\u00e1s claros para guiar el estudio probatorio ordenado en &nbsp;primera instancia. &nbsp;<\/p>\n<p>De &nbsp;este modo, objetivamente se puede considerar desacatada la orden &nbsp;constitucional, pero al haber sido la decisi\u00f3n de esta Sala la &nbsp;que especific\u00f3 su alcance, sin que el juzgador accionado la &nbsp;haya podido sopesar por la pot\u00edsima raz\u00f3n de que la &nbsp;desconoc\u00eda para el momento en que emiti\u00f3 el nuevo &nbsp;fallo, no puede hablarse de una intenci\u00f3n subjetiva de &nbsp;apartarse de la orden de tutela, sino de una equivocaci\u00f3n en &nbsp;la interpretaci\u00f3n de la misma, situaci\u00f3n que entonces &nbsp;impide configurar el desacato solicitado. &nbsp;<\/p>\n<p>N\u00f3tese &nbsp;como la valoraci\u00f3n probatoria realizada por el accionado no &nbsp;puede necesariamente interpretarse como un actuar voluntariamente &nbsp;direccionado en contra de la orden constitucional, pues el &nbsp;funcionario destin\u00f3 un aparte espec\u00edfico del fallo a &nbsp;efectuar la misma, s\u00f3lo que sin el alcance y rigor que el &nbsp;fallo de esta Sala posteriormente encontr\u00f3 necesario. &nbsp;<\/p>\n<p>Recu\u00e9rdese &nbsp;que la sanci\u00f3n resulta de haberse probado en el tr\u00e1mite &nbsp;incidental que el compelido no solo desobedeci\u00f3 la orden &nbsp;constitucional, sino que lo hizo con probada negligencia o culpa, &nbsp;pues como lo ha explicado la Corte Constitucional, &nbsp;<\/p>\n<p>El &nbsp;desacato es un ejercicio del poder disciplinario y por lo mismo la &nbsp;responsabilidad de quien incurra en aquel es una responsabilidad &nbsp;subjetiva. Es decir, que debe haber negligencia comprobada en la &nbsp;persona para el incumplimiento del fallo, no pudiendo presumirse la &nbsp;responsabilidad por el s\u00f3lo hecho del incumplimiento (\u2026)1. &nbsp;<\/p>\n<p>Analizada &nbsp;dicha providencia advierte la Corte que esta no &nbsp;refleja lo que hab\u00eda previsto la Corporaci\u00f3n en el &nbsp;fallo de tutela, sin &nbsp;embargo, tal diferencia no traduce ese prop\u00f3sito de apartarse &nbsp;del &nbsp;mismo, sino al parecer es el resultado de una percepci\u00f3n &nbsp;equivocada &nbsp;del sentido del amparo concedido y subsecuentemente &nbsp;de la orden emitida. No encuentra la &nbsp;Sala &nbsp;manifestaciones &nbsp;dirigidas, de manera clara y contundente, a &nbsp;desviar &nbsp;la protecci\u00f3n concedida, o sea, no hay esa actitud subjetiva &nbsp;de desconocer la determinaci\u00f3n procedente de esta Corporaci\u00f3n, &nbsp;y en esas circunstancias, sin duda alguna, es palpable &nbsp;que no hay lugar a sanci\u00f3n por desacato. Desde luego, lo &nbsp;anterior no es \u00f3bice para zanjar la situaci\u00f3n planteada &nbsp;con miras &nbsp;a evitar mayores dilaciones y, generar, plenamente, la satisfacci\u00f3n &nbsp;del derecho protegido. (CSJ, &nbsp;exp 11001 02 03 000 2009 01427 00, 14 sept. 2009). &nbsp;<\/p>\n<p>M\u00e1s &nbsp;recientemente, en otro asunto de contornos similares se dijo que, &nbsp;<\/p>\n<p>Ahora, &nbsp;aun cuando objetivamente se incumpli\u00f3 el fallo de tutela, ello &nbsp;no obedeci\u00f3 a una intenci\u00f3n subjetiva de la autoridad &nbsp;encargada de honrarlo y, por tanto, no se incurri\u00f3 en &nbsp;desacato. &nbsp;<\/p>\n<p>T\u00e9ngase &nbsp;en cuenta, adem\u00e1s, que, para sancionar en el procedimiento &nbsp;incidental, no s\u00f3lo debe mediar el desobedecimiento &nbsp;manifiesto, debidamente probado, sino tambi\u00e9n aspectos &nbsp;subjetivos de quien incumple la decisi\u00f3n de tutela, pues no &nbsp;puede endilgarse culpa ni presumirse, ni debe olvidarse que la &nbsp;responsabilidad objetiva, en materia sancionatoria, est\u00e1 &nbsp;proscrita en nuestro ordenamiento (ATC882-2021). &nbsp;<\/p>\n<p>7. &nbsp; &nbsp; &nbsp; &nbsp;De &nbsp;otro lado, se tiene establecido que el prop\u00f3sito del desacato &nbsp;no es la sanci\u00f3n, sino lograr el cumplimiento efectivo de la &nbsp;orden de tutela, para de esa manera garantizar la protecci\u00f3n &nbsp;de los derechos fundamentales, de ah\u00ed que, como en este caso &nbsp;no hubo desacato, pero si incumplimiento, para la efectividad de la &nbsp;protecci\u00f3n dispensada sobre las garant\u00edas superiores de &nbsp;los accionantes, se dejar\u00e1 sin efecto el fallo emitido por el &nbsp;Juzgado Octavo Civil del Circuito de Medell\u00edn el 6 de &nbsp;diciembre de 2022 y se le reiterar\u00e1 a \u00e9ste que cumpla &nbsp;con la orden constitucional que se le imparti\u00f3 dentro del &nbsp;asunto, en los t\u00e9rminos dictaminados en ambas instancias. &nbsp;<\/p>\n<p>8. &nbsp; &nbsp; &nbsp; &nbsp;Por &nbsp;tanto, la determinaci\u00f3n consultada habr\u00e1 de revocarse &nbsp;en cuanto a la declaratoria de desacato del accionado, pero se &nbsp;mantendr\u00e1 respecto al cumplimiento de la orden de tutela, para &nbsp;lo cual se dejar\u00e1 sin efecto la sentencia antes &nbsp;individualizada. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto la Corte Suprema de Justicia, en Sala de &nbsp;Casaci\u00f3n Civil, resuelve: &nbsp;<\/p>\n<p>Primero. &nbsp;REVOCAR &nbsp;el prove\u00eddo de 30 &nbsp;de enero de 2023, emitido dentro del asunto, en cuanto declar\u00f3 &nbsp;en desacato a Carlos Arturo Guerra Higuita, titular del Juzgado &nbsp;Octavo Civil del Circuito de Medell\u00edn, respecto de la orden &nbsp;impartida por la Sala Civil del Tribunal Superior de la misma ciudad &nbsp;el 28 de noviembre de 2022, dentro de la acci\u00f3n de tutela que &nbsp;contra aquel promovieron \u00c1lvaro y Andr\u00e9s Felipe Arenas &nbsp;Villegas. &nbsp;<\/p>\n<p>En &nbsp;consecuencia, tambi\u00e9n queda sin efecto la sanci\u00f3n all\u00ed &nbsp;impuesta. &nbsp;<\/p>\n<p>Segundo. &nbsp; &nbsp; &nbsp; &nbsp;DEJAR &nbsp;SIN EFECTO &nbsp;la sentencia proferida el 6 de diciembre de 2022 por el Juzgado &nbsp;Octavo Civil del Circuito de Medell\u00edn, dentro del proceso de &nbsp;restituci\u00f3n de inmueble arrendado que \u00c1lvaro y Andr\u00e9s &nbsp;Felipe Arenas Villegas promovieron contra Fernando Enrique Rodr\u00edguez &nbsp;Gonz\u00e1lez y Mar\u00eda Pilar Rodr\u00edguez Acosta &nbsp;(05001-40-03-021-2015-00436-04). &nbsp;<\/p>\n<p>Tercero. &nbsp; &nbsp; &nbsp; &nbsp;ORDENAR &nbsp;al &nbsp;Juzgado Octavo Civil del Circuito de Medell\u00edn que cumpla con &nbsp;la orden de tutela que le fue impartida por el Tribunal el 28 de &nbsp;noviembre de 2022 y confirmada por esta Corte en prove\u00eddo &nbsp;STC294-2023, dentro del asunto, en el t\u00e9rmino all\u00ed &nbsp;se\u00f1alado, contado a partir del momento en que reciba el &nbsp;expediente de parte del Juzgado Veintiuno Civil Municipal de Oralidad &nbsp;de Medell\u00edn. &nbsp;<\/p>\n<p>A &nbsp;su turno, el precitado estrado deber\u00e1 enviar al despacho &nbsp;accionado el dossier &nbsp;del &nbsp;descrito proceso de restituci\u00f3n de inmueble arrendado, en el &nbsp;lapso m\u00e1ximo de un (1) d\u00eda siguiente a aquel en el que &nbsp;resulte notificado, a fin de que se pueda impartir cumplimiento a lo &nbsp;aqu\u00ed mandado. &nbsp;<\/p>\n<p>Quinto. &nbsp;ORDENAR &nbsp;la devoluci\u00f3n de las diligencias al despacho de origen. &nbsp;<\/p>\n<p>Notif\u00edquese &nbsp;telegr\u00e1ficamente &nbsp;lo aqu\u00ed resuelto a las partes y dem\u00e1s intervinientes. &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Presidenta &nbsp;de Sala &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>14 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Corte Constitucional Sentencia T- 763 de 1998. &nbsp;<\/p>\n<p>6 &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>ATC092-2023 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp; Magistrado &nbsp;ponente &nbsp; ATC092-2023 &nbsp; Radicaci\u00f3n &nbsp;n\u00b0 &nbsp;05001-22-03-000-2022-00670-01 &nbsp; (Aprobado &nbsp;en sesi\u00f3n de tres (03) de febrero de dos mil veintitr\u00e9s) &nbsp; Bogot\u00e1, &nbsp;D. C., tres (03) de febrero de dos mil veintitr\u00e9s (2023). &nbsp; Se &nbsp;decide la consulta del auto de 30 de enero [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-70492","post","type-post","status-publish","format-standard","hentry","category-febrero-2023"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=70492"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70492\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=70492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=70492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=70492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}