{"id":70642,"date":"2024-05-20T22:42:06","date_gmt":"2024-05-20T22:42:06","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc1218-2023\/"},"modified":"2024-05-20T22:42:06","modified_gmt":"2024-05-20T22:42:06","slug":"stc1218-2023","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc1218-2023\/","title":{"rendered":"STC1218 2023"},"content":{"rendered":"<p>STC1218-2023<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>Magistrado &nbsp;ponente &nbsp;<\/p>\n<p>STC1218-2023 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n.\u00b0 11001-02-03-000-2023-00389-00 &nbsp;<\/p>\n<p>(Aprobado &nbsp;en sesi\u00f3n de quince de febrero de dos mil veintitr\u00e9s) &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D. C., quince &nbsp;(15) de febrero de &nbsp;dos mil veintitr\u00e9s (2023). &nbsp;<\/p>\n<p>Se &nbsp;decide la acci\u00f3n de tutela promovida por Mario Restrepo contra &nbsp;la Sala Civil-Familia del Tribunal Superior del Distrito Judicial de &nbsp;Antioquia, a cuyo tr\u00e1mite fueron vinculadas las partes e &nbsp;intervinientes en el asunto que origin\u00f3 la queja &nbsp;constitucional. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>1. &nbsp; &nbsp; &nbsp; &nbsp;El &nbsp;actor reclam\u00f3 la protecci\u00f3n de su garant\u00eda &nbsp;esencial al debido proceso, presuntamente vulnerada por el Tribunal &nbsp;convocado porque en la acci\u00f3n popular que instaur\u00f3 &nbsp;contra Juan \u00c1lvaro Pareja Mej\u00eda (rad. &nbsp;2022-00053), &nbsp;declar\u00f3 desierta la apelaci\u00f3n que inco\u00f3 contra &nbsp;la sentencia de primer grado, \u00abdesconociendo &nbsp;abiertamente derecho sustancial, inaplicando la doble instancia en &nbsp;muestra clara de un exceso ritual manifiesto y desconociendo tutelas &nbsp;(sic)\u00bb. &nbsp;<\/p>\n<p>2. &nbsp; &nbsp; &nbsp; &nbsp;Solicit\u00f3, &nbsp;entonces, ordenar a la Colegiatura accionada \u00abdar &nbsp;tr[\u00e1]mite a [su] alzada, amparad[a] [en el] art[.] 37 [de la] &nbsp;ley 472 de 1998\u00bb; &nbsp;y \u00abaplicar &nbsp;[el] art[.] 84 [ib\u00eddem]\u00bb. &nbsp;<\/p>\n<p>3. &nbsp; &nbsp; &nbsp; &nbsp;La &nbsp;Corte admiti\u00f3 el libelo de amparo, orden\u00f3 librar las &nbsp;comunicaciones de rigor y pidi\u00f3 rendir los informes a que &nbsp;alude el canon 19 del Decreto 2591 de 1991. &nbsp;<\/p>\n<p>LAS &nbsp;RESPUESTAS DE LOS CONVOCADOS &nbsp;<\/p>\n<p>1. &nbsp; &nbsp; &nbsp; &nbsp;El &nbsp;Juzgado Civil del Circuito de Andes limit\u00f3 su intervenci\u00f3n &nbsp;a proporcionar link de acceso al expediente del asunto fustigado y &nbsp;los datos de ubicaci\u00f3n de todos los all\u00ed &nbsp;intervinientes. &nbsp;<\/p>\n<p>2. &nbsp; &nbsp; &nbsp; &nbsp;Juan &nbsp;\u00c1lvaro Pareja Mej\u00eda deprec\u00f3 \u00abno &nbsp;acceder a las peticiones de la acci\u00f3n de tutela\u00bb &nbsp;por \u00abcarencia &nbsp;de objeto\u00bb, &nbsp;comoquiera que ya construy\u00f3 la rampa que se le exigi\u00f3 &nbsp;en el tr\u00e1mite popular fustigado. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>1. &nbsp; &nbsp; &nbsp; &nbsp;Conforme &nbsp;al art\u00edculo 86 de la Constituci\u00f3n Pol\u00edtica, la &nbsp;acci\u00f3n de tutela es un mecanismo jur\u00eddico concebido &nbsp;para proteger los derechos fundamentales, cuando son vulnerados o &nbsp;amenazados por los actos u omisiones de las autoridades p\u00fablicas &nbsp;y, en determinadas hip\u00f3tesis, de los particulares, cuya &nbsp;naturaleza subsidiaria y residual no permite sustituir o desplazar a &nbsp;los jueces funcionalmente competentes, ni los medios comunes de &nbsp;defensa judicial. &nbsp;<\/p>\n<p>Por &nbsp;lineamiento jurisprudencial, en trat\u00e1ndose de actuaciones y &nbsp;providencias judiciales, el resguardo se abre paso de manera &nbsp;excepcional y limitado a la presencia de una irrefutable v\u00eda &nbsp;de hecho, cuando \u00abel &nbsp;proceder ileg\u00edtimo no es dable removerlo a trav\u00e9s de &nbsp;los medios ordinarios previstos en la ley\u00bb &nbsp;(CSJ STC, 11 may. 2001, rad. 2001-00183-01); y por supuesto, se &nbsp;cumpla el requisito de la inmediatez. &nbsp;<\/p>\n<p>2. &nbsp; &nbsp; &nbsp; &nbsp;Puestas &nbsp;as\u00ed las cosas, es patente que la presente solicitud de &nbsp;protecci\u00f3n est\u00e1 llamada al fracaso, comoquiera que, &nbsp;revisado el expediente del asunto fustigado, se observa que la acci\u00f3n &nbsp;popular referida por el quejoso apenas arrib\u00f3 al Tribunal &nbsp;convocado el 24 de enero de \u00faltimo, misma data en que se &nbsp;admiti\u00f3 el mentado recurso de apelaci\u00f3n, sin que, para &nbsp;cuando se interpuso este ruego tutelar, existiese auto alguno que lo &nbsp;declarara desierto. &nbsp;<\/p>\n<p>De &nbsp;all\u00ed que la situaci\u00f3n criticada por el inconforme sea &nbsp;inexistente, raz\u00f3n por la cual pierde motivo el amparo, pues &nbsp;no tendr\u00eda objeto impartir alguna orden si la misma carecer\u00eda &nbsp;de objeto. &nbsp;<\/p>\n<p>En &nbsp;un caso con alguna simetr\u00eda con el de ahora, en el que, al &nbsp;igual que aqu\u00ed, el tutelante se quej\u00f3 de una actuaci\u00f3n &nbsp;judicial irreal, la Sala indic\u00f3 que: &nbsp;<\/p>\n<p>En &nbsp;consecuencia, se observa que los supuestos de hecho aducidos en la &nbsp;queja como vulneratorios de derechos no existen\u2026, en tal &nbsp;raz\u00f3n, pierde motivo el amparo, pues no tendr\u00eda objeto &nbsp;impartir alguna orden si la misma carecer\u00eda de objeto. &nbsp;<\/p>\n<p>Al &nbsp;respecto se ha reiterado que: &nbsp;<\/p>\n<p>\u2026[L]a &nbsp;carencia de objeto (\u2026), se presenta: \u2018si la omisi\u00f3n &nbsp;por la cual la persona se queja no existe &nbsp;(\u2026), [o ya ha sido superada,] en el sentido que la pretensi\u00f3n &nbsp;erigida en defensa del derecho conculcado (\u2026) ha sido &nbsp;totalmente [satisfecha], pues la tutela pierde su eficacia y raz\u00f3n &nbsp;de ser, por lo que la posible orden que llegase a impartir el juez &nbsp;del amparo carecer\u00eda de sentido\u2026 (CSJ STC1638, 12 feb. &nbsp;2016, rad. 73-2015-00544-01) (Se &nbsp;destac\u00f3 &#8211; CSJ STC1417-2018, 8 feb. 2018, rad. 2017-00822-01). &nbsp;<\/p>\n<p>3. &nbsp; &nbsp; &nbsp; &nbsp;Lo &nbsp;sucintamente consignado se muestra suficiente para despachar &nbsp;adversamente la salvaguarda rogada. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, en Sala &nbsp;de Casaci\u00f3n Civil, administrando justicia en nombre de la &nbsp;Rep\u00fablica y por autoridad de la ley, &nbsp;declara &nbsp;improcedente &nbsp;la protecci\u00f3n pedida. &nbsp;<\/p>\n<p>Comun\u00edquese &nbsp;a todos los interesados y, en caso de no impugnarse este veredicto, &nbsp;oportunamente rem\u00edtanse las actuaciones respectivas a la Corte &nbsp;Constitucional, para su eventual revisi\u00f3n. &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Presidenta &nbsp;de Sala &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC1218-2023 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp; Magistrado &nbsp;ponente &nbsp; STC1218-2023 &nbsp; Radicaci\u00f3n &nbsp;n.\u00b0 11001-02-03-000-2023-00389-00 &nbsp; (Aprobado &nbsp;en sesi\u00f3n de quince de febrero de dos mil veintitr\u00e9s) &nbsp; Bogot\u00e1, &nbsp;D. C., quince &nbsp;(15) de febrero de &nbsp;dos mil veintitr\u00e9s (2023). &nbsp; Se &nbsp;decide la acci\u00f3n de tutela promovida por Mario Restrepo contra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-70642","post","type-post","status-publish","format-standard","hentry","category-febrero-2023"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=70642"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70642\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=70642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=70642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=70642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}