{"id":70780,"date":"2024-05-20T22:42:10","date_gmt":"2024-05-20T22:42:10","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc1483-2023\/"},"modified":"2024-05-20T22:42:10","modified_gmt":"2024-05-20T22:42:10","slug":"stc1483-2023","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc1483-2023\/","title":{"rendered":"STC1483 2023"},"content":{"rendered":"<p>STC1483-2023<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>Magistrado &nbsp;Ponente &nbsp;<\/p>\n<p>STC1483-2023 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00b0 68001-22-13-000-2023-00030-01 &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D.C., veintid\u00f3s (22) de febrero de dos mil veintitr\u00e9s &nbsp;(2023). &nbsp;<\/p>\n<p>Decide &nbsp;la Corte la impugnaci\u00f3n formulada frente al fallo proferido &nbsp;por la Sala &nbsp;Civil Familia del Tribunal Superior del Distrito Judicial de &nbsp;Bucaramanga el &nbsp;3 de febrero de 2023, &nbsp;dentro de la acci\u00f3n de tutela promovida por Dayan &nbsp;Patricia Fontecha Acevedo contra &nbsp;el Juzgado &nbsp;Sexto de Familia de esa ciudad, &nbsp;tr\u00e1mite al cual fueron vinculados los intervinientes en el &nbsp;litigio n\u00b0 2019-00540. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>1. &nbsp; &nbsp; &nbsp; &nbsp;Actuando &nbsp;a trav\u00e9s de apoderada judicial, la solicitante reclama la &nbsp;protecci\u00f3n de los derechos fundamentales al debido proceso y &nbsp;vivienda digna, presuntamente vulnerados por la autoridad convocada &nbsp;durante el tr\u00e1mite y definici\u00f3n del asunto antes &nbsp;referido. &nbsp;<\/p>\n<p>2. &nbsp; &nbsp; &nbsp; &nbsp;En &nbsp;s\u00edntesis, expuso que, en el Juzgado Sexto de Familia de &nbsp;Bucaramanga, \u00abse &nbsp;tramit\u00f3 el respectivo proceso de petici\u00f3n de herencia &nbsp;adelantado por el se\u00f1or Guillermo Su\u00e1rez Palomino, &nbsp;en &nbsp;donde eran demandados en principio, Cecilia Su\u00e1rez Palomino, &nbsp;Gilberto Su\u00e1rez Palomino y Gonzalo Palomino\u00bb, &nbsp;y en \u00abaudiencia &nbsp;del 20 de octubre de 2020 [se] &nbsp;orden\u00f3 vincular a la se\u00f1ora Dayan Patricia Fontecha &nbsp;Acevedo (\u2026)\u00bb, &nbsp;habida &nbsp;cuenta su calidad de &nbsp;\u00abcompradora &nbsp;de buena fe (\u2026) de la cuota de dominio equivalente al 16,68% &nbsp;del bien con folio inmobiliario N\u00b0 300-55482 &nbsp;[adquirido mediante compraventa celebrada con Gonzalo Palomino, seg\u00fan &nbsp;escritura p\u00fablica otorgada el 20 de marzo de 2014]\u00bb. &nbsp;<\/p>\n<p>Que &nbsp;su notificaci\u00f3n \u00abno &nbsp;se surti\u00f3 conforme a lo indicado y normado por el art\u00edculo &nbsp;8 del Decreto 806 de 2020\u00bb, &nbsp;en tanto \u00abse &nbsp;han incurrido en yerros\u00bb, &nbsp;puesto que ella \u00aben &nbsp;ning\u00fan momento se identifica con el apellido con el cual se le &nbsp;requiri\u00f3 (\u2026), toda vez que [su] &nbsp;nombre es DAYAN PATRICIA FONTECHA (no Fonteche) ACEVEDO\u00bb, &nbsp;lo cual &nbsp; \u00abha &nbsp;sido motivo suficiente para entender que no se trata de ella sino de &nbsp;persona que tiene nombre similar ya que los interesados han contado &nbsp;con la informaci\u00f3n clara y precisa respecto a [su] &nbsp;plena identidad\u00bb. &nbsp;<\/p>\n<p>Que &nbsp;no obstante la normativa en comento exigir \u00abla &nbsp;implementaci\u00f3n o uso de sistema de \u201cconfirmaci\u00f3n &nbsp;de recibido de los correos electr\u00f3nicos o mensajes de datos\u201d &nbsp;(\u2026), en ninguna parte del proceso se avizora prueba siquiera &nbsp;sumaria de que el env\u00edo de mensaje de datos si fuera recibido &nbsp;y le\u00eddo en la bandeja de entrada del canal digital que se ha &nbsp;informado como de &nbsp;[ella]\u00bb, y &nbsp;que \u00abla &nbsp;acreditaci\u00f3n de env\u00edo no fue expedido por una empresa &nbsp;de correo que certificara que efectivamente los archivos adjuntos &nbsp;estuviesen debidamente cotejados y que dicho mensaje haya llegado a &nbsp;su destinatario, ni mucho menos que fuera le\u00eddo\u00bb. &nbsp;<\/p>\n<p>Que &nbsp;como su notificaci\u00f3n se realiz\u00f3 de manera &nbsp;\u00abincorrecta &nbsp;e indebida\u00bb, &nbsp;ello \u00ablimita &nbsp;e impide que el ejercicio de derecho de defensa t\u00e9cnica y &nbsp;protecci\u00f3n de sus derechos [como] &nbsp;comprador de buena fe, se efectu\u00e9 de forma plena y &nbsp;satisfactoria\u00bb, &nbsp;pues en su condici\u00f3n de \u00ablitisconsorte &nbsp;necesario\u00bb &nbsp;dentro &nbsp;del juicio en cuesti\u00f3n, advierte que &nbsp;\u00abel &nbsp;fallo N\u00b0 017 del 17 de febrero de 2021, transgrede de forma &nbsp;directa [sus] &nbsp;intereses y derechos fundamentales\u00bb. &nbsp;<\/p>\n<p>3. &nbsp; &nbsp; &nbsp; &nbsp;Pretende, &nbsp;que \u00abse &nbsp;ordene al Juzgado Sexto de Familia de Bucaramanga que modifique el &nbsp;sentido del fallo N\u00b0 017 del 17 de febrero de 2021, y ordene &nbsp;rehacer el trabajo de partici\u00f3n teniendo en cuenta la &nbsp;legalidad y legitimidad de la compra de buena fe (\u2026), respecto &nbsp;de la cuota de dominio equivalente al 16,68% del inmueble (\u2026)\u00bb. &nbsp;<\/p>\n<p>RESPUESTA &nbsp;DEL ACCIONADO Y VINCULADOS &nbsp;<\/p>\n<p>1. &nbsp; &nbsp; &nbsp; &nbsp;La &nbsp;titular del despacho judicial encartado inform\u00f3 que revisado &nbsp;el expediente, \u00aba &nbsp;la accionante se le notific\u00f3 todas las actuaciones surtidas &nbsp;dentro del proceso de acci\u00f3n de petici\u00f3n de herencia al &nbsp;correo por ella aportado\u00bb; &nbsp;record\u00f3 que en virtud del fallo estimatorio, \u00abse &nbsp;deja sin efecto todas las inscripciones que se realizaron con &nbsp;anterioridad [empero] &nbsp;la escritura de la cesionaria sigue vigente para que exija sus &nbsp;derechos como tal, [y &nbsp;por ello, la decisi\u00f3n] &nbsp;no significa que haya perdido el derecho [solo &nbsp;que ella] &nbsp;desplaza al heredero cedente Gonzalo, por ende ella tambi\u00e9n &nbsp;puede dar inicio al proceso de sucesi\u00f3n e ingresar en calidad &nbsp;de cesionaria [en &nbsp;lugar de acudir a] &nbsp;una tutela 2 a\u00f1os despu\u00e9s de haberse proferido un fallo &nbsp;ajustado a derecho\u00bb. &nbsp;Por lo dem\u00e1s, indic\u00f3 que \u00abno &nbsp;ha violado ning\u00fan derecho &nbsp;[en tanto], &nbsp;me posesion\u00e9 el pasado 21 de noviembre del a\u00f1o 2022\u00bb. &nbsp;<\/p>\n<p>2. &nbsp; &nbsp; &nbsp; &nbsp;Gilberto &nbsp;Su\u00e1rez Palomino, se opuso a lo pretendido al aseverar que el &nbsp;correo electr\u00f3nico al cual le dirigieron las notificaciones &nbsp;procesales, efectivamente corresponde al de la reclamante, y que \u00abno &nbsp;es excusa el cambio de una vocal en el apellido para inferir que la &nbsp;notificaci\u00f3n del proceso no la vinculaba a ella\u00bb. &nbsp;<\/p>\n<p>3. &nbsp; &nbsp; &nbsp; &nbsp;El &nbsp;curador ad &nbsp;litem &nbsp;de Gonzalo Palomino, manifest\u00f3 que la acci\u00f3n es &nbsp;improcedente porque la \u00abpresunta &nbsp;vulneraci\u00f3n [que &nbsp;aduce la actora] &nbsp;por virtud de su presunta indebida notificaci\u00f3n (\u2026), no &nbsp;ha planteado la nulidad que predica al interior del proceso de &nbsp;petici\u00f3n de herencia, ni ha solicitado el recurso de &nbsp;revisi\u00f3n\u00bb. &nbsp;<\/p>\n<p>SENTENCIA &nbsp;DE PRIMER GRADO &nbsp;<\/p>\n<p>Desestim\u00f3 &nbsp;el auxilio al advertir que \u00abla &nbsp;nulidad por indebida notificaci\u00f3n que plantea la parte actora &nbsp;en esta sede, aquella de que trata el numeral 8\u00b0 del art\u00edculo &nbsp;133 del CGP, no ha sido planteada por esta al interior del proceso &nbsp;ordinario mediante el recurso de revisi\u00f3n establecido en el &nbsp;art\u00edculo 354 y 355 del CGP\u00bb, &nbsp;raz\u00f3n por la cual \u00abla &nbsp;promotora cuenta con un mecanismo de defensa judicial id\u00f3neo y &nbsp;principal, distinto a la excepcional y residual acci\u00f3n de &nbsp;tutela\u00bb. &nbsp;<\/p>\n<p>IMPUGNACI\u00d3N &nbsp;<\/p>\n<p>La &nbsp;interpuso la querellante, asegurando que \u00abse &nbsp;est\u00e1n desconociendo los derechos que le asisten [en &nbsp;su calidad de] &nbsp;tercero comprador de buena fe, y ante la ley es sujeto de protecci\u00f3n &nbsp;jur\u00eddica, ya que [en &nbsp;el juicio] el &nbsp;comprador no se manifiesta ni se hace parte\u00bb. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>1. &nbsp; &nbsp; &nbsp; &nbsp;Problema &nbsp;jur\u00eddico. &nbsp;<\/p>\n<p>Corresponde &nbsp;a la Corte establecer, preliminarmente, si la demanda satisface los &nbsp;requisitos de la subsidiariedad, y de superarse lo anterior, si el &nbsp;Juzgado Sexto de Familia de Bucaramanga, &nbsp;vulner\u00f3 &nbsp;las prerrogativas fundamentales invocadas por la accionante, al &nbsp;haberla tenida por notificada como litisconsorte por pasiva dentro &nbsp;del proceso de petici\u00f3n de herencia n\u00b0 2019-00540, y &nbsp;proseguirlo hasta su culminaci\u00f3n con fallo ejecutoriado del 17 &nbsp;de febrero de 2021. &nbsp;<\/p>\n<p>2. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;De la tutela contra providencias judiciales y de los requisitos &nbsp;gen\u00e9ricos de procedibilidad. &nbsp;<\/p>\n<p>Esta &nbsp;Corporaci\u00f3n ha dicho y reiterado, en l\u00ednea de &nbsp;principio, que en aras a mantener inc\u00f3lumes los principios que &nbsp;contemplan los art\u00edculos 228 y 230 de la Carta Pol\u00edtica, &nbsp;la &nbsp;salvaguarda no procede contra esta clase de actuaciones, ya que al &nbsp;juez constitucional no le es dable inmiscuirse en el escenario de los &nbsp;tr\u00e1mites ordinarios en curso o terminados, para variar las &nbsp;decisiones proferidas o para disponer que lo haga de cierta manera. &nbsp;<\/p>\n<p>Asimismo, &nbsp;la Corte Constitucional ha establecido los presupuestos y requisitos &nbsp;generales de procedibilidad que deben confluir y verificarse para &nbsp;tornar imperiosa la intervenci\u00f3n del juez excepcional con el &nbsp;fin de restablecer el orden jur\u00eddico. Enlista como tales: &nbsp;<\/p>\n<p>\u00ab(i) &nbsp;que la cuesti\u00f3n discutida resulte de evidente relevancia &nbsp;constitucional y que, como en cualquier acci\u00f3n de tutela, est\u00e9 &nbsp;acreditada la vulneraci\u00f3n de un derecho fundamental, requisito &nbsp;sine qua non de esta acci\u00f3n de tutela que, en estos casos, &nbsp;exige una carga especial al actor; (ii) &nbsp;que &nbsp;la persona afectada haya agotado todos los medios ordinarios y &nbsp;extraordinarios de defensa judicial a su alcance y haya alegado, en &nbsp;sede judicial ordinaria, y siempre que ello fuera posible, la &nbsp;cuesti\u00f3n iusfundamental que alega en sede de tutela; &nbsp;(iii) &nbsp;que se cumpla el requisito de la inmediatez, es decir, que la tutela &nbsp;se hubiere interpuesto en un t\u00e9rmino razonable y proporcionado &nbsp;a partir del hecho que origin\u00f3 la vulneraci\u00f3n; (iv) &nbsp;en el caso de irregularidades procesales, se requiere que \u00e9stas &nbsp;tengan un efecto decisivo en la decisi\u00f3n de fondo que se &nbsp;impugna; y (v) &nbsp;que no se trate de sentencias de tutela\u00bb (CC &nbsp;C-590\/05 y SU-813\/07). &nbsp;<\/p>\n<p>3. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Del &nbsp;caso concreto. &nbsp;<\/p>\n<p>Revisados &nbsp;los argumentos de la presente reclamaci\u00f3n y con apoyo en las &nbsp;piezas procesales adosadas al expediente, la Sala respaldar\u00e1 &nbsp;el fallo desestimatorio de primer grado, toda vez que la censura en &nbsp;relaci\u00f3n con el acto de notificaci\u00f3n personal de la hoy &nbsp;accionante, quien fungi\u00f3 dentro del proceso de petici\u00f3n &nbsp;de herencia como demandada, no supera el &nbsp;requisito general de la subsidiariedad. &nbsp;<\/p>\n<p>En &nbsp;efecto, el &nbsp;mencionado impedimento general de procedibilidad &nbsp;del amparo, emerge por la existencia de otro medio de defensa &nbsp;judicial, habida cuenta que antes de acudir a este instrumento &nbsp;jur\u00eddico, la querellante no acredit\u00f3 que, de cara a la &nbsp;\u00abincorrecta &nbsp;e indebida\u00bb &nbsp;vinculaci\u00f3n al pleito ordinario como \u00ablitisconsorte &nbsp;necesario\u00bb, &nbsp;hubiera formulado el &nbsp;recurso extraordinario de revisi\u00f3n contra el fallo proferido &nbsp;el 17 de febrero de 2021, encaminado a solucionar la afectaci\u00f3n &nbsp;que le enrostra al despacho accionado. &nbsp;<\/p>\n<p>Esto, &nbsp;porque aunado a que el inciso 2\u00b0 del art\u00edculo 134 del &nbsp; C\u00f3digo General del Proceso advierte que \u00ab[l]a &nbsp;nulidad por indebida representaci\u00f3n o falta de notificaci\u00f3n &nbsp;o emplazamiento en legal forma, o la originada en la sentencia contra &nbsp;la cual no proceda recurso, podr\u00e1 tambi\u00e9n alegarse en &nbsp;la diligencia de entrega o como excepci\u00f3n en la ejecuci\u00f3n &nbsp;de la sentencia, o mediante el recurso de revisi\u00f3n, si no se &nbsp;pudo alegar por la parte en las anteriores oportunidades\u00bb, &nbsp;el numeral 7\u00ba del canon 355 ibidem, &nbsp;establece como causal de revisi\u00f3n, \u00ab[e]star &nbsp;el recurrente en alguno de los casos de indebida representaci\u00f3n &nbsp;o falta de notificaci\u00f3n o emplazamiento, siempre que no haya &nbsp;sido saneada la nulidad\u00bb, &nbsp;y siendo esa la discrepancia de la actora con el fallador de la &nbsp;causa, tal mecanismo es el que -con observancia en el precepto 356 &nbsp;del mismo estatuto-, deber\u00eda activarse, ya que al juez &nbsp;excepcional no le es dable intervenir en raz\u00f3n a la naturaleza &nbsp;subsidiaria y residual de la tutela. &nbsp;<\/p>\n<p>Del &nbsp;mismo modo, en casos de similares contornos al que ahora se analiza, &nbsp;asever\u00f3 que: \u00abel &nbsp;promotor cuenta con la opci\u00f3n de debatir la indebida &nbsp;notificaci\u00f3n que alega en el juicio ordinario, mediante la &nbsp;formulaci\u00f3n del recurso extraordinario de revisi\u00f3n &nbsp;(&#8230;), el cual puede [formular] &nbsp;independientemente de su desenlace, siempre y cuando se atienda la &nbsp;oportunidad legal y apoye la petici\u00f3n en una de las causales &nbsp;establecidas en el art\u00edculo 380 del C\u00f3digo de &nbsp;Procedimiento Civil [hoy &nbsp;art\u00edculo 355 del C\u00f3digo General del Proceso]\u00bb &nbsp;(CSJ STC, 24 may. 2012, rad. 00999-00, citada, entre otras, en &nbsp;STC9677-2022, &nbsp;28 jul., rad. 00125-01). &nbsp;<\/p>\n<p>Recu\u00e9rdese &nbsp;que por la naturaleza &nbsp;subsidiaria y residual que se consagra en el art\u00edculo 86 de la &nbsp;Carta Pol\u00edtica y el Decreto 2591 de 1991, el uso racional de &nbsp;la tutela se reserva para los casos en que el ciudadano carece de &nbsp;otros instrumentos para salvaguardar sus derechos, pues la acci\u00f3n &nbsp;no es &nbsp;sustitutiva, alternativa, paralela ni complementaria de las dem\u00e1s &nbsp;herramientas que prev\u00e9 el ordenamiento jur\u00eddico. &nbsp;<\/p>\n<p>Ahora, &nbsp;sobre la posibilidad de conceder la salvaguarda de manera transitoria &nbsp;para evitar un perjuicio irremediable, la Sala no encuentra que se &nbsp;hubieran probado las exigencias que la hagan posible, pues para ello &nbsp;se requiere que el &nbsp;da\u00f1o \u00abrevista &nbsp;cierta gravedad e inminencia m\u00e1s all\u00e1 de lo puramente &nbsp;eventual, y que s\u00f3lo pueda evitarse con medidas urgentes e &nbsp;impostergables propias de la tutela\u00bb &nbsp;(CSJ &nbsp;STC, 1\u00ba sep. 2011, exp. 00194-01). &nbsp;<\/p>\n<p>4. &nbsp; &nbsp; &nbsp; &nbsp;Conclusi\u00f3n. &nbsp;<\/p>\n<p>Por &nbsp;lo discurrido, al no haberse acreditado el agotamiento de los medios &nbsp;de defensa, cuya aptitud e idoneidad no est\u00e1 en entredicho, el &nbsp;estudio de fondo de esta acci\u00f3n se torna improcedente, &nbsp;y en esas condiciones se ratificar\u00e1 la sentencia &nbsp;desestimatoria del amparo. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, en Sala &nbsp;de Casaci\u00f3n Civil, administrando justicia en nombre de la &nbsp;Rep\u00fablica de Colombia y por autoridad de la ley, CONFIRMA &nbsp;el &nbsp;fallo impugnado. &nbsp;<\/p>\n<p>Comun\u00edquese &nbsp;lo resuelto a las partes y al a-quo &nbsp;por medio expedito, y en oportunidad rem\u00edtase el expediente a &nbsp;la Corte Constitucional para su eventual revisi\u00f3n. &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Presidente &nbsp;de Sala &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>(Comisi\u00f3n &nbsp;de Servicios) &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC1483-2023 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; LUIS &nbsp;ALONSO RICO PUERTA &nbsp; Magistrado &nbsp;Ponente &nbsp; STC1483-2023 &nbsp; Radicaci\u00f3n &nbsp;n\u00b0 68001-22-13-000-2023-00030-01 &nbsp; Bogot\u00e1, &nbsp;D.C., veintid\u00f3s (22) de febrero de dos mil veintitr\u00e9s &nbsp;(2023). &nbsp; Decide &nbsp;la Corte la impugnaci\u00f3n formulada frente al fallo proferido &nbsp;por la Sala &nbsp;Civil Familia del Tribunal Superior del Distrito Judicial de &nbsp;Bucaramanga el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-70780","post","type-post","status-publish","format-standard","hentry","category-febrero-2023"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=70780"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70780\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=70780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=70780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=70780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}