{"id":70808,"date":"2024-05-20T22:42:10","date_gmt":"2024-05-20T22:42:10","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc1513-2023\/"},"modified":"2024-05-20T22:42:10","modified_gmt":"2024-05-20T22:42:10","slug":"stc1513-2023","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc1513-2023\/","title":{"rendered":"STC1513 2023"},"content":{"rendered":"<p>STC1513-2023<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>Magistrado Ponente &nbsp;<\/p>\n<p>STC1513-2023 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00b0. &nbsp;11001-02-03-000-2023-00497-00 &nbsp;<\/p>\n<p>(Aprobado en sesi\u00f3n de &nbsp;veintid\u00f3s de febrero de dos mil veintitr\u00e9s) &nbsp;<\/p>\n<p>Bogot\u00e1 &nbsp;D.C., veintid\u00f3s (22) de febrero de dos mil veintitr\u00e9s &nbsp;(2023). &nbsp;<\/p>\n<p>La Corte decide la &nbsp;acci\u00f3n de tutela promovida por Ramiro Alfonso Chamorro L\u00f3pez, &nbsp;quien dice actuar como apoderado de Gloria Roc\u00edo Jim\u00e9nez &nbsp;Aristiz\u00e1bal y de Jos\u00e9 Arist\u00f3bulo Chaverra &nbsp;Fl\u00f3rez, contra la Sala Civil Especializada en Restituci\u00f3n &nbsp;de Tierras del Tribunal Superior del Distrito Judicial de Antioquia. &nbsp;Al tr\u00e1mite se dispuso vincular a las partes e intervinientes &nbsp;del proceso de restituci\u00f3n de tierras con radicado &nbsp;2300131210032018001041. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>I. ANTECEDENTES &nbsp;<\/p>\n<p>1. El promotor &nbsp;procura la salvaguarda de las garant\u00edas superiores al debido &nbsp;proceso, igualdad, propiedad privada y dignidad humana de las &nbsp;personas que dice representar. &nbsp;<\/p>\n<p>2. Del &nbsp;escrito inicial y las pruebas allegadas, se resaltan los siguientes &nbsp;hechos y alegaciones relevantes: &nbsp;<\/p>\n<p>2.2. En dicho &nbsp;tr\u00e1mite, Gloria &nbsp;Roc\u00edo Jim\u00e9nez Aristiz\u00e1bal y Jos\u00e9 &nbsp;Arist\u00f3bulo Chaverra Fl\u00f3rez se opusieron, no obstante, &nbsp;la Sala Civil Especializada en Restituci\u00f3n de Tierras del &nbsp;Tribunal Superior de Antioquia, al fallar el asunto el 5 de mayo de &nbsp;20222, &nbsp;desestim\u00f3 sus pretensiones y orden\u00f3 la restituci\u00f3n &nbsp;del inmueble al reclamante y a los sucesores de Martida Rosa Solano &nbsp;P\u00e9rez. &nbsp;<\/p>\n<p>3. El gestor tacha &nbsp;de irregular la sentencia dictada por la Colegiatura criticada, &nbsp;porque desconoci\u00f3 el precedente jurisprudencial aplicable e &nbsp;incurri\u00f3 en defecto f\u00e1ctico, dado que la oposici\u00f3n &nbsp;planteada por quienes dice representar s\u00ed estaba llamada a &nbsp;prosperar, pues adquirieron e ingresaron al bien leg\u00edtimamente &nbsp;y con buena fe exenta de culpa. &nbsp;<\/p>\n<p>4. Con sustento en &nbsp;lo relatado, pide que se deje sin efectos el fallo del Tribunal y que &nbsp;se dicte otro ajustado a derecho. &nbsp;<\/p>\n<p>II. &nbsp;RESPUESTAS RECIBIDAS &nbsp;<\/p>\n<p>1. La Colegiatura &nbsp;accionada defendi\u00f3 la legalidad de su actuar y destac\u00f3 &nbsp;que la tutela no satisfac\u00eda el requisito de la inmediatez, en &nbsp;tanto el fallo atacado se profiri\u00f3 8 meses atr\u00e1s. &nbsp;<\/p>\n<p>2. La Unidad &nbsp;Administrativa Especial de Restituci\u00f3n y Gesti\u00f3n de &nbsp;Tierras Despojadas -UAEGRDT- pidi\u00f3 se le desvinculara del &nbsp;asunto, ya que no hab\u00eda violentado derecho fundamental alguno. &nbsp;Similar proceder desplegaron la Unidad Administrativa Especial &nbsp;Atenci\u00f3n y Reparaci\u00f3n Integral de V\u00edctimas &nbsp;-UARIV-, la Agencia Nacional de Hidrocarburos -ANH- y el Servicio &nbsp;Nacional de Aprendizaje -SENA-. &nbsp;<\/p>\n<p>3. La Gobernaci\u00f3n &nbsp;de Antioquia inform\u00f3 las actuaciones adelantadas para el &nbsp;cumplimiento del fallo de restituci\u00f3n. &nbsp;<\/p>\n<p>4. La Procuradur\u00eda &nbsp;18 Judicial II de Restituci\u00f3n de Tierras sostuvo que el amparo &nbsp;no reun\u00eda el presupuesto de la tempestividad y que ninguno de &nbsp;los defectos atribuidos por el gestor se estructuraba. &nbsp;<\/p>\n<p>III. &nbsp;CONSIDERACIONES &nbsp;<\/p>\n<p>1. &nbsp;En &nbsp;el sub &nbsp;examine, &nbsp;el &nbsp;censor pretende que &nbsp;se deje sin efectos el fallo proferido por el Tribunal accionado el 5 &nbsp;de mayo de 2022, porque vulner\u00f3 los derechos de quienes dice &nbsp;representar. &nbsp;<\/p>\n<p>2. Revisadas las &nbsp;piezas procesales allegadas, observa la &nbsp;Sala que el promotor no se encuentra legitimado para instaurar la &nbsp;presente tutela, dado que no es el titular de los derechos &nbsp;fundamentales cuya vulneraci\u00f3n se atribuye a la Colegiatura &nbsp;accionada y no alleg\u00f3 poder especial que lo faculte a &nbsp;intervenir en esta causa. &nbsp;<\/p>\n<p>2.1. &nbsp;Referente a la legitimaci\u00f3n en la causa en las acciones de &nbsp;tutela, el art\u00edculo 10 del Decreto 2591 de 1991 dispone que &nbsp;\u00abpodr\u00e1 &nbsp;ser ejercida (\u2026) por cualquier persona vulnerada o amenazada &nbsp;en uno de sus derechos fundamentales, quien actuar\u00e1 por s\u00ed &nbsp;misma o a trav\u00e9s de representante\u00bb. Al &nbsp;respecto, esta Sala &nbsp;ha establecido que la persona habilitada para promover la&nbsp;acci\u00f3n &nbsp;de tutela es aquella a la que se le violan o amenazan sus&nbsp;derechos &nbsp;fundamentales, de manera que el profesional del derecho que &nbsp;la&nbsp;representa en el proceso rebatido o en otro asunto \u00abes &nbsp;un&nbsp;simple apoderado judicial y, en ning\u00fan momento, &nbsp;resulta afectado&nbsp;en tales derechos cuando los funcionarios &nbsp;judiciales incurren&nbsp;presuntamente en v\u00edas de hecho\u00bb&nbsp;(CSJ &nbsp;STC &nbsp;29 sep.&nbsp;2003, rad 00245-01, reiterada en CSJ STC926-2018, CSJ &nbsp;STC4611-&nbsp;2018, CSJ STC1042-2019). &nbsp;<\/p>\n<p>Igualmente, &nbsp;la Sala ha se\u00f1alado que la falta de poder especial del abogado &nbsp;impulsor, aun cuando \u00abtenga &nbsp;poder espec\u00edfico o general en otros asuntos, no [lo] &nbsp;habilita &nbsp;para ejercer la acci\u00f3n de amparo\u00bb &nbsp;y que tal omisi\u00f3n &nbsp;torna &nbsp;improcedente la tutela (CSJ &nbsp;STC1042-2019). &nbsp;<\/p>\n<p>2.2. &nbsp;En cuanto al mandato requerido, la Corte Constitucional, en sentencia &nbsp;CC T-001-1997, manifest\u00f3 que &nbsp;<\/p>\n<p>todo &nbsp;poder en materia de tutela debe ser especial, es decir, que \u00abse &nbsp;otorga una sola vez para el fin espec\u00edfico y determinado de &nbsp;representar los intereses del accionante en punto de los derechos &nbsp;fundamentales que alega, contra cierta autoridad o persona y en &nbsp;relaci\u00f3n&nbsp;con unos hechos concretos que dan lugar a su &nbsp;pretensi\u00f3n\u00bb. &nbsp;Bajo &nbsp;las anteriores circunstancias, como lo refiri\u00f3 la Corte &nbsp;Constitucional en sentencia CC T-1025-2006, el poder especial debe &nbsp;contener en forma clara y expresa: &nbsp;<\/p>\n<p>(i) &nbsp;los nombres y datos de identificaci\u00f3n tanto del poderdante &nbsp;como del apoderado; (ii) la persona natural o jur\u00eddica contra &nbsp;la cual se va a incoar la acci\u00f3n de tutela; (iii) el acto o &nbsp;documento causa del litigio y, (iv) el derecho fundamental que se &nbsp;pretende proteger y garantizar. Los anteriores elementos permiten &nbsp;reconocer la situaci\u00f3n f\u00e1ctica que origina el proceso &nbsp;de tutela, los sujetos procesales de la misma y las actuaciones &nbsp;cuestionadas dentro del amparo. En consecuencia, la ausencia de &nbsp;alguno de los elementos esenciales de un poder desconfigura la &nbsp;legitimaci\u00f3n en la causa por activa, haciendo improcedente la &nbsp;acci\u00f3n3. &nbsp;<\/p>\n<p>2.3. &nbsp;Pues bien, en el presente asunto, el tutelante pretende &nbsp;la protecci\u00f3n de los derechos fundamentales de Gloria &nbsp;Roc\u00edo Jim\u00e9nez Aristiz\u00e1bal y de Jos\u00e9 &nbsp;Arist\u00f3bulo Chaverra Fl\u00f3rez; &nbsp;sin embargo, no alleg\u00f3 poder especial para actuar en su &nbsp;nombre, pues solo aport\u00f3 un mandato dirigido a la UAEGRTD, &nbsp;que no re\u00fane las caracter\u00edsticas de especialidad &nbsp;exigidas para la acci\u00f3n de tutela, sumado a que no aleg\u00f3 &nbsp;ni acredit\u00f3 las condiciones para actuar como su agente &nbsp;oficioso y, por tanto, la tutela es improcedente, &nbsp;ante &nbsp;la falta de legitimaci\u00f3n en la causa del proponente. &nbsp;<\/p>\n<p>3. Por lo &nbsp;anterior, se declarar\u00e1 improcedente la tutela. &nbsp;<\/p>\n<p>IV. &nbsp;DECISI\u00d3N &nbsp;<\/p>\n<p>En m\u00e9rito &nbsp;de lo expuesto, la Corte Suprema de Justicia, en Sala de Casaci\u00f3n &nbsp;Civil, administrando justicia, en nombre de la Rep\u00fablica de &nbsp;Colombia y por autoridad de la ley, DECLARA &nbsp;IMPROCEDENTE el &nbsp;amparo reclamado. &nbsp;<\/p>\n<p>Comun\u00edquese &nbsp;lo resuelto en esta providencia a los interesados, por el medio m\u00e1s &nbsp;expedito, de conformidad con lo previsto en el art\u00edculo 30 del &nbsp;Decreto 2591 de 1991, y oportunamente env\u00edese el expediente a &nbsp;la Corte Constitucional, para su eventual revisi\u00f3n. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>MARTHA PATRICIA &nbsp;GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Presidente de Sala &nbsp;<\/p>\n<p>HILDA GONZ\u00c1LEZ &nbsp;NEIRA &nbsp;<\/p>\n<p>AROLDO WILSON &nbsp;QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS ALONSO &nbsp;RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>1\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Juzgado &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Tercero Civil Especializado en Restituci\u00f3n de Tierras de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Monter\u00eda, Rigoberto Antonio Montalvo, a los sucesores de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Martida Rosa Solano P\u00e9rez, la &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Alcald\u00eda Municipal de C\u00e1ceres, la Unidad &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Administrativa Especial de Gesti\u00f3n y Restituci\u00f3n de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Tierras Despojadas, la Unidad Especial para la Atenci\u00f3n y &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Reparaci\u00f3n Integral de V\u00edctimas, el Servicio Nacional &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;de Aprendizaje -SENA-, a la Direcci\u00f3n de Catastro \u2013 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Seccional Antioquia y a la Oficina de Registro de Instrumentos &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;P\u00fablicos de Caucasia. &nbsp;<\/p>\n<p>2\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Ejecutoriada el 12 de mayo siguiente. &nbsp;<\/p>\n<p>3\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Postura reiterada por esta Sala en CSJ STC1284-2022. &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC1513-2023 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; FRANCISCO &nbsp;TERNERA BARRIOS &nbsp; Magistrado Ponente &nbsp; STC1513-2023 &nbsp; Radicaci\u00f3n &nbsp;n\u00b0. &nbsp;11001-02-03-000-2023-00497-00 &nbsp; (Aprobado en sesi\u00f3n de &nbsp;veintid\u00f3s de febrero de dos mil veintitr\u00e9s) &nbsp; Bogot\u00e1 &nbsp;D.C., veintid\u00f3s (22) de febrero de dos mil veintitr\u00e9s &nbsp;(2023). &nbsp; La Corte decide la &nbsp;acci\u00f3n de tutela promovida por Ramiro Alfonso Chamorro L\u00f3pez, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-70808","post","type-post","status-publish","format-standard","hentry","category-febrero-2023"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=70808"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70808\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=70808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=70808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=70808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}