{"id":70859,"date":"2024-05-20T22:42:12","date_gmt":"2024-05-20T22:42:12","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc1572-2023-1\/"},"modified":"2024-05-20T22:42:12","modified_gmt":"2024-05-20T22:42:12","slug":"stc1572-2023-1","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc1572-2023-1\/","title":{"rendered":"STC1572 2023 1"},"content":{"rendered":"<p>STC1572-2023_1<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>ANOTACI\u00d3N &nbsp;PRELIMINAR &nbsp;<\/p>\n<p>De &nbsp;conformidad con el \u00abART\u00cdCULO &nbsp;PRIMERO\u00bb &nbsp;del Acuerdo No. 034 de esta Sala, expedido el pasado 16 de diciembre, &nbsp;atendiendo a que en esta providencia se resuelve una situaci\u00f3n &nbsp;jur\u00eddica relacionada con una persona menor de edad, como &nbsp;medida de protecci\u00f3n a su intimidad, se emiten dos versiones &nbsp;de esta sentencia, &nbsp;\u00abcon &nbsp;id\u00e9ntico tenor, una reemplazando los nombres y los datos e &nbsp;informaciones (familiares), que permitan conocer su identidad y &nbsp;ubicaci\u00f3n, para efectos de publicaci\u00f3n en los &nbsp;repositorios, medios de comunicaciones y motores de b\u00fasqueda &nbsp;virtuales, y otra con la informaci\u00f3n real y completa de las &nbsp;partes, que se utilizar\u00e1 \u00fanicamente para notificaci\u00f3n &nbsp;a los sujetos procesales e intervinientes y que se mantendr\u00e1 &nbsp;con reserva a terceros interesados\u00bb. &nbsp;<\/p>\n<p>NOTA. &nbsp;Este &nbsp;ejemplar de la decisi\u00f3n corresponde al que contiene los &nbsp;\u00abnombres &nbsp;ficticios\u00bb &nbsp;de las partes. &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Magistrada &nbsp;ponente &nbsp;<\/p>\n<p>STC1572-2023 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n.\u00b0 &nbsp;15001-22-13-000-2022-00224-01 &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D.C., veintid\u00f3s (22) febrero de dos mil veintitr\u00e9s &nbsp;(2023). &nbsp;<\/p>\n<p>Decide &nbsp;la Corte la impugnaci\u00f3n de la sentencia proferida por la Sala &nbsp;Civil Familia del Tribunal Superior de Tunja el 13 de enero de 2023, &nbsp;en la acci\u00f3n de tutela que Mar\u00eda formul\u00f3 contra &nbsp;la Caja de Retiro de las Fuerzas Militares CREMIL, tr\u00e1mite en &nbsp;el que dispuso la vinculaci\u00f3n del Juzgado de Familia de &nbsp;Chiquinquir\u00e1 y fueron citadas las partes e intervinientes en &nbsp;el proceso de reducci\u00f3n de cuota alimentaria con radicado &nbsp;2019-0110. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>1. La &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;solicitante actuando en representaci\u00f3n de sus menores hijos &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Juanita y Juanito, invoc\u00f3 la protecci\u00f3n de los &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;derechos fundamentales al m\u00ednimo vital y a la vida digna, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;presuntamente &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;vulnerados por la entidad accionada. &nbsp;<\/p>\n<p>Como &nbsp;sustento refiri\u00f3 que en el proceso de disminuci\u00f3n de &nbsp;cuota alimentaria promovido por el padre de sus hijos menores de edad &nbsp;Jos\u00e9 y que curs\u00f3 en el Juzgado de Familia de &nbsp;Chiquinquir\u00e1, fue proferida sentencia a su favor el 4 de &nbsp;noviembre de 2020, en la que se estableci\u00f3 una cuota de &nbsp;alimentos por valor de $621.124. &nbsp;<\/p>\n<p>Reproch\u00f3 &nbsp;que, pese a que en el citado fallo se estableci\u00f3 en el numeral &nbsp;cuarto que \u00abAdicionalmente &nbsp;el demandado JOSE, cancelara a favor de sus menores hijos JUANITA Y &nbsp;JUANITO, el 33,33% de las primas a que tenga derecho y que se le &nbsp;cancele semestral o anualmente y luego de las deducciones de ley\u00bb, &nbsp;esto &nbsp;no se ha cumplido, pues desde el 4 de noviembre hasta la fecha no se &nbsp;reflejan aumentos en el monto fijado. &nbsp;<\/p>\n<p>Aleg\u00f3 &nbsp;que la entidad CREMIL ha hecho caso omiso a lo ordenado por el &nbsp;Juzgado de conocimiento en la sentencia, en tanto que, no ha &nbsp;efectuado los descuentos correspondientes mes a mes del 33,33% del &nbsp;total devengado por el se\u00f1or Jos\u00e9, desde el 4 de &nbsp;noviembre de 2020, respecto a las primas de diciembre 2020, junio y &nbsp;diciembre de 2021 y junio y diciembre de 2022. &nbsp;<\/p>\n<p>Refiri\u00f3 &nbsp;que ha remitido al Juzgado de Familia de Chiquinquir\u00e1 y a la &nbsp;entidad CREMIL y derechos de petici\u00f3n, quienes \u00abcontestan &nbsp;con evasivas menoscabando el m\u00ednimo vital y la vida digna de &nbsp;mis menores hijos\u00bb. &nbsp;<\/p>\n<p>2. &nbsp;Con fundamento en lo anterior, solicit\u00f3 ordenar a la Caja &nbsp;de Retiro de las Fuerzas Militares que d\u00e9 cumplimiento a lo &nbsp;dispuesto por el Juzgado de Familia de Chiquinquir\u00e1 en la &nbsp;sentencia de 4 de noviembre de 2020 \u00abnumerales &nbsp;TERCERO Y CUARTO 33.33% del valor del TOTAL DEVENGADO mes a mes y los &nbsp;meses de JUNIO Y DICIEMBRE las correspondientes primas de ley en el &nbsp;porcentaje tal y como se orden\u00f3, de la pensi\u00f3n que &nbsp;percibe el se\u00f1or JOS\u00c9\u00bb. &nbsp;<\/p>\n<p>RESPUESTA &nbsp;DE LA ACCIONADA Y LOS VINCULADOS &nbsp;<\/p>\n<p>1. &nbsp;El Juzgado de Familia de Chiquinquir\u00e1, luego de referir los &nbsp;procesos que all\u00ed se adelantaron en donde intervino la &nbsp;accionante, se\u00f1al\u00f3 que &nbsp;la &nbsp;cuota alimentaria actualmente vigente para los menores de edad, &nbsp;corresponde al 33.33% de la pensi\u00f3n y primas del se\u00f1or &nbsp;Jos\u00e9, fijada en el proceso 2019-00110-00 de disminuci\u00f3n &nbsp;de cuota de alimentos y ante el incumplimiento de la obligaci\u00f3n &nbsp;Mar\u00eda &nbsp;promovi\u00f3 &nbsp;demanda ejecutiva de alimentos, la cual corresponde al proceso &nbsp;virtual 2020-00163-00, en el cual mediante auto de 30 de noviembre de &nbsp;2020, se libr\u00f3 orden de pago, se decret\u00f3 y est\u00e1 &nbsp;vigente el embargo del 50% de la asignaci\u00f3n de retiro, con la &nbsp;orden de dos descuentos: uno para cubrir la cuota alimentaria mensual &nbsp;y el restante del 50%, para amortizar la deuda. &nbsp;<\/p>\n<p>2. &nbsp;La Comisar\u00eda de Familia de Chiquinquir\u00e1 se refiri\u00f3 &nbsp;a cada uno de los hechos del escrito inicial. &nbsp;<\/p>\n<p>3. &nbsp;La Caja de Retiro de las Fuerzas Militares sostuvo que actualmente &nbsp;se encuentra vigente y operando la medida de embargo de alimentos &nbsp;sobre la asignaci\u00f3n de retiro del se\u00f1or Jos\u00e9 en &nbsp;favor de la se\u00f1ora Mar\u00eda ordenada en el proceso &nbsp;Ejecutivo de Alimentos con radicado 2020-00163 que se adelanta en el &nbsp;Juzgado de Familia de Chiquinquir\u00e1, medida cautelar que fue &nbsp;comunicada mediante oficio N\u00b0 1337 del 3 de diciembre de 2020 y &nbsp;que se viene aplicando a partir del 1\u00ba de enero de 2021, por una &nbsp;cuota mensual de $ 621.124 conforme a lo estipulado en el citado &nbsp;oficio que no indic\u00f3 incremento alguno ni orden\u00f3 &nbsp;incluir las primas. &nbsp;<\/p>\n<p>4. &nbsp;La Procuradora 30 Judicial para La Defensa de los Derechos de la &nbsp;Infancia, la Adolescencia, la Familia y las Mujeres con funci\u00f3n &nbsp;en Tunja, se\u00f1al\u00f3 que la orden de amparo debe estar &nbsp;dirigida a que CREMIL proceda de inmediato a efectuar el descuento &nbsp;por n\u00f3mina de la totalidad de &nbsp;la cuota alimentaria fijada en sentencia de 4 de noviembre de 2020 y &nbsp;a consignar a \u00f3rdenes del proceso 2019-110 oportunamente las &nbsp;correspondientes sumas de dinero, con la advertencia de que debe &nbsp;observar las disposiciones legales de los l\u00edmites m\u00e1ximos &nbsp;a descontar. &nbsp;<\/p>\n<p>LA &nbsp;SENTENCIA IMPUGNADA &nbsp;<\/p>\n<p>El &nbsp;Tribunal Superior de Tunja, declar\u00f3 improcedente el amparo &nbsp;constitucional, tras se\u00f1alar que, &nbsp;<\/p>\n<p>(\u2026) &nbsp;De tal forma que no hay reticencia, ni hay omisi\u00f3n en el &nbsp;cumplimiento de los embargos dispuestos por el juzgado de &nbsp;conocimiento, esto es, el Juzgado de familia del Circuito de &nbsp;Chiquinquir\u00e1. En la sentencia dada en audiencia el 4 de &nbsp;noviembre de 2020, se especific\u00f3 el porcentaje de la cuota. Se &nbsp;fij\u00f3 el valor de dicha cuota, y se estableci\u00f3 que los &nbsp;descuentos alcanzaran las prima a que tenga derecho y se le cancelen &nbsp;semestralmente. En la misma providencia, en el hecho sexto se dispuso &nbsp;que, para garantizar el pago de la cuota alimentaria integral, se &nbsp;ordenaba el embargo de la pensi\u00f3n, y el abono en la cuenta de &nbsp;dep\u00f3sitos judiciales del juzgado. Decisi\u00f3n que se &nbsp;comunic\u00f3 y atendi\u00f3. La respuesta del CREMIL est\u00e1 &nbsp;a folio 18, donde se muestra el cumplimiento. El juez ha sido garante &nbsp;de derechos, cualquier inconformidad, debe ir al juez ordinario a &nbsp;peticionarla y no al juez de tutela. &nbsp;<\/p>\n<p>De &nbsp;tal forma que la respuesta obrante en el archivo 18 del expediente &nbsp;digital, dada por CREMIL, es decir, por la Caja de Retiro de las &nbsp;Fuerzas Militares, al explicar que la medida de embargo se viene &nbsp;aplicando desde el 1 de enero de 2021, conforme con lo ordenado por &nbsp;el juzgado. Por lo que no ha desatendido la orden, no se ha privado a &nbsp;los alimentarios de la cuota, y no se ha afectado su m\u00ednimo &nbsp;vital. No le asiste raz\u00f3n a la actora, y en todo caso, al &nbsp;interior de los diferentes procesos que ha tramitado de orden &nbsp;declarativo, como ejecutivo, tiene los medios para controlar el &nbsp;ingreso de la cuota, la entrega de los t\u00edtulos, y el valor de &nbsp;los descuentos. Por lo que, al tener elementos de defensa, &nbsp;reclamaci\u00f3n y correcci\u00f3n en v\u00eda ordinaria, no le &nbsp;es de recibo acudir a la acci\u00f3n de tutela. La condici\u00f3n &nbsp;o caracter\u00edstica de subsidiariedad, hace improcedente que el &nbsp;juez constitucional supla o avoque competencias propias del juez &nbsp;ordinario. &nbsp;<\/p>\n<p>LA &nbsp;IMPUGNACI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;desacuerdo con la decisi\u00f3n de primer grado, la accionante la &nbsp;impugn\u00f3, exponiendo que en efecto se han realizado los &nbsp;descuentos por parte de CREMIL de la cuota de alimentos de sus hijos, &nbsp;no ocurriendo lo mismo con el rubro de primas de junio y diciembre, &nbsp;ya que la entidad pagadora no ha efectuado los descuentos ordenados &nbsp;frente a ese concepto, como lo dispuso el Juzgado de Familia en la &nbsp;sentencia de 4 de noviembre de 2020, as\u00ed como tampoco el &nbsp;aumento de la cuota desde el a\u00f1o 2020. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>1. &nbsp;Por regla general, la acci\u00f3n de tutela no procede contra &nbsp;determinaciones judiciales, salvo que el funcionario respectivo &nbsp;hubiese adoptado una decisi\u00f3n por completo desviada del &nbsp;sendero previamente dise\u00f1ado por el legislador, sin ninguna &nbsp;objetividad y edificada en sus particulares interpretaciones, a tal &nbsp;extremo que se configure un proceder que pudiese encuadrar en una v\u00eda &nbsp;de hecho, situaci\u00f3n frente a la que se abre paso este &nbsp;mecanismo excepcional para restablecer las garant\u00edas &nbsp;esenciales vulneradas, siempre que se cumplan los conocidos &nbsp;requisitos generales y espec\u00edficos. &nbsp;<\/p>\n<p>2. En &nbsp;el asunto que ocupa la atenci\u00f3n de la Sala, el amparo &nbsp;propuesto no puede prosperar, toda vez que, en las piezas digitales &nbsp;allegadas a este tr\u00e1mite, no se observa la vulneraci\u00f3n &nbsp;alegada por la accionante, teniendo en cuenta que, en el Juzgado de &nbsp;Familia de Chiquinquir\u00e1 se adelantan los siguientes procesos. &nbsp;<\/p>\n<p>Promovido &nbsp;por Jos\u00e9 contra Mar\u00eda quien representa a los menores &nbsp;Juanita y Juanito, que fue admitido en auto de 10 de junio de 2019. &nbsp;<\/p>\n<p>Adelantados &nbsp;los tr\u00e1mites de rigor, en audiencia de 4 &nbsp;de noviembre de 2020 &nbsp;se dispuso, i) &nbsp;Acceder a la solicitud de disminuci\u00f3n de cuota alimentaria, &nbsp;ii) &nbsp;Fijar como cuota alimentaria integral mensual con la que el &nbsp;demandante Jos\u00e9 debe contribuir con la manutenci\u00f3n de &nbsp;sus menores hijos, el 33,33% de su pensi\u00f3n o asignaci\u00f3n &nbsp;mensual que como soldado profesional del Ejercito Nacional recibe, es &nbsp;decir que se fija como cuota integral para cada uno de los ni\u00f1os &nbsp;el 16,665 de la pensi\u00f3n del demandado, iii) &nbsp;Jos\u00e9 cancelar\u00e1 a favor de los dos menores el 33,33% de &nbsp;las primas a que tenga derecho y que se le cancelen semestral o &nbsp;anualmente, iv) &nbsp;para garantizar el pago de la cuota alimentaria integral fijada a &nbsp;favor de los ni\u00f1os, se ordena el embargo de la pensi\u00f3n &nbsp;o asignaci\u00f3n mensual y de las primas en el monto establecido. &nbsp;<\/p>\n<p>La &nbsp;anterior orden se hizo efectiva mediante oficio N\u00b0 1147 de 6 de &nbsp;noviembre de 2020, mediante el cual se le comunic\u00f3 a la Caja &nbsp;de Retiro de las Fuerzas Militares CREMIL la sentencia de 4 de &nbsp;noviembre de 2020. &nbsp;<\/p>\n<p>Con &nbsp;posterioridad, la accionante presenta peticiones al Juzgado de &nbsp;conocimiento, tendientes a que se requiera al pagador a fin de que, &nbsp;de cumplimiento a lo estipulado en el fallo de 2020, respecto a la &nbsp;omisi\u00f3n de descontar el respectivo monto de las primas &nbsp;percibidas por el padre de los menores, raz\u00f3n que llev\u00f3 &nbsp;al despacho a requerir a CREMIL, quien inform\u00f3, &nbsp;<\/p>\n<p>[Derivado &nbsp;expediente digital. Expediente &nbsp;2019-0110.01-15176311000120190011000.DISMINUCI\u00d3N] &nbsp;<\/p>\n<p>2.2 &nbsp;Proceso Ejecutivo de Alimentos 2020-00163 &nbsp;<\/p>\n<p>Promovido &nbsp;por Mar\u00eda quien representa a los menores Juanita y Juanito &nbsp;contra Jos\u00e9, en el que mediante auto de 30 de noviembre de &nbsp;2020 se libr\u00f3 mandamiento de pago por concepto de las cuotas &nbsp;alimentarias e incrementos adeudados de los a\u00f1os 2019 y 2020 &nbsp;y, de manera posterior, ante la actitud silente del ejecutado, se &nbsp;profiri\u00f3 orden de seguir adelante la ejecuci\u00f3n. &nbsp;<\/p>\n<p>En el &nbsp;cuaderno de medidas cautelares se observa, que el 30 de noviembre de &nbsp;2020 se decret\u00f3 el embargo y retenci\u00f3n del 50% de la &nbsp;asignaci\u00f3n del ejecutado, como pensionado de CREMIL \u00abteniendo &nbsp;en cuenta que la deuda a capital a octubre de 2020 asciende a la suma &nbsp;de $8.622.053 y la cuota alimentaria para el corriente a\u00f1o, es &nbsp;por el valor de $621.124.oo\u00bb &nbsp;<\/p>\n<p>La &nbsp;orden fue comunicada a la Caja de Retiro, en oficio N\u00b0 1337 de 3 &nbsp;de diciembre de 2020, en los t\u00e9rminos del auto que decret\u00f3 &nbsp;la medida cautelar, pues as\u00ed lo dio a conocer al Juzgado de &nbsp;conocimiento. &nbsp;<\/p>\n<p>[Derivado &nbsp;expediente digital. Expediente 2020-0163. Principal y medidas &nbsp;cautelares] &nbsp;<\/p>\n<p>Y es &nbsp;que si bien, la inconforme alega que no se le est\u00e1 cancelando &nbsp;el porcentaje correspondiente a las primas que devenga el ejecutado &nbsp;en su calidad de pensionado de la Caja de Retiro de las Fuerzas &nbsp;Militares CREMIL, lo cierto es que, fueron allegados los anexos en &nbsp;donde la entidad pagadora acredita los descuentos efectuados al &nbsp;ejecutado, por los dos valores que inform\u00f3 en la respuesta &nbsp;allegada a esta acci\u00f3n, y, ante cualquier inconformidad, tiene &nbsp;los mecanismos ordinarios para acudir en los respectivos tr\u00e1mites &nbsp;que se adelantan en el Juzgado de Familia de Chiquinquir\u00e1, a\u00fan &nbsp;si lo que pretende es el aumento de la cuota alimentaria. &nbsp;<\/p>\n<p>4. De &nbsp;lo anterior, se desprende que la reclamaci\u00f3n de la accionante &nbsp;resulta claramente infundada, ya que la entidad accionada y el &nbsp;Juzgado vinculado, han adelantado las actuaciones respectivas para &nbsp;garantizar los derechos de los menores involucrados en el litigio. &nbsp;<\/p>\n<p>En &nbsp;eventos como este, cuando del examen de la demanda constitucional se &nbsp;revela la ausencia &nbsp;de vulneraci\u00f3n &nbsp;de las garant\u00edas invocadas, sobreviene su desestimaci\u00f3n, &nbsp;pues es imprescindible, \u00abel &nbsp;cumplimiento de algunos requisitos, siendo uno de ellos y quiz\u00e1s &nbsp;el primero y m\u00e1s elemental, la &nbsp;existencia cierta del agravio, lesi\u00f3n o puesta en peligro de &nbsp;la prerrogativa constitucional invocada &nbsp;que demande la inmediata intervenci\u00f3n del juez de tutela en &nbsp;orden a hacerla cesar, motivo por el cual la solicitud de amparo debe &nbsp;contener un m\u00ednimo de demostraci\u00f3n en cuanto a la &nbsp;vulneraci\u00f3n que afecta los derechos que se quieren proteger, &nbsp;pues si no son objeto de ataque o coacci\u00f3n, carece de sentido &nbsp;hablar de la necesidad de la salvaguarda\u00bb &nbsp;(CSJ. &nbsp;STC5337-2018, STC8053-2019 y, STC13801-2022, entre otros). &nbsp;<\/p>\n<p>5. En conclusi\u00f3n &nbsp;de lo expuesto, se confirmar\u00e1 el fallo impugnado, al no &nbsp;evidenciarse la vulneraci\u00f3n reclamada por la accionante. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia en Sala de &nbsp;Casaci\u00f3n Civil, administrando justicia en nombre de la &nbsp;Rep\u00fablica de Colombia y por autoridad de la ley, CONFIRMA &nbsp;la sentencia impugnada. &nbsp;<\/p>\n<p>Comun\u00edquese &nbsp;lo aqu\u00ed resuelto a las partes por el medio m\u00e1s expedito &nbsp;y oportunamente rem\u00edtanse las presentes diligencias a la Corte &nbsp;Constitucional para su eventual revisi\u00f3n. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y CUMPLASE &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Presidente &nbsp;de Sala &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>(Comisi\u00f3n &nbsp;de servicios) &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC1572-2023_1 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; ANOTACI\u00d3N &nbsp;PRELIMINAR &nbsp; De &nbsp;conformidad con el \u00abART\u00cdCULO &nbsp;PRIMERO\u00bb &nbsp;del Acuerdo No. 034 de esta Sala, expedido el pasado 16 de diciembre, &nbsp;atendiendo a que en esta providencia se resuelve una situaci\u00f3n &nbsp;jur\u00eddica relacionada con una persona menor de edad, como &nbsp;medida de protecci\u00f3n a su intimidad, se emiten dos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-70859","post","type-post","status-publish","format-standard","hentry","category-febrero-2023"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=70859"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70859\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=70859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=70859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=70859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}