{"id":70863,"date":"2024-05-20T22:42:12","date_gmt":"2024-05-20T22:42:12","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc1576-2023\/"},"modified":"2024-05-20T22:42:12","modified_gmt":"2024-05-20T22:42:12","slug":"stc1576-2023","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc1576-2023\/","title":{"rendered":"STC1576 2023"},"content":{"rendered":"<p>STC1576-2023<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>LUIS ALONSO &nbsp;RICO PUERTA &nbsp;<\/p>\n<p>Magistrado &nbsp;ponente &nbsp;<\/p>\n<p>STC1576-2023 &nbsp;<\/p>\n<p>Radicaci\u00f3n n.\u00ba &nbsp;11001-02-03-000-2023-00581-00 &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D.C., veintid\u00f3s (22) de febrero de dos mil veintitr\u00e9s &nbsp;(2023). &nbsp;<\/p>\n<p>Decide la Corte la acci\u00f3n de tutela promovida por &nbsp;Mario &nbsp;Alberto Restrepo Zapata contra &nbsp;la &nbsp;Sala Civil Familia del Tribunal Superior del Distrito Judicial de &nbsp;Pereira; &nbsp;tr\u00e1mite al cual fueron vinculados el Juzgado Civil del &nbsp;Circuito de Santa Rosa de Cabal, la Procuradur\u00eda General de la &nbsp;Naci\u00f3n, la Comisi\u00f3n Nacional de Disciplina Judicial, la &nbsp;Seccional de Disciplina Judicial de Risaralda, el Consejo Superior de &nbsp;la Judicatura y las partes e intervinientes en la acci\u00f3n &nbsp;popular n.\u00ba &nbsp;2022-00027. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>1. &nbsp; &nbsp; &nbsp; &nbsp;El &nbsp;solicitante, actuando en nombre propio, reclam\u00f3 la protecci\u00f3n &nbsp;de su derecho fundamental al debido proceso, presuntamente vulnerado &nbsp;por la corporaci\u00f3n judicial convocada. &nbsp;<\/p>\n<p>2. &nbsp; &nbsp; &nbsp; &nbsp;Relata &nbsp;que, la autoridad accionada desatendi\u00f3 los t\u00e9rminos &nbsp;establecidos en el art\u00edculo 37 de la ley 472 de 1998, puesto &nbsp;que, luego de \u00ab9 &nbsp;meses, decide fallar\u00bb &nbsp;el recurso de apelaci\u00f3n que interpuso contra la sentencia de &nbsp;primera instancia proferida por el Juzgado Civil del Circuito de &nbsp;Santa Rosa de Cabal en la acci\u00f3n popular radicado 2022-00027. &nbsp;<\/p>\n<p>Al &nbsp;respecto cuestiona que, \u00abno &nbsp;tiene sentido que la ley especial [\u2026] &nbsp;ordene t\u00e9rminos perentorios para tener un veredicto final, si &nbsp;estos se incumplen por el tutelado y, sin embargo, se exige su &nbsp;cumplimiento inexorable y estricto por parte de los actores &nbsp;populares\u00bb. &nbsp;<\/p>\n<p>Agrega &nbsp;que, por un d\u00eda que pase despu\u00e9s del tiempo que otorga &nbsp;la ley para presentar apelaciones, aquellas se declaran &nbsp;extempor\u00e1neas, pero \u00abel &nbsp;tutelado desconoce el art\u00edculo 37 de la ley 472 de 1998 y &nbsp;simplemente debo resignarme a que solo yo cumpla t\u00e9rmino de &nbsp;tiempo que impone la ley\u00bb. &nbsp;<\/p>\n<p>Aduce &nbsp;que esta Corte ha destacado la importancia de la estricta observancia &nbsp;de los t\u00e9rminos procesales (cita la STC15220-2019), y que el &nbsp;accionado \u00abno &nbsp;gusta cumplir nunca los t\u00e9rminos de tiempo que le impone la &nbsp;ley [\u2026] &nbsp;y tampoco se da aplicaci\u00f3n al art\u00edculo 84 de la ley 472 &nbsp;de 1998\u00bb. &nbsp;Solicita finalmente la intervenci\u00f3n de la Procuradora General &nbsp;de la Naci\u00f3n en este amparo y para que presente \u00abacciones &nbsp;legales a mi nombre [\u2026] &nbsp;pues &nbsp;no soy abogado\u00bb &nbsp;<\/p>\n<p>3. &nbsp; &nbsp; &nbsp; &nbsp;Por &nbsp;lo anterior pretende que, se conceda la protecci\u00f3n al debido &nbsp;proceso y por lo tanto, \u00abse &nbsp;determine cu\u00e1nto tiempo contaba el tutelado para fallar, pues &nbsp;seg\u00fan la ley ten\u00eda 20 d\u00edas para ello (\u2026) &nbsp;se inste al tutelado aplicar art\u00edculo 84 de la ley especial y &nbsp;aut\u00f3noma 472 de 1998 (\u2026) se ordene una constancia &nbsp;secretarial de todas las etapas procesales realizadas [\u2026] &nbsp;a fin de probar la mora judicial (\u2026) se ordene la intervenci\u00f3n &nbsp;de la Procuradora Gral de la Naci\u00f3n a fin de que act\u00fae &nbsp;en mi amparo (\u2026) se oficie al Consejo Superior de la &nbsp;Judicatura, Sala Disciplinaria a fin de que aporte copia digital de &nbsp;todas las quejas presentadas contra el accionado (\u2026) se me &nbsp;brinde copia aut\u00e9ntica de todo lo actuado a fin de que obre &nbsp;ante la Comisi\u00f3n Interamericana DDHH\u00bb. &nbsp;<\/p>\n<p>RESPUESTA DE LA ACCIONADA Y VINCULADOS &nbsp;<\/p>\n<p>1. &nbsp; &nbsp; &nbsp; &nbsp;La secretar\u00eda de la Sala Civil del &nbsp;Tribunal Superior de Pereira inform\u00f3 que, la acci\u00f3n &nbsp;popular que se menciona en la tutela \u2013 radicado 2022-00027 \u2013 &nbsp;corresponde a la promovida por Gerardo Herrera, con la coadyuvancia &nbsp;de Cotty Morales Caama\u00f1o, dirigida contra Leonor Duque R\u00edos, &nbsp;propietaria del establecimiento de comercio Unimovil, &nbsp;tr\u00e1mite al cual fueron vinculados la Defensor\u00eda del &nbsp;Pueblo de Risaralda, la Alcald\u00eda, la Secretar\u00eda de &nbsp;Planeaci\u00f3n y la Personer\u00eda Municipal de Santa Rosa de &nbsp;Cabal, y la Procuradur\u00eda General de la Naci\u00f3n. Aport\u00f3 &nbsp;el link de acceso al expediente digital de la referida actuaci\u00f3n. &nbsp;<\/p>\n<p>2. &nbsp; &nbsp; &nbsp; &nbsp;El magistrado Edder Jimmy S\u00e1nchez &nbsp;Calamb\u00e1s, de la Sala Civil Familia del Tribunal Superior de &nbsp;Pereira precis\u00f3 que, en la acci\u00f3n popular con radicado &nbsp;2022-00027, incoada por Gerardo Herrera, profiri\u00f3 sentencia de &nbsp;segunda instancia el 6 de febrero de 2023 confirmando parcialmente la &nbsp;decisi\u00f3n del a quo &nbsp;y revoc\u00f3 el numeral 6\u00ba, \u00abpara &nbsp;en su lugar condenar a la demandada a pagar al accionante las costas &nbsp;procesales de la primera instancia\u00bb; &nbsp;adicionalmente, se\u00f1al\u00f3 que, con auto del 14 de febrero &nbsp;inadmiti\u00f3 el recurso propuesto por Cotty Morales, coadyuvante &nbsp;del actor popular; finalmente, agreg\u00f3 que, no incurri\u00f3 &nbsp;en \u00abviolaci\u00f3n &nbsp;de los derechos fundamentales atribuidos por el se\u00f1or Mario &nbsp;Restrepo, puesto que se ha actuado conforme las normas que rigen la &nbsp;materia\u00bb. &nbsp;<\/p>\n<p>3. &nbsp; &nbsp; &nbsp; &nbsp;La &nbsp;Procuradur\u00eda General de la Naci\u00f3n en cuanto a los &nbsp;reproches que dirigi\u00f3 el tutelante contra esa entidad y su &nbsp;titular, sostuvo que, \u00aben &nbsp;calidad de ente de control, siempre ha estado presto a dar tr\u00e1mite &nbsp;a cada una de las solicitudes radicadas por los ciudadanos con el fin &nbsp;de dar orientaci\u00f3n para el disfrute y goce de sus derechos y &nbsp;las respuestas a las diferentes peticiones [\u2026] empero, en el &nbsp;presente caso, escapan de la \u00f3rbita funcional las &nbsp;circunstancias expuestas, cuando por dem\u00e1s, nunca han sido de &nbsp;conocimiento de esta Procuradur\u00eda\u00bb. &nbsp;<\/p>\n<p>4. &nbsp; &nbsp; &nbsp; &nbsp;El Procurador &nbsp;12 Judicial II para Asuntos Civiles resalt\u00f3 que, en lo que &nbsp;tiene que ver con la solicitud del actor frente al Ministerio P\u00fablico &nbsp;a fin de que intervenga en su favor o promueva acciones en su nombre, &nbsp;este \u00abno &nbsp;acredit\u00f3 haber elevado tal petici\u00f3n, lo que descarta de &nbsp;plano que frente a este preciso pedimento se cumpla el presupuesto de &nbsp;la subsidiariedad\u00bb. &nbsp;<\/p>\n<p>5. &nbsp; &nbsp; &nbsp; &nbsp;La Comisi\u00f3n &nbsp;Nacional de Disciplina Judicial por intermedio de su presidenta, &nbsp;indic\u00f3 que, en el sistema de consulta judicial no se advierte &nbsp;proceso disciplinario que haya promovido el gestor del amparo contra &nbsp;el magistrado accionado, sin embargo, comoquiera que en la presente &nbsp;acci\u00f3n de tutela se cuestiona una posible mora del citado &nbsp;funcionario, \u00abesta &nbsp;presidencia someter\u00e1 a reparto la aludida queja, para ejercer &nbsp;la potestad disciplinaria a que haya lugar\u00bb. &nbsp;<\/p>\n<p>6. &nbsp; &nbsp; &nbsp; &nbsp;El Juzgado &nbsp;Civil del Circuito de Santa Rosa de Cabal, sin pronunciarse sobre las &nbsp;pretensiones de esta tutela, alleg\u00f3 copia digital del cuadro &nbsp;de control o acta de audiencia de pacto de cumplimiento llevada a &nbsp;cabo el 25 de marzo de 2022 dentro de la acci\u00f3n popular con &nbsp;radicado n\u00ba 66682-31-13-001-2022-00027-00, accionante: Gerardo &nbsp;Herrera, accionada: Leonor Duque R\u00edos, propietaria &nbsp;establecimiento de comercio Unimovil Plus. &nbsp;<\/p>\n<p>7. &nbsp; &nbsp; &nbsp; &nbsp;La Comisi\u00f3n &nbsp;Seccional de Disciplina Judicial de Risaralda y el Consejo Superior &nbsp;de la Judicatura, por intermedio de sus respectivos presidentes, &nbsp;solicitaron la desvinculaci\u00f3n del tr\u00e1mite tutelar en la &nbsp;medida en que, no han vulnerado los derechos fundamentales del gestor &nbsp;pues, no son las llamadas a responder por las reclamaciones y &nbsp;cuestionamientos que aqu\u00e9l formula. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>1. &nbsp; &nbsp; &nbsp; &nbsp;Problema &nbsp;jur\u00eddico. &nbsp;<\/p>\n<p>Corresponde a la Corte establecer, inicialmente, si el &nbsp;precursor de la salvaguarda est\u00e1 legitimado para interponerla &nbsp;y, en caso de superarse lo anterior, si la Sala Civil Familia del &nbsp;Tribunal Superior del Distrito Judicial de Pereira vulner\u00f3 la &nbsp;prerrogativa reclamada por el accionante, al incurrir, supuestamente, &nbsp;en mora judicial por &nbsp;desatender el t\u00e9rmino previsto legalmente para resolver la &nbsp;segunda instancia de la acci\u00f3n popular n.\u00ba 2022-00027. &nbsp;<\/p>\n<p>2. &nbsp; &nbsp; &nbsp; &nbsp;La &nbsp;legitimaci\u00f3n en la causa. &nbsp;<\/p>\n<p>2.1. &nbsp; &nbsp; &nbsp; &nbsp;M\u00e1s &nbsp;all\u00e1 de la especial naturaleza del resguardo constitucional, &nbsp;resulta claro que al mismo no le son ajenos algunos de los &nbsp;presupuestos b\u00e1sicos de ciertos actos procesales, tal cual es &nbsp;el caso de la legitimaci\u00f3n en la causa, ya sea por activa o &nbsp;por pasiva. &nbsp;<\/p>\n<p>En &nbsp;lo que a la primera modalidad se refiere, el art\u00edculo 10 del &nbsp;Decreto 2591 de 1991, prev\u00e9 que este mecanismo podr\u00e1 &nbsp;ser ejercido \u00aben &nbsp;todo momento y lugar, por cualquiera persona vulnerada o amenazada en &nbsp;uno de sus derechos fundamentales, quien actuar\u00e1 por s\u00ed &nbsp;misma o a trav\u00e9s de representante. Los poderes se presumir\u00e1n &nbsp;aut\u00e9nticos. Tambi\u00e9n se pueden agenciar derechos ajenos &nbsp;cuando el titular de los mismos no est\u00e9 en condiciones de &nbsp;promover su propia defensa. Cuando tal circunstancia ocurra, deber\u00e1 &nbsp;manifestarse en la solicitud\u00bb. &nbsp;<\/p>\n<p>Sobre &nbsp;el alcance jur\u00eddico de la disposici\u00f3n legal en cita, la &nbsp;jurisprudencia constitucional sostiene que: \u00abla &nbsp;legitimaci\u00f3n por activa en la acci\u00f3n de tutela se &nbsp;refiere al titular de los derechos fundamentales presuntamente &nbsp;vulnerados o amenazados. Sin embargo, tanto las normas como la &nbsp;jurisprudencia, consideran v\u00e1lidas tres v\u00edas procesales &nbsp;adicionales para la interposici\u00f3n de la acci\u00f3n de &nbsp;tutela: (i) a trav\u00e9s del representante legal del titular de &nbsp;los derechos fundamentales presuntamente conculcados (menores de &nbsp;edad, incapaces absolutos, interdictos y personas jur\u00eddicas); &nbsp;(ii) por intermedio de apoderado judicial (abogado titulado con poder &nbsp;o mandato expreso); y, (iii) por medio de agente oficioso\u00bb &nbsp;(CC &nbsp;T-878\/07). &nbsp;<\/p>\n<p>Ahora, &nbsp;cuando se cuestiona una actuaci\u00f3n judicial, se ha entendido &nbsp;que s\u00f3lo puede acudir a este medio excepcional para debatirla &nbsp;quien funge como parte o tercero reconocido con inter\u00e9s en la &nbsp;misma o, s\u00ed resultaba necesaria su vinculaci\u00f3n y se &nbsp;omiti\u00f3, pues: &nbsp;<\/p>\n<p>\u00ab(\u2026) &nbsp;en punto de la trasgresi\u00f3n de los derechos fundamentales con &nbsp;ocasi\u00f3n de una decisi\u00f3n judicial, es claro que quienes &nbsp;ostentan legitimaci\u00f3n en la causa para demandar el amparo &nbsp;superior, en principio, son aquellas personas, naturales o jur\u00eddicas, &nbsp;que intervinieron en el correspondiente proceso o que, siendo &nbsp;imperativa su vinculaci\u00f3n a \u00e9ste, no fueron citadas, de &nbsp;manera que, en principio, carecen de vocaci\u00f3n jur\u00eddica &nbsp;para activar la jurisdicci\u00f3n constitucional con el fin de &nbsp;cuestionar una actuaci\u00f3n judicial quienes no fueron parte en &nbsp;ella\u00bb &nbsp;(CS. &nbsp;STC de 11 ago. 2011, exp, 00087 &nbsp;01, reiterada el 15 &nbsp;abr. 2016, STC4739). &nbsp;<\/p>\n<p>2.2. &nbsp; &nbsp; &nbsp; &nbsp;Revisado &nbsp;el tr\u00e1mite surtido, se establece que el aqu\u00ed accionante &nbsp;no est\u00e1 &nbsp;facultado para formular las pretensiones invocadas a trav\u00e9s de &nbsp;la presente tutela, ya que la acci\u00f3n popular objeto de su &nbsp;reproche, identificada con el radicado 66682-31-03-001-2022-00027-01 &nbsp;fue incoada por Gerardo &nbsp;Alonso Herrera Hoyos &nbsp;y, como bien puede constatarse del expediente digital aportado por la &nbsp;secretar\u00eda de la colegiatura acusada, Mario Alberto Restrepo &nbsp;Zapata no fue sujeto procesal dentro de la misma, pues ni &nbsp;siquiera intervino en ella en la condici\u00f3n de &nbsp;coadyuvante &nbsp;(en esa calidad actu\u00f3 la se\u00f1ora Cotty Morales Caama\u00f1o), &nbsp;luego, es evidente que carece de inter\u00e9s leg\u00edtimo &nbsp;respecto de aqu\u00e9l pleito. &nbsp;<\/p>\n<p>En &nbsp;suma, de acuerdo con la jurisprudencia en cita, la &nbsp;facultad para refutar o cuestionar el referido tr\u00e1mite est\u00e1 &nbsp;reservada exclusivamente para las partes o terceros reconocidos en &nbsp;dicho litigio, condici\u00f3n que, se reitera, el gestor del amparo &nbsp;no detenta. Sobre el particular, esta &nbsp;Sala tambi\u00e9n dijo que: &nbsp;<\/p>\n<p>\u00ab[E]n &nbsp;el &nbsp;promotor del amparo debe existir un inter\u00e9s que legitime su &nbsp;intervenci\u00f3n, el cual, trat\u00e1ndose de violaciones &nbsp;derivadas de actuaciones judiciales, radica en cabeza de quienes &nbsp;conforman alguno de los extremos de la litis o fueron tenidos o &nbsp;reconocidos como intervinientes. &nbsp;<\/p>\n<p>(\u2026) En &nbsp;el sub lite, es claro el fracaso de la salvaguarda porque del relato &nbsp;del [tutelista] y de las evidencias adosadas a este expediente, &nbsp;emerge que \u00e9l no particip\u00f3 en el pleito denunciado en &nbsp;ninguna de las dos se\u00f1aladas calidades, luego es &nbsp;incontrovertible que carece de legitimaci\u00f3n para reprochar por &nbsp;esta v\u00eda las decisiones all\u00ed adoptadas\u00bb &nbsp;(CSJ &nbsp;STC, 14 nov. 2013, rad. 02643-00, reiterada en STC21436-2017, &nbsp;14 dic. &nbsp;2017, rad. 03445-00; STC4001-2018, 22 mar. 2018, rad. 00041-01 y &nbsp;STC15343-2018, 23 nov. 2018, rad. 00890-01, entre otras). &nbsp;<\/p>\n<p>3. &nbsp; &nbsp; &nbsp; &nbsp;Consideraciones &nbsp;adicionales. &nbsp;<\/p>\n<p>3.1. &nbsp; &nbsp; &nbsp; &nbsp;Finalmente, &nbsp;la Sala se abstendr\u00e1 de pronunciarse respecto a la pretensi\u00f3n &nbsp;que involucra a la Procuradur\u00eda General de la Naci\u00f3n y &nbsp;su titular, de quien el precursor del amparo reclam\u00f3 su &nbsp;intervenci\u00f3n para que eleve \u00abacciones &nbsp;en su nombre\u00bb &nbsp;y d\u00e9 aplicaci\u00f3n a la sanci\u00f3n prevista en el &nbsp;art\u00edculo 84 de la ley 472 de 1998 contra la magistratura aqu\u00ed &nbsp;accionada, por el presunto incumplimiento de los t\u00e9rminos &nbsp;legales, pues, &nbsp;como qued\u00f3 establecido, el citado libelista carece de &nbsp;legitimaci\u00f3n para ello, al no haber hecho parte del juicio en &nbsp;cuesti\u00f3n. &nbsp;<\/p>\n<p>3.2. &nbsp; &nbsp; &nbsp; &nbsp;Por &nbsp;lo dem\u00e1s, sobre la petici\u00f3n al Consejo Superior de la &nbsp;Judicatura y a la Comisi\u00f3n Nacional de Disciplina Judicial a &nbsp;fin de que aporten copias de todas las quejas que ha presentado &nbsp;contra el funcionario tutelado \u2013 magistrado Edder Jmmy S\u00e1nchez &nbsp;Calamb\u00e1s \u2013 de la Sala Civil Familia del Tribunal &nbsp;Superior de Pereira, basta se\u00f1alar que el promotor no acredit\u00f3 &nbsp;haber dirigido pedimento alguno a las mencionadas corporaciones en &nbsp;ese sentido; motivo por el cual, dicho planteamiento no puede ser &nbsp;atendido en este escenario, dado su resaltado car\u00e1cter &nbsp;subsidiario y residual. &nbsp;<\/p>\n<p>3.3. &nbsp; &nbsp; &nbsp; &nbsp;De &nbsp;la solicitud de copias de esta acci\u00f3n de tutela, en &nbsp;cumplimiento de la labor habitual de notificaci\u00f3n en estos &nbsp;tr\u00e1mites, por secretar\u00eda de la Sala, se le remitir\u00e1 &nbsp;lo pedido al correo electr\u00f3nico suministrado por el &nbsp;interesado. &nbsp;<\/p>\n<p>4. &nbsp; &nbsp; &nbsp; &nbsp;Conclusi\u00f3n. &nbsp;<\/p>\n<p>Con fundamento en &nbsp;lo discurrido, ser\u00e1 la negativa de la protecci\u00f3n pedida &nbsp;porque: &nbsp;<\/p>\n<p>El aqu\u00ed &nbsp;accionante carece de legitimaci\u00f3n en la causa por activa para &nbsp;cuestionar las actuaciones surtidas al interior de la acci\u00f3n &nbsp;popular radicado n\u00ba 2022-00027, en la que no se encuentra &nbsp;reconocido ni como coadyuvante de quien all\u00ed funge como actor &nbsp;ni en ninguna de las calidades procesales que eventualmente lo &nbsp;habiliten para ese prop\u00f3sito. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia en Sala de &nbsp;Casaci\u00f3n Civil, administrando justicia en nombre de la &nbsp;Rep\u00fablica de Colombia y por autoridad de la ley, NIEGA &nbsp;el &nbsp;amparo incoado a trav\u00e9s de la acci\u00f3n de tutela &nbsp;referenciada. &nbsp;<\/p>\n<p>Comun\u00edquese &nbsp;lo aqu\u00ed resuelto a las partes por medio expedito y, en caso de &nbsp;no ser impugnado el fallo, rem\u00edtanse las presentes diligencias &nbsp;a la Corte Constitucional para su eventual revisi\u00f3n. &nbsp;<\/p>\n<p>Env\u00edese &nbsp;copia del expediente de la presente tutela al correo electr\u00f3nico &nbsp;que proporcion\u00f3 el convocante para recibir notificaciones. &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Presidente &nbsp;de Sala &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>Comisi\u00f3n &nbsp;de Servicios &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC1576-2023 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; LUIS ALONSO &nbsp;RICO PUERTA &nbsp; Magistrado &nbsp;ponente &nbsp; STC1576-2023 &nbsp; Radicaci\u00f3n n.\u00ba &nbsp;11001-02-03-000-2023-00581-00 &nbsp; Bogot\u00e1, &nbsp;D.C., veintid\u00f3s (22) de febrero de dos mil veintitr\u00e9s &nbsp;(2023). &nbsp; Decide la Corte la acci\u00f3n de tutela promovida por &nbsp;Mario &nbsp;Alberto Restrepo Zapata contra &nbsp;la &nbsp;Sala Civil Familia del Tribunal Superior del Distrito Judicial [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-70863","post","type-post","status-publish","format-standard","hentry","category-febrero-2023"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=70863"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70863\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=70863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=70863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=70863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}