{"id":70915,"date":"2024-05-20T22:42:14","date_gmt":"2024-05-20T22:42:14","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc593-2023\/"},"modified":"2024-05-20T22:42:14","modified_gmt":"2024-05-20T22:42:14","slug":"stc593-2023","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc593-2023\/","title":{"rendered":"STC593 2023"},"content":{"rendered":"<p>STC593-2023<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>Magistrado &nbsp;ponente &nbsp;<\/p>\n<p>STC593-2023 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00ba11001-02-03-000-2023-00249-00 &nbsp;<\/p>\n<p>(Aprobado en &nbsp;sesi\u00f3n del primero de febrero de dos mil veintitr\u00e9s) &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D.C., primero (1\u00ba) de febrero de dos mil veintitr\u00e9s &nbsp;(2023). &nbsp;<\/p>\n<p>Se &nbsp;resuelve la tutela que Gerardo Alonso Herrera Hoyos instaur\u00f3 &nbsp;contra la Secretar\u00eda de la Sala Civil Familia del Tribunal &nbsp;Superior del Distrito Judicial de Pereira y la Procuradur\u00eda &nbsp;General de la Naci\u00f3n. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>1.El &nbsp;libelista solicit\u00f3 que se ordene a la autoridad encartada &nbsp;brindar las constancias que solicit\u00f3, adicionalmente pidi\u00f3 &nbsp;que se requiera a la Procuradur\u00eda General de la Naci\u00f3n &nbsp;para que determine \u00absi &nbsp;el tutelado incumple su funcion[sic] &nbsp;deber, ley 734 de 2002 y dilata, entorpece el tramite[sic] &nbsp;constitucional de la accion[sic]&nbsp;popular &nbsp;al negar las constancias pedidas a saciedad\u00bb. &nbsp;<\/p>\n<p>En &nbsp;sustento, adujo que ha solicitado \u00abinfructuosa &nbsp;y persistentemente\u00bb &nbsp;al encartado una \u00abCONSTANCIA &nbsp;de todas las etapas procesales en acciones populares e igualmente me &nbsp;brinde CONSTANCIA de las fechas de llegada a dicha secretaria de las &nbsp;acciones populares\u00bb &nbsp;(23 ene.2023), &nbsp;sin obtener respuesta por parte de este. &nbsp;<\/p>\n<p>2. La Procuradur\u00eda &nbsp;General de la Naci\u00f3n aleg\u00f3 ausencia de legitimaci\u00f3n &nbsp;en la causa por pasiva, se\u00f1al\u00f3 que &nbsp;no tiene asignadas competencias para administrar justicia, y por &nbsp;ende, no es quien debe decidir con respecto a lo solicitado por el &nbsp;accionante; asegur\u00f3 que tampoco es competente para representar &nbsp;al accionante judicialmente, por lo que asever\u00f3 que las &nbsp;pretensiones del actor desbordan sus competencias. A &nbsp;la fecha de elaboraci\u00f3n de esta providencia no se presentaron &nbsp;manifestaciones adicionales. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>La protecci\u00f3n &nbsp;constitucional invocada no est\u00e1 llamada a prosperar habida &nbsp;cuenta que, de &nbsp;entrada, la Sala avizora la ausencia de vulneraci\u00f3n de derecho &nbsp;fundamental alguno, por las razones que se exponen a continuaci\u00f3n: &nbsp;<\/p>\n<p>Luego, teniendo en &nbsp;cuenta que la solicitud referida fue radicada el 23 &nbsp;de enero de 20231 &nbsp; y que &nbsp;esta acci\u00f3n de tutela fue presentada el 24 &nbsp;de enero siguiente2, &nbsp;resulta evidente que para la data en que se promovi\u00f3 el amparo &nbsp;no hab\u00eda acaecido el t\u00e9rmino con que contaba el &nbsp;encartado para dar respuesta a la solicitud, m\u00e1xime si se &nbsp;tiene en cuenta que en &nbsp;el expediente &nbsp;no consta que el actor hubiese presentado otras &nbsp;solicitudes ante la referida autoridad; &nbsp;raz\u00f3n por la cual no puede endilgarse vulneraci\u00f3n &nbsp;alguna, &nbsp;por lo que se &nbsp;negar\u00e1 el amparo invocado. &nbsp;<\/p>\n<p>Frente a las &nbsp;rogativas dirigidas a la Procuradur\u00eda General de la Naci\u00f3n, &nbsp;el resguardo carece del presupuesto de subsidiariedad, toda vez que &nbsp;no se evidencia que el actor hubiese provocado de dicho organismo una &nbsp;soluci\u00f3n a la problem\u00e1tica que exhibe, sin que pueda &nbsp;suscitarla a trav\u00e9s de este mecanismo, dado su car\u00e1cter &nbsp;residual y excepcional. As\u00ed que, si el peticionario considera &nbsp;que dicha autoridad debe intervenir en asuntos asociados al tema, le &nbsp;incumbe a \u00e9l gestionar directamente los resultados que anhela. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En m\u00e9rito &nbsp;de lo expuesto, la Corte Suprema de Justicia, en Sala de Casaci\u00f3n &nbsp;Civil, administrando justicia en nombre de la Rep\u00fablica de &nbsp;Colombia y por autoridad de la Constituci\u00f3n, &nbsp;resuelve &nbsp;NEGAR la &nbsp;tutela instada. &nbsp;<\/p>\n<p>Inf\u00f3rmese a &nbsp;los participantes por el medio m\u00e1s expedito y rem\u00edtase &nbsp;el paginario a la Corte Constitucional para su eventual revisi\u00f3n, &nbsp;de no impugnarse esta resoluci\u00f3n. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Presidente &nbsp;de Sala &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>1\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Ver expediente de tutela; PDF \u00abpara TUTELAR SECRETARIO &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;CONSTANCIA SECRETARIAL\u00bb &nbsp;<\/p>\n<p>2\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Ibidem; PDF \u00ab11001020300020230024900-0002Demanda\u00bb &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC593-2023 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp; Magistrado &nbsp;ponente &nbsp; STC593-2023 &nbsp; Radicaci\u00f3n &nbsp;n\u00ba11001-02-03-000-2023-00249-00 &nbsp; (Aprobado en &nbsp;sesi\u00f3n del primero de febrero de dos mil veintitr\u00e9s) &nbsp; Bogot\u00e1, &nbsp;D.C., primero (1\u00ba) de febrero de dos mil veintitr\u00e9s &nbsp;(2023). &nbsp; Se &nbsp;resuelve la tutela que Gerardo Alonso Herrera Hoyos instaur\u00f3 &nbsp;contra la Secretar\u00eda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-70915","post","type-post","status-publish","format-standard","hentry","category-febrero-2023"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=70915"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70915\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=70915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=70915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=70915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}