{"id":70920,"date":"2024-05-20T22:42:14","date_gmt":"2024-05-20T22:42:14","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc598-2023\/"},"modified":"2024-05-20T22:42:14","modified_gmt":"2024-05-20T22:42:14","slug":"stc598-2023","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc598-2023\/","title":{"rendered":"STC598 2023"},"content":{"rendered":"<p>STC598-2023<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>Magistrado &nbsp;ponente &nbsp;<\/p>\n<p>STC598-2023 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00ba 11001-02-03-000-2023-00251-00&nbsp; &nbsp;<\/p>\n<p>(Aprobado &nbsp;en sesi\u00f3n del primero de febrero de dos mil veintitr\u00e9s)&nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>Bogot\u00e1 &nbsp;D.C., &nbsp;primero (1\u00ba) de febrero de dos mil veintitr\u00e9s (2023). &nbsp;<\/p>\n<p>Se &nbsp;resuelve la tutela que Jos\u00e9 Rub\u00e9n Salcedo C\u00e1rdenas &nbsp;y Yolanda Salcedo de Salcedo&nbsp;instauraron contra la Sala \u00danica &nbsp;del Tribunal Superior de Florencia, extensiva al Juzgado Promiscuo &nbsp;del Circuito de Bel\u00e9n de Los Andaqu\u00edes y a las &nbsp;autoridades, partes e intervinientes en el proceso divisorio No. &nbsp;2017-00088-00. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>1. Los &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;gestores pretenden que se adicione y\/o aclare la sentencia emitida &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;por el Juzgado accionado en el proceso divisorio en comento (30 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;septiembre 2019) con el fin que se atiendan los requerimientos de la &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Oficina de Registro de Instrumentos P\u00fablicos de Florencia &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;(Caquet\u00e1). &nbsp;<\/p>\n<p>En &nbsp;sustento indicaron que promovieron el proceso divisorio mencionado. &nbsp;El asunto le correspondi\u00f3 al Juzgado &nbsp;Promiscuo del Circuito de Bel\u00e9n de Los Andaqu\u00edes &nbsp;quien profiri\u00f3 sentencia en la que aprob\u00f3 la divisi\u00f3n &nbsp;material del inmueble objeto de controversia efecto para el cual &nbsp;dispuso segregar del lote denominado \u00abLa Muralla\u00bb, una &nbsp;porci\u00f3n de terreno denominada \u00abLa Estrella\u00bb (30 &nbsp;septiembre 2019). Informaron que, al momento de realizar el registro &nbsp;respectivo de la sentencia, la oficina encargada emiti\u00f3 una &nbsp;nota devolutiva, lo que condujo a que el Juzgado aclarara la &nbsp;sentencia (9 marzo 2020); sin embargo, aunque intentaron efectuar el &nbsp;nuevo registro, el mismo fue rechazado. &nbsp;<\/p>\n<p>Ante &nbsp;dicha circunstancia, elevaron un derecho de petici\u00f3n ante la &nbsp;Superintendencia de Notariado y Registro con el fin de establecer la &nbsp;raz\u00f3n por la cual su tr\u00e1mite no se hab\u00eda &nbsp;efectuado, ante lo cual les fue informado que la sentencia divisorio &nbsp;no era clara, toda vez que no exist\u00eda certeza \u00absi &nbsp;la segregaci\u00f3n de objeto del PROCESO DIVISORIO, se har\u00e1 &nbsp;en dos predios de 21 hect\u00e1reas con 4750 metros cuadrados y &nbsp;1400 metros cuadrados respectivamente, o si por el contrario, se debe &nbsp;segregar un predio de 21 hect\u00e1reas con 6150 metros cuadrados\u00bb; &nbsp; &nbsp;adem\u00e1s, no fue establecida la destinaci\u00f3n del predio. &nbsp;<\/p>\n<p>En &nbsp;vista de lo anterior, solicitaron la adici\u00f3n y\/o aclaraci\u00f3n &nbsp;de la sentencia; no obstante, el Juzgado del Circuito neg\u00f3 la &nbsp;solicitud (17 noviembre 2022). Frente a esa decisi\u00f3n &nbsp;promovieron recurso de reposici\u00f3n y subsidiario de apelaci\u00f3n, &nbsp;el primero no prosper\u00f3 y el segundo fue concedido (6 diciembre &nbsp;2022), sin que hasta la fecha se hubiera decidido el mismo. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>2. Para &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;la fecha de elaboraci\u00f3n de la decisi\u00f3n no se hab\u00edan &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;recibido respuestas de las autoridades accionadas. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>El &nbsp;resguardo solicitado ser\u00e1 negado, toda vez que el mismo es &nbsp;prematuro, habida cuenta que se encuentra en tr\u00e1mite, ante la &nbsp;Sala \u00fanica del Tribunal Superior de Florencia, el recurso de &nbsp;apelaci\u00f3n promovido por los actores contra la decisi\u00f3n &nbsp;que neg\u00f3 la solicitud de adici\u00f3n y aclaraci\u00f3n de &nbsp;la sentencia de primera instancia proferida en el proceso divisorio &nbsp;mencionado, por lo que es necesario que se resuelva dicho medio de &nbsp;impugnaci\u00f3n antes de que se establezca si es necesaria o no la &nbsp;intervenci\u00f3n del juez constitucional. &nbsp;<\/p>\n<p>En &nbsp;este sentido, resulta pertinente evocar que en casos an\u00e1logos &nbsp;se ha destacado que: &nbsp;<\/p>\n<p>(\u2026) &nbsp;este &nbsp;medio de resguardo no fue establecido para sustituir o desplazar las &nbsp;competencias propias de las autoridades judiciales o &nbsp;administrativas, ni &nbsp;para anticipar las decisiones de determinado asunto sometido a su &nbsp;consideraci\u00f3n, pretextando la supuesta violaci\u00f3n de &nbsp;derechos fundamentales. &nbsp;Mientras &nbsp;las personas tengan a su alcance otros medios defensivos &nbsp;o &nbsp;los mismos est\u00e9n siguiendo su curso normal, &nbsp;no &nbsp;es dable acudir a este mecanismo de protecci\u00f3n, &nbsp;ya que no fue instituido para alternar con las herramientas de &nbsp;defensa judicial que el ordenamiento jur\u00eddico ha contemplado, &nbsp;sino cuando carezca de \u00e9stas &nbsp;(CSJ STC, 28 oct. 2011, rad. 00312-01, reiterada en STC8897-2017, &nbsp;STC10432-2017 y STC6904-2020, entre otras). &nbsp;<\/p>\n<p>Por &nbsp;lo anterior se negar\u00e1 la protecci\u00f3n reclamada. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, en Sala &nbsp;de Casaci\u00f3n Civil, administrando justicia en nombre de la &nbsp;Rep\u00fablica y por autoridad de la Constituci\u00f3n, &nbsp;resuelve &nbsp;NEGAR por improcedente la &nbsp;tutela instada. &nbsp;Inf\u00f3rmese &nbsp;a los participantes por el medio m\u00e1s expedito y rem\u00edtase &nbsp;el paginario a la Corte Constitucional para su eventual revisi\u00f3n, &nbsp;de no impugnarse esta resoluci\u00f3n. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Presidente &nbsp;de Sala &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC598-2023 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp; Magistrado &nbsp;ponente &nbsp; STC598-2023 &nbsp; Radicaci\u00f3n &nbsp;n\u00ba 11001-02-03-000-2023-00251-00&nbsp; &nbsp; (Aprobado &nbsp;en sesi\u00f3n del primero de febrero de dos mil veintitr\u00e9s)&nbsp; &nbsp; &nbsp; &nbsp; Bogot\u00e1 &nbsp;D.C., &nbsp;primero (1\u00ba) de febrero de dos mil veintitr\u00e9s (2023). &nbsp; Se &nbsp;resuelve la tutela que Jos\u00e9 Rub\u00e9n Salcedo C\u00e1rdenas &nbsp;y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-70920","post","type-post","status-publish","format-standard","hentry","category-febrero-2023"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=70920"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70920\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=70920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=70920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=70920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}