{"id":70983,"date":"2024-05-20T22:42:16","date_gmt":"2024-05-20T22:42:16","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc681-2023\/"},"modified":"2024-05-20T22:42:16","modified_gmt":"2024-05-20T22:42:16","slug":"stc681-2023","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc681-2023\/","title":{"rendered":"STC681 2023"},"content":{"rendered":"<p>STC681-2023<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Magistrada &nbsp;ponente &nbsp;<\/p>\n<p>STC681-2023 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00b0 25000-22-13-000-2022-00573-01 &nbsp;<\/p>\n<p>(Aprobado &nbsp;en sesi\u00f3n de primero de febrero de dos mil veintitr\u00e9s) &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D.C., primero (1\u00b0) de febrero de dos mil veintitr\u00e9s &nbsp;(2023). &nbsp;<\/p>\n<p>Decide &nbsp;la Corte la impugnaci\u00f3n de la sentencia proferida por el &nbsp;Tribunal Superior de Cundinamarca el 1\u00b0 de diciembre de 2022, &nbsp;en &nbsp;la acci\u00f3n de tutela que Garz\u00f3n Romero G. SAS formul\u00f3 &nbsp;contra el Juzgado Civil del Circuito de Funza y el municipio de &nbsp;Mosquera, por hechos relacionados con la Resoluci\u00f3n n\u00famero &nbsp;001 de 25 de febrero de 2022, proferida por la Alcald\u00eda de &nbsp;Mosquera, y el proceso radicado bajo el n\u00famero 2016-00697-00. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>1. La &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;sociedad invoc\u00f3 la protecci\u00f3n del derecho fundamental &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;al debido proceso, presuntamente vulnerado por las autoridades &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;accionadas. &nbsp;<\/p>\n<p>Manifest\u00f3, &nbsp;en s\u00edntesis, que desde hace doce a\u00f1os present\u00f3 &nbsp;una solicitud de tr\u00e1mite administrativo para aval\u00fao de &nbsp;perjuicios de servidumbre minera sobre el predio denominado \u00abLoma &nbsp;Pelada\u00bb &nbsp;con folio de matr\u00edcula inmobiliaria 50C-471940 y \u00abT\u00edtulo &nbsp;de concesi\u00f3n minera 20718 &nbsp;[\u2026] ante &nbsp;el Municipio de Mosquera\u00bb, &nbsp;que la alcald\u00eda de Mosquera resolvi\u00f3 en Resoluci\u00f3n &nbsp;n\u00famero 1\u00ba de 25 de febrero de 2022. &nbsp;<\/p>\n<p>Agreg\u00f3, &nbsp;que en cumplimiento a lo dispuesto en el inciso 2\u00ba del art\u00edculo &nbsp;285 de la Ley 685 de 2001, en el acto administrativo se dispuso que, &nbsp;una vez en firme, se remitiera el expediente al Juzgado Civil &nbsp;Municipal para su revisi\u00f3n, lo que no le fue informado. &nbsp;<\/p>\n<p>Explic\u00f3, &nbsp;que el 18 de noviembre de 2022, su apoderado se present\u00f3 en la &nbsp;Oficina Jur\u00eddica de la alcald\u00eda para preguntar por el &nbsp;tr\u00e1mite administrativo referido, y le fue informado que no &nbsp;hab\u00eda regresado del Juzgado Civil Municipal de Mosquera, y &nbsp;tampoco le suministraron fecha de radicaci\u00f3n, ni el n\u00famero &nbsp;de proceso, raz\u00f3n por la que ese mismo d\u00eda se dirigi\u00f3 &nbsp;al referido Juzgado para conocer el tr\u00e1mite judicial &nbsp;adelantado, y obtuvo como respuesta verbal que ese despacho se hab\u00eda &nbsp;declarado \u00abincompetente &nbsp;para conocer el tr\u00e1mite\u00bb, &nbsp;y lo remiti\u00f3 al Juzgado Civil del Circuito de Funza. &nbsp;<\/p>\n<p>Afirm\u00f3 &nbsp;que, en esa misma fecha, el abogado se dirigi\u00f3 al Juzgado &nbsp;Civil del Circuito mencionado y all\u00ed le indicaron que deb\u00eda &nbsp;acudir el micrositio web &nbsp;para &nbsp;averiguar las actuaciones, sin n\u00famero de proceso, y, luego de &nbsp;una extensa b\u00fasqueda, logr\u00f3 ubicar la actuaci\u00f3n &nbsp;con radicado 2016-00697-00, en la que en auto de 15 de septiembre de &nbsp;2022 se dispuso no revisar la cauci\u00f3n. &nbsp;<\/p>\n<p>Resalt\u00f3, &nbsp;que esa providencia se adopt\u00f3 \u00absin &nbsp;notificaci\u00f3n alguna de la interesada\u00bb &nbsp;(accionante) por lo que no pudo esgrimir sus argumentos para que se &nbsp;pronunciaran sobre la revisi\u00f3n de todo el actuar desplegado &nbsp;por el municipio en el tr\u00e1mite administrativo de aval\u00fao &nbsp;de perjuicios de servidumbre minera. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>2. Con &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;fundamento en lo narrado, solicit\u00f3 la revisi\u00f3n del &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;\u00abactuar &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;del municipio de Mosquera, toda vez que un tr\u00e1mite preciso en &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;35 d\u00edas, se extendi\u00f3 por 12 a\u00f1os y se &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;transgredi\u00f3 el ordenamiento civil en cuanto al procedimiento &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;del aval\u00fao\u00bb, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;y, \u00absolo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;con la solicitud de revisi\u00f3n del Municipio de Mosquera, se &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;debi\u00f3 avocar conocimiento para la revisi\u00f3n de la &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;actuaci\u00f3n, notificar a las partes, e interesados, en el &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;tr\u00e1mite administrativo para que expres[aran] &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;sus argumentos de conformidad o no del tr\u00e1mite y la decisi\u00f3n &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;administrativa, para posteriormente resolver en derecho.\u00bb. &nbsp;<\/p>\n<p>RESPUESTAS &nbsp;DE LOS ACCIONADOS Y VINCULADOS &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>1. La &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Secretaria Jur\u00eddica del municipio de Mosquera se\u00f1al\u00f3, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;que la sociedad Garz\u00f3n Romero G. S en C, hoy SAS, present\u00f3 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;solicitud en la que requiri\u00f3 se fijar\u00e1 cauci\u00f3n &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;y se impusiera servidumbre en su favor como titular del contrato de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;concesi\u00f3n minera 20178 de 17 de julio de 2007, sobre el &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;predio denominado Loma Pelada, ubicado en el municipio de Mosquera &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;con folio de matr\u00edcula inmobiliaria 50C- 471940, y adelantado &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;el tr\u00e1mite, se expidi\u00f3 la Resoluci\u00f3n 001 de 25 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;de febrero de 2022. &nbsp;<\/p>\n<p>Adicion\u00f3, &nbsp;que en el art\u00edculo 7\u00b0 de dicha resoluci\u00f3n, se &nbsp;orden\u00f3 la remisi\u00f3n del expediente al juzgado civil &nbsp;municipal, acto administrativo que fue notificado al apoderado de la &nbsp;sociedad actora, quien no interpuso recurso de apelaci\u00f3n ante &nbsp;el Gobernador, acorde con lo dispuesto en el art\u00edculo 285 de &nbsp;la Ley 685 de 2001, sino que &nbsp;solicit\u00f3 la revocatoria directa, &nbsp;la que fue resuelta con la Resoluci\u00f3n 002 de 23 de mayo de &nbsp;2022 en forma negativa, que igualmente fue notificada a los &nbsp;apoderados de Garz\u00f3n Romero G. SAS e Inversiones Mondo\u00f1edo &nbsp;SAS. &nbsp;<\/p>\n<p>Indic\u00f3 &nbsp;que con oficio 1001-49, remiti\u00f3 el proceso al Juzgado Civil &nbsp;Municipal de Mosquera para la respectiva revisi\u00f3n, situaci\u00f3n &nbsp;conocida por los apoderados de las partes, y, se\u00f1al\u00f3 &nbsp;que como ese oficio no pod\u00eda ser considerado un acto &nbsp;administrativo, no era imperativo su comunicaci\u00f3n o &nbsp;notificaci\u00f3n. &nbsp;<\/p>\n<p>Agreg\u00f3, &nbsp;que el art\u00edculo 285 de la Ley 685 de 2001, establece que la &nbsp;cauci\u00f3n \u00abpodr\u00e1 &nbsp;ser revisada\u00bb, &nbsp;lo que es facultativo del Juez. &nbsp;<\/p>\n<p>Afirm\u00f3 &nbsp;que el abogado de la sociedad actora se hizo presente en la &nbsp;secretar\u00eda jur\u00eddica de la alcald\u00eda, donde se le &nbsp;inform\u00f3 que la abogada que ten\u00eda archivado el oficio no &nbsp;se encontraba, pero se le remiti\u00f3 por correo electr\u00f3nico &nbsp;el 25 de noviembre de 2022, desconociendo los tr\u00e1mites &nbsp;adelantados ante los juzgados. &nbsp;<\/p>\n<p>Asimismo, &nbsp;se\u00f1al\u00f3 que con el \u00abescrito &nbsp;de tutela el doctor Miguel \u00c1ngel Salamanca Rodr\u00edguez, &nbsp;cuesti\u00f3n[\u00f3] &nbsp;la decisi\u00f3n adoptada mediante el Auto de fecha 15 de &nbsp;septiembre de 2022, por el Juez Civil del Circuito de Funza &nbsp;Cundinamarca, y no la decisi\u00f3n adoptada por la Alcald\u00eda &nbsp;de Mosquera a trav\u00e9s de la Resoluci\u00f3n No. 001 del 25 de &nbsp;febrero de 2022 [\u2026] &nbsp;Sin embargo, llam\u00f3 la atenci\u00f3n [en &nbsp;cuanto a] &nbsp;que el Doctor Salamanca Rodr\u00edguez, pretende que el se\u00f1or &nbsp;Magistrado, orden\u00e9 al Juez Civil del Circuito de Funza, dejar &nbsp;sin efecto la decisi\u00f3n adoptada el d\u00eda 15 de septiembre &nbsp;de 2022, y como consecuencia de ello, se ordene la revisi\u00f3n &nbsp;del proceso adelantado por la Alcald\u00eda de Mosquera, a pesar de &nbsp;que como se indic\u00f3 en el p\u00e1rrafo precedente, cuando &nbsp;cont\u00f3 con la oportunidad de controvertir la decisi\u00f3n &nbsp;adoptada por la Administraci\u00f3n Municipal, decidi\u00f3 no &nbsp;interponer recurso de apelaci\u00f3n, estando de esa manera de &nbsp;acuerdo con la decidido en la Resoluci\u00f3n No. 001 del 25 de &nbsp;febrero de 2022\u00bb. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>2. El &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Juzgado Civil Municipal de Mosquera, indic\u00f3 que el proceso &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2016-0779 fue radicado en ese juzgado por la alcald\u00eda de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Mosquera y, con auto de 14 de julio de 2022 lo remiti\u00f3 por &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;competencia por raz\u00f3n de la cuant\u00eda al Juzgado Civil &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;del Circuito de Funza, con oficio de 28 de julio siguiente. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>3. Inversiones &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Mondo\u00f1edo SAS se pronunci\u00f3 frente a los hechos, y &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;destac\u00f3 que la resoluci\u00f3n 001 de 2022 que impuso &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;cauci\u00f3n e indemnizaci\u00f3n a la Sociedad Garz\u00f3n &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Romero G. SAS, por el ejercicio de servidumbre minera en predio de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;propiedad de Inversiones Mondo\u00f1edo SAS, fij\u00f3 el valor &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;de la misma y se\u00f1al\u00f3 los recursos que proced\u00edan &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;en su contra y, en cumplimiento de lo dispuesto en el art\u00edculo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;285 de la Ley 685 de 2001, orden\u00f3 la remisi\u00f3n del &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;expediente para su revisi\u00f3n. &nbsp;<\/p>\n<p>Se\u00f1al\u00f3 &nbsp;la firmeza del acto administrativo acorde con la Ley 1437 de 2011, &nbsp;porque la sociedad actora notificada del mismo, en lugar de presentar &nbsp;recursos, solicit\u00f3 la revocatoria directa de la resoluci\u00f3n, &nbsp;lo que prueba que, &nbsp;<\/p>\n<p>\u00abi.) &nbsp;conoc\u00eda la Resoluci\u00f3n 001 de 2022 y su contenido, pues &nbsp;como se indic\u00f3 anteriormente fue notificado y de no serlo, que &nbsp;no es as\u00ed, estar\u00eda igualmente notificado por conducta &nbsp;concluyente, decidiendo de manera voluntaria no presentar recurso &nbsp;sino revocatoria directa, &nbsp;<\/p>\n<p>ii.) &nbsp;Dicha solicitud de revocatoria directa fue resuelta de forma negativa &nbsp;a Garz\u00f3n Romero G SAS mediante Resoluci\u00f3n 002 del 23 de &nbsp;mayo de 2022 la que en su art\u00edculo Primero [neg\u00f3] la &nbsp;solicitud de revocatoria de la Resoluci\u00f3n 001 de 2022 y, &nbsp;<\/p>\n<p>iii.) &nbsp;Acorde a la ley 1437 de 2011, la revocatoria directa no hace parte &nbsp;del tr\u00e1mite administrativo dado en el proceso que culmina con &nbsp;la Resoluci\u00f3n 001 de 2022 y adicional el art\u00edculo 96 &nbsp;ib\u00eddem se\u00f1ala los efectos de la dicha figura al indicar &nbsp;que ni la petici\u00f3n de revocatoria, ni la decisi\u00f3n de la &nbsp;misma revivir\u00e1n los t\u00e9rminos legales ni para demandar &nbsp;ni para silencio administrativo\u00bb. &nbsp;<\/p>\n<p>Indic\u00f3 &nbsp;que \u00aben &nbsp;ejercicio del deber de revisi\u00f3n, cuidado y seguimiento\u00bb &nbsp;Inversiones Mondo\u00f1edo SAS luego de notificarse de la &nbsp;Resoluci\u00f3n 001 de 2022, se enter\u00f3, que la alcald\u00eda &nbsp;de Mosquera remiti\u00f3 al Juez Circuito el tr\u00e1mite &nbsp;mediante oficio No. 11001-49 de 2022, el cual \u00absolicitado &nbsp;a esta autoridad fue entregado de manera inmediata a la empresa que &nbsp;represento\u00bb, &nbsp;cuidado que no despleg\u00f3 la sociedad accionante. &nbsp;<\/p>\n<p>Agreg\u00f3, &nbsp;que la decisi\u00f3n del Juzgado Civil de abstenerse de revisar la &nbsp;Resoluci\u00f3n 001 de 2022 citando como fundamento la \u00abfacultad &nbsp;discrecional y no imperativa\u00bb, &nbsp;se\u00f1alada en la Ley 685 de 2001 tan solo fue un lapsus &nbsp;calami &nbsp;porque &nbsp;\u00e9sta no sufri\u00f3 modificaci\u00f3n alguna por la Ley &nbsp;1382 de 2010 en tanto que, su contenido frente a la revisi\u00f3n &nbsp;no \u00abvari\u00f3, &nbsp;no se modific\u00f3 o elimin\u00f3, siendo igual tanto en la ley &nbsp;1382 de 2010, como en la ley 685 de 2001, luego el lapsus calami que &nbsp;pudo presentarse en el auto del juzgado al citar la norma, en nada &nbsp;afect[\u00f3] &nbsp;el debido proceso ni la legalidad del mismo\u00bb. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>4. La &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Agencia Nacional Minera, expuso que, de las circunstancias expuestas &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;en el escrito de tutela, esa agencia no ten\u00eda capacidad &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;f\u00edsica ni jur\u00eddica para dar soluci\u00f3n a las &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;peticiones elevadas y solicit\u00f3 su desvinculaci\u00f3n del &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;tr\u00e1mite por falta de legitimaci\u00f3n en la causa por &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;pasiva. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>5. La &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Procuradora 31 Judicial II Ambiental y Agraria de Bogot\u00e1, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;refiri\u00f3 que, efectivamente, el Juzgado Civil del Circuito de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Funza motiv\u00f3 el auto proferido en una norma sustra\u00edda &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;del ordenamiento jur\u00eddico por declaratoria de exequibilidad &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;mediante sentencia C-366 de 2011, y modulado su efecto por el &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;t\u00e9rmino de dos a\u00f1os. &nbsp;<\/p>\n<p>Destac\u00f3, &nbsp;que la Ley 685 de 2001, regula lo atinente a la revisi\u00f3n &nbsp;minera y en el art\u00edculo 263 \u00abdispone &nbsp;que en general el procedimiento gubernativo ser\u00e1 oficio salvo &nbsp;en lo que corresponde a los recursos y oposiciones de terceros\u00bb, &nbsp;y, la Ley 1955 de 2018, en su art\u00edculo 27 dispuso que el &nbsp;procedimiento para la imposici\u00f3n de las servidumbres mineras &nbsp;ser\u00e1 conforme a la Ley 1274 de 2009, estableciendo el &nbsp;procedimiento de las servidumbres petroleras, norma que fij\u00f3 &nbsp;un procedimiento de \u00abnegociaci\u00f3n &nbsp;directa que al fracasar convoca por parte del interesado un proceso &nbsp;judicial ante el Juez Civil Municipal de la jurisdicci\u00f3n donde &nbsp;se encuentra ubicado el inmueble, sin atenci\u00f3n a su cuant\u00eda, &nbsp;cuyo aval\u00fao final puede ser revisado por el juez civil del &nbsp;circuito a solicitud de parte dentro del mes siguiente a la fecha de &nbsp;la decisi\u00f3n\u00bb. &nbsp;<\/p>\n<p>Adicion\u00f3, &nbsp;que la remisi\u00f3n del art\u00edculo 287 de la Ley 685 de 2001 &nbsp;al C\u00f3digo de Procedimiento Civil, refer\u00eda a una norma &nbsp;expresa que advert\u00eda que se tramitar\u00eda por proceso &nbsp;abreviado de los enlistados en el numeral 1\u00ba del art\u00edculo &nbsp;408 del referido Estatuto Procedimental relacionados con &nbsp;servidumbres, por lo que, derogada esa codificaci\u00f3n en 2016 &nbsp;\u00absin &nbsp;que se hubiese iniciado actuaci\u00f3n judicial dentro del asunto &nbsp;la referencia corresponder\u00eda al C\u00f3digo General del &nbsp;Proceso\u00bb &nbsp; y, frente a las servidumbres establece en su art\u00edculo 26, que &nbsp;la cuant\u00eda se determina por el aval\u00fao catastral del &nbsp;predio sirviente. &nbsp;<\/p>\n<p>Finaliz\u00f3 &nbsp;diciendo que de los hechos de la tutela se \u00abinfiere &nbsp;una interpretaci\u00f3n que otorga a la eventual revisi\u00f3n &nbsp;por parte del Juez Municipal un car\u00e1cter oficioso, pues no se &nbsp;encuentra solicitud o manifestaci\u00f3n por parte del accionante &nbsp;en el sentido de solicitar la revisi\u00f3n de la decisi\u00f3n &nbsp;en instancia judicial\u00bb, &nbsp;la cual \u00aba &nbsp;juicio de esta procuradora es caprichosa, pues ella no puede &nbsp;inferirse de forma alguna de las disposiciones legales vigentes en la &nbsp;materia\u00bb, &nbsp;no obstante y pese al yerro del Juzgado del Circuito al citar para su &nbsp;motivaci\u00f3n una norma que no se encuentra en el ordenamiento &nbsp;jur\u00eddico \u00ablo &nbsp;cierto es que la norma aplicable al asunto no modifica de forma &nbsp;alguna el hecho de que [la &nbsp;accionante] &nbsp;no reclam[\u00f3] &nbsp;la revisi\u00f3n de la decisi\u00f3n jurisdiccional de la &nbsp;autoridad administrativa, y no existe norma alguna que permita &nbsp;inferir una (sic) &nbsp;deber &nbsp;vinculante que haga la revisi\u00f3n oficiosa\u00bb. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>6. El &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Juez Civil del Circuito de Funza, expuso que en el proceso &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2016-00697-00 recibido el 14 de septiembre de 2022 proveniente del &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Juzgado Civil Municipal de Mosquera, en providencia de 15 de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;septiembre de 2022 \u00abse &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;desat[\u00f3] &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;la llegada del proceso de marras, ordenando su remisi\u00f3n a la &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Alcald\u00eda Municipal de Mosquera (Cundinamarca) para efectos de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;la continuaci\u00f3n de dicho tr\u00e1mite en esa dependencia\u00bb, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;acorde con lo normado en el art\u00edculo 285 de la Ley 685 de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2001, providencia que no fue objeto de reproche por los interesados, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;incluida la parte actora, pese a que se notific\u00f3 en debida &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;forma por estado 43 de 16 de septiembre de 2022. &nbsp;<\/p>\n<p>LA &nbsp;SENTENCIA IMPUGNADA &nbsp;<\/p>\n<p>El &nbsp;Tribunal Superior de Cundinamarca, declar\u00f3 improcedente el &nbsp;amparo por ausencia del requisito de la subsidiariedad, en la medida &nbsp;en que la sociedad accionante tuvo la oportunidad de presentar &nbsp;recursos contra el auto de 15 de septiembre de 2022, pero no lo hizo. &nbsp;<\/p>\n<p>En &nbsp;ese sentido sostuvo, que la sociedad interesada ten\u00eda la &nbsp;obligaci\u00f3n de \u00abrealizar &nbsp;el seguimiento del tr\u00e1mite siguiente a la ejecutoria de la &nbsp;resoluci\u00f3n No. 001 de 25 de febrero de 2022 dictada por la &nbsp;alcald\u00eda municipal de Mosquera, particularmente, frente al &nbsp;cumplimiento de su numeral s\u00e9ptimo, sin embargo, ese no fue su &nbsp;proceder, en tanto que no elev\u00f3 manifestaci\u00f3n alguna &nbsp;ante el Juzgado Civil Municipal de Mosquera, como tampoco, frente al &nbsp;Juzgado Civil del Circuito de Funza en aras de obtener respuesta ante &nbsp;las inconformidades que pudiera tener respecto a lo resuelto, &nbsp;particularmente en cuanto a la cauci\u00f3n fijada . En ese mismo &nbsp;sentido, no aparece petici\u00f3n que se le haya efectuado al Juez &nbsp;donde le presente los posibles vicios o irregularidades que atribuye &nbsp;sucedieron -art. 132 y ss C.G.P.-, como tampoco, para que se aclare, &nbsp;corrija o adicione lo decidido -art 285, 286 y 287 del C.G.P.-\u00bb. &nbsp;<\/p>\n<p>La &nbsp;formul\u00f3 la sociedad accionante para insistir en sus &nbsp;pretensiones, y enfatizar en que no present\u00f3 el recurso de &nbsp;apelaci\u00f3n que proced\u00eda contra la mencionada resoluci\u00f3n, &nbsp;toda vez que no contaba con el dinero para constituir la cauci\u00f3n &nbsp;establecida en la ley. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>1. Por &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;regla general, la acci\u00f3n de tutela no procede contra &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;providencias judiciales, salvo que el funcionario respectivo hubiese &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;adoptado una decisi\u00f3n por completo desviada del sendero &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;dise\u00f1ado por el Legislador, sin ninguna objetividad y &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;edificada en sus particulares interpretaciones, a tal extremo que se &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;configure un proceder que pudiese encuadrar en una v\u00eda de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;hecho, situaci\u00f3n frente a la que se abre paso este mecanismo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;excepcional para restablecer las garant\u00edas esenciales &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;vulneradas, siempre y cuando se cumplan ciertos requisitos &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;establecidos por la jurisprudencia, entre otros, que previamente se &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;agoten todos los recursos ordinarios existentes en la ley para &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;solucionar la situaci\u00f3n concreta, debido el car\u00e1cter &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;subsidiario y residual de este amparo. (CSJ. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;STC1526-2022, STC6747-2022, STC7925-2022 y STC10431-2022, entre &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;muchas). &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>2. Ahora &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;bien, cuando de actos administrativos se trata, la jurisprudencia ha &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;se\u00f1alado que la excepcionalidad del recurso de amparo se &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;vuelve especialmente estricta, en tanto que no es el mecanismo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;id\u00f3neo para atacarlos, ya que, por su propia naturaleza, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;aquellos se encuentran amparados por la presunci\u00f3n de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;legalidad, pues se parte del presupuesto de que la administraci\u00f3n, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;al momento de manifestarse a trav\u00e9s de sus distintos canales, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;debe acatar las prerrogativas constitucionales y legales a las que &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;se encuentra subordinada. &nbsp;<\/p>\n<p>De &nbsp;all\u00ed que la legitimidad de un acto administrativo se presuma, &nbsp;obligando a demostrar a quien pretende controvertirlo, que aquel se &nbsp;apart\u00f3, sin justificaci\u00f3n alguna, del ordenamiento &nbsp;jur\u00eddico, debate que, en principio, se debe adelantar ante la &nbsp;Jurisdicci\u00f3n Contencioso Administrativa. (CSJ. &nbsp;STC11851-2022) &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>3. En &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;el asunto que ocupa la atenci\u00f3n de la Sala, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Garz\u00f3n &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Romero G. SAS acudi\u00f3 inconforme con la Resoluci\u00f3n &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;n\u00famero 1\u00ba de 25 de febrero de 2022 emanada de la &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Alcald\u00eda de Mosquera, as\u00ed como con el auto proferido &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;por el Juzgado Civil del Circuito de Funza el 15 de septiembre de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2022 en el proceso radicado bajo el n\u00famero 2016-00697-00, en &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;s\u00edntesis, porque un tr\u00e1mite que debi\u00f3 tardar &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;apenas 35 d\u00edas, se demor\u00f3 12 a\u00f1os y, seg\u00fan &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;afirm\u00f3, no se le notific\u00f3 en debida forma, por lo que &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;no le fue posible presentar recursos. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>4. Al &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;examinar las pruebas aportadas se advirti\u00f3 que, contrario a &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;lo afirmado por la sociedad accionante, el 3 de marzo de 2022 fue &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;debidamente notificada de la referida Resoluci\u00f3n, al punto &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;que present\u00f3 solicitud de revocatoria directa de la misma, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;que posteriormente le fue negada, sin embargo, no observ\u00f3, ni &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;acredit\u00f3, que hubiera presentado el recurso de apelaci\u00f3n &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;que legalmente proced\u00eda ante el respectivo Gobernador, en los &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;t\u00e9rminos del numeral 4\u00ba del art\u00edculo 285 de la &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Ley 685 de 2001. &nbsp;<\/p>\n<p>Tampoco &nbsp;se prob\u00f3 que la interesada hubiese radicado recursos o &nbsp;inconformidades contra los autos proferidos por los Juzgados Civil &nbsp;Municipal de Mosquera y Civil del Circuito de Funza. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>5. As\u00ed &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;las cosas, es clara la ausencia del requisito de la subsidiariedad &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;que ech\u00f3 de menos el Tribunal de primera instancia, pues no &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;cabe duda que la sociedad accionante pudo presentar ante las &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;autoridades competentes, los recursos procedentes contra las &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;decisiones que considerara adversas a sus intereses, sin que as\u00ed &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;se hubiera procedido. Tal omisi\u00f3n, determin\u00f3 que la &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;acci\u00f3n de tutela estuviera llamada a su fracaso desde el &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;inicio, y de ah\u00ed el resultado obtenido en primera instancia. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>6. Ahora, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;la falta de recursos econ\u00f3micos expuesta por Garz\u00f3n &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Romero G. SAS para no presentar el recurso de apelaci\u00f3n que &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;proced\u00eda contra la resoluci\u00f3n administrativa objeto de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;su inconformidad, y que solo refiri\u00f3 hasta el momento de la &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;impugnaci\u00f3n del fallo de tutela aqu\u00ed estudiado1, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;no resulta raz\u00f3n suficiente para omitir sus deberes legales. &nbsp;<\/p>\n<p>Igual &nbsp;situaci\u00f3n se observ\u00f3 en relaci\u00f3n con las &nbsp;actuaciones de los Juzgados accionados ante los cuales la sociedad &nbsp;accionante guard\u00f3 silencio, pese a su evidente inconformidad &nbsp;con las decisiones all\u00ed proferidas. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>8. Adem\u00e1s, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;en este asunto tampoco se demostr\u00f3 la existencia de un &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;perjuicio irremediable con las caracter\u00edsticas requeridas &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;para activar esta herramienta de manera excepcional, pues para &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;lograr esa finalidad, como es conocido, no basta con realizar una &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;serie de manifestaciones sin fundamento probatorio, ya que estas &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;requieren del sustento suficiente para proceder a revisar la &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;imperiosa necesidad de inmiscuirse o no, en el caso concreto. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>9. Como &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;consecuencia de lo anterior, se confirmar\u00e1 la sentencia &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;impugnada. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, en Sala &nbsp;de Casaci\u00f3n Civil, administrando justicia en nombre de la &nbsp;Rep\u00fablica de Colombia y por autoridad de la Ley, CONFIRMA &nbsp;la &nbsp;sentencia de fecha, naturaleza y procedencia conocida. &nbsp;<\/p>\n<p>Comun\u00edquese &nbsp;a los interesados por el medio m\u00e1s expedito y rem\u00edtase &nbsp;el expediente a la Corte Constitucional para su eventual revisi\u00f3n. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;y C\u00daMPLASE, &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Presidente &nbsp;de Sala &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>(ausencia &nbsp;justificada) &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>1\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;En &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;el escrito de tutela no la refiri\u00f3. &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC681-2023 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp; Magistrada &nbsp;ponente &nbsp; STC681-2023 &nbsp; Radicaci\u00f3n &nbsp;n\u00b0 25000-22-13-000-2022-00573-01 &nbsp; (Aprobado &nbsp;en sesi\u00f3n de primero de febrero de dos mil veintitr\u00e9s) &nbsp; Bogot\u00e1, &nbsp;D.C., primero (1\u00b0) de febrero de dos mil veintitr\u00e9s &nbsp;(2023). &nbsp; Decide &nbsp;la Corte la impugnaci\u00f3n de la sentencia proferida por el &nbsp;Tribunal [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-70983","post","type-post","status-publish","format-standard","hentry","category-febrero-2023"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=70983"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/70983\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=70983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=70983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=70983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}