{"id":71001,"date":"2024-05-20T22:42:16","date_gmt":"2024-05-20T22:42:16","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc699-2023\/"},"modified":"2024-05-20T22:42:16","modified_gmt":"2024-05-20T22:42:16","slug":"stc699-2023","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc699-2023\/","title":{"rendered":"STC699 2023"},"content":{"rendered":"<p>STC699-2023<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>Magistrada &nbsp;ponente &nbsp;<\/p>\n<p>STC699-2023 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00ba 68679 22 14 000 2022 00057 01 &nbsp;<\/p>\n<p>(Aprobado en Sesi\u00f3n de &nbsp;primero de febrero de dos mil veintitr\u00e9s) &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D.C., dos (2) de febrero de dos mil veintitr\u00e9s (2023). &nbsp;<\/p>\n<p>Desata &nbsp;la Corte la impugnaci\u00f3n del fallo proferido el 12 de enero de &nbsp;2023 por la Sala &nbsp;Civil Familia Laboral del Tribunal Superior del Distrito Judicial de &nbsp;San Gil, &nbsp;en la tutela que Ilmer Torres Quiroga le &nbsp;instaur\u00f3 al Juzgado Primero Promiscuo de Familia de V\u00e9lez, &nbsp;extensiva a los dem\u00e1s &nbsp;intervinientes en el consecutivo 68861 31 84 001 2003 00066. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>1.- &nbsp;El actor invoc\u00f3 la protecci\u00f3n de los derechos al &nbsp;\u00abdebido &nbsp;proceso\u00bb &nbsp;y \u00abdefensa\u00bb, &nbsp;para &nbsp;que se ordenara al estrado convocado \u00abmodificar\u00bb &nbsp;la sentencia que emiti\u00f3 el 7 de octubre de 2022. &nbsp;<\/p>\n<p>El demandado &nbsp;contest\u00f3 el libelo y propuso las excepciones previas de &nbsp;\u00abfalta de &nbsp;legitimaci\u00f3n en la causa\u00bb &nbsp;y \u00abprescripci\u00f3n &nbsp;de cuotas alimentarias atrasadas\u00bb &nbsp;y, de m\u00e9rito que denomin\u00f3 \u00abprescripci\u00f3n &nbsp;de cuotas alimentarias\u00bb, \u00abcobro de lo no debido\u00bb, &nbsp;\u00abtemeridad y mala fe\u00bb. &nbsp;<\/p>\n<p>Posteriormente, el &nbsp;juzgado resolvi\u00f3: a) &nbsp;No dar tr\u00e1mite a las \u00abexcepciones &nbsp;previas\u00bb, &nbsp;en atenci\u00f3n a que \u00abno &nbsp;fueron presentados como recurso de reposici\u00f3n dentro de los &nbsp;tres d\u00edas siguientes a la notificaci\u00f3n del mandamiento &nbsp;ejecutivo\u00bb &nbsp;y, no estaban \u00abestablecidos &nbsp;dentro de los se\u00f1alados expresamente en el art\u00edculo 100 &nbsp;del [C\u00f3digo General del Proceso] (\u2026)\u00bb; &nbsp;b) &nbsp;Negar &nbsp;la petici\u00f3n tendiente a tenerlas como \u00abde &nbsp;fondo\u00bb, &nbsp;ya que las de \u00abm\u00e9rito &nbsp;no tienen el car\u00e1cter de subsidiarias\u00bb; &nbsp;c) &nbsp;Solventar &nbsp;\u00fanicamente la \u00abexcepci\u00f3n &nbsp;de m\u00e9rito denominada prescripci\u00f3n de cuotas &nbsp;alimentarias\u00bb, &nbsp;en raz\u00f3n a que \u00abel &nbsp;t\u00edtulo ejecutivo corresponde a una providencia\u00bb &nbsp;y, de acuerdo con el numeral 2\u00b0 del art\u00edculo 442 ib\u00eddem &nbsp;es &nbsp;una de las que puede invocar, en tanto se encuentra enlistada de &nbsp;manera taxativa; d) &nbsp;Decret\u00f3 &nbsp;pruebas y, e) &nbsp;Program\u00f3 la audiencia del canon 392 \u00eddem &nbsp;para el 6 de octubre siguiente a las 9:00 a.m. (12 sep. 2022). &nbsp;<\/p>\n<p>Finalmente, el 7 &nbsp;de los mismos mes y a\u00f1o, declar\u00f3 infundada la &nbsp;\u00abprescripci\u00f3n &nbsp;de las cuotas alimentarias\u00bb &nbsp;y, mand\u00f3 seguir adelante con el cobro. &nbsp;<\/p>\n<p>Afirm\u00f3 que &nbsp;con &nbsp;la \u00faltima determinaci\u00f3n se incurri\u00f3 &nbsp;en v\u00eda de hecho, porque el &nbsp;iudex pas\u00f3 &nbsp;por alto que: &nbsp;<\/p>\n<p>i) &nbsp;Su descendiente (ya mayor de edad) carece de legitimaci\u00f3n en &nbsp;la causa, debido a que la base del juicio coactivo es un acuerdo &nbsp;conciliatorio suscrito con la madre del joven y no con \u00e9l &nbsp;mismo, quien es tan solo un \u00abbeneficiario\u00bb, &nbsp;de modo que aqu\u00e9lla es la facultada para exigir su pago. &nbsp;<\/p>\n<p>ii) &nbsp;Los &nbsp;instalamentos reclamados est\u00e1n \u00abprescritos\u00bb &nbsp;en los t\u00e9rminos de los preceptos 426 y 2536 del C\u00f3digo &nbsp;Civil, puesto que la verdadera acreedora no los cobr\u00f3, han &nbsp;transcurrido 14 a\u00f1os desde que se hicieron exigibles y, tal &nbsp;fen\u00f3meno jur\u00eddico oper\u00f3 sin que se aplicara la &nbsp;suspensi\u00f3n reglamentada en el art\u00edculo 2541 ib\u00eddem. &nbsp;<\/p>\n<p>iii) &nbsp;El &nbsp;incumplimiento de su obligaci\u00f3n obedeci\u00f3 a que se &nbsp;encontraba desempleado como consecuencia de una \u00abenfermedad &nbsp;psicol\u00f3gica esquizo-afectiva\u00bb &nbsp;que padece. &nbsp;<\/p>\n<p>2.- &nbsp;El &nbsp;Juzgado &nbsp;Primero Promiscuo de Familia de V\u00e9lez &nbsp;se &nbsp;atuvo a las reflexiones vertidas en los prove\u00eddos dictados en &nbsp;la &nbsp;lid &nbsp;controvertida. &nbsp;<\/p>\n<p>La Caja Promotora &nbsp;de Vivienda Militar y de Polic\u00eda rog\u00f3 &nbsp;su desvinculaci\u00f3n, en raz\u00f3n a que lo anhelado &nbsp;por el precursor \u00abest\u00e1 &nbsp;ligado a temas de competencia y que deben ser solucionados por el &nbsp;Juzgado Primero Promiscuo de Familia de V\u00e9lez\u00bb; &nbsp;adem\u00e1s, &nbsp;resalt\u00f3 &nbsp;que ha acatado el mandato del referido estrado, pues est\u00e1 &nbsp;\u00abaplicando &nbsp;la medida de embargo sobre el 25% de las cesant\u00edas del se\u00f1or &nbsp;Ilmer Torres Quiroga\u00bb. &nbsp;<\/p>\n<p>3.- &nbsp;La Sala &nbsp;Civil Familia Laboral del Tribunal Superior del Distrito Judicial de &nbsp;San Gil no accedi\u00f3 al &nbsp;resguardo, &nbsp;comoquiera que: 1) &nbsp;En cuanto al \u00abtr\u00e1mite &nbsp;de la excepci\u00f3n de falta de legitimaci\u00f3n\u00bb, &nbsp;\u00abel actor no &nbsp;utiliz\u00f3 los mecanismos ordinarios con que contaba\u00bb &nbsp;frente al &nbsp;auto que lo neg\u00f3 (reposici\u00f3n) y, 2) &nbsp;El veredicto corresponde a un criterio razonable, en tanto \u00abla &nbsp;teor\u00eda de la aplicaci\u00f3n de prescripci\u00f3n de las &nbsp;cuotas alimentarias frente a los menores de edad solo inicia su &nbsp;conteo a partir de que el beneficiario de alimentos cumpli\u00f3 &nbsp;los dieciocho a\u00f1os de edad, esto es, en el presente caso a &nbsp;partir del 12 de agosto de 2020, y la demanda fue presentada el 19 de &nbsp;abril de 2022, fecha en que se interrumpi\u00f3 la prescripci\u00f3n\u00bb. &nbsp;<\/p>\n<p>4.- &nbsp;El impulsor replic\u00f3, &nbsp;haciendo \u00e9nfasis en que el despacho acusado no analiz\u00f3 &nbsp;la \u00abfalta &nbsp;de legitimaci\u00f3n\u00bb &nbsp;ni, la solicitud de nulidad que formul\u00f3 con fundamento en que &nbsp;\u00abal no haber &nbsp;otorgado poder en el proceso la se\u00f1ora Yolanda Nieves Serrano, &nbsp;se encontraba en una indebida representaci\u00f3n de las partes, &nbsp;siendo esta la persona legitimada en la causa para el cobro de las &nbsp;cuotas de alimentos atrasadas (\u2026)\u00bb. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>1.- &nbsp;De entrada, se advierte el decaimiento de la \u00abtutela\u00bb &nbsp;y la refrendaci\u00f3n del fallo de primer grado, por las razones &nbsp;que a continuaci\u00f3n se exponen. &nbsp;<\/p>\n<p>1.1.- &nbsp;En &nbsp;lo atinente a la queja por no resolverse la \u00abexcepci\u00f3n &nbsp;previa\u00bb &nbsp;de &nbsp;\u00abfalta &nbsp;de legitimaci\u00f3n en la causa\u00bb, &nbsp;se observa que el accionante desaprovech\u00f3 &nbsp;la herramienta con que contaba en el litigio confutado para ventilar &nbsp;el descontento que trae a este escenario especial. &nbsp;<\/p>\n<p>En efecto, &nbsp;auscultada la encuadernaci\u00f3n n\u00b0 2003-00066, se evidencia &nbsp;que &nbsp;el 12 de septiembre de 2022, el Juzgado Primero Promiscuo de Familia &nbsp;de V\u00e9lez, &nbsp;refiri\u00f3, entre otros aspectos: &nbsp;<\/p>\n<p>(\u2026) ser\u00eda &nbsp;del caso dar tr\u00e1mite a las excepciones previas sino fuera &nbsp;porque no cumplen con lo previsto en el numeral 3 del art\u00edculo &nbsp;442 del C.G.P., en primer lugar, porque no fueron presentados como &nbsp;recurso de reposici\u00f3n dentro de los tres d\u00edas &nbsp;siguientes a la notificaci\u00f3n del mandamiento ejecutivo. En &nbsp;segundo lugar, porque no est\u00e1n establecidas dentro de las &nbsp;se\u00f1aladas expresamente en el art\u00edculo 100 del mismo &nbsp;estatuto procesal, por tal raz\u00f3n no se dar\u00e1 tr\u00e1mite &nbsp;a las mismas. &nbsp;<\/p>\n<p>De otra parte, en cuanto a &nbsp;la petici\u00f3n \u201cDE NO SER ATENDIDA POR ATACAR EL FONDO, &nbsp;SOLICITO SER TENIDA EN CUENTA COMO EXCEPCION DE FONDO\u201d se niega &nbsp;dicha solicitud en raz\u00f3n a que las excepciones de m\u00e9rito &nbsp;no tienen el car\u00e1cter de subsidiarias. &nbsp;<\/p>\n<p>Ahora bien, en cuanto a las &nbsp;excepciones de m\u00e9rito, en este caso como el t\u00edtulo &nbsp;ejecutivo corresponde a una providencia, las mismas se encuentran de &nbsp;manera taxativa en el numeral 2 del art\u00edculo 4422 del estatuto &nbsp;procesal vigente, \u00fanicamente se decidir\u00e1 en su &nbsp;oportunidad lo referente a la excepci\u00f3n de prescripci\u00f3n &nbsp;de cuotas alimentarias (\u2026). &nbsp;<\/p>\n<p>Decisi\u00f3n &nbsp;que qued\u00f3 en firme, toda vez que no fue impugnada por el &nbsp;gestor, a pesar que contra la misma cab\u00eda recurso de &nbsp;reposici\u00f3n, de acuerdo con el art\u00edculo 318 del C\u00f3digo &nbsp;General del Proceso. &nbsp;<\/p>\n<p>As\u00ed las &nbsp;cosas, Torres Quiroga tuvo la oportunidad de manifestar &nbsp;las &nbsp;inconformidades que ahora plantea en este sendero supralegal, pero lo &nbsp;dej\u00f3 fenecer. De ah\u00ed que deba soportar las &nbsp;consecuencias adversas de su omisi\u00f3n por haber desperdiciado &nbsp;esa herramienta. &nbsp;<\/p>\n<p>Al respecto, esta &nbsp;Corporaci\u00f3n tiene dicho que &nbsp;<\/p>\n<p>(&#8230;) el &nbsp;descuido en el empleo de los medios de protecci\u00f3n que existen &nbsp;hacia el interior de las actuaciones judiciales, impide al juez de &nbsp;tutela interferir los tr\u00e1mites respectivos, pues la justicia &nbsp;constitucional no es remedio de \u00faltimo momento para rescatar &nbsp;oportunidades precluidas o t\u00e9rminos fenecidos, lo que &nbsp;significa que cuando no se utilizan los mecanismos de protecci\u00f3n &nbsp;previstos en el orden jur\u00eddico, las partes quedan vinculadas a &nbsp;las consecuencias de las decisiones que le sean adversas, en tanto el &nbsp;resultado ser\u00eda el fruto de su propia incuria (\u2026) &nbsp;STC6663-2018, &nbsp;citada en STC6916-2020 y STC070-2023. &nbsp;<\/p>\n<p>Ello, &nbsp;en virtud a que &nbsp;<\/p>\n<p>(\u2026) [e]ste mecanismo, &nbsp;por lo excepcional, am\u00e9n de su naturaleza subsidiaria, no &nbsp;deviene como un recurso alterno o suplementario y su invocaci\u00f3n &nbsp;resulta leg\u00edtima en la medida en que el afectado no cuente con &nbsp;recursos legales para evitar la vulneraci\u00f3n de la que se &nbsp;duele. Contrario a ello, esto es, si existen tales medios surge inane &nbsp;la utilizaci\u00f3n de la tutela; consecuencia similar emerge &nbsp;cuando el interesado teniendo dichos recursos los ha menospreciado o &nbsp;no ha hecho uso de ellos, dado que en tal hip\u00f3tesis culmina &nbsp;invocando su propia negligencia o incuria, lo que no es permitido y &nbsp;menos a trav\u00e9s de la acci\u00f3n constitucional que ocupa la &nbsp;atenci\u00f3n de la Sala &nbsp;(STC7966-2018, &nbsp;STC10541-2018 &nbsp;citada en STC6916-2020 y STC070-2023). &nbsp;<\/p>\n<p>1.2.- &nbsp;Frente al reproche del quejoso, porque, en su criterio, el juzgado &nbsp;censurado no debi\u00f3 tener por &nbsp;no probada \u00abla &nbsp;excepci\u00f3n de prescripci\u00f3n de las cuotas alimentarias\u00bb &nbsp;ni, disponer la continuidad del coactivo (7 oct. 2022), al &nbsp;reflexionar \u00aberradamente\u00bb: &nbsp;<\/p>\n<p>(\u2026) en &nbsp;la presente situaci\u00f3n (\u2026) es necesario determinar de &nbsp;cu\u00e1nto es el tiempo de prescripci\u00f3n de cada cuota &nbsp;alimentaria, de acuerdo al art\u00edculo 2536 del C\u00f3digo &nbsp;Civil esas obligaciones prescriben en 5 a\u00f1os. Sin embargo debe &nbsp;recordarse que el t\u00e9rmino se suspende para los menores de edad &nbsp;o sea los incapaces, esto de acuerdo al art\u00edculo 2530 del &nbsp;mismo estatuto (\u2026) tal como lo indica en inciso primero del &nbsp;art\u00edculo 2541 de esa misma norma, resalt\u00e1ndose que esta &nbsp;suspensi\u00f3n no puede durar m\u00e1s de 10 a\u00f1os en el &nbsp;caso de los menores de edad, pues se reanudar\u00eda el t\u00e9rmino &nbsp;de prescripci\u00f3n una vez el menor llegue a la mayor\u00eda de &nbsp;edad, siempre en cuando ese hecho no sea superior a 10 a\u00f1os, &nbsp;pues es el t\u00e9rmino m\u00e1ximo de la prescripci\u00f3n (\u2026) &nbsp;y una vez vencido ese t\u00e9rmino se contar\u00e1n los 5 a\u00f1os &nbsp;(\u2026) seg\u00fan el art\u00edculo 2536 del c\u00f3digo &nbsp;civil. &nbsp;<\/p>\n<p>En este &nbsp;caso la primera de las cuotas alimentarias cobradas data de enero en &nbsp;2008, quedando suspendida la prescripci\u00f3n hasta enero de 2018 &nbsp;e, iniciando el t\u00e9rmino de los 5 a\u00f1os en febrero de ese &nbsp;mismo a\u00f1o, lo que indica que la primera de las cuotas &nbsp;alimentarias vencer\u00eda aproximadamente para enero del a\u00f1o &nbsp;2023 (\u2026) se vio interrumpida por la interposici\u00f3n de la &nbsp;demanda ejecutiva el d\u00eda 19 de abril del a\u00f1o 2022, en &nbsp;ese orden de ideas no pod\u00eda entrar a fallarse a favor del &nbsp;demandado y, por tanto, se declara infundada la excepci\u00f3n &nbsp;propuesta (\u2026). &nbsp;<\/p>\n<p>Ahora &nbsp;bien, el demandado manifest\u00f3 que no debe las cuotas cobradas &nbsp;en la demanda, argumentando en principio, que existi\u00f3 un &nbsp;acuerdo entre \u00e9l y la progenitora ejecutable en agosto del a\u00f1o &nbsp;2009 cuando este era un menor de edad; no obstante, esa afirmaci\u00f3n &nbsp;no se corrobor\u00f3 por la prueba documental respectiva (\u2026) &nbsp;una vez practicada la prueba oficiosa, es decir, al tener &nbsp;comunicaci\u00f3n con la Comisaria de Familia del municipio de &nbsp;V\u00e9lez el d\u00eda de ayer, \u00e9sta funcionaria se\u00f1al\u00f3 &nbsp;que en el archivo de la entidad no reposa el documento mencionado por &nbsp;el ejecutado, es decir, la supuesta acta de conciliaci\u00f3n de &nbsp;reducci\u00f3n de alimentos. &nbsp;<\/p>\n<p>A la par &nbsp;la progenitora (\u2026) Yolanda Nieves Serrano manifest\u00f3 que &nbsp;nunca ha acordado la reducci\u00f3n de la cuota conciliada en este &nbsp;Juzgado en el a\u00f1o 2003, a pesar que los testigos, Rosalba &nbsp;Quiroga y Freddy Torres Quiroga, madre y hermano de ejecutado, &nbsp;manifestaron que le colaboraba a el entonces menor Ilmer Julian con &nbsp;algunas cosas requer\u00eda como implementos para jugar futbol o en &nbsp;su cuidado, estas actuaciones son solo muestras de cari\u00f1o de &nbsp;un familiar cercano que no pueden catalogarse como un aporte del &nbsp;\u00fanico obligado a cumplir con las cuotas alimentarias, en este &nbsp;caso pues el padre Ilmer Juli\u00e1n. &nbsp;<\/p>\n<p>Es &nbsp;entendible que el ejecutado Torres Quiroga present\u00f3 una serie &nbsp;de [enfermedades] (\u2026) que afectaron su vida laboral, familiar &nbsp;y emocional, sin embargo, debi\u00f3 asegurarse que la referida &nbsp;cuota alimentaria fuera ajustada a su realidad econ\u00f3mica, &nbsp;recurriendo a las instancias administrativas y\/o legales &nbsp;correspondientes, por lo anterior la afirmaci\u00f3n del pago total &nbsp;de lo adeudado por el imputado no logr\u00f3 demostrarse. &nbsp;<\/p>\n<p>Para &nbsp;la Corte, tal razonamiento no &nbsp;fue el resultado de criterios subjetivos u ostensiblemente alejados &nbsp;del ordenamiento jur\u00eddico o de la realidad procesal, excepto &nbsp;en lo que respecta al &nbsp;examen de la \u00abprescripci\u00f3n\u00bb, &nbsp;que &nbsp;eventualmente &nbsp;podr\u00eda configurar un defecto sustantivo porque, &nbsp;el administrador de justicia opt\u00f3 por una interpretaci\u00f3n &nbsp;sistem\u00e1tica de los art\u00edculos 2530, 2536 y 2541 del &nbsp;C\u00f3digo Civil que &nbsp;no corresponde a los efectos all\u00ed establecidos por el &nbsp;legislador, si no fuera porque, dicha situaci\u00f3n &nbsp;no reviste relevancia constitucional o resulta &nbsp;intrascendente. &nbsp;<\/p>\n<p>Ello, &nbsp;en &nbsp;la medida que, de \u00abtutelarse\u00bb &nbsp;y disponerse dejar sin &nbsp;valor ni efecto el auto de 7 de octubre de 2022, para que proceda a &nbsp;resolver nuevamente la controversia en torno a la \u00abprescripci\u00f3n\u00bb; &nbsp;la resoluci\u00f3n que se expidiera llegar\u00eda a igual &nbsp;definici\u00f3n, al encontrar que &nbsp;\u00abel &nbsp;t\u00e9rmino para que por ese modo se extinga la acci\u00f3n &nbsp;ejecutiva, actualmente previsto en cinco (5) a\u00f1os, empieza a &nbsp;correr respecto de aquellas cuotas no cobradas oportunamente, desde &nbsp;que el beneficiario de alimentos cumpli\u00f3 los dieciocho a\u00f1os &nbsp;de edad (\u2026)\u00bb &nbsp;(STC13255-2018 &nbsp;reiterada en STC12208-2022) y, en el sub &nbsp;judice, Ilmer &nbsp;Juli\u00e1n Torres Nieves obtuvo la mayor\u00eda de edad el 12 &nbsp;de agosto de 2020, &nbsp;present\u00f3 la demanda el 19 &nbsp;de abril de 2022, &nbsp;siendo notificado el ejecutado el 8 &nbsp;de julio de 2022, &nbsp;de modo que, &nbsp;la &nbsp;obligaci\u00f3n no se pod\u00eda extinguir por el paso del &nbsp;tiempo, en vista que con la radicaci\u00f3n del l\u00edbelo se &nbsp;\u00abinterrumpi\u00f3\u00bb &nbsp;y hasta dicho momento no hab\u00eda vencido el aludido periodo de 5 &nbsp;a\u00f1os, en tanto ello acaecer\u00eda hasta el 12 &nbsp;de agosto de 2025, &nbsp;lo que implicar\u00e1 necesariamente volver a adoptar el mismo &nbsp;desenlace. &nbsp;<\/p>\n<p>Sobre el &nbsp;particular esta Corporaci\u00f3n ha puntualizado que, &nbsp;<\/p>\n<p>En &nbsp;relaci\u00f3n con los &nbsp;presupuestos de procedibilidad de la acci\u00f3n de tutela, &nbsp;recordemos que la &nbsp;jurisprudencia constitucional ha decantado con suficiencia los &nbsp;\u00abrequisitos generales de procedibilidad\u00bb que deben &nbsp;confluir y verificarse a la hora de establecer la procedencia de la &nbsp;intervenci\u00f3n del juez de tutela, ellos son: \u00ab(i) \u2026que &nbsp;la cuesti\u00f3n discutida resulte de evidente relevancia &nbsp;constitucional &nbsp;y que, como en cualquier acci\u00f3n de tutela, est\u00e9 &nbsp;acreditada la vulneraci\u00f3n de un derecho fundamental, requisito &nbsp;sine qua non de esta acci\u00f3n de tutela que, en estos casos, &nbsp;exige una carga especial al actor; &nbsp;(ii) que la persona afectada haya agotado todos los medios ordinarios &nbsp;y extraordinarios de defensa judicial a su alcance y haya alegado, en &nbsp;sede judicial ordinaria, y siempre que ello fuera posible, la &nbsp;cuesti\u00f3n iusfundamental que alega en sede de tutela; (iii) que &nbsp;se cumpla el requisito de la inmediatez, es decir, que la tutela se &nbsp;hubiere interpuesto en un t\u00e9rmino razonable y proporcionado a &nbsp;partir del hecho que origin\u00f3 la vulneraci\u00f3n; (iv) en el &nbsp;caso de irregularidades procesales, se requiere que \u00e9stas &nbsp;tengan un efecto decisivo en la decisi\u00f3n de fondo que se &nbsp;impugna; y (v) que no se trate de sentencias de tutela\u00bb. CC. &nbsp;Sentencias C-590\/05; SU-813\/07. &nbsp;<\/p>\n<p>Resulta &nbsp;imprescindible entonces que en el examen previo se constate la &nbsp;presencia de los se\u00f1alados presupuestos, pero forzosamente se &nbsp;requiere que el supuesto de hecho planteado desvele una situaci\u00f3n &nbsp;en la que se hallen ciertamente comprometidos derechos fundamentales, &nbsp;de no ser as\u00ed, el amparo no puede prosperar &nbsp;(STC10170-2021, reiterada en STC034-2023). &nbsp;<\/p>\n<p>1.3.- &nbsp;Ahora, &nbsp;la inconformidad del impugnante que sugiere que el Juzgado Promiscuo &nbsp;de Familia no estudi\u00f3 la \u00absolicitud &nbsp;de nulidad\u00bb &nbsp;que elev\u00f3 aduciendo la causal 4\u00aa del art\u00edculo 133 &nbsp;del C\u00f3digo General del Proceso, &nbsp;como &nbsp;no hizo parte de los supuestos f\u00e1cticos expresados en el &nbsp;escrito superlativo, constituye un hecho nuevo, respecto del cual los &nbsp;convocados no tuvieron \u00aboportunidad\u00bb &nbsp;de defenderse ni controvertir, por lo que ninguna determinaci\u00f3n &nbsp;se adoptar\u00e1 en ese sentido. &nbsp;<\/p>\n<p>2.- &nbsp;Lo &nbsp;discurrido conlleva a refrendar el pronunciamiento opugnado. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, en Sala &nbsp;de Casaci\u00f3n Civil, administrando justicia en nombre de la &nbsp;Rep\u00fablica de Colombia y por autoridad de la Constituci\u00f3n, &nbsp;CONFIRMA &nbsp;la &nbsp;sentencia de fecha, naturaleza y procedencia conocidas. &nbsp;<\/p>\n<p>Notif\u00edquese &nbsp;por el medio m\u00e1s expedito y rem\u00edtase &nbsp;el expediente a la Corte Constitucional para su eventual revisi\u00f3n. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>MARTHA PATRICIA &nbsp;GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Presidente de Sala &nbsp;<\/p>\n<p>HILDA GONZ\u00c1LEZ &nbsp;NEIRA &nbsp;<\/p>\n<p>AROLDO WILSON &nbsp;QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS ALONSO &nbsp;RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO AUGUSTO &nbsp;TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC699-2023 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp; Magistrada &nbsp;ponente &nbsp; STC699-2023 &nbsp; Radicaci\u00f3n &nbsp;n\u00ba 68679 22 14 000 2022 00057 01 &nbsp; (Aprobado en Sesi\u00f3n de &nbsp;primero de febrero de dos mil veintitr\u00e9s) &nbsp; Bogot\u00e1, &nbsp;D.C., dos (2) de febrero de dos mil veintitr\u00e9s (2023). &nbsp; Desata &nbsp;la Corte la impugnaci\u00f3n del fallo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-71001","post","type-post","status-publish","format-standard","hentry","category-febrero-2023"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/71001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=71001"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/71001\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=71001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=71001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=71001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}