{"id":75341,"date":"2024-05-20T22:41:16","date_gmt":"2024-05-20T22:41:16","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc7635-2023\/"},"modified":"2024-05-20T22:41:16","modified_gmt":"2024-05-20T22:41:16","slug":"stc7635-2023","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc7635-2023\/","title":{"rendered":"STC7635 2023"},"content":{"rendered":"<p>STC7635-2023<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Magistrada &nbsp;Ponente &nbsp;<\/p>\n<p>STC7635-2023 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00b0 11001-02-04-000-2023-01128-01 &nbsp;<\/p>\n<p>(Aprobado &nbsp;en sesi\u00f3n de dos de agosto de dos mil veintitr\u00e9s) &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D.C., dos (2) de agosto de dos mil veintitr\u00e9s &nbsp;(2023). &nbsp;<\/p>\n<p>Decide &nbsp;la Corte la impugnaci\u00f3n de la sentencia proferida por la Sala &nbsp;de Casaci\u00f3n Penal el 20 de junio de 2023, en la acci\u00f3n &nbsp;de tutela formulada por Pablo Emilio Ria\u00f1o Guzm\u00e1n &nbsp;contra la Sala de Descongesti\u00f3n n\u00ba 2 de la Sala de &nbsp;Casaci\u00f3n Laboral, la Sala Laboral del Tribunal Superior de &nbsp;Distrito Judicial de Bogot\u00e1 y el Juzgado Treinta y Nueve &nbsp;Laboral del Circuito de esta ciudad, tr\u00e1mite al que fueron &nbsp;citadas las partes e intervinientes en el proceso ordinario con &nbsp;radicado n\u00b0 2017-00763. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>1. &nbsp;El solicitante invoc\u00f3 la &nbsp;protecci\u00f3n de los derechos fundamentales al debido proceso, &nbsp;defensa y libertad de empresa, presuntamente vulnerados por las &nbsp;autoridades judiciales accionadas. &nbsp;<\/p>\n<p>Manifest\u00f3 &nbsp;que &nbsp;promovi\u00f3 juicio ordinario laboral contra el Servicio Nacional &nbsp;de Aprendizaje \u2013SENA- y la Administradora Colombiana de &nbsp;Pensiones \u2013Colpensiones-, con el fin de que se declarara que &nbsp;era beneficiario de la pensi\u00f3n convencional estipulada en el &nbsp;art\u00edculo 109 de la convenci\u00f3n colectiva de trabajo &nbsp;suscrita con Sintrasena, teniendo en cuenta que ha prestado sus &nbsp;servicios al SENA por m\u00e1s de 20 a\u00f1os y tiene m\u00e1s &nbsp;de 55 a\u00f1os de edad, de manera subsidiaria, requiri\u00f3 &nbsp;declarar que era beneficiario del r\u00e9gimen pensional &nbsp;establecido para empleados oficiales en el art\u00edculo 1\u00ba &nbsp;Ley 33 de 1985. &nbsp;<\/p>\n<p>Indic\u00f3 &nbsp;que el Juzgado Treinta y Nueve Laboral del Circuito de Bogot\u00e1 &nbsp;en sentencia de 6 de diciembre de 2019 absolvi\u00f3 a las &nbsp;demandadas de todas las pretensiones, decisi\u00f3n que la Sala &nbsp;Laboral del Tribunal Superior de esta ciudad confirm\u00f3 el 30 de &nbsp;noviembre de 2020. &nbsp;<\/p>\n<p>Inconforme &nbsp;con ese pronunciamiento, interpuso recurso extraordinario de casaci\u00f3n &nbsp;y, la Sala de Descongesti\u00f3n n\u00ba 2 de la Sala de Casaci\u00f3n &nbsp;Laboral mediante sentencia SL230-2023 de 30 de enero de 2023, dispuso &nbsp;no casar el fallo de segundo grado. &nbsp;<\/p>\n<p>2. &nbsp;Con fundamento en lo narrado, solicit\u00f3 dejar sin efectos las &nbsp;decisiones proferidas en el proceso cuestionado y, en su lugar, &nbsp;acceder a las pretensiones formuladas en la demanda ordinaria. &nbsp;<\/p>\n<p>RESPUESTA &nbsp;DE LOS ACCIONADOS Y VINCULADOS &nbsp;<\/p>\n<p>1. &nbsp;La Sala de Descongesti\u00f3n n\u00ba 2 de la Sala de Casaci\u00f3n &nbsp;Laboral remiti\u00f3 copia de la sentencia SL230-2023. &nbsp;<\/p>\n<p>2. &nbsp;La Sala Laboral del Tribunal Superior de Bogot\u00e1, expuso en &nbsp;s\u00edntesis las actuaciones adelantadas en el proceso ordinario &nbsp;iniciado por Pablo Emilio Ria\u00f1o Guzm\u00e1n, ye indic\u00f3 &nbsp;que la Sala de Casaci\u00f3n accionada remiti\u00f3 el expediente &nbsp;a esa Corporaci\u00f3n el 24 de marzo de 2023, el cual se regres\u00f3 &nbsp;al Juzgado de origen el 17 de abril del a\u00f1o en curso, despacho &nbsp;que emiti\u00f3 auto de obedecimiento y cumplimiento a los resuelto &nbsp;por el superior. &nbsp;<\/p>\n<p>3. &nbsp;El Juzgado Treinta y Nueve Laboral del Circuito de Bogot\u00e1 &nbsp;remiti\u00f3 copias de las decisiones proferidas en instancias y en &nbsp;sede extraordinaria. &nbsp;<\/p>\n<p>4. &nbsp;El &nbsp;Patrimonio Aut\u00f3nomo de Remanentes del Instituto de Seguros &nbsp;Sociales en Liquidaci\u00f3n (PARISS) indic\u00f3 que una vez &nbsp;revisados los aplicativos de consulta de la entidad, la p\u00e1gina &nbsp;web &nbsp;de &nbsp;la rama judicial, as\u00ed como el escrito de tutela, se pudo &nbsp;establecer que en el asunto estudiado no hizo parte ni se vincul\u00f3 &nbsp;al extinto ISS, como tampoco a ese Patrimonio. &nbsp;<\/p>\n<p>5. La &nbsp;directora regional (E) del SENA solicit\u00f3 negar el amparo, &nbsp;porque las autoridades accionadas actuaron dentro de los par\u00e1metros &nbsp;del debido proceso y en cumplimiento de la normatividad dentro del &nbsp;marco legal y jurisprudencial. &nbsp;<\/p>\n<p>6. &nbsp;Colpensiones solicit\u00f3 declarar la improcedencia de la acci\u00f3n &nbsp;de tutela, por cuanto no se materializ\u00f3 ning\u00fan defecto &nbsp;o vulneraci\u00f3n de las prerrogativas invocadas, y adem\u00e1s, &nbsp;existe cosa juzgada en el asunto y este mecanismo no puede &nbsp;constituirse en una tercera instancia. &nbsp;<\/p>\n<p>LA &nbsp;SENTENCIA IMPUGNADA &nbsp;<\/p>\n<p>La &nbsp;Sala de Casaci\u00f3n Penal, neg\u00f3 la solicitud de amparo al &nbsp;determinar que la decisi\u00f3n que puso fin al debate en sede &nbsp;extraordinaria resultaba razonable, habida cuenta que, la Sala de &nbsp;Descongesti\u00f3n n\u00ba 2 de la Sala de Casaci\u00f3n Laboral, &nbsp;fundament\u00f3 la improcedencia de la pensi\u00f3n convencional &nbsp;reclamada por Pablo Emilio Ria\u00f1o Guzm\u00e1n, en el hecho de &nbsp;que, si bien cumpl\u00eda con los 55 a\u00f1os de edad exigidos, &nbsp;no acredit\u00f3 el requisito de tiempo de servicio a la entidad &nbsp;mayor a 20 a\u00f1os continuos o discontinuos. &nbsp;<\/p>\n<p>LA &nbsp;IMPUGNACI\u00d3N &nbsp;<\/p>\n<p>Fue &nbsp;formulada por el accionante, insistiendo en los argumentos iniciales. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>1. &nbsp; Recuerda la Sala que en l\u00ednea de principio, la acci\u00f3n &nbsp;de tutela no procede contra las providencias o actuaciones &nbsp;judiciales, pues ello significar\u00eda un desconocimiento de los &nbsp;principios contemplados en los art\u00edculos 228 y 230 de la &nbsp;Constituci\u00f3n Pol\u00edtica; no obstante, cuando los &nbsp;funcionarios judiciales incurran en un proceder abiertamente opuesto &nbsp;al ordenamiento legal, sin ninguna objetividad y, los interesados no &nbsp;cuenten con otro medio de defensa judicial, esta jurisdicci\u00f3n &nbsp;est\u00e1 llamada a intervenir en aras de conjurar o evitar la &nbsp;vulneraci\u00f3n de las garant\u00edas fundamentales &nbsp;involucradas. &nbsp;<\/p>\n<p>2. En &nbsp;el asunto que ocupa la atenci\u00f3n de la Sala, el se\u00f1or &nbsp;Pablo Emilio Ria\u00f1o Guzm\u00e1n acude a este mecanismo &nbsp;excepcional en busca de la protecci\u00f3n de los derechos &nbsp;fundamentales, que considera vulnerados con las decisiones proferidas &nbsp;en el proceso ordinario que inici\u00f3 contra el &nbsp;Servicio Nacional de Aprendizaje \u2013SENA- y la Administradora &nbsp;Colombiana de Pensiones \u2013Colpensiones-, con el fin de obtener &nbsp;el reconocimiento de la pensi\u00f3n convencional estipulada en el &nbsp;art\u00edculo 109 de la convenci\u00f3n colectiva de trabajo &nbsp;suscrita con Sintrasena. &nbsp;<\/p>\n<p>3. &nbsp;Debe se\u00f1alarse inicialmente, que el an\u00e1lisis de la &nbsp;presente solicitud de protecci\u00f3n constitucional se &nbsp;circunscribir\u00e1 a la tesis defendida por la Sala de &nbsp;Descongesti\u00f3n n\u00ba 2 de la Sala de Casaci\u00f3n Laboral &nbsp;en la sentencia SL230-2023 &nbsp;de 30 de enero de 2023, &nbsp;por cuanto con ella se dirimi\u00f3 la controversia y, en \u00faltimas, &nbsp;ese es el criterio que se impone mientras no sea revocado o &nbsp;invalidado. &nbsp;<\/p>\n<p>4. &nbsp;Ahora bien, analizados &nbsp;los fundamentos de la inconformidad del actor, se anticipa la &nbsp;confirmaci\u00f3n de la providencia impugnada, teniendo en cuenta &nbsp;que, una vez examinados los argumentos expuestos por la Sala de &nbsp;Descongesti\u00f3n accionada, no se identific\u00f3 el ejercicio &nbsp;de una actividad judicial arbitraria susceptible de ser remediada a &nbsp;trav\u00e9s de esta v\u00eda extraordinaria, como pasa a &nbsp;exponerse. &nbsp;<\/p>\n<p>4.1 &nbsp;En efecto, la Corporaci\u00f3n accionada al estudiar el recurso &nbsp;extraordinario formulado por el &nbsp;demandante, se\u00f1al\u00f3 que el escrito con el que se &nbsp;pretend\u00eda sustentar la acusaci\u00f3n conten\u00eda graves &nbsp;deficiencias t\u00e9cnicas que compromet\u00edan la prosperidad &nbsp;de los cargos propuestos y que no era factible subsanar dado el &nbsp;car\u00e1cter dispositivo del recurso de casaci\u00f3n. &nbsp;<\/p>\n<p>Respecto &nbsp;al primer cargo, se\u00f1al\u00f3, &nbsp;<\/p>\n<p>\u00abel &nbsp;demandante no plasm\u00f3 planteamiento en concreto alguno, pues se &nbsp;limit\u00f3 a transcribir diversos apartes de sentencias de la &nbsp;Sala, refiriendo de forma gen\u00e9rica que versaban sobre la &nbsp;aplicaci\u00f3n del AL 01 de 2005 y casos similares, sin explicar &nbsp;en qu\u00e9 consist\u00eda la intelecci\u00f3n errada del &nbsp;fallador de segundo grado. &nbsp;<\/p>\n<p>De &nbsp;modo tal que no es posible extraer el yerro de legalidad a analizar, &nbsp;dislate que no puede ser subsanado oficiosamente\u00bb. &nbsp;<\/p>\n<p>En &nbsp;relaci\u00f3n con el segundo, destac\u00f3, &nbsp;<\/p>\n<p>(\u2026) &nbsp;Cuando la acusaci\u00f3n se encuentra encaminada por la v\u00eda &nbsp;indirecta, como lo estipula el censor, es necesario que se precise de &nbsp;forma detallada los errores f\u00e1cticos y evidentes cometidos por &nbsp;juzgador; determinar qu\u00e9 elementos de convicci\u00f3n no &nbsp;fueron valorados \u00ab[\u2026] &nbsp;y en cu\u00e1les de ellos se cometi\u00f3 err\u00f3nea &nbsp;estimaci\u00f3n, demostrando en qu\u00e9 consisti\u00f3 \u00e9sta &nbsp;\u00faltima, [\u2026] explicar c\u00f3mo la falta o la &nbsp;defectuosa valoraci\u00f3n probatoria, lo condujo a los desatinos &nbsp;que tienen esa calidad y determinar en forma clara lo que la prueba &nbsp;en verdad acredita\u00bb &nbsp;(CSJ SL1301-2018). &nbsp;<\/p>\n<p>Conforme &nbsp;a lo anterior y visto el embate, se observa que, si bien se &nbsp;enlistaron los errores de hecho y las pruebas a analizar, no se &nbsp;realiz\u00f3 ejercicio alguno a fin de demostrar c\u00f3mo estas &nbsp;\u00faltimas incidieron en las supuestas trasgresiones, de modo que &nbsp;no es posible estudiar la controversia suscitada. &nbsp;<\/p>\n<p>(\u2026) &nbsp;<\/p>\n<p>Aunado &nbsp;a lo dicho, el censor incurre en error al denunciar de forma &nbsp;simult\u00e1nea la apreciaci\u00f3n indebida y la falta de &nbsp;valoraci\u00f3n de una prueba, pues son actos totalmente &nbsp;contrarios, ya que no ser\u00eda posible haber estudiado &nbsp;incorrectamente un elemento de convicci\u00f3n que ni siquiera se &nbsp;tuvo en cuenta\u00bb. &nbsp;<\/p>\n<p>Igualmente, &nbsp;determin\u00f3 que la censura presentaba una argumentaci\u00f3n &nbsp;que se traduc\u00eda m\u00e1s en un alegato de instancia, que, en &nbsp;la sustentaci\u00f3n de un recurso de casaci\u00f3n, sin tener en &nbsp;cuenta que, para su estudio de fondo la acusaci\u00f3n debe ser &nbsp;completa en su formulaci\u00f3n y suficiente en su desarrollo, lo &nbsp;cual no se acat\u00f3 en el asunto examinado. &nbsp;<\/p>\n<p>Sostuvo &nbsp;que, si en gracia de discusi\u00f3n se omitieran dichas falencias y &nbsp;se abordara el estudio del caso, no habr\u00eda lugar a casar la &nbsp;decisi\u00f3n de segunda instancia, porque la misma supon\u00eda &nbsp;como elemento fundamental de su ataque, que el demandante era &nbsp;beneficiario del derecho pensional reclamado, al cumplir con la &nbsp;densidad del tiempo de servicios exigida por la norma convencional, y &nbsp;la edad era un mero requisito de exigibilidad. &nbsp;<\/p>\n<p>Con &nbsp;fundamento en lo anterior determin\u00f3 la improsperidad del &nbsp;recurso y dispuso no casar la sentencia proferida por &nbsp;la Sala Laboral &nbsp;del &nbsp;Tribunal Superior de Bogot\u00e1 el 30 &nbsp;de noviembre de 2020. &nbsp;<\/p>\n<p>5. &nbsp; Tal &nbsp;y como se anunci\u00f3, la sentencia constitucional impugnada &nbsp;habr\u00e1 &nbsp;de ser confirmada, como &nbsp;quiera que no se evidenci\u00f3 desafuero o arbitrariedad &nbsp;manifiesta que revele los defectos alegados por Pablo Emilio Ria\u00f1o &nbsp;Guzm\u00e1n y que imponga la intervenci\u00f3n de esta especial &nbsp;jurisdicci\u00f3n, teniendo en cuenta que, el &nbsp;descuido del recurrente &nbsp;en la formulaci\u00f3n adecuada de los ataques, comprometi\u00f3 &nbsp;la prosperidad &nbsp;del mecanismo extraordinario y llev\u00f3 &nbsp;a la Sala de Descongesti\u00f3n n\u00ba 2 de la Sala de Casaci\u00f3n &nbsp;Laboral a abstenerse de estudiar de fondo el asunto impidi\u00e9ndole &nbsp;pronunciarse de la manera esperada por el demandante. &nbsp;<\/p>\n<p>De &nbsp;manera que, el interesado desaprovech\u00f3 la oportunidad que la &nbsp;norma laboral concede para exponer las inconformidades que presenta a &nbsp;trav\u00e9s de este mecanismo, sin que pueda ahora valerse &nbsp;del mismo para solventar su desatenci\u00f3n, porque era el proceso &nbsp;ordinario el escenario id\u00f3neo en donde deb\u00eda hacer &nbsp;valer las garant\u00edas invocadas, &nbsp;debido al car\u00e1cter residual del amparo. &nbsp;<\/p>\n<p>En un &nbsp;asunto similar, esta Sala explic\u00f3, &nbsp;<\/p>\n<p>\u00abAdem\u00e1s, &nbsp;el &nbsp;car\u00e1cter extraordinario del recurso de casaci\u00f3n impone &nbsp;a la demandante cumplir los requisitos de fondo y de forma previstos &nbsp;por el legislador para el \u00e9xito de la censura; la ausencia de &nbsp;rigor t\u00e9cnico o de los requerimientos legales al formular el &nbsp;cargo para demostrar los errores de la sentencia recurrida, no es &nbsp;tarea que pueda ser superada por medio de la tutela, porque \u00e9sta &nbsp;no es instrumento para suplir la ineptitud formal de la demanda de &nbsp;casaci\u00f3n. &nbsp;<\/p>\n<p>Lo &nbsp;instrumental es garant\u00eda para materializar la igualdad ante la &nbsp;ley y para frenar la arbitrariedad, por &nbsp;tanto, no se trata de exceso ritual manifiesto, &nbsp;sino de derechos irrenunciables, cuyo respeto es finalidad del &nbsp;proceso para la realizaci\u00f3n del derecho sustancial &nbsp;(CSJ. STC5305-2020, STC7201-2021, STC9826-2021 y 5744-2022, entre &nbsp;muchas). &nbsp;<\/p>\n<p>6. &nbsp; As\u00ed las cosas, en el caso en estudio se estructura la causal &nbsp;de improcedencia prevista en el numeral 1\u00ba del art\u00edculo &nbsp;6\u00ba del Decreto 2591 de 1991, puesto que la acci\u00f3n &nbsp;constitucional no fue concebida como sustituto de los mecanismos &nbsp;judiciales creados por el legislador. &nbsp;<\/p>\n<p>No &nbsp;puede olvidarse que en otras oportunidades se ha se\u00f1alado que, &nbsp;si las personas que reprochan determinaciones judiciales adoptadas en &nbsp;perjuicio de sus intereses \u00abdejan &nbsp;de utilizar los dispositivos de defensa previstos por el orden &nbsp;jur\u00eddico, &nbsp;[o no hacen un uso adecuado de los mismos] &nbsp;quedan sujetas a las consecuencias de las determinaciones que le sean &nbsp;adversas, que ser\u00edan el fruto de su propia incuria\u00bb. &nbsp;(CSJ. &nbsp;STC6580-2021, STC12011-2021, STC2296-2022, STC2818-2022 STC2912-2022 &nbsp;y STC4795-2022 entre otras). &nbsp;<\/p>\n<p>7. &nbsp;Ahora, en relaci\u00f3n con lo manifestado por el actor, frente a &nbsp;las sentencias SL3329-2021, &nbsp;SL3671-2021 proferidas en casos similares al suyo en las que se ha &nbsp;otorgado la pensi\u00f3n convencional reclamada, debe indicarse que &nbsp;los cargos estudiados en las mismas, fueron planteados debidamente a &nbsp;diferencia de lo ocurrido en su caso, pues se reitera que, las &nbsp;deficiencias t\u00e9cnicas contenidas en la acusaci\u00f3n por \u00e9l &nbsp;planteada, comprometieron la prosperidad del recurso. &nbsp;<\/p>\n<p>8. &nbsp;Resta indicar que esta &nbsp;Sala en pronunciamientos recientes se ha referido al respeto por las &nbsp;decisiones judiciales, m\u00e1xime cuando se trata de organismos de &nbsp;cierre, salvo cuando aparezcan visibles las causales de &nbsp;procedibilidad del amparo. &nbsp;Postura que se ha venido acogiendo con m\u00e1s firmeza a partir de &nbsp;los precedentes STC13814-2021, STC13815-2021, STC13816-2021, &nbsp;STC2310-2022 y, &nbsp;STC3514-2022 entre otros. &nbsp;<\/p>\n<p>9. &nbsp;De conformidad con lo expuesto, la &nbsp;sentencia impugnada ser\u00e1 confirmada. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En m\u00e9rito &nbsp;de lo expuesto, la Corte Suprema de Justicia, en Sala de Casaci\u00f3n &nbsp;Civil y Agraria, administrando justicia en nombre de la Rep\u00fablica &nbsp;de Colombia y por autoridad de la Ley, CONFIRMA &nbsp;la &nbsp;sentencia de fecha, naturaleza y procedencia conocida. &nbsp;<\/p>\n<p>Comun\u00edquese &nbsp;por el medio m\u00e1s expedito y rem\u00edtase el expediente a la &nbsp;Corte Constitucional para su eventual revisi\u00f3n. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Presidente &nbsp;de Sala &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>(Ausencia &nbsp;justificada) &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC7635-2023 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp; Magistrada &nbsp;Ponente &nbsp; STC7635-2023 &nbsp; Radicaci\u00f3n &nbsp;n\u00b0 11001-02-04-000-2023-01128-01 &nbsp; (Aprobado &nbsp;en sesi\u00f3n de dos de agosto de dos mil veintitr\u00e9s) &nbsp; Bogot\u00e1, &nbsp;D.C., dos (2) de agosto de dos mil veintitr\u00e9s &nbsp;(2023). &nbsp; Decide &nbsp;la Corte la impugnaci\u00f3n de la sentencia proferida por la Sala [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[],"class_list":["post-75341","post","type-post","status-publish","format-standard","hentry","category-agosto-2023"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/75341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=75341"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/75341\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=75341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=75341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=75341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}