{"id":75379,"date":"2024-05-20T22:41:18","date_gmt":"2024-05-20T22:41:18","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc7767-2023\/"},"modified":"2024-05-20T22:41:18","modified_gmt":"2024-05-20T22:41:18","slug":"stc7767-2023","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc7767-2023\/","title":{"rendered":"STC7767 2023"},"content":{"rendered":"<p>STC7767-2023<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>Magistrada &nbsp;ponente &nbsp;<\/p>\n<p>STC7767-2023 &nbsp;<\/p>\n<p>(Aprobado &nbsp;en sesi\u00f3n de nueve de agosto de dos mil veintitr\u00e9s) &nbsp;<\/p>\n<p>Bogot\u00e1 &nbsp;D.C., nueve (9) de agosto de dos mil veintitr\u00e9s (2023). &nbsp;<\/p>\n<p>Desata &nbsp;la Corte la tutela que &nbsp;Jos\u00e9 Jorge Bracho Daza instaur\u00f3 &nbsp;contra la &nbsp;Sala Civil Familia del Tribunal Superior del Distrito Judicial de &nbsp;Bucaramanga y el Consejo Seccional de la Judicatura de Santander, &nbsp;extensiva al Tribunal Superior de San Gil y dem\u00e1s &nbsp;participantes en el Concurso de M\u00e9ritos para proveer cargos de &nbsp;carrera de Tribunales, Juzgados y Centros de Servicios de los &nbsp;Distritos Judiciales de Bucaramanga y San Gil, y Administrativo de &nbsp;Santander \u2013 Convocatoria n\u00b0 4 (Acuerdos CSJSAA17-3609, &nbsp;CSJSAA17-3610 y CSJSAA17-3611 de 2017). &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>1.- &nbsp;El libelista reclam\u00f3 la protecci\u00f3n de los derechos al &nbsp;\u00abdebido &nbsp;proceso, acceso a los cargos p\u00fablicos y la unidad familiar\u00bb, &nbsp;para &nbsp;que se ordenara a la Magistratura accionada \u00abdesignar[lo] &nbsp;en &nbsp;el cargo de secretario (\u2026) por ser el participante que tiene &nbsp;derecho a ello al ser el primero de la lista de elegibles vigente en &nbsp;la actualidad\u00bb. &nbsp;<\/p>\n<p>En &nbsp;compendio, adujo que, mediante Resoluci\u00f3n n.\u00b0 CSJAR22-298 &nbsp;del 21 de octubre de 2022, fue reclasificado en el referido \u00abconcurso &nbsp;de m\u00e9ritos\u00bb con &nbsp;\u00ab838,295 &nbsp;puntos\u00bb, &nbsp;quedando \u00abprimero &nbsp;en la lista de elegibles para &nbsp;el cargo de Secretario de Tribunal Nominado\u00bb, &nbsp;lo &nbsp;que le permiti\u00f3 optar para la vacante de \u00abSecretario &nbsp;General\u00bb que &nbsp;se present\u00f3 en el Tribunal Superior de Bucaramanga en enero &nbsp;hoga\u00f1o; sin embargo, este nombr\u00f3 a quien fung\u00eda &nbsp;en propiedad como \u00abSecretaria &nbsp;de la Sala Civil y de Familia\u00bb &nbsp;(traslado). &nbsp;<\/p>\n<p>Al &nbsp;quedar cesante la plaza de la Sala Civil Familia Laboral del Tribunal &nbsp;Superior de San Gil (feb.), as\u00ed como la de la Sala Civil &nbsp;Familia del Tribunal de Bucaramanga por la aceptaci\u00f3n de la &nbsp;renuncia de la citada funcionaria (27 abr.), se postul\u00f3 para &nbsp;ser \u00abnombrado &nbsp;en propiedad\u00bb en &nbsp;ambos &nbsp;empleos, cuyo acto s\u00f3lo de verific\u00f3 frente a la primera &nbsp;(21 jul.), ya que el Tribunal de Bucaramanga, a trav\u00e9s de la &nbsp;Resoluci\u00f3n n\u00b0 19 del 14 de julio anterior, dispuso &nbsp;\u00absuspender &nbsp;el nombramiento\u00bb &nbsp;de aqu\u00e9l \u00abcargo\u00bb, &nbsp;con fundamento en que \u00abel &nbsp;participante Edwin Rodrigo Duarte hab\u00eda informado sobre su &nbsp;reclasificaci\u00f3n se\u00f1alando que deb\u00eda ocupar el &nbsp;primer lugar de la lista\u00bb, &nbsp;decisi\u00f3n que pidi\u00f3 reponer, a la vez que solicit\u00f3 &nbsp;al Consejo Seccional de la Judicatura de Santander que aclarara la &nbsp;situaci\u00f3n. &nbsp;<\/p>\n<p>Relat\u00f3 &nbsp;que, si bien por &nbsp;medio de la \u00abResoluci\u00f3n &nbsp;No. 138 de 23 de marzo\u00bb &nbsp;se &nbsp;\u00abreclasific\u00f3\u00bb &nbsp;a &nbsp;M\u00f3nica Alejandra Cifuentes Berm\u00fadez, dicho acto &nbsp;administrativo \u00abno &nbsp;se encontraba en firme para el momento en que la vacante se gener\u00f3\u00bb, &nbsp;dado que contra el mismo \u00abpresent[\u00f3] &nbsp;recurso de reposici\u00f3n (\u2026), por errores en la &nbsp;calificaci\u00f3n de los cursos presentados por [\u00e9stos]\u00bb. &nbsp;<\/p>\n<p>Afirm\u00f3 &nbsp;que la actuaci\u00f3n de la Corporaci\u00f3n acusada le est\u00e1 &nbsp;causando un \u00abperjuicio &nbsp;irremediable\u00bb, &nbsp;en la medida que le venci\u00f3 el plazo para \u00abaceptar &nbsp;el cargo de secretario del Tribunal Superior de San Gil\u00bb, &nbsp;sumado a que se encuentra \u00abradicado &nbsp;en la ciudad de Bucaramanga desde 2014, en ella se encuentra [su] &nbsp;familia &nbsp;y [su] &nbsp;hijo de 3 a\u00f1os\u00bb, &nbsp;lugar donde tiene inter\u00e9s de ser \u00abnombrado\u00bb. &nbsp;<\/p>\n<p>2.- &nbsp;La &nbsp;Presidencia de la Sala Civil Familia del Tribunal Superior de &nbsp;Bucaramanga destac\u00f3 la improcedencia del ruego, toda vez que &nbsp;la falta de &nbsp;\u00abnombramiento en propiedad\u00bb &nbsp;denunciado por el accionante, \u00abse &nbsp;debe \u00fanica y exclusivamente a que el CONSEJO SECCIONAL DE LA &nbsp;JUDICATURA DE SANTANDER no ha emitido las respuestas requeridas\u00bb &nbsp;en los oficios &nbsp;\u00abSSCF-142 del 5 de mayo\u00bb &nbsp;y \u00abPSCF-008 &nbsp;del 12 de julio de 2023\u00bb, &nbsp;atinentes a la correcci\u00f3n de \u00abla &nbsp;denominaci\u00f3n de la Corporaci\u00f3n o Despacho donde se &nbsp;encuentra la vacante ofertada el 2 de mayo de 2023 en tanto que fue &nbsp;publicado el correspondiente a SECRETARIA SALA CIVIL &#8211; FAMILIA &#8211; &nbsp;LABORAL TRIBUNAL SUPERIOR DEL DISTRITO JUDICIAL, la cual es diferente &nbsp;a la nuestra correspondiente a la SECRETARIA SALA CIVIL &#8211; FAMILIA &#8211; &nbsp;TRIBUNAL SUPERIOR DEL DISTRITO JUDICIAL\u00bb &nbsp;y, &nbsp;\u00abla firmeza de la Resoluci\u00f3n No. CSJSAR23-138 23 de &nbsp;marzo de 2023\u00bb, &nbsp;necesarias para solventar el \u00abrecurso &nbsp;de reposici\u00f3n\u00bb &nbsp;que aqu\u00e9l interpuso contra la \u00abRESOLUCI\u00d3N &nbsp;19 del 14 de julio de 2023\u00bb, &nbsp;por medio de la cual se aprob\u00f3 \u00abla &nbsp;suspensi\u00f3n de t\u00e9rminos del nombramiento del cargo\u00bb. &nbsp;<\/p>\n<p>Posteriormente, &nbsp;inform\u00f3 que \u00abcon &nbsp;fundamento en la respuesta allegada a trav\u00e9s de oficio &nbsp;CSJSAO23-1211 de 2 de agosto de 2023 por el Consejo Seccional de la &nbsp;Judicatura de Santander, procedi\u00f3 a nombrar en propiedad en el &nbsp;cargo de secretario nominado de la Sala Civil Familia del Tribunal &nbsp;Superior del Distrito Judicial de Bucaramanga al promotor de la &nbsp;presente acci\u00f3n- Jos\u00e9 Jorge Bracho Daza, identificado &nbsp;con c\u00e9dula de ciudadan\u00eda n\u00b0 77.092.234, a quien le &nbsp;fue notificada la decisi\u00f3n a trasv\u00e9s del correo &nbsp;electr\u00f3nico jbrachod@cendoj.ramajudicial.gov.co.\u00bb. &nbsp;<\/p>\n<p>El &nbsp;Consejo Seccional de la Judicatura de Santander se opuso al auxilio, &nbsp;tras se\u00f1alar que \u00abpara &nbsp;la vacante del cargo de Secretario de Tribunal Grado Nominado de la &nbsp;Sala Civil-Familia del Tribunal Superior del Distrito Judicial de &nbsp;Bucaramanga, se precisa que dicho cargo qued\u00f3 en vacancia &nbsp;definitiva el d\u00eda 27 de abril de 2023, en la medida que la &nbsp;Dra. ELIANA &nbsp;MARIA GUERRERO BARRERO, &nbsp;tom\u00f3 posesi\u00f3n en atenci\u00f3n a un traslado por &nbsp;motivos de carrera a la Secretar\u00eda General del Tribunal &nbsp;Superior del Distrito Judicial de Bucaramanga, as\u00ed las cosas &nbsp;el cargo fue publicado en opciones de sede los cinco (5) primeros &nbsp;d\u00edas del mes de mayo de 2023, tiempo en el cual los &nbsp;concursantes podr\u00edan optar por sede, as\u00ed mismo se debe &nbsp;recordar que, para la \u00e9poca la Resoluci\u00f3n CSJSAR23-138 &nbsp;del 23 de marzo de 2023, aun no se encontraba en firme\u00bb. &nbsp;<\/p>\n<p>Agreg\u00f3, &nbsp;que \u00ab[p]ara &nbsp;la opci\u00f3n de sede de la referencia, se presentaron siete (7) &nbsp;concursantes, los cuales fueron enlistados por esta Corporaci\u00f3n, &nbsp;de conformidad con su puntaje final del Registro Seccional de &nbsp;Elegibles, vigente al momento de producirse la vacante\u00bb, &nbsp;encabezando la misma el precursor, \u00aben &nbsp;cumplimiento del Acuerdo PSAA08-4856 del 10 de junio de 2008, &nbsp;proferido por el H. Consejo Superior de la Judicatura\u00bb, &nbsp;de ah\u00ed que \u00abexpidi\u00f3 &nbsp;la lista de elegibles y esta se conform\u00f3 y se materializ\u00f3 &nbsp;mediante Acuerdo No. CSJSAA23-210 del 22 de junio de 2023, en &nbsp;atenci\u00f3n a la reglamentaci\u00f3n de la convocatoria, &nbsp;cumpliendo lo dispuesto por los Acuerdos de convocatoria y dem\u00e1s &nbsp;reglamentaci\u00f3n concordante al ser obligatoria y reguladora del &nbsp;proceso de selecci\u00f3n\u00bb. &nbsp;<\/p>\n<p>Edwin &nbsp;Buitrago Duarte mostr\u00f3 inconformidad con la salvaguarda, por &nbsp;cuanto \u00abel &nbsp;accionante procedi\u00f3 a presentar recursos frente a un acto &nbsp;administrativo en el que nada se decidi\u00f3 frente a \u00e9l y &nbsp;su \u00fanico inter\u00e9s en reponer la resoluci\u00f3n de &nbsp;reclasificaci\u00f3n era la de tratar de evitar que este acto &nbsp;administrativo adquiriera firmeza para poder \u00e9l de manera &nbsp;fraudulenta seguirse manteniendo en un primer lugar que a todas luces &nbsp;no le correspond\u00eda\u00bb. &nbsp;<\/p>\n<p>M\u00f3nica &nbsp;Alejandra Cifuentes Berm\u00fadez requiri\u00f3 que se \u00abdefina &nbsp;de fondo (\u2026) la acci\u00f3n tutelar de la referencia [y] &nbsp;se &nbsp;[l]e &nbsp;comparta la decisi\u00f3n toda vez que las resultas de la misma &nbsp;tambi\u00e9n involucran [sus] &nbsp;derechos fundamentales\u00bb. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>1.- &nbsp;Confrontado &nbsp;el escrito genitor con la evidencia acopiada en el plenario, muy &nbsp;pronto se anuncia el decaimiento del resguardo, por carecer de objeto &nbsp;ante la superaci\u00f3n del hecho que lo gener\u00f3. &nbsp;<\/p>\n<p>Mem\u00f3rese &nbsp;que, el impulsor acudi\u00f3 a esta senda excepcional, en &nbsp;estrictez, porque Sala &nbsp;Civil Familia del Tribunal Superior de Bucaramanga, a trav\u00e9s &nbsp;de la \u00abResoluci\u00f3n &nbsp;N\u00b0 19 del 14 de julio de 2023\u00bb, &nbsp;decidi\u00f3 \u00absuspender\u00bb &nbsp;el procedimiento de \u00abnombramiento &nbsp;en propiedad\u00bb &nbsp;del \u00abcargo\u00bb &nbsp;de \u00abSecretario &nbsp;Nominado\u00bb &nbsp;ofertado en el &nbsp;Concurso de M\u00e9ritos \u00abpara &nbsp;proveer empleos de carrera de Tribunales, Juzgados y Centros de &nbsp;Servicios de los Distritos Judiciales de Bucaramanga y San Gil, y &nbsp;Administrativo de Santander\u00bb &nbsp;(Convocatoria &nbsp;n\u00b0 4), actuaci\u00f3n que, en su sentir, conculca los atributos &nbsp;b\u00e1sicos invocados, comoquiera que ocupa el \u00abprimer &nbsp;lugar\u00bb &nbsp;de &nbsp;la \u00ablista &nbsp;de elegibles vigente\u00bb &nbsp;a la fecha en que este qued\u00f3 \u00abvacante\u00bb, &nbsp;motivo por el cual debe ser \u00abnombrado\u00bb &nbsp;sin m\u00e1s dilaciones. &nbsp;<\/p>\n<p>No &nbsp;obstante, la aludida situaci\u00f3n ya est\u00e1 superada y, &nbsp;en esa medida, \u00abcarecer\u00eda &nbsp;de objeto\u00bb &nbsp;y &nbsp;raz\u00f3n expedir alg\u00fan \u00abmandato\u00bb &nbsp;en &nbsp;tal sentido, puesto que el fin que se persegu\u00eda ya se &nbsp;cristaliz\u00f3. &nbsp;<\/p>\n<p>En &nbsp;efecto, de los &nbsp;elementos de convicci\u00f3n obrantes en el infolio &nbsp;se vislumbra que, por medio de la \u00abResoluci\u00f3n &nbsp;No. 21 del 3 de agosto de 2023\u00bb, &nbsp;notificada en la misma data al Jos\u00e9 Jorge, esto es, antes del &nbsp;fallo de primera instancia, el Cuerpo Colegiado criticado resolvi\u00f3, &nbsp;entre otros: \u00abLevantar &nbsp;la suspensi\u00f3n &nbsp;de t\u00e9rminos decretada\u00bb &nbsp;y, &nbsp;en consecuencia, \u00abNombrar &nbsp;al se\u00f1or JOS\u00c9 &nbsp;JORGE BRACHO DAZA, &nbsp;(\u2026) en el cargo de secretario grado nominado de la Sala Civil &nbsp;Familia Tribunal Superior del Distrito Judicial de Bucaramanga, en &nbsp;propiedad\u00bb. &nbsp;<\/p>\n<p>As\u00ed &nbsp;las cosas, como la gesti\u00f3n &nbsp;que interesaba al tutelante est\u00e1 &nbsp;solventada, es indudable que aflora &nbsp;la \u00abausencia &nbsp;actual de objeto\u00bb &nbsp;y, &nbsp;por tanto, se itera, no hay raz\u00f3n alguna para que el \u00abjuez &nbsp;de tutela\u00bb &nbsp;imparta &nbsp;\u00ab\u00f3rdenes\u00bb &nbsp;de &nbsp;inmediato cumplimiento en relaci\u00f3n con un suceso que en el &nbsp;pasado hubiera podido ser pasible de subvenci\u00f3n, pero que, &nbsp;ahora dej\u00f3 de existir. &nbsp;<\/p>\n<p>Sobre &nbsp;ese tema, la Corte Constitucional ha esgrimido: &nbsp;<\/p>\n<p>(\u2026) &nbsp;[La] &nbsp;jurisprudencia, ha indicado que la &nbsp;carencia &nbsp;actual de objeto &nbsp;se configura cuando frente a las pretensiones esbozadas en la acci\u00f3n &nbsp;de tutela, cualquier orden emitida por el juez no tendr\u00eda &nbsp;alg\u00fan efecto o simplemente \u201ccaer\u00eda en el vac\u00edo\u201d. &nbsp;Espec\u00edficamente, esta figura se materializa a trav\u00e9s en &nbsp;las siguientes circunstancias: (\u2026). &nbsp;<\/p>\n<p>Hecho &nbsp;superado. &nbsp;Este escenario se presenta cuando entre &nbsp;el momento de interposici\u00f3n de la acci\u00f3n de tutela y el &nbsp;fallo, se evidencia que [,] como consecuencia del obrar de la &nbsp;accionada, se super\u00f3 o ces\u00f3 la vulneraci\u00f3n de &nbsp;derechos fundamentales alegada por el accionante. &nbsp;Dicha superaci\u00f3n se configura cuando se realiz\u00f3 la &nbsp;conducta pedida (acci\u00f3n u abstenci\u00f3n) y, por tanto, &nbsp;termin\u00f3 la afectaci\u00f3n resultando inocua cualquier &nbsp;intervenci\u00f3n del juez constitucional en aras de proteger &nbsp;derecho fundamental alguno, pues ya la accionada los ha garantizado &nbsp;(\u2026). &nbsp;T-038 &nbsp;de 2019; Exp. T-7.000.184; citada hace poco en STC2073-2023 y &nbsp;STC5439-2023, resalto intencional. &nbsp;<\/p>\n<p>2.- &nbsp;Ergo, surge &nbsp;inviable &nbsp;la ayuda exhortada. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, en Sala &nbsp;de Casaci\u00f3n Civil y Agraria, administrando justicia en nombre &nbsp;de la Rep\u00fablica de Colombia y por autoridad de la &nbsp;Constituci\u00f3n, &nbsp;DECLARA &nbsp;IMPROCEDENTE &nbsp;la tutela instada por &nbsp;Jos\u00e9 Jorge Bracho Daza. &nbsp;<\/p>\n<p>Inf\u00f3rmese &nbsp;por el medio m\u00e1s expedito y, de no impugnarse este fallo, &nbsp;rem\u00edtase el expediente a la Corte Constitucional para su &nbsp;eventual revisi\u00f3n. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE Y C\u00daMPLASE&nbsp; &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC7767-2023 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp; Magistrada &nbsp;ponente &nbsp; STC7767-2023 &nbsp; (Aprobado &nbsp;en sesi\u00f3n de nueve de agosto de dos mil veintitr\u00e9s) &nbsp; Bogot\u00e1 &nbsp;D.C., nueve (9) de agosto de dos mil veintitr\u00e9s (2023). &nbsp; Desata &nbsp;la Corte la tutela que &nbsp;Jos\u00e9 Jorge Bracho Daza instaur\u00f3 &nbsp;contra la &nbsp;Sala Civil Familia del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[],"class_list":["post-75379","post","type-post","status-publish","format-standard","hentry","category-agosto-2023"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/75379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=75379"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/75379\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=75379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=75379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=75379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}