{"id":75488,"date":"2024-05-20T22:41:20","date_gmt":"2024-05-20T22:41:20","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc7898-2023\/"},"modified":"2024-05-20T22:41:20","modified_gmt":"2024-05-20T22:41:20","slug":"stc7898-2023","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc7898-2023\/","title":{"rendered":"STC7898 2023"},"content":{"rendered":"<p>STC7898-2023<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>Magistrado &nbsp;Ponente &nbsp;<\/p>\n<p>STC7898-2023 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00b0. 11001-22-03-000-2023-01378-01 &nbsp;<\/p>\n<p>(Aprobado &nbsp;en sesi\u00f3n de nueve de agosto de dos mil veintitr\u00e9s). &nbsp;<\/p>\n<p>La &nbsp;Corte decide la impugnaci\u00f3n interpuesta frente a la sentencia &nbsp;proferida el 29 de junio de 2023 por la Sala Civil del Tribunal &nbsp;Superior del Distrito Judicial de Bogot\u00e1, que neg\u00f3 el &nbsp;amparo reclamado por Fabio Edilberto Vallejo Heredia contra la &nbsp;Superintendencia de Sociedades. Al tr\u00e1mite se vincul\u00f3 a &nbsp;los intervinientes en el proceso de reorganizaci\u00f3n 70.303. &nbsp;<\/p>\n<p>I. &nbsp;ANTECEDENTES. &nbsp;<\/p>\n<p>1. &nbsp;El accionante demand\u00f3 la protecci\u00f3n constitucional de &nbsp;su derecho fundamental de petici\u00f3n. &nbsp;<\/p>\n<p>2. &nbsp;El actor manifest\u00f3 que \u00abllev[a] &nbsp;un proceso con la SuperSociedades (sic) de aprobaci\u00f3n de pago &nbsp;de salarios y acreencias derivado de una relaci\u00f3n laboral con &nbsp;la empresa Obs Oil Bussines Services\u00bb. &nbsp;Indic\u00f3 que en esa causa, con escrito del 16 de marzo de 2023, &nbsp;present\u00f3 solicitud ante la autoridad cuestionada, relativa a &nbsp;obtener informaci\u00f3n sobre el \u00abestado &nbsp;de pago de [sus] salarios sobre fallo de tutela de noviembre de &nbsp;2021\u00bb. &nbsp;Asimismo, con memorial del 23 siguiente, elev\u00f3 pedimento en el &nbsp;mismo sentido. En virtud de lo anterior, censur\u00f3 que \u00abal &nbsp;d\u00eda de hoy no [ha] tenido respuesta alguna de las dos &nbsp;solicitudes radicadas ante la SuperSociedades (sic)\u00bb. &nbsp;<\/p>\n<p>3. &nbsp;Por &nbsp;lo expuesto, requiri\u00f3 que se le ordene a &nbsp;la entidad &nbsp;querellada \u00abresolver &nbsp;de fondo en el t\u00e9rmino de 48 horas las peticiones presentadas &nbsp;en la fecha 16 y 23 de marzo de 2023\u00bb. &nbsp;Y, acceda a las \u00abpeticiones &nbsp;que se fundamentan en el derecho de petici\u00f3n ya que debido a &nbsp;su negligencia [se] expone a una condici\u00f3n de desigualdad, &nbsp;vulnerabilidad, con afectaci\u00f3n al m\u00ednimo vital m\u00f3vil\u00bb. &nbsp;<\/p>\n<p>II. &nbsp;RESPUESTAS RECIBIDAS. &nbsp;<\/p>\n<p>La &nbsp;Superintendencia de Sociedades mencion\u00f3 que \u00abno &nbsp;se le puede aplicar los t\u00e9rminos de respuesta que establece el &nbsp;CPACA a un proceso de naturaleza jurisdiccional [\u2026] y, se &nbsp;presenta el acaecimiento de un hecho superado bajo el entendido del &nbsp;pronunciamiento que mediante auto 2023-01-486906 se realiz\u00f3, &nbsp;en torno a lo solicitado [\u2026]\u00bb. &nbsp;Por lo tanto, estim\u00f3 que \u00abno &nbsp;ha vulnerado ning\u00fan derecho fundamental del accionante\u00bb. &nbsp;<\/p>\n<p>III. &nbsp;LA &nbsp;SENTENCIA IMPUGNADA. &nbsp;<\/p>\n<p>El &nbsp;a &nbsp;quo &nbsp;constitucional deneg\u00f3 el amparo. Para ello, estim\u00f3 \u00ablas &nbsp;solicitudes impetradas tienen como finalidad pretender el pago de una &nbsp;obligaci\u00f3n dentro de la actuaci\u00f3n judicial precitada, &nbsp;la cual se encuentra regulada por la ley 1116 de 2006 y, por lo tanto &nbsp;la intervenci\u00f3n de los interesados debe ajustarse a lo &nbsp;previsto en el tr\u00e1mite especial que le concierne, quienes &nbsp;ser\u00e1n notificados de los pronunciamientos all\u00ed dictados &nbsp;conforme a lo consagrado en el ordenamiento procesal vigente; siendo &nbsp;el deber del tutelante hacer el seguimiento de rigor a trav\u00e9s &nbsp;de las herramientas para ello dispuestas\u00bb. &nbsp;Y, &nbsp;consider\u00f3 que \u00abla &nbsp;autoridad atacada acredit\u00f3 haber resuelto lo pretendido por el &nbsp;actor en Auto 2023-01-4869066, providencia en la que rechaz\u00f3 &nbsp;por improcedente los derechos de petici\u00f3n presentados el 16 y &nbsp;23 de marzo poniendo de presente los mecanismos ofrecidos para la &nbsp;consulta f\u00edsica y virtual del referido expediente\u00bb. &nbsp;<\/p>\n<p>IV. &nbsp;LA &nbsp;IMPUGNACI\u00d3N. &nbsp;<\/p>\n<p>El &nbsp;actor fund\u00f3 su inconformidad bajo argumentos similares a los &nbsp;expuestos en el escrito inicial. &nbsp;<\/p>\n<p>V. &nbsp;CONSIDERACIONES. &nbsp;<\/p>\n<p>1. &nbsp;Sobre el particular, revisada la providencia censurada, esta Sala -en &nbsp;su calidad de juez constitucional- advierte que la acci\u00f3n no &nbsp;tiene vocaci\u00f3n de prosperidad. Y, por tanto, el fallo &nbsp;impugnado habr\u00e1 de ser confirmado. Por &nbsp;lo que viene. Ciertamente, &nbsp;esta Sala concluye &nbsp;que la solicitud de amparo constitucional carece de vocaci\u00f3n &nbsp;de prosperidad, dado que se configur\u00f3 la \u00abcarencia &nbsp;actual de objeto por hecho superado\u00bb &nbsp;en &nbsp;referencia a la pretensi\u00f3n tocante con que se resuelvan los &nbsp;derechos de petici\u00f3n presentados. &nbsp;<\/p>\n<p>2. &nbsp;En efecto, se evidencia que la autoridad acusada, a trav\u00e9s de &nbsp;prove\u00eddo 2023-01-486906 del 31 de mayo de 20231, &nbsp;resolvi\u00f3 rechazar \u00abpor &nbsp;improcedente los derechos de petici\u00f3n presentados con &nbsp;memoriales 2023-01-137860 y 2023-01-146978 del 16 y 23 de marzo de &nbsp;2023, de conformidad a lo expuesto en la parte considerativa de esta &nbsp;providencia\u00bb, al &nbsp;considerar que \u00abtrat\u00e1ndose &nbsp;de un proceso judicial, el derecho de petici\u00f3n no es el &nbsp;mecanismo id\u00f3neo para que las partes o terceros interesados en &nbsp;el tr\u00e1mite concursal, promuevan solicitudes tendientes a poner &nbsp;en marcha el aparato judicial o a solicitar a un servidor p\u00fablico &nbsp;el cumplimiento de las funciones jurisdiccionales que tiene a su &nbsp;cargo, por cuanto no es posible en este tipo de procesos, hacer uso &nbsp;de las actuaciones previstas para los procesos administrativos\u00bb. &nbsp;Sin &nbsp;perjuicio de lo anterior, le indic\u00f3 que \u00abal &nbsp;estar todos los bienes y acreedores vinculados al proceso, las &nbsp;peticiones presentadas para obtener el pago de obligaciones causadas &nbsp;con anterioridad a la apertura del proceso de liquidaci\u00f3n, no &nbsp;est\u00e1n llamadas a prosperar, habida consideraci\u00f3n que &nbsp;est\u00e1n sujetas a la suerte del proceso de insolvencia\u00bb. &nbsp;<\/p>\n<p>3. &nbsp;Esto es, se constata que la reclamaci\u00f3n que enfila el &nbsp;suplicante fue plenamente atendida por el Despacho querellado, lo &nbsp;cual denota que la queja perdi\u00f3 eficacia frente a la censura &nbsp;propuesta2. &nbsp;<\/p>\n<p>VI. &nbsp;DECISI\u00d3N. &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Sala de Casaci\u00f3n Civil y &nbsp;Agraria de la Corte Suprema de Justicia, administrando justicia en &nbsp;nombre de la Rep\u00fablica y por autoridad de la ley, CONFIRMA &nbsp;la sentencia impugnada. Comun\u00edquese &nbsp;esta providencia a los interesados en la forma prevista por el &nbsp;art\u00edculo 30 del Decreto 2591 de 1991. Oportunamente, rem\u00edtase &nbsp;el expediente a la Corte Constitucional para su eventual revisi\u00f3n. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Presidente &nbsp;de Sala &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>1\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Archivo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;PDF \u00ab10AnexoSuperSociedades &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;BDSS01-#114180196-v1-2023-01-486906-000\u00bb. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC7898-2023 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; FRANCISCO &nbsp;TERNERA BARRIOS &nbsp; Magistrado &nbsp;Ponente &nbsp; STC7898-2023 &nbsp; Radicaci\u00f3n &nbsp;n\u00b0. 11001-22-03-000-2023-01378-01 &nbsp; (Aprobado &nbsp;en sesi\u00f3n de nueve de agosto de dos mil veintitr\u00e9s). &nbsp; La &nbsp;Corte decide la impugnaci\u00f3n interpuesta frente a la sentencia &nbsp;proferida el 29 de junio de 2023 por la Sala Civil del Tribunal &nbsp;Superior del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[],"class_list":["post-75488","post","type-post","status-publish","format-standard","hentry","category-agosto-2023"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/75488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=75488"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/75488\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=75488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=75488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=75488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}