{"id":75864,"date":"2024-05-20T22:44:40","date_gmt":"2024-05-20T22:44:40","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/ac2524-2023-2023-02942-00\/"},"modified":"2024-05-20T22:44:40","modified_gmt":"2024-05-20T22:44:40","slug":"ac2524-2023-2023-02942-00","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/ac2524-2023-2023-02942-00\/","title":{"rendered":"AC 2524 2023"},"content":{"rendered":"<p>AC2524-2023 (2023-02942-00)<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>AC2524-2023 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n. &nbsp;11001-02-03-000-2023-02942-00 &nbsp;<\/p>\n<p>Bucaramanga, &nbsp;primero (1\u00b0) de septiembre de dos mil veintitr\u00e9s (2023) &nbsp;<\/p>\n<p>Se resuelve el &nbsp;conflicto de competencia suscitado entre los Juzgados Veinticuatro &nbsp;Civil Municipal de Peque\u00f1as Causas y Competencia M\u00faltiple &nbsp;de Bogot\u00e1 &nbsp;y &nbsp;Primero Promiscuo Municipal de Flandes \u2013Tolima-, con ocasi\u00f3n &nbsp;de la demanda ejecutiva promovida por la &nbsp;Corporaci\u00f3n Social de Cundinamarca contra &nbsp;Henry \u00c1lvarez Rubio. &nbsp;<\/p>\n<p>I. &nbsp; &nbsp; &nbsp; &nbsp;ANTECEDENTES &nbsp;<\/p>\n<p>1.- &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;La &nbsp;parte actora solicit\u00f3 librar mandamiento de pago con &nbsp;fundamento en el pagar\u00e9 allegado como base de recaudo. &nbsp;<\/p>\n<p>En cuanto a la &nbsp;competencia indic\u00f3 que le correspond\u00eda al juzgado de &nbsp;esta ciudad, \u00abpor &nbsp;el lugar de cumplimiento de la obligaci\u00f3n\u00bb. &nbsp;<\/p>\n<p>2.- &nbsp; &nbsp; &nbsp; &nbsp;El &nbsp;escrito inicial se asign\u00f3 al Juzgado Veinticuatro &nbsp;Civil Municipal de Peque\u00f1as Causas y Competencia M\u00faltiple &nbsp;de Bogot\u00e1, el cual mediante &nbsp;auto de 5 de junio de 2023, &nbsp;rechaz\u00f3 la demanda por falta de competencia territorial, &nbsp;tras argumentar que el convocado &nbsp;tiene su domicilio en el municipio de Flandes. &nbsp;<\/p>\n<p>Igualmente, &nbsp;advirti\u00f3 qu\u00e9 como no se consign\u00f3 expresamente en &nbsp;el t\u00edtulo valor d\u00f3nde deb\u00eda cumplirse la &nbsp;obligaci\u00f3n, en el presente asunto aplica lo dispuesto en el &nbsp;art\u00edculo 621 del C\u00f3digo de Comercio, siendo el &nbsp;domicilio del deudor el lugar para el pago. &nbsp;<\/p>\n<p>Por &nbsp;lo tanto, los jueces de esa localidad son los competentes para &nbsp;conocer de la acci\u00f3n instaurada, pues de lo contrario se &nbsp;vulnerar\u00eda el derecho de defensa y contradicci\u00f3n del &nbsp;deudor. &nbsp;<\/p>\n<p>3.- &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Cumplidos &nbsp;los tr\u00e1mites pertinentes, el expediente se remiti\u00f3 al &nbsp;Juzgado &nbsp;Primero &nbsp;Promiscuo Municipal de Flandes, despacho que mediante providencia &nbsp;del pasado 5 de julio, resolvi\u00f3 no avocar conocimiento del &nbsp;asunto y, en consecuencia, promovi\u00f3 el conflicto negativo. &nbsp;<\/p>\n<p>Explic\u00f3 &nbsp;que, la Corporaci\u00f3n Social de Cundinamarca es una persona &nbsp;jur\u00eddica de derecho p\u00fablico con domicilio en la ciudad &nbsp;de Bogot\u00e1 D.C., lo que habilita la aplicaci\u00f3n del &nbsp;numeral 10\u00ba del art\u00edculo 28 del C\u00f3digo General del &nbsp;Proceso, el cual ordena que la competencia queda radicada &nbsp;privativamente en el despacho judicial del domicilio de la entidad &nbsp;que ostente dicho car\u00e1cter. &nbsp;<\/p>\n<p>II. &nbsp; &nbsp; &nbsp; &nbsp;CONSIDERACIONES &nbsp;<\/p>\n<p>1.- &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Como &nbsp;el conflicto planteado involucra dos juzgados de diferente distrito &nbsp;judicial, el superior funcional com\u00fan a ambos es esta Sala de &nbsp;la Corte, siendo la competente para resolverlo, de conformidad con lo &nbsp;estipulado en los art\u00edculos 139 del C\u00f3digo General del &nbsp;Proceso y 16 de la Ley 270 de 1996, modificado por el art\u00edculo &nbsp;7\u00b0 de la Ley 1285 de 2009. &nbsp;<\/p>\n<p>2.- &nbsp; &nbsp; &nbsp; &nbsp;El &nbsp;ordenamiento jur\u00eddico consagra los par\u00e1metros para la &nbsp;asignaci\u00f3n de los procesos entre las distintas autoridades &nbsp;judiciales, a partir de diversos factores de competencia tales como &nbsp;el objetivo, el subjetivo, el funcional, el de atracci\u00f3n o &nbsp;conexidad y el territorial. &nbsp;<\/p>\n<p>Con respecto al &nbsp;factor territorial, la competencia se determina con sujeci\u00f3n a &nbsp;diferentes fueros, entre ellos, el denominado subjetivo que tiene en &nbsp;consideraci\u00f3n las calidades especiales de las partes del &nbsp;litigio, que otorga, entre otros, un fuero preferente &nbsp;para las entidades del Estado (n\u00fam. 10\u00ba art. 28 del C. G. &nbsp;P.). &nbsp;<\/p>\n<p>3.- &nbsp; &nbsp; &nbsp; &nbsp;En &nbsp;los procesos ejecutivos, es &nbsp;aplicable el numeral 1\u00ba del art\u00edculo 28 del C\u00f3digo &nbsp;General del Proceso, el cual establece que \u00ab[e]n &nbsp;los &nbsp;procesos contenciosos, salvo disposici\u00f3n legal en contrario, &nbsp;es &nbsp;competente el juez del domicilio del demandado &nbsp;(\u2026)\u00bb &nbsp;(se &nbsp;subraya). &nbsp;<\/p>\n<p>Igualmente, &nbsp;procede la aplicaci\u00f3n del numeral 3\u00ba de la misma norma &nbsp;que indica que en los \u00abprocesos &nbsp;originados en un negocio jur\u00eddico o que involucren &nbsp;t\u00edtulos ejecutivos es tambi\u00e9n competente el juez del &nbsp;lugar de cumplimiento de cualquiera de las obligaciones. &nbsp;La estipulaci\u00f3n de domicilio contractual para efectos &nbsp;judiciales se tendr\u00e1 por no escrita\u00bb. &nbsp;<\/p>\n<p>Sin embargo, el &nbsp;numeral 10\u00ba de la misma disposici\u00f3n establece que \u00ab[e]n &nbsp;los procesos contenciosos en que sea parte &nbsp;una entidad territorial, o una entidad descentralizada por servicios &nbsp;o cualquier otra entidad p\u00fablica, conocer\u00e1 en forma &nbsp;privativa el juez del domicilio de la respectiva entidad\u00bb &nbsp;(Se subraya). &nbsp;<\/p>\n<p>4.- &nbsp;Para &nbsp;el caso concreto, una &nbsp;vez revisado el escrito inicial se constata que la demandante es la &nbsp;Corporaci\u00f3n Social de Cundinamarca, cuya naturaleza jur\u00eddica &nbsp;es la de un \u00abestablecimiento &nbsp;p\u00fablico del orden departamental descentralizado\u00bb, &nbsp;domiciliada en Bogot\u00e1, de conformidad con el art\u00edculo &nbsp;2\u00ba, Ordenanza n.\u00ba &nbsp;5 de 1972 de la Asamblea de Cundinamarca; por lo que, el tr\u00e1mite &nbsp;concuerda con lo previsto en el numeral 10\u00b0 del art\u00edculo &nbsp;28 Ib\u00eddem &nbsp;y, entonces, debe ser conocido de forma &nbsp;prevalente y preferente &nbsp;por el juez de su domicilio. &nbsp;<\/p>\n<p>Desde esa \u00f3ptica, &nbsp;no le asiste raz\u00f3n al Juzgado de esta ciudad al rehusar el &nbsp;conocimiento del asunto porque, si bien es cierto, existe una &nbsp;competencia general descrita en el numeral 1\u00ba del art\u00edculo &nbsp;28 ib\u00eddem, &nbsp;que la fija en el lugar de domicilio del demandado, no lo es menos &nbsp;que el criterio que debe prevalecer es el fuero del domicilio de la &nbsp;parte actora por ser un establecimiento p\u00fablico del orden &nbsp;departamental descentralizado; por lo tanto, esta Corporaci\u00f3n &nbsp;debe ce\u00f1irse a la regla imperativa que, para este caso &nbsp;espec\u00edfico, es el domicilio establecido en la ciudad de Bogot\u00e1 &nbsp;D.C., pues as\u00ed se desprende de la informaci\u00f3n adosada &nbsp;al plenario. &nbsp;<\/p>\n<p>III.&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;DECISI\u00d3N &nbsp;<\/p>\n<p>En m\u00e9rito &nbsp;de lo expuesto, la Corte Suprema de Justicia, Sala de Casaci\u00f3n &nbsp;Civil, Agraria y Rural, &nbsp;<\/p>\n<p>RESUELVE &nbsp;<\/p>\n<p>PRIMERO: &nbsp; &nbsp; &nbsp; &nbsp;Declarar &nbsp;que &nbsp;el Juzgado &nbsp;Veinticuatro Civil Municipal de Peque\u00f1as Causas y Competencia &nbsp;M\u00faltiple de Bogot\u00e1 es el competente para conocer el &nbsp;asunto. &nbsp;<\/p>\n<p>SEGUNDO: &nbsp; &nbsp; &nbsp; &nbsp;Remitir &nbsp;el expediente a la se\u00f1alada autoridad judicial, para que &nbsp;avoque conocimiento e &nbsp;imparta el tr\u00e1mite correspondiente. &nbsp;<\/p>\n<p>TERCERO: &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Comunicar &nbsp;esta decisi\u00f3n al Juzgado Primero &nbsp;Promiscuo Municipal de Flandes \u2013Tolima-, as\u00ed &nbsp;como a la parte actora. &nbsp;<\/p>\n<p>Notif\u00edquese &nbsp;<\/p>\n<p>MARTHA PATRICIA &nbsp;GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Magistrada &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>AC2524-2023 (2023-02942-00) &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; AC2524-2023 &nbsp; Radicaci\u00f3n &nbsp;n. &nbsp;11001-02-03-000-2023-02942-00 &nbsp; Bucaramanga, &nbsp;primero (1\u00b0) de septiembre de dos mil veintitr\u00e9s (2023) &nbsp; Se resuelve el &nbsp;conflicto de competencia suscitado entre los Juzgados Veinticuatro &nbsp;Civil Municipal de Peque\u00f1as Causas y Competencia M\u00faltiple &nbsp;de Bogot\u00e1 &nbsp;y &nbsp;Primero Promiscuo Municipal de Flandes \u2013Tolima-, con ocasi\u00f3n &nbsp;de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"class_list":["post-75864","post","type-post","status-publish","format-standard","hentry","category-septiembre-2023"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/75864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=75864"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/75864\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=75864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=75864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=75864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}