{"id":76180,"date":"2024-05-20T22:44:50","date_gmt":"2024-05-20T22:44:50","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc8923-2023\/"},"modified":"2024-05-20T22:44:50","modified_gmt":"2024-05-20T22:44:50","slug":"stc8923-2023","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc8923-2023\/","title":{"rendered":"STC8923 2023"},"content":{"rendered":"<p>STC8923-2023<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>Magistrado &nbsp;ponente &nbsp;<\/p>\n<p>STC8923-2023 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00ba 05001-22-03-000-2023-00316-01 &nbsp;<\/p>\n<p>(Aprobado &nbsp;en sesi\u00f3n del seis de septiembre de dos mil veintitr\u00e9s) &nbsp;<\/p>\n<p>Bogot\u00e1 &nbsp;D.C., seis (6) de septiembre de dos mil veintitr\u00e9s (2023). &nbsp;<\/p>\n<p>Se &nbsp;resuelve la impugnaci\u00f3n del fallo del 27 de julio de 2023 &nbsp;dictado por la Sala Segunda de Decisi\u00f3n Civil del Tribunal &nbsp;Superior de Medell\u00edn, en el amparo que promovieron Jorge Hugo &nbsp;Silva Arroyave, Didier Le\u00f3n Arbel\u00e1ez Arias y Rosa &nbsp;Ang\u00e9lica Arbel\u00e1ez Montoya contra la Superintendencia de &nbsp;Sociedades, regional Medell\u00edn, extensiva &nbsp;a las partes e intervinientes en el proceso de reorganizaci\u00f3n &nbsp;abreviada de Inversiones Sucurezza S.A.S. con No. de expediente &nbsp;107444. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>1.- &nbsp;Los &nbsp;accionantes solicitaron dejar sin efecto el auto del 27 de junio de &nbsp;2023 mediante el cual se decidi\u00f3 desestimar la solicitud de &nbsp;nulidad y, como consecuencia, se anule lo actuado y se ordene &nbsp;fijaci\u00f3n de nueva fecha para reuni\u00f3n de conciliaci\u00f3n &nbsp;de objeciones a la calificaci\u00f3n y graduaci\u00f3n de &nbsp;cr\u00e9ditos y determinaci\u00f3n de derechos de voto y &nbsp;presentaci\u00f3n de nuevo acuerdo de reorganizaci\u00f3n, as\u00ed &nbsp;como remover al promotor Juan Ricardo Montoya Rua por no actuar de &nbsp;forma diligente. &nbsp;<\/p>\n<p>Por &nbsp;ello, presentaron incidente de nulidad por indebida notificaci\u00f3n &nbsp;(31 may. 2023), resuelto por la intendencia regional atacada (27 jun. &nbsp;2023) de forma negativa, dado que a este tipo de procesos se les da &nbsp;publicidad de varias maneras, lo cual estimaron vulnera su debido &nbsp;proceso. &nbsp;<\/p>\n<p>2.- &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;La Superintendencia de Sociedades se pronunci\u00f3 frente a los &nbsp;hechos de la tutela en donde afirm\u00f3 que la nulidad estuvo bien &nbsp;negada pues s\u00ed se les env\u00edo comunicaci\u00f3n a los &nbsp;acreedores y en el proceso ejecutivo 2020-00023-00, en el cual los &nbsp;demandantes son los gestores, tambi\u00e9n comunic\u00f3 mediante &nbsp;auto notificado en estados del inicio del proceso de reorganizaci\u00f3n &nbsp;y env\u00edo del proceso a la superintendencia para su &nbsp;conocimiento. &nbsp;<\/p>\n<p>La &nbsp;curadora ad litem de los vinculados manifest\u00f3 no contar con &nbsp;elementos necesarios para enervar las pretensiones. &nbsp;<\/p>\n<p>3.- &nbsp;El &nbsp;Tribunal Superior de Medell\u00edn neg\u00f3 el amparo por &nbsp;subsidiariedad. &nbsp;<\/p>\n<p>4.- &nbsp;El gestor impugn\u00f3. Manifest\u00f3 que en la parte resolutiva &nbsp;se decidi\u00f3 \u201ccerrar &nbsp;el incidente de nulidad\u201d &nbsp;sin hacer referencia a los recursos que proced\u00edan. A\u00f1adi\u00f3 &nbsp;que hay dos excepciones a la subsidiariedad de la tutela, cuando se &nbsp;utiliza como mecanismo transitorio para evitar un perjuicio &nbsp;irremediable o cuando no se cuente con ning\u00fan mecanismo &nbsp;judicial efectivo para los derechos. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>Estudiados &nbsp;los reclamos tutelares pronto se avizora que el desenlace opugnado &nbsp;ser\u00e1 confirmado, dado que los &nbsp;inconformes no colmaron el requisito de subsidiariedad. &nbsp;<\/p>\n<p>De &nbsp;la revisi\u00f3n del expediente, destaca la Sala que los &nbsp;accionantes no hicieron uso del medio ordinario de protesta que &nbsp;tuvieron a su alcance para lograr la revocatoria del auto reprochado, &nbsp;de ah\u00ed que emerja su incuria, ya que pudieron formular el &nbsp;recurso de reposici\u00f3n contra el auto que neg\u00f3 la &nbsp;nulidad invocada. &nbsp;<\/p>\n<p>De &nbsp;igual forma, frente a la solicitud de remoci\u00f3n del promotor, &nbsp;debe manifestarse que no se observa en los documentos allegados al &nbsp;expediente, que los gestores hayan efectuado previamente una &nbsp;solicitud en tal sentido ante el juez del concurso. As\u00ed, &nbsp;mem\u00f3rese que la Sala ha reiterado que los actores no pueden &nbsp;acudir al amparo constitucional \u00ab(\u2026) &nbsp;en &nbsp;pos de oportunidades defensivas adicionales, ya que la falta de &nbsp;proposici\u00f3n oportuna de los medios de resguardo dise\u00f1ados &nbsp;para las correspondientes actuaciones, constituye una desidia &nbsp;procesal que no puede sanearse con la subsidiaria acci\u00f3n de &nbsp;tutela (\u2026)\u00bb &nbsp;(STC9227-2022). &nbsp;<\/p>\n<p>En &nbsp;este orden de ideas, t\u00e9ngase en cuenta que los convocantes del &nbsp;resguardo no acreditaron la ocurrencia de un menoscabo apremiante de &nbsp;sus garant\u00edas o circunstancias insalvables que ameriten la &nbsp;intervenci\u00f3n del juez constitucional ni siquiera como &nbsp;mecanismo transitorio, en raz\u00f3n a que \u00abno &nbsp;se han demostrado las circunstancias necesarias para conceder la &nbsp;tutela como mecanismo transitorio, por cuanto que sin la presencia de &nbsp;los supuestos del perjuicio irremediable que la doctrina &nbsp;constitucional reclama para su prosperidad, lo alegado tampoco cumple &nbsp;con las caracter\u00edsticas de gravedad, inminencia y apremio de &nbsp;la intervenci\u00f3n del Juez Constitucional\u00bb &nbsp;(CSJ, STC5535-2021). &nbsp;<\/p>\n<p>As\u00ed &nbsp;las cosas, como quiera que los accionantes ten\u00edan a su alcance &nbsp;otros recursos ordinarios de defensa para ventilar su inconformidad, &nbsp;se hace ostensible la improcedencia del resguardo por falta de &nbsp;subsidiariedad y, &nbsp;sin m\u00e1s razones por innecesarias, habr\u00e1 que &nbsp;desestimarse la protecci\u00f3n reclamada. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, en Sala &nbsp;de Casaci\u00f3n Civil, Agraria y Rural, administrando justicia en &nbsp;nombre de la Rep\u00fablica y por autoridad de la Constituci\u00f3n &nbsp;y la Ley CONFIRMA &nbsp;la &nbsp;sentencia de fecha, naturaleza y procedencia conocida. &nbsp;<\/p>\n<p>Inf\u00f3rmese &nbsp;a las partes e intervinientes por el medio m\u00e1s expedito y &nbsp;rem\u00edtase el expediente a la Corte Constitucional para su &nbsp;eventual revisi\u00f3n. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Presidente &nbsp;de Sala &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>Comisi\u00f3n &nbsp;de servicios &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>Ausencia &nbsp;justificada &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC8923-2023 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp; Magistrado &nbsp;ponente &nbsp; STC8923-2023 &nbsp; Radicaci\u00f3n &nbsp;n\u00ba 05001-22-03-000-2023-00316-01 &nbsp; (Aprobado &nbsp;en sesi\u00f3n del seis de septiembre de dos mil veintitr\u00e9s) &nbsp; Bogot\u00e1 &nbsp;D.C., seis (6) de septiembre de dos mil veintitr\u00e9s (2023). &nbsp; Se &nbsp;resuelve la impugnaci\u00f3n del fallo del 27 de julio de 2023 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"class_list":["post-76180","post","type-post","status-publish","format-standard","hentry","category-septiembre-2023"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/76180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=76180"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/76180\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=76180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=76180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=76180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}