{"id":76297,"date":"2024-05-20T22:44:54","date_gmt":"2024-05-20T22:44:54","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc9297-2023\/"},"modified":"2024-05-20T22:44:54","modified_gmt":"2024-05-20T22:44:54","slug":"stc9297-2023","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc9297-2023\/","title":{"rendered":"STC9297 2023"},"content":{"rendered":"<p>STC9297-2023<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>Magistrado &nbsp;Ponente &nbsp;<\/p>\n<p>STC9297-2023 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00ba 11001-02-03-000-2023-03224-00 &nbsp;<\/p>\n<p>(Aprobado en sesi\u00f3n &nbsp;del trece de septiembre de dos mil veintitr\u00e9s). &nbsp;<\/p>\n<p>Bogot\u00e1, D. &nbsp;C., quince (15) de septiembre de dos mil veintitr\u00e9s (2023). &nbsp;<\/p>\n<p>Esta &nbsp;Sala decide la acci\u00f3n de tutela instaurada por Ecelmira Torres &nbsp;P\u00e9rez contra el Juzgado Segundo Civil del Circuito de Sogamoso &nbsp;y Sala \u00danica del Tribunal Superior de Santa Rosa de Viterbo. &nbsp;Al &nbsp;tr\u00e1mite se vincul\u00f3 a las partes e intervinientes en el &nbsp;proceso de radicado 2018-00118. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>I. ANTECEDENTES &nbsp;<\/p>\n<p>1. &nbsp;La accionante -a trav\u00e9s de apoderado- reclama &nbsp;la protecci\u00f3n de los derechos fundamentales &nbsp;al debido proceso, defensa y acceso a la administraci\u00f3n de &nbsp;justicia, presuntamente vulnerados por las autoridades judiciales &nbsp;censuradas. &nbsp;<\/p>\n<p>2. &nbsp;Del expediente allegado se resalta lo que viene. El 7 de septiembre &nbsp;de 20181, &nbsp;la accionante promovi\u00f3 proceso de declaraci\u00f3n de &nbsp;pertenencia contra los herederos determinados de Carlos Julio Puentes &nbsp;Salcedo: Carlos Julio Puentes Tibamosca, Luis Antonio Puentes Cusba, &nbsp;Mar\u00eda Puentes de Cristancho, Rafael Mar\u00eda y Jos\u00e9 &nbsp;de los Reyes Puentes C\u00e1rdenas, la c\u00f3nyuge sup\u00e9rstite &nbsp;Blanca Nubia P\u00e9rez de Puentes, Lady Paola Puentes Torres, &nbsp;heredera determinada de Rafael Puentes Salcedo, los herederos &nbsp;indeterminados de Carlos Julio Puentes Salcedo, Rafael Mar\u00eda &nbsp;Puentes Salcedo y contra las personas indeterminadas con inter\u00e9s &nbsp;en el proceso2. &nbsp;Una vez repartida la demanda, el Juzgado Segundo Civil del Circuito &nbsp;de Sogamoso -con prove\u00eddo del 20 de septiembre de 20183- &nbsp;la admiti\u00f3 a tr\u00e1mite. &nbsp;<\/p>\n<p>2.1. &nbsp;Surtidos los tr\u00e1mites de enteramiento, designado el curador &nbsp;ad-litem de los herederos indeterminados de Carlos Julio Puentes &nbsp;Salcedo, Rafael Mar\u00eda Puentes y de las personas &nbsp;indeterminadas4, &nbsp;descorrido el traslado de las excepciones previas5, &nbsp;en sesiones del 12 de marzo de 20206, &nbsp;28 de septiembre de 20217 &nbsp;y 14 de septiembre de 20218 &nbsp;se evacuaron las pruebas decretadas, enunci\u00f3 el sentido del &nbsp;fallo y anunci\u00f3 que la sentencia ser\u00eda proferida por &nbsp;escrito. En consecuencia, el 16 de septiembre de 2022, neg\u00f3 &nbsp;las pretensiones de la demanda, conden\u00f3 en costas a la parte &nbsp;demandante y fij\u00f3 agencias en derecho, entre otras9. &nbsp;Inconforme con lo decidido, el apoderado de la accionante interpuso &nbsp;recurso de apelaci\u00f3n10, &nbsp;el cual fue concedido en el efecto suspensivo -el 28 de octubre de &nbsp;2022-11. &nbsp;<\/p>\n<p>2.2. &nbsp;El &nbsp;Tribunal accionado \u2013con providencia del 18 de noviembre de &nbsp;2022- admiti\u00f3 a tr\u00e1mite el recurso12 &nbsp;y &nbsp;el 5 de mayo de 2023 profiri\u00f3 sentencia que confirm\u00f3 la &nbsp;proferida en primera instancia. Consider\u00f3 que \u00abno &nbsp;se prob\u00f3 el presupuesto de la posesi\u00f3n exclusiva y &nbsp;excluyente en cabeza de la demandante13\u00bb. &nbsp;<\/p>\n<p>2.3. &nbsp;La gestora censura que la sentencia de segunda instancia incurri\u00f3 &nbsp;en \u00abdefecto &nbsp;f\u00e1ctico por indebida valoraci\u00f3n probatoria\u00bb, al &nbsp;concluir que \u00abno &nbsp;tiene la calidad de ama y se\u00f1ora del fundo que pretende en &nbsp;pertenencia [\u2026] sin valorar en su integridad el interrogatorio &nbsp;de parte absuelto por la demandante [\u2026] ni el dem\u00e1s &nbsp;acervo probatorio [\u2026] para concluir de manera errada que quien &nbsp;lleg\u00f3 como poseedor de la totalidad del predio potrero nuevo, &nbsp;en el a\u00f1o 1982, esto es, de su cuota parte 50% y la de su &nbsp;hermano, el restante 50% fue el se\u00f1or RAFAEL MARIA PUENTES &nbsp;SALCEDO, ello seg\u00fan la juzgadora en raz\u00f3n a que CARLOS &nbsp;JULIO PUENTES SALCEDO le otorg\u00f3 posesi\u00f3n de dicho &nbsp;predio en compensaci\u00f3n a la renuncia de la posesi\u00f3n que &nbsp;RAFAEL MARIA PUENTES SALCESO ten\u00eda sobre la casa ubicada en el &nbsp;centro de la ciudad de Sogamoso y que como ECELMIRA TORRES PEREZ era &nbsp;la esposa de RAFAEL MARIA PUENTES SALCEDO no se configura en cabeza &nbsp;de esta la posesi\u00f3n en raz\u00f3n al v\u00ednculo &nbsp;sentimental, lo que fue visto por la juzgadora como un acto de mera &nbsp;tolerancia [\u2026] acuerdo hipot\u00e9tico que [\u2026] dej\u00f3 &nbsp;de existir a la fecha de la muerte de CARLOS JULIO PUENTES SALCEDO, &nbsp;fallecimiento ocurrido el 11 de marzo de 2006, es decir a los diez &nbsp;(10) a\u00f1os antes de la presentaci\u00f3n de la demanda de &nbsp;pertenencia\u00bb. &nbsp;<\/p>\n<p>Aduce &nbsp;que, ni \u00aben &nbsp;la ley procesal como en la ley sustancial no est\u00e1 previsto &nbsp;que, la continuidad de la indivisi\u00f3n de una comunidad &nbsp;interrumpa o impida la prescripci\u00f3n\u00bb; sumado &nbsp;a que \u00abarbitrariamente &nbsp;ignor\u00f3 [\u2026] los testimonios de JORGE ELIECER BARRERA &nbsp;PRECIADO, LUIS ANTONIO IZQUIERDO PABLO CAMARGO PUERTO, ORLANDO &nbsp;FIGUEREDO Y ELSA VARGAS [que] son muy claros y concretos en afirmar &nbsp;como lo hicieron que ECELMIRA [\u2026] ha ejercido la posesi\u00f3n &nbsp;material exclusiva sobre el predio objeto de usucapi\u00f3n y lo ha &nbsp;hecho por m\u00e1s de treinta a\u00f1os [\u2026]ante la &nbsp;configuraci\u00f3n clara [\u2026] de la intervenci\u00f3n (sic) &nbsp;del t\u00edtulo de tenedora a la de poseedora \u00fanica y &nbsp;exclusiva de la totalidad del predio\u00bb. &nbsp;Por lo que, en su sentir, los \u00ablos &nbsp;argumentos de los fallos de primera y segunda instancia\u00bb no &nbsp;valoraron las pruebas que daban cuenta del cambio de \u00absu &nbsp;posici\u00f3n de tenedora a la de poseedora [y] haber ignorado por &nbsp;completo el registro civil de defunci\u00f3n de CARLOS JULIO &nbsp;PUENTES SALCEDO [y que] la fecha de presentaci\u00f3n de la demanda &nbsp;[fue] despu\u00e9s de m\u00e1s de diez a\u00f1os del &nbsp;fallecimiento\u00bb. &nbsp;<\/p>\n<p>3. &nbsp;Depreca que se amparen sus derechos. En consecuencia, se declare que &nbsp;existi\u00f3 el defecto alegado. Y, que se revoquen las sentencias &nbsp;de instancia que negaron sus pretensiones. Y \u00abse &nbsp;profiera un nuevo fallo en las instancias respectivas en el cual se &nbsp;valore en su integridad todo el material probatorio recaudado y se &nbsp;acceda en consecuencia a las pretensiones de la parte demandante\u00bb. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>II. RESPUESTAS &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;RECIBIDAS &nbsp;<\/p>\n<p>1. &nbsp;El Tribunal y el Juzgado accionados defendieron la legalidad de lo &nbsp;actuado y remitieron el enlace del expediente. &nbsp;<\/p>\n<p>2. &nbsp;Luis Antonio y Flora Puentes Cusba defendieron la legalidad de lo &nbsp;actuado. Y pidieron \u00abdefender &nbsp;los derechos constitucionales de los afectados que son los herederos &nbsp;de CARLOS JULIO PUENTES SALCEDO; cuyos derechos fueron respetados en &nbsp;las sentencias de primera y segunda instancia\u00bb. &nbsp;Por su parte, Marina Puentes de Cristancho, en escrito separado &nbsp;esboz\u00f3 similares argumentos y resalt\u00f3 \u00abla &nbsp;mala fe de la accionante y su apoderado\u00bb dada &nbsp;la &nbsp;\u00abprocedencia fraudulenta en que ha actuado la accionante con su &nbsp;apoderado Dr HENRY ORLANDO CEPEDA IBA\u00d1EZ como lo he expresado &nbsp;una y otra vez en los diferentes proceso judiciales y policivos\u00bb. &nbsp;<\/p>\n<p>3. &nbsp;La Unidad de V\u00edctimas y la Agencia Nacional de Tierras, &nbsp;solicitaron su desvinculaci\u00f3n por falta de legitimaci\u00f3n &nbsp;en la causa por activa. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>III. CONSIDERACIONES &nbsp;<\/p>\n<p>1. &nbsp;Revisada la providencia cuestionada, esta Sala advierte que la acci\u00f3n &nbsp;constitucional no tiene vocaci\u00f3n de prosperidad. En efecto, el &nbsp;Tribunal &nbsp;encartado \u2013con providencia del 5 de mayo de 2023-, que en &nbsp;\u00faltimas resolvi\u00f3 el fondo del asunto, tras definir que &nbsp;el problema jur\u00eddico se circunscrib\u00eda a determinar si &nbsp;la accionante \u00abre\u00fane &nbsp;los requisitos procesales y sustanciales para adquirir por &nbsp;prescripci\u00f3n adquisitiva extraordinaria de dominio el bien &nbsp;inmueble objeto de la demanda, de acuerdo con el material probatorio &nbsp;obrante en el plenario\u00bb, destac\u00f3 &nbsp;que los reparos de la recurrente, consist\u00edan en \u00abque &nbsp;el juez de primer grado no analiz\u00f3 la totalidad de las &nbsp;pruebas, y que, de tenerse como un bien de una comunidad, la &nbsp;demandante supera los presupuestos para adquirir el bien inmueble\u00bb. &nbsp;En &nbsp;esa l\u00ednea, defini\u00f3 el instituto jur\u00eddico de la &nbsp;prescripci\u00f3n con los elementos requeridos como presupuesto &nbsp;para su acreditaci\u00f3n. Se\u00f1al\u00f3 las caracter\u00edsticas &nbsp;de la posesi\u00f3n y los elementos que la integran conforme las &nbsp;prescripciones del art\u00edculo 762 del C\u00f3digo Civil. &nbsp;<\/p>\n<p>1.1. &nbsp;Con base en ello, sostuvo que \u00abdicha &nbsp;tenencia material para ser calificada como posesi\u00f3n requiere &nbsp;la concurrencia de una intenci\u00f3n o consideraci\u00f3n &nbsp;volitiva del individuo de considerarse se\u00f1or o due\u00f1o de &nbsp;la cosa, as\u00ed, cuando la persona que acude a dicha acci\u00f3n &nbsp;acepta haber ejercido actos de tenencia sobre el bien objeto de la &nbsp;misma y aduce que modific\u00f3 esa situaci\u00f3n porque ahora &nbsp;se considera detentador con \u00e1nimo de se\u00f1or y due\u00f1o\u00bb &nbsp;Sumado &nbsp;a que debe acreditar \u00abel &nbsp;momento de tal cambio\u00bb. &nbsp;En &nbsp;desarrollo del argumento, se centr\u00f3 en las pruebas allegadas, &nbsp;para determinar \u00absi &nbsp;la demandante ostenta la calidad de poseedora o tenedora\u00bb. Y, &nbsp;del interrogatorio de parte absuelto por la accionante, resalt\u00f3 &nbsp;que: &nbsp;<\/p>\n<p>A &nbsp;trav\u00e9s de lo manifestado por parte de la demandante ECELMIRA &nbsp;TORRES, se infiere que contrajo matrimonio con el se\u00f1or RAFAEL &nbsp;MAR\u00cdA PUENTES SALCEDO el 25 de abril de 1981; &nbsp;adem\u00e1s &nbsp;que el predio fue adquirido por la sociedad existente entre su esposo &nbsp;RAFAEL MAR\u00cdA PUENTES SALCEDO y su hermano CARLOS JULIO PUENTES &nbsp;SALCEDO, afirmando adem\u00e1s que ingres\u00f3 al predio porque &nbsp;se fue a vivir con su esposo, que era socio en el predio y por un &nbsp;acuerdo entre los hermanos PUENTES SALCEDO, esto en 1982, quedando de &nbsp;esta forma determinado que el predio no correspondi\u00f3 a un bien &nbsp;de la sociedad entre RAFAEL MAR\u00cdA PUENTES SALCEDO y la aqu\u00ed &nbsp;demandante, pues como lo afirm\u00f3 bajo la gravedad del juramento &nbsp;la demandante, se trat\u00f3 de un bien de propiedad de su esposo y &nbsp;el hermano, se\u00f1or CARLOS JULIO, es decir, que el predio &nbsp;exist\u00eda y era de propiedad de los hermanos PUENTES SALCEDO, &nbsp;con anterioridad de contraer matrimonio la aqu\u00ed demandante con &nbsp;el se\u00f1or RAFAEL MAR\u00cdA FUENTES SALCEDO, quedando claro &nbsp;que el bien no se trat\u00f3 de un bien de comunidad entre la &nbsp;demandante y su esposo, como as\u00ed concluy\u00f3 la jueza de &nbsp;primera instancia. &nbsp;<\/p>\n<p>[\u2026] &nbsp;que los se\u00f1ores CARLOS JULIO PUENTES SALCEDO y el c\u00f3nyuge &nbsp;de la aqu\u00ed demandante, mantuvieron una comunidad indivisa y &nbsp;que conforme con lo afirmado bajo la gravedad del jumento dicha &nbsp;comunidad entre los hermanos, se mantiene, toda vez, que seg\u00fan &nbsp;el dicho de la demandante, no se ha liquidado la sucesi\u00f3n de &nbsp;ninguno de los hermanos PUENTES SALCEDO, como tampoco existi\u00f3 &nbsp;divorcio, por parte de la se\u00f1ora ECELMIRA y el se\u00f1or &nbsp;RAFAEL MARIA PUENTES SALCEDO [\u2026] la misma demandante reconoce &nbsp;la comunidad y la indivisi\u00f3n que pesa sobre el inmueble que se &nbsp;pretende en pertenencia, la cual coexiste respecto de su esposo &nbsp;RAFAEL MARIA y el hermano CARLOS JULIO PUENTES SALCEDO, desvirtuando &nbsp;as\u00ed que la demandante hubiere pose\u00eddo con \u00e1nimo &nbsp;de se\u00f1ora y due\u00f1a y de manera exclusiva el 50% del &nbsp;inmueble con desconocimiento del derecho que le asist\u00eda al &nbsp;se\u00f1or CARLOS JULIO PUENTES SALCEDO, pues como se observa del &nbsp;interrogatorio absuelto por la demandante, la existencia de la &nbsp;comunidad entre los hermanos PUENTES SALCEDO. &nbsp;<\/p>\n<p>[\u2026] &nbsp;esta confesi\u00f3n es diferente a lo afirmado en los hechos de la &nbsp;demanda, donde expuso que entr\u00f3 en posesi\u00f3n en 1982, &nbsp;por cuanto el se\u00f1or CARLOS JULIO PUENTES abandon\u00f3 el &nbsp;predio, afirmaci\u00f3n diferente a lo afirmado en interrogatorio &nbsp;de parte, donde expuso de manera clara que lleg\u00f3 al predio una &nbsp;vez contrajo matrimonio con RAFAEL MARIA PUENTES SALCEDO, adem\u00e1s &nbsp;del hecho de haber se\u00f1alado que con el copropietario CARLOS &nbsp;JULIO PUENTES, se pusieron de acuerdo para que la demandante y su &nbsp;esposo se fueran a vivir al predio objeto de demanda y CARLOS JULIO &nbsp;PUENTES y su esposa en una casa en Sogamoso. &nbsp;<\/p>\n<p>1.2. &nbsp;Asimismo, destac\u00f3 que dichas circunstancias \u00abno &nbsp;tienen eficacia posesoria, por su car\u00e1cter circunstancial, &nbsp;temporal o de mera cortes\u00eda, o por su naturaleza anfibol\u00f3gica &nbsp;o ambigua\u00bb CSJ &nbsp;SC17221-2014, criterio que ha sido reiterado por esta Sala en &nbsp;sentencia CSJ SC3381-2021. Al respecto, indic\u00f3 que \u00abel &nbsp;simple paso del tiempo no muda la mera tenencia en posesi\u00f3n, &nbsp;quien ha reconocido dominio ajeno no puede al titular del se\u00f1or\u00edo, &nbsp;trocarse en poseedor [pues] &nbsp;debe &nbsp;aportarse la prueba fehaciente de la interversi\u00f3n &nbsp;de &nbsp;ese t\u00edtulo, esto es, la existencia de hechos que la demuestren &nbsp;inequ\u00edvocamente incluyendo el momento &nbsp;a partir del cual se revel\u00f3 contra el titular y empez\u00f3 &nbsp;a ejecutar actos de se\u00f1or y due\u00f1o desconociendo &nbsp;su dominio, para contabilizar a partir de dicha fecha el tiempo &nbsp;exigido de posesi\u00f3n Aut\u00f3noma y continua del &nbsp;prescribiente\u00bb. &nbsp;<\/p>\n<p>1.3. &nbsp;Bajo ese contexto, y con respaldo en tales consideraciones, cit\u00f3 &nbsp;apartes de los interrogatorios y declaraciones absueltas por Rafael &nbsp;Mar\u00eda Puentes, Luis Antonio Puentes, Jorge Eliecer Barrera &nbsp;Preciado, Luis Antonio Izquierdo, Pablo Camargo Puerto, Orlando &nbsp;Figueredo, Elsa Vargas, Evangelina Alvarado y Gustavo Guerrero. &nbsp;Adem\u00e1s, indic\u00f3 que la inspecci\u00f3n judicial \u00abno &nbsp;da cuenta de la \u00e9poca en la que la demandante transform\u00f3 &nbsp;la tenencia en posesi\u00f3n\u00bb, &nbsp;tampoco las pruebas documentales llevaron a determinar la fecha de la &nbsp;interversi\u00f3n del t\u00edtulo de la accionante. Y, concluy\u00f3 &nbsp;que: &nbsp;<\/p>\n<p>\u2026existe &nbsp;prueba fehaciente, como lo exige la reciente jurisprudencia, sobre la &nbsp;interversi\u00f3n de t\u00edtulo de tenedora a poseedora y, en &nbsp;tal situaci\u00f3n, no se puede contabilizar el tiempo a partir del &nbsp;cual asegura inici\u00f3 a ejecutar actos de se\u00f1ora y due\u00f1a &nbsp;sin tener en cuenta la comunidad, pues [\u2026]NINGUNO DE LOS &nbsp;RECEPCIONADOS DIO CUENTA DE LA FECHA EN QUE LA DEMANDANTE INTERVIRTI\u00d3 &nbsp;EL TITULO de tenedora a poseedora, siendo del caso se\u00f1alar que &nbsp;a algunos de los testigos les consta que la misma lleg\u00f3 al &nbsp;predio una vez la demandante contrajo matrimonio con RAFAEL MARIA &nbsp;PUENTES SALCEDO, por acuerdo entre los hermanos RAFAEL MARIA Y CARLOS &nbsp;JULIO quienes ya eran propietarios del bien inmueble, lo que quiere &nbsp;decir, que lleg\u00f3 como tenedora y a otros testigos solo les &nbsp;consta que la demandante ha ejercitado actos posesorios, han &nbsp;realizado mejoras, como lo indic\u00f3 el se\u00f1or PABLO &nbsp;CAMARGO, pero a ning\u00fan testigo les consta la fecha o el &nbsp;momento en que hubo el cambio entre tenedora a poseedora, como lo &nbsp;pretende en esta acci\u00f3n, pues recu\u00e9rdese que los &nbsp;testigos EVANGELINA ALVARADO Y GUSTAVO GUERRERO, los demandados en &nbsp;interrogatorio de parte y la aqu\u00ed demandante en interrogatorio &nbsp;absuelto afirman que la sociedad entre RAFAEL MARIA PUENTES Y CARLOS &nbsp;JULIO PUENTES SALCEDO, a\u00fan no se ha liquidado. &nbsp;<\/p>\n<p>Deja &nbsp;claro la Sala que a ninguno de los testigos les consta cu\u00e1ndo &nbsp;ocurri\u00f3 el cambio por parte de la se\u00f1ora ECELMIRA &nbsp;TORRES de tenedor a poseedora o, que a trav\u00e9s de sus dichos &nbsp;existan elementos de juicios a trav\u00e9s de los cuales logre &nbsp;identificarse que la demandante no hubiese detentado una condici\u00f3n &nbsp;distinta a la de tenedora, pues seg\u00fan lo establecido por los &nbsp;deponentes se infiere a las claras que en todo momento se reconoci\u00f3 &nbsp;la propiedad de su difunto esposo bajo las condiciones establecidas &nbsp;por este con su tambi\u00e9n fallecido hermano. &nbsp;<\/p>\n<p>[\u2026] &nbsp;De acuerdo con el an\u00e1lisis probatorio y jurisprudencial, no es &nbsp;otra la conclusi\u00f3n a la que arriba la Sala, que la aqu\u00ed &nbsp;demandante ingres\u00f3 al inmueble a una vez contrajo matrimonio &nbsp;con uno de los propietarios, esto fue con el se\u00f1or RAFAEL &nbsp;MAR\u00cdA PUENTES SALCEDO, y de acuerdo con la jurisprudencia &nbsp;antes transcrita cuando el propietario y \/o poseedor de un inmueble &nbsp;ha permitido o consentido la permanencia de una persona sobre el &nbsp;mismo, en raz\u00f3n de alg\u00fan v\u00ednculo sentimental o &nbsp;familiar con \u00e9ste no puede configurarse acto posesorio alguno. &nbsp;<\/p>\n<p>3. &nbsp;De lo expuesto, para esta Sala, con independencia de que se compartan &nbsp;o no todas las conclusiones del juez ordinario, la decisi\u00f3n &nbsp;cuestionada no podr\u00eda ser recibida como irrazonable.14 &nbsp;Ello &nbsp;pues, fue proferida por el juez natural, sirvi\u00e9ndose de un &nbsp;an\u00e1lisis normativo y probatorio del tema debatido, en el que &nbsp;la actora no acredit\u00f3 el momento efectivo de cambio jur\u00eddico &nbsp;de tenedora a poseedora, requerido para adquirir la prescripci\u00f3n &nbsp;extraordinaria de dominio. Se reitera, el &nbsp;juez constitucional no es el llamado a intervenir a manera de &nbsp;autoridad de instancia para establecer cu\u00e1les de los &nbsp;planteamientos expuestos resultan ser los m\u00e1s acertados. &nbsp;Sumado &nbsp;a que en &nbsp;el sub &nbsp;judice lo &nbsp;que se identifica es una disparidad de criterios entre lo considerado &nbsp;por la autoridad cuestionada -en el desarrollo de sus facultades y &nbsp;amparada en los principios de autonom\u00eda e independencia &nbsp;judicial- y lo planteado por la accionante. En una palabra, el juez &nbsp;constitucional no es el llamado a dirimir la controversia a modo de &nbsp;autoridad de instancia. Y \u00abmenos &nbsp;acometer, bajo ese pretexto, como lo pretende la parte actora, la &nbsp;revisi\u00f3n oficiosa del asunto, como si fuese uno de instancia15\u00bb &nbsp;Aunado &nbsp;a que, \u00abla &nbsp;adversidad de la decisi\u00f3n no es por s\u00ed misma fundamento &nbsp;que le allane el camino al vencido para perseverar en sus &nbsp;discrepancias frente a lo resuelto por el juez natural\u00bb &nbsp;(CSJ &nbsp;STC 28 mar. 2012, Rad. 00022-01, CSJ STC 3446- 2020, reiterada en STC &nbsp;2462-2021, 12 de marzo). &nbsp;<\/p>\n<p>VI. &nbsp;DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, en Sala &nbsp;de Casaci\u00f3n Civil, Agraria y Rural, administrando justicia en &nbsp;nombre de la Rep\u00fablica de Colombia y por autoridad de la ley, &nbsp;NIEGA &nbsp;la &nbsp;acci\u00f3n de tutela impetrada. Notif\u00edquese esta &nbsp;providencia a los interesados en la forma prevista por el art\u00edculo &nbsp;30 del Decreto 2591 de 1991. En caso de no ser impugnada, remitir el &nbsp;expediente a la Corte Constitucional para su eventual revisi\u00f3n. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Presidente &nbsp;de Sala &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>1\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Carpeta 02 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Segunda Instancia. Documento 02.Actuaciones Digitalizadas, Pdf &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;1Demanda y anexos. Expediente digital &nbsp;<\/p>\n<p>2\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Carpeta 02 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Segunda Instancia. Documento 02.Actuaciones Digitalizadas, Pdf &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;1Demanda y Anexos. Expediente digital. &nbsp;<\/p>\n<p>3\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Carpeta 02 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Segunda Instancia. Documento 02.Actuaciones Digitalizadas, Pdf 1. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Auto admisorio. Expediente digital. &nbsp;<\/p>\n<p>4\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Carpeta 02 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Segunda Instancia. Documento 2.2. autos varios. Pdf Auto designa &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;curador. Expediente digital. &nbsp;<\/p>\n<p>5\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Carpeta 02 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Segunda Instancia. Documento 2.2. autos varios. Pdf auto agrega &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;contestaci\u00f3n corre traslado de las excepciones previas. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Expediente digital &nbsp;<\/p>\n<p>6\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Carpeta 02 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Segunda Instancia. Documento 6. Audiencia inicial. Pdf Acta &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;audiencia. Expediente digital &nbsp;<\/p>\n<p>8\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Carpeta 02 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Segunda Instancia. Documento02. Pdf90ActaContinuaci\u00f3n &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Instrucci\u00f3n y Juzgamiento. Expediente digital &nbsp;<\/p>\n<p>9\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Carpeta 02 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Segunda Instancia. Documento02.Pdf95SentenciaEscrita. Expediente &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;digital &nbsp;<\/p>\n<p>10\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Carpeta 02 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Segunda Instancia. Documento02. Pdf97RecursoApelaci\u00f3n. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Expediente digital &nbsp;<\/p>\n<p>11\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Carpeta 02 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Segunda Instancia. Documento2Continuacipon Expediente. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Pdf101AutoConcedeApelacionSentencia. Expediente digital &nbsp;<\/p>\n<p>12\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Carpeta 02 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Segunda Instancia. Documento03AdmiteRecurso. Expediente digital &nbsp;<\/p>\n<p>13\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Carpeta 02 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Segunda Instancia. Documento17Sentencia Segunda Instancia. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Expediente digital &nbsp;<\/p>\n<p>14\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Aquello que se recibe como \u201crazonable\u201d &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;tambi\u00e9n puede recibirse como \u201cracional\u201d &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;(Atienza, M. Para &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;una razonable definici\u00f3n de razonable, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Doxa, 1987, p\u00e1g. 197 y ss.). Y como \u201cv\u00e1lido\u201d, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;puesto que \u201csatisface &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;los requisitos afincados en las reglas de reconocimiento\u201d &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;(Hart, H. The &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;concept of law, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Oxford University Press, 1961, p\u00e1g. 128). &nbsp;<\/p>\n<p>15\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;CSJ STC.7 mar. 2008, Rad. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2007-00514-01 Reiterada en CSJ STC 4454. 15 de jul. 2020 &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC9297-2023 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; FRANCISCO &nbsp;TERNERA BARRIOS &nbsp; Magistrado &nbsp;Ponente &nbsp; STC9297-2023 &nbsp; Radicaci\u00f3n &nbsp;n\u00ba 11001-02-03-000-2023-03224-00 &nbsp; (Aprobado en sesi\u00f3n &nbsp;del trece de septiembre de dos mil veintitr\u00e9s). &nbsp; Bogot\u00e1, D. &nbsp;C., quince (15) de septiembre de dos mil veintitr\u00e9s (2023). &nbsp; Esta &nbsp;Sala decide la acci\u00f3n de tutela instaurada por Ecelmira Torres &nbsp;P\u00e9rez [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"class_list":["post-76297","post","type-post","status-publish","format-standard","hentry","category-septiembre-2023"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/76297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=76297"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/76297\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=76297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=76297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=76297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}