{"id":81593,"date":"2024-05-29T22:05:14","date_gmt":"2024-05-29T22:05:14","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/29\/s-085-98\/"},"modified":"2024-05-29T22:05:14","modified_gmt":"2024-05-29T22:05:14","slug":"s-085-98","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/29\/s-085-98\/","title":{"rendered":"S 085 98"},"content":{"rendered":"<p>S-085-98<\/p>\n<p>&nbsp; &nbsp; &nbsp; CORTE SUPREMA DE JUSTICIA &nbsp;<\/p>\n<p>SALA DE CASACION CIVIL Y AGRARIA &nbsp;<\/p>\n<p>Magistrado ponente:&nbsp; Doctor PEDRO LAFONT PIANETTA &nbsp;<\/p>\n<p>Santaf\u00e9 de Bogot\u00e1, D.C., veintinueve (29) de septiembre de mil novecientos noventa y ocho (1998) &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Referencia: Expediente No. 5191 &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Contra la sentencia del 10 de marzo de 1994 proferida por el Tribunal Superior del Distrito Judicial de Santaf\u00e9 de Bogot\u00e1, en el proceso ordinario (reivindicatorio) adelantado por ROSINA PAEZ BELLO contra JOSE DEL CARMEN TUTA, ALVARO BARBOSA y MARIA CASTIBLANCO DE VEGA, interpuso el recurso extraordinario de casaci\u00f3n el demandado JOSE DEL CARMEN TUTA, el que por haber tramitado procede la Corte a decidirlo. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;I &#8211; EL LITIGIO &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;1.- Mediante demanda presentada el 31 de enero de 1986 (fls. 16 a 18, C-1), admitida por el Juzgado Cuarto Civil del Circuito de Santaf\u00e9 de Bogot\u00e1 luego de su correcci\u00f3n; la se\u00f1ora Rosina Paez Bello, convoc\u00f3 en proceso ordinario a Jos\u00e9 del Carmen Tuta, Alvaro Barbosa y a Marina Castiblanco de Vega, para que en la sentencia que ponga fin al proceso se hiciesen las siguientes declaraciones y condenas: &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;1.1.- Que se ordene la restituci\u00f3n y entrega junto con sus mejoras, usos, costumbres y servidumbres por tener la calidad de leg\u00edtima propietaria del inmueble ubicado en la ciudad de Bogot\u00e1, distinguido en la nomenclatura urbana con el n\u00famero 7-94 de la carrera 22 sur, direcci\u00f3n actual, pero en la oficina de catastro se identifica con el No. 20-82 de la calle 8\u00aa sur, predio que corresponde al lote&nbsp; No. 1 de la manzana \u00abF\u00bb, zona \u00abF\u00bb de la urbanizaci\u00f3n Luna Park, comprendido dentro de los linderos que en el pedimento se expresaron, inmueble este cuya extensi\u00f3n superficiaria aproximada es de 353.60 mts. cuadrados. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;1.2.- Que se condene a los demandados a pagar los frutos civiles&nbsp; que estima en la suma de $50.000,oo mensuales, liquidados desde la fecha en que adquiri\u00f3 la actora el inmueble y\/o subsidiariamente se haga una condena in genere de los da\u00f1os y perjuicios ocasionados con la ocupaci\u00f3n de mala fe del inmueble; y, &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2.- Como fundamentos de su acci\u00f3n expuso la actora los hechos que enseguida se sintetizan: &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2.1.- Mediante escritura p\u00fablica No. 0205 del 18 de febrero de 1981 otorgada en la Notar\u00eda Veintid\u00f3s del c\u00edrculo de Bogot\u00e1, aclarado dicho instrumento posteriormente con escritura 1524 del 26 de agosto del mismo a\u00f1o, la demandante adquiri\u00f3 la propiedad del lote identificado en la nomenclatura urbana de Bogot\u00e1 bajo el n\u00famero 7-94 de la carrera 92, que catastralmente y en escritura figura con el No. 20-82 de la calle 8\u00aa sur, con registro catastral 8 S 20-11, cuyos linderos en el libelo se precisan, predio en el que actualmente se encuentra funcionando un local comercial dedicado a la venta de aceites y combustibles denominado \u00abLubricantes El Porvenir\u00bb, un taller de mec\u00e1nica y f\u00e1brica de exostos (sic). &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2.2.- Cuando se efect\u00fao la compra del inmueble estaba ocupado por los se\u00f1ores Julio Barbosa e hijos y el se\u00f1or Gilberto&nbsp; Medina en calidad de arrendatario del mismo, pero al solicitarles su entrega se opusieron Jos\u00e9 del Carmen Tuta, Alvaro Barbosa y \u00faltimamente Marina Castiblanco de Vega, quienes arguyen ser sus poseedores, afirmaci\u00f3n que es de mala fe porque el se\u00f1or Tuta fue muchos a\u00f1os arrendatario de Julio Barbosa y Alvaro Barbosa es hijo extramatrimonial del mismo arrendatario, y Marina de Castiblanco creen se encuentra bajo \u00f3rdenes de los anteriores. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2.3.- Quienes alegan la posesi\u00f3n del inmueble han manifestado que entregar\u00e1n el mismo a condici\u00f3n de que se les pague cierta cantidad de dinero, exigencia que ha sido rechazada por su propietaria se\u00f1ora Rosina Paez Bello. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2.4.- En varias oportunidades desde su adquisici\u00f3n se ha insistido en la entrega del predio, pero todos los esfuerzos han resultado in\u00fatiles, raz\u00f3n por la cual se acude a la reivindicaci\u00f3n, ya que no son poseedores de buena fe pues carecen de t\u00edtulo escriturario y ostentan la posesi\u00f3n vali\u00e9ndose de artima\u00f1as. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2.5.- Jos\u00e9 del Carmen Tuta y sus compa\u00f1eros vienen usufructuando el inmueble ya de manera directa o ya arrend\u00e1ndolo a terceros, obteniendo as\u00ed pingues ganancias y un enriquecimiento sin causa. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2.6.- La posesi\u00f3n que alegan es de mala fe puesto que los demandados conocen a ciencia cierta quien fue el anterior due\u00f1o, esto es, la Caja Social de Ahorros por intermedio de su socio \u00abFundaci\u00f3n C\u00edrculo de Obreros\u00bb, sociedad que lo tuvo en su poder y en arrendamiento a Julio Barbosa y Gilberto Medina. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2.7.- Los perjuicios que se le han causado a la actora deben ser pagados por los poseedores desde el d\u00eda 18 de febrero desde 1981 hasta cuando se haga la entrega. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2.8.-La actora es quien como leg\u00edtima propietaria del inmueble viene pagando los impuestos de catastro, valorizaci\u00f3n y dem\u00e1s. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2.9.- Por \u00faltimo que al libelo se adjunta el certificado de libertad del predio, documento con el que se demuestra que la demandante es la \u00fanica propietaria inscrita y que adem\u00e1s no se encuentra proceso alguno en contra del inmueble (sic). &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;3.- Trabada la relaci\u00f3n jur\u00eddico procesal con el demandado Alvaro Barbosa por notificaci\u00f3n que se hizo del auto admisorio de la demanda al curador ad-litem que se design\u00f3 para representarlo y a Marina Castiblanco de Vega y Jos\u00e9 del Carmen Tuta por notificaci\u00f3n personal, este \u00faltimo mediante apoderado di\u00f3 contestaci\u00f3n al libelo (fls.28 al 31, C-1), oponi\u00e9ndose a las pretensiones de la actora, negando la totalidad de los hechos y proponiendo adem\u00e1s como excepci\u00f3n previa la de pleito pendiente, medio defensivo que a la postre no prosper\u00f3; y como excepciones de fondo, la de prescripci\u00f3n extraordinaria del dominio y la que denomin\u00f3 \u00abfalta de presupuesto necesario para reivindicar\u00bb. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;4.- Surtido el tr\u00e1mite propio de la instancia, el juzgado le puso fin mediante sentencia proferida el 25 de enero de 1991 (folios 117 a 125, C-1), en la que se decidi\u00f3 declarar no probada la excepci\u00f3n de prescripci\u00f3n adquisitiva del dominio y acceder a las pretensiones de la demandante, en el sentido de que a ella pertenece el dominio pleno y absoluto del inmueble en litigio, es decir, el distinguido con el No. 7-94 de la calle 22 sur de Bogot\u00e1, orden\u00e1ndose consecuencialmente su entrega dentro de los 6 d\u00edas siguientes al de la ejecutoria de la sentencia. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;5.- Apelada la decisi\u00f3n anterior por la parte demandada, recurso al que se adhiri\u00f3 la actora para que se condene a los demandados al pago de los frutos civiles, el Tribunal Superior del Distrito Judicial de Santaf\u00e9 de Bogot\u00e1&nbsp;&nbsp;&nbsp;&nbsp; -Sala Civil- confirm\u00f3 \u00edntegramente la sentencia de primer grado, adicion\u00e1ndola en cuanto a la condena al pago de los perjuicios que concret\u00f3 en la suma de $7&#8217;870.521 como frutos civiles liquidados hasta el 17 de febrero de 1994 y los que se causen hasta que se restituya el predio. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;6.- Interpuesto entonces el recurso extraordinario de casaci\u00f3n contra la sentencia del tribunal y cumplido el tr\u00e1mite propio, de su decisi\u00f3n se ocupa ahora la Corte. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;II&nbsp;&nbsp;&nbsp; LA SENTENCIA DEL TRIBUNAL &nbsp;<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Luego de hacer un recuento de los antecedentes del litigio, de dar por establecidos los presupuestos procesales y de no hallar causal de nulidad que invalide la actuaci\u00f3n, precisa el tribunal que en este asunto se est\u00e1 frente a la acci\u00f3n reivindicatoria de que trata el art\u00edculo 946 del C\u00f3digo Civil, en virtud de la cual el propietario de una cosa singular que est\u00e1 privado de su posesi\u00f3n, obliga al poseedor que no es su propietario a restituir el respectivo bien a su due\u00f1o, acci\u00f3n cuyos elementos estructurales la doctrina y la jurisprudencia concretan en los siguientes: a) El dominio de la cosa por parte del demandante; b) la cosa debe ser singular, individualizada,&nbsp; o&nbsp; de&nbsp; una&nbsp; cuota&nbsp; determinada&nbsp; de&nbsp; la cosa singular; c) la posesi\u00f3n de la cosa singular o la cuota de \u00e9sta por parte del demandado y, d) la identidad plena entre la cosa que se pretende reivindicar y la pose\u00edda por el demandado. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Elementos anteriores que afirma el tribunal en el sub-lite se encuentran presentes y debidamente demostrados as\u00ed:&nbsp; La propiedad de la demandante del inmueble ubicado en la carrera 22 # 7-94 sur de esta ciudad, se la transfiri\u00f3 la \u00abFundaci\u00f3n C\u00edrculo de Obreros de Bogot\u00e1\u00bb mediante escritura p\u00fablica No. 0205 del 18 de febrero de 1981 otorgada en la Notar\u00eda Veintid\u00f3s del C\u00edrculo de Bogot\u00e1 y la escritura de aclaraci\u00f3n de la anterior No. 1524 del 26 de agosto del mismo a\u00f1o, inscritas ambas en la Oficina de Registro de Instrumentos P\u00fablicos y Privados de Bogot\u00e1 en el folio de matr\u00edcula No. 050-0326806. El segundo elemento, esto es, que el respectivo bien sea singularizado o se trate de una cuota parte de una cosa singular, en este asunto se encuentra presente pues desde el texto de la demanda se indic\u00f3 en forma precisa y clara que se trataba de un&nbsp; lote de terreno ubicado en la carrera 22 No. 7-94 sur de la ciudad capital, indic\u00e1ndose tanto los linderos generales como especiales, los que fueron debidamente constatados en la inspecci\u00f3n judicial y ratificados en el dictamen pericial, aspecto este sobre el que existe certeza plena y ninguna discusi\u00f3n se plante\u00f3 sobre el punto. El tercer elemento, o sea la posesi\u00f3n en cabeza del demandado, afirma el tribunal quetambi\u00e9n acude en el asunto en an\u00e1lisis, posesi\u00f3n que est\u00e1 demostrada no solo con la prueba testimonial arrimada al proceso, sino tambi\u00e9n con la posesi\u00f3n del demandado Jos\u00e9 del Carmen Tuta, quien manifest\u00f3 que pose\u00eda el inmueble de manera legal, regular y de buena fe, siendo precisamente esta la raz\u00f3n por la cual propuso la excepci\u00f3n perentoria de prescripci\u00f3n extraordinaria del dominio. En lo que respecta a la posesi\u00f3n de los dem\u00e1s demandados, afirma el tribunal, aparece que al ser notificados del auto admisorio de la demanda ning\u00fan reparo sobre el tema hicieron, ni se\u00f1alaron que otra persona era la poseedora. El cuarto y \u00faltimo elemento relacionado con la identidad entre el bien que se pretende reivindicar y el que posee el demandado, anota el ad-quem que no hay duda respecto a que el inmueble pretendido en reivindicaci\u00f3n es el mismo que posee el demandado, pues \u00e9ste acept\u00f3 ser el poseedor del predio reclamado, confesi\u00f3n que fue ratificada con los restantes medios de prueba allegados, especialmente con las constancias que se plasmaron en el acta de inspecci\u00f3n judicial. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Reunidos as\u00ed los elementos estructurales de la acci\u00f3n reivindicatoria, dice el tribunal, refi\u00e9rese enseguida a las excepciones que propuso el demandado Jos\u00e9 del Carmen Tuta, de las que afirma no est\u00e1n llamadas a prosperar puesto que de los elementos de orden probatorio, especialmente de los testimonios de Jos\u00e9 Eliseo Carre\u00f1o Pulido, David Romero M\u00e9ndez, Gilberto Medina Osorio, Edilberto Garc\u00eda Rivera, Abraham Medina Garc\u00eda, Jorge Enrique Pinz\u00f3n Hern\u00e1ndez, Cristina Murillo de D\u00e1vila y los interrogatorios a que fueron sometidas las partes, se concluye en efecto que el demandado Jos\u00e9 del Carmen Tuta ostenta la calidad de poseedor del inmueble, m\u00e1s no por 20 a\u00f1os o m\u00e1s, sino de 10 a\u00f1os aproximadamente, posesi\u00f3n que califica el Tribunal como de mala fe teniendo en cuenta que la parte demandada no acredit\u00f3 haber obtenido la posesi\u00f3n por los medios legales, vale decir, no acredit\u00f3 un justo t\u00edtulo. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;En lo relacionado con las mejoras precisa el Tribunal que el demandado no aleg\u00f3 nada sobre este aspecto y no existe adem\u00e1s prueba que \u00e9ste las hubiera realizado. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Finalmente dice el Tribunal, que como el a-quo no tuvo en cuenta lo atinente a la condena en los frutos civiles dejados de percibir por la demandante por encontrar que no estaban probados, para su valoraci\u00f3n se orden\u00f3 en la segunda instancia el correspondiente dictamen pericial que fue objetado por error grave, y para resolverlo, se orden\u00f3 una segunda pericia que arroj\u00f3 como resultado un valor de los frutos de $7&#8217;870.521,oo, decidiendo por esto adicionar el tribunal la sentencia de primer grado en el sentido de condenar a los demandados a su pago, confirm\u00e1ndola en su integridad. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;III &#8211; LA DEMANDA DE CASACION &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Un cargo le formula el recurrente a la sentencia que se acaba de resumir, apoyado en la causal segunda de casaci\u00f3n prevista en el art\u00edculo 368 del C\u00f3digo de Procedimiento Civil, que la Corte procede a resolver. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;CARGO UNICO &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Acusa la sentencia del Tribunal por no estar en consonancia con los hechos del libelo y las pretensiones de la parte demandante. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Los fundamentos de la censura se resumen de la siguiente manera: &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Precisa que el poder conferido por la se\u00f1ora Rosina Paez Bello es para reivindicar el inmueble ubicado en la carrera 22 No. 7-94 sur de Bogot\u00e1, e identificado en la oficina de Catastro con el No. 20-82 de la calle 8a. sur y que, en ejercicio del mencionado poder el abogado en el hecho primero de su demanda reivindicatoria, dice que el predio se encuentra situado en la calle 92 No. 7-94 sur y en la pretensi\u00f3n marcada (sic) con la letra \u00aba\u00bb solicita la reivindicaci\u00f3n del inmueble de la carrera 22 No. 9-74 sur de Bogot\u00e1, pretensi\u00f3n esta que corrigi\u00f3 dentro del t\u00e9rmino, para decir que el predio est\u00e1 ubicado en la carrera 22 No. 7-94 sur. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Que a pesar de haberse corregido la demanda la mayor\u00eda de los que en el proceso intervinieron se guiaron por el libelo primario. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Pasa enseguida el recurrente a detallar los errores que sostiene se cometieron en la demanda y la tramitaci\u00f3n procesal de la misma: &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Pasa enseguida el&nbsp; recurrente en casaci\u00f3n a referirse a que los elementos para que opere la pretensi\u00f3n de dominio, que dice, seg\u00fan el a-quo y el tribunal han sido identificados doctrinaria y jurisprudencialmente. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Sostiene en lo que toca con el primer elemento, vale decir, el derecho de propiedad de la demandante respecto al bien cuya reivindicaci\u00f3n se invoca, que de acuerdo con lo demostrado en el proceso, \u00e9sta es propietaria del lote de terreno situado en la calle 8\u00aa sur No. 20-82 de Bogot\u00e1, pero jam\u00e1s ha probado que es due\u00f1a del lote situado en la carrera 22 No. 7-94 sur de la misma ciudad. Luego este presupuesto no se cumple en la sentencia que se ataca. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Respecto al elemento de la acci\u00f3n reivindicatoria consistente en que se trate de cosa singular reivindicable, afirma la recurrente que tampoco acude en la sentencia del tribunal, dado que lo que existe es una pluralidad de bienes, as\u00ed: el de la Cra. 22 No. 7-94 sur de Bogot\u00e1 que es pedido en reivindicaci\u00f3n; el de la carrera 22 No. 9-74 considerado por el a-quo en la sentencia; el distinguido con el n\u00famero 7-94 de la carrera 92 sur de Bogot\u00e1, considerado por el tribunal en la sentencia; el avaluado por los peritos, es decir, el de la carrera 22 No. 9-74 sur de Bogot\u00e1; el inspeccionado&nbsp; (sic)&nbsp; por&nbsp; el&nbsp; a-quo,&nbsp; esto&nbsp; es,&nbsp; el&nbsp; de&nbsp; la&nbsp; carrera&nbsp; 22 No.7-94 sur de Bogot\u00e1; el comprado por la actora con la escritura No.1524 situado en la calle 8\u00aa&nbsp; No. 20-82 sur, y el certificado por la Tesorer\u00eda Distrital es decir, el situado en la carrera 22 No. 7-94 Sur. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;En lo relacionado con el presupuesto de la posesi\u00f3n material del demandado sobre el bien a reivindicar, sostiene que el inmueble pedido en la demanda est\u00e1 situado en la calle 8a. sur No. 20-82 de Bogot\u00e1, mientras que el demandado est\u00e1 en posesi\u00f3n material de un inmueble diferente, situado en otra direcci\u00f3n, cual es el de la carrera 22 No. 7-94 sur de Bogot\u00e1. Luego tampoco en el sub-lite, sostiene, se cumple este presupuesto. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;En cuanto a la identidad entre la cosa pose\u00edda por el demandado y la pretendida por el demandante, afirma no puede existir identidad entre el inmueble que tiene en posesi\u00f3n Jos\u00e9 del Carmen Tuta y el considerado por el Tribunal, porque uno est\u00e1 situado en el barrio Luna Park y el otro en la plaza de mercado de Corabastos; que no puede existir identidad entre el inmueble pose\u00eddo por el demandado y el avaluado por los peritos porque entre el inmueble de la carrera 22 No. 7-94 y el avaluado en la carrera 22 No. 9-74 existe una diferencia de m\u00e1s de 200 mts; que no puede existir identidad entre el predio pose\u00eddo por el demandado, esto es, el de la carrera 22 No. 7-94 sur y el comprado por la demandante el que est\u00e1 situado en la calle 8\u00aa sur No. 20-82 de Bogot\u00e1, los que tienen un \u00e1rea diferente, puesto que el primero tiene 313.20 mts. cuadrados y el segundo 353.60 mts. cuadrados. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Concluye su censura la recurrente diciendo que de acuerdo con lo anterior, los presupuestos procesales consagrados por la ley para esta clase de procesos, en el sub-lite no se cumplieron y por ende solicita a la Corte acceder a los pedimentos de la demanda de casaci\u00f3n. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;CONSIDERACIONES &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;1.- Es verdad averiguada que el recurso de casaci\u00f3n no obstante su origen dispositivo se encuentra sujeto al r\u00e9gimen de la t\u00e9cnica, dentro de cuyas reglas se destaca la de la autonom\u00eda de las causales y los cargos. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;1.1.- En efecto, la casaci\u00f3n como recurso que es, se encuentra sujeto al principio dispositivo, el cual impone al recurrente la carga de su formulaci\u00f3n y sustentaci\u00f3n a fin de que la Corte asuma la competencia para su correspondiente conocimiento; y, como extraordinario, asume un car\u00e1cter excepcional no solo en cuanto a su procedencia, formulaci\u00f3n, admisi\u00f3n y sustentaci\u00f3n, sino tambi\u00e9n en las exigencias de sus respectivas acusaciones, tal como las que ata\u00f1en a la presunci\u00f3n de acierto de las sentencias impugnadas, la limitaci\u00f3n de las causales, la individualizaci\u00f3n de los cargos, la autonom\u00eda de los mismos, etc. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;1.2.- Pues bien, una de las reglas t\u00e9cnicas es la que se refiere a la autonom\u00eda de las causales y de los cargos.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 1.2.1.- Consiste esta autonom\u00eda en que las causales de casaci\u00f3n que se estructuran sobre motivos dis\u00edmiles, son de orden p\u00fablico, de interpretaci\u00f3n restringida y por ello las razones o circunstancias que en cada una se consagran como suficientes para impugnar la sentencia gozan de autonom\u00eda e individualidad propia, y en consecuencia, no es posible configurar dos o m\u00e1s de ellas en la misma censura y que los cargos no solo respeten la independencia de las causales en que se fundan, sino que se formulen por separado de acuerdo con la exigencia del art\u00edculo 374 del C\u00f3digo de Procedimiento Civil. Ha dicho sobre el punto la Corte: \u00abla t\u00e9cnica del recurso de casaci\u00f3n exige los cargos se formulen en forma correcta y completa, sin ser posible la integraci\u00f3n de unos con otros, en virtud de los principios de autonom\u00eda e independencia que gobiernan el recurso.\u00bb (Cas. Civ. del 16 de Junio de 1.985). &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;1.2.1.1.- Esta exigencia de la autonom\u00eda de los cargos si bien tiene aplicaci\u00f3n en los que se formulan con fundamento en la causal primera, antes transitoriamente atenuada por lo dispuesto por el art\u00edculo 51 del Decreto 2651 de 1991 y hoy norma permanente (art. 162, Ley 446 de 1998), no es menos cierto que tiene su mayor aplicaci\u00f3n entre las diversas causales. Porque dicha autonom\u00eda exige que cada acusaci\u00f3n se formule en forma coherente y arm\u00f3nica en una misma causal y no en varias, no solo por ser diferentes y a veces contradictorias, sino porque el principio dispositivo le impone al recurrente el deber de seleccionar debidamente la causal, sin que la Corte pueda hacerlo por \u00e9l. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;1.2.1.2.- De all\u00ed que no sea posible mezclar o combinar en una misma acusaci\u00f3n censuras de la causal segunda y de la causal primera, porque obedecen a infracciones diferentes que deben aducirse por separado. Por ello ha dicho esta Sala que \u00ab&#8230;la causal primera de casaci\u00f3n por violaci\u00f3n de la ley sustancial no solo difiere de la causal segunda por inconsonancia, sino que tambi\u00e9n quedan sometidas a algunas reglas t\u00e9cnicas especiales. En efecto, la causal primera de casaci\u00f3n se debe edificar arm\u00f3nicamente (sin contradicciones) sobre vicios sustanciales de todos los fundamentos que siendo bases del fallo estructuren una violaci\u00f3n directa o indirecta de normas sustanciales, esto es que, seg\u00fan el caso, quebrante la ley de manera frontal y sin fundamentos de apreciaciones probatorias, o que se infrinjan dichos preceptos a consecuencia de yerros de hecho o de derecho en la apreciaci\u00f3n de todas las pruebas que constituyen el sustento de la sentencia atacada. En cambio, la causal segunda de casaci\u00f3n solamente se estructura sobre determinados vicios de procedimiento consistentes en \u00abno estar la sentencia en consonancia con los hechos, las pretensiones de la demanda, o con las excepciones propuestas por el demandado o que el juez ha debido reconocer de oficio\u00bb. (art. 368, num.2, C.P.C.), raz\u00f3n por la cual las reglas de t\u00e9cnica correspondientes a esta causal, imponen que la censura se dirija a estructurar en forma precisa y concreta en los casos all\u00ed indicados, una deficiencia en el ejercicio de la atribuci\u00f3n jurisdiccional que acarrea una inconsonancia o incongruencia entre los extremos procesales de la sentencia y las pretensiones o hechos de la demanda o de las excepciones del demandado o que han debido declararse de oficio\u00bb. (Cas. agosto 4 de 1994, aun sin publicar). &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Y refiri\u00e9ndose a la causal segunda ha expresado esta Corporaci\u00f3n que la incongruencia debe apreciarse en lo que constituye la esencia del libelo y de la sentencia, pero no en las simples diferencias de palabras o expresiones. Dijo esta corporaci\u00f3n en sentencia del 15 de diciembre de 1976, sobre el tema lo siguiente: \u00abMas de que la sentencia debe ser consonante con los requerimientos oportunamente deducidos por las partes, es decir que deba ser congruente con las peticiones del demandante y las excepciones del demandado, no se sigue que entre \u00e9stas y el fallo deba guardarse simetr\u00eda tal que a cada petici\u00f3n o a cada defensa deba responder la sentencia con las mismas palabras empleadas por los litigantes. Lo sustancial es que el fallador no omita decidir los temas que le plantean las partes y que, realmente, los decida sin exceder sus facultades en el punto, as\u00ed no guarde el mismo orden propuesto o as\u00ed no utilice el mismo lenguaje utilizado por \u00e9stos\u00bb. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;1.2.2.- Ahora bien, esta regla t\u00e9cnica de la autonom\u00eda de los cargos que exige que cada cargo debe fundarse en una causal y no en varias, o que fund\u00e1ndose en una no involucre acusaciones correspondientes a otras causales, aun se encuentra vigente dentro del r\u00e9gimen antes transitorio del art\u00edculo 51 del Decreto 2651 de 1991 y hoy permanente (art. 162 Ley 446 de 1998) puesto que esta norma solamente aten\u00faa el rigor de la t\u00e9cnica de la causal primera de casaci\u00f3n, o sea cuando se invoque la infracci\u00f3n de normas de derecho sustancial, ya que dicho precepto se\u00f1ala que \u00absin perjuicio de lo dispuesto en los respectivos c\u00f3digos de procedimiento acerca de los requisitos formales que deben reunir las demandas de casaci\u00f3n cuando se invoque la infracci\u00f3n de normas de derecho sustancial, se observar\u00e1n las siguientes reglas&#8230;\u00bb. Luego solamente en acusaciones que se formulen con fundamento exclusivo en la causal primera de casaci\u00f3n, se encuentra autorizada la Corte para tener como suficiente la invocaci\u00f3n de una norma sustancial relativa a lo debatido y fallado , as\u00ed como para separar o unir los cargos por la causal primera que lo requieran y no sean incompatibles (numerales 2o.,3o. y 4o., art. 51 Ib.). Pero en manera alguna se autoriza a separar las acusaciones que se refieren a varias causales, pero que se encuentren en un mismo cargo. Porque, como se dijo, solo es procedente la separaci\u00f3n de varias censuras de un mismo cargo, cuando quiera que todas ellas pertenezcan a la causal primera y que, adem\u00e1s, requieran de esa separaci\u00f3n porque han debido formularse en cargos separados. Pero ello no procede cuando la pluralidad de censuras de un mismo cargo se fundan expl\u00edcita o impl\u00edcitamente en varias causales de casaci\u00f3n. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2.- Seguidamente aborda la Corte el estudio del llamado por el recurrente primer cargo de casaci\u00f3n. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2.1.- En este evento se ataca la sentencia del tribunal por la parte demandada por ser incongruente con los hechos y pretensiones de la demanda.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; 2.1.1.- Previamente precisa la Corte que el ad-quem decide confirmar la sentencia de primer grado y adicionarla en el sentido de condenar a los demandados a pagar a la demandante dentro de los cinco d\u00edas siguientes al de la ejecutoria de la sentencia, la suma de $7&#8217;870.521,oo por concepto de los frutos civiles producidos por el inmueble, liquidados hasta el 17 de febrero de 1994, y los que se causen hasta que se restituya el bien. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Y a su vez el juzgador de primera instancia resolvi\u00f3 declarar no probada la excepci\u00f3n de prescripci\u00f3n adquisitiva del dominio propuesta por el demandado Jos\u00e9 del Carmen Tuta; declarar que pertenece el dominio pleno y absoluto a la se\u00f1ora Rosina Paez Bello, el inmueble ubicado en la carrera 22 No. 7-94 sur de Bogot\u00e1; en consecuencia ordena a Jos\u00e9 del Carmen Tuta, Alvaro Barbosa Marina Castiblanco y dem\u00e1s que ocupen el inmueble, a restituir y entregar el mismo dentro de los seis (6) d\u00edas siguientes a la ejecutoria de la providencia y, conden\u00f3 al demandado Jos\u00e9 del Carmen Tuta al pago de las costas del proceso. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2.1.2.- Contra aquel fallo, el casacionista lo acusa por la causal segunda en los siguientes t\u00e9rminos:&nbsp; \u00abla sentencia dictada por el honorable tribunal no est\u00e1 en consonancia con los hechos y pretensiones solicitadas por la parte activa\u00bb. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; M\u00e1s adelante, como dicen los antecedentes se\u00f1ala estos tres errores a saber: 1) Que el poder conferido por la demandante a su procurador judicial es para solicitar la reivindicaci\u00f3n del inmueble de la carrera 22 No. 7-94 sur de Bogot\u00e1, el que adquiri\u00f3 mediante escritura No. 0205 del 18 de Febrero de 1981, la cual fue aclarada con escritura No. 1524 del 26 de agosto del mismo a\u00f1o, instrumentos estos en los que se dice que el lote tiene una cabida de 353.60 mts. cuadrados.-&nbsp; 2) Que en el ejercicio de dicho poder, el abogado invoca la reivindicaci\u00f3n del inmueble ubicado en la carrera 92 No. 7-94 sur de Bogot\u00e1 y que en el ac\u00e1pite de pretensiones del libelo solicita la reivindicaci\u00f3n del lote situado en la carrera 22 No. 9-74 sur de Bogot\u00e1, y, 3) Que pese a haberse subsanado la demanda en cuanto a la direcci\u00f3n del inmueble, la que se precis\u00f3 era la carrera 22 No. 7-94 sur de Bogot\u00e1, todos los que intervinieron en el proceso se guiaron por el libelo primario. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Seguidamente el recurrente se\u00f1ala como errores en la demanda y su tramitaci\u00f3n los siguientes: 1) Que en la sentencia demandada, en sus antecedentes se afirma que el inmueble a reivindicar se encuentra ubicado en la Cra. 92 No.7-94 sur de Bogot\u00e1. 2) La sentencia del a-quo confirmada por el tribunal, dice que la se\u00f1ora Rosina Paez Bello es considerada titular del derecho de dominio del predio de la carrera 22 No. 9-74 sur de Bogot\u00e1. 3) En las consideraciones de la sentencia atacada se afirma que se trata de un lote ubicado en la carrera 22 No. 7-94 sur de Bogot\u00e1. 4) Los peritos designados para hacer el aval\u00fao de los frutos producidos por el inmueble, afirman que practicaron el mismo sobre el inmueble de la carrera 22 No. 9-74 sur de Bogot\u00e1, lo que conlleva que el dictamen se realiz\u00f3 en otro inmueble, dado que el que tiene en posesi\u00f3n el demandado es el distinguido con el No. 7-94 de la carrera 22 sur. 5) Los peritos nombrados para hacer el segundo aval\u00fao de los frutos, rinden su experticio diciendo que lo hicieron sobre el inmueble de la carrera 22 No. 9-74 sur de Bogot\u00e1, luego vuelven y cometen el mismo error anterior. 6) El tribunal al adicionar la sentencia del a-quo en cuanto al pago de los frutos producidos por el predio, no tuvo en cuenta que su estimaci\u00f3n se hizo sobre inmueble distinto al pose\u00eddo por el demandado, raz\u00f3n por la que el dictamen no ten\u00eda valor probatorio alguno para condenar a la demandada. 7) Que la escritura 0205 del 18 de febrero de 1981 con la que compr\u00f3 Rosina Paez Bello el inmueble de la carrera 22 No. 7-94 sur de Bogot\u00e1, la que se aclar\u00f3 mediante escritura No.1524 del 26 de agosto del mismo a\u00f1o en cuanto a que la verdadera direcci\u00f3n y nomenclatura es la calle 8a. sur No. 20-82 de Bogot\u00e1, lo que indica que la actora compr\u00f3 un inmueble diferente al que tiene en posesi\u00f3n el demandado y que, no puede pensarse que se trata de un solo inmueble con dos direcciones diferentes, porque existen pruebas en el proceso que determinan que se trata de dos bienes distintos, como es el caso de la afirmaci\u00f3n dada en la inspecci\u00f3n ocular, el dictamen pericial ordenado como requisito previo para otorgar el recurso de casaci\u00f3n, etc. y, 8) Que el apoderado del extremo activo tuvo acceso al proceso y se notific\u00f3 de todas las providencias y de los aval\u00faos, dej\u00f3 pasar los errores permiendo que se aprobaran y causaran ejecutoria. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2.2.- Al respecto la Corte encuentra que tal impugnaci\u00f3n no solo desatiende la regla t\u00e9cnica de casaci\u00f3n de la autonom\u00eda de las causales y de los cargos que impiden su estudio de fondo, sino que tambi\u00e9n carece de fundamento legal. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2.2.1.- En efecto, est\u00e1 claro que inicialmente invoca la causal segunda, pero luego se\u00f1ala aspectos que comprenden ataques de infracci\u00f3n de normas sustanciales, pertenecientes a la causal primera, tal como cuando se\u00f1ala que los peritos que practicaron los dos aval\u00faos de los frutos producidos por el inmueble, lo hicieron en el demarcado con el No. 9-74 de la carrera 22 sur de Bogot\u00e1, predio que afirma es diferente al pose\u00eddo por el demandado que es el de la carrera 22 No. 7-94 sur de Bogot\u00e1, se\u00f1alando la carencia de valor probatorio del aval\u00fao, o cuando dice el recurrente que la demandante Rosina Paez que compr\u00f3, seg\u00fan la escritura No. 1524 aclaratoria de la 0205 el inmueble de la calle 8a. sur No. 20-82 de Bogot\u00e1, que es diferente al de la carrera 22 No. 7-94 sur que tiene en posesi\u00f3n el demandado, y las afirmaciones que hace el recurrente en su censura en el sentido de que no se prob\u00f3 la propiedad del lote pose\u00eddo, que hubo pluralidad de bienes, que el pose\u00eddo es otro bien y que no hay identidad de objeto. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Luego al combinar en un mismo cargo dos causales se choca contra el citado postulado de la autonom\u00eda e individualidad de cada una de las causales, lo que es suficiente para desechar el cargo as\u00ed propuesto. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2.2.2.- No obstante, ser lo anterior suficiente para desechar el cargo, la Sala observa que no puede darse incongruencia cuando existe consonancia entre la pretensi\u00f3n reivindicatoria inicial y su posterior reforma (fls. 20 y 21, C-1), con la parte resolutiva de la sentencia de segunda instancia confirmatoria de la primera, cuando al rompe ambas piezas procesales refieren al lote de la carrera 22 No. 7-94 sur de Bogot\u00e1, pues son notoriamente irrelevantes algunos lapsus cometidos en otras piezas procesales y pruebas y, por lo dem\u00e1s, aducidos aqu\u00ed temerariamente. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Por lo anterior se desecha el cargo propuesto. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;3.- Sin embargo, la Sala no pasa por alto que la anterior acusaci\u00f3n formulada en la demanda de casaci\u00f3n sub-examine, en vez de ajustarse a un sano y razonable ejercicio del derecho de defensa que le asiste a las partes de un proceso y a su representante judicial, revela, por el contrario, un abuso del mismo que conduce a calificar dicha demanda como temeraria, en vista de \u201cla carencia de fundamento legal\u201d. Porque cuando, a sabiendas, como lo reconoce el recurrente, este \u00faltimo hace descansar dicha acusaci\u00f3n en el aparte del texto de una demanda original&nbsp; cuando ella hab\u00eda sido eficazmente reformada&nbsp; o corregida, sin contradicci\u00f3n de la misma, no puede menos que reconocerse que esa defensa no se edifica en fundamento eficaz del proceso. Y si a ello se agrega que, adem\u00e1s de guardar silencio sobre el particular durante las instancias, la misma parte recurrente, tambi\u00e9n a sabiendas de que la demanda corregida y la parte resolutiva de la sentencia coinciden en la identificaci\u00f3n correcta del inmueble reivindicado, pero sin embargo aduce como argumentos de su acusaci\u00f3n algunos errores o lapsus gramaticales en las referencias en algunas piezas procesales y probatorias, que por tanto a todas luces son irrelevantes para poner en duda la decisi\u00f3n adoptada; tambi\u00e9n hay que concluir que no se trata de ning\u00fan \u201cfundamento legal\u201d que sostenga la acusaci\u00f3n formulada dentro del marco del derecho de defensa. Por lo que, entonces, se trata de una demanda de casaci\u00f3n temeraria, que obliga a la Corte a imponer a la parte recurrente (Jos\u00e9 del Carmen Tuta) y a su apoderada judicial (Liliana M\u00e9ndez Alfonso), al pago por cada uno, de la multa fijada en la ley en la cuant\u00eda m\u00e1xima, sin perjuicio de la solidaridad en las costas y la orden de expedici\u00f3n de copias para la investigaci\u00f3n disciplinaria que fuere legalmente pertinente (arts. 74 y 73 C.P.C.) &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;IV &#8211; DECISION &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;En m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, en Sala de Casaci\u00f3n Civil, administrando justicia en nombre de la Rep\u00fablica de Colombia y por autoridad de la ley, NO CASA la sentencia proferida por el Tribunal Superior del Distrito Judical de Santaf\u00e9 de Bogot\u00e1 -Sala Civil-, el 10 de marzo de 1994, en el proceso ordinario promovido por ROSINA PAEZ BELLO contra JOSE DEL CARMEN TUTA ABELLA, ALVARO BARBOSA y MARIA CASTIBLANCO DE VEGA. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;As\u00ed mismo, por lo expuesto en las consideraciones de esta providencia, se dispone: &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;1.- Imponer a la parte recurrente en casaci\u00f3n, Jos\u00e9 del Carmen Tuta, y a su apoderada judicial, Liliana M\u00e9ndez Alfonso, multa a cada uno equivalente a veinte salarios m\u00ednimos mensuales en favor de la Naci\u00f3n &#8211; Consejo Superior de la Judicatura. Of\u00edciese y env\u00edense las copias pertinentes. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;2.- Cond\u00e9nase en costas del recurso de casaci\u00f3n en forma solidaria a la parte recurrente y a su apoderada judicial mencionados. T\u00e1sense. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;3.- Comp\u00falsense copias de esta providencia y dem\u00e1s piezas pertinentes, y rem\u00edtanse a la Sala Disciplinaria del Consejo Seccional de la Judicatura de Santaf\u00e9 de Bogot\u00e1 para lo de su cargo. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;C\u00f3piese, notif\u00edquese y devu\u00e9lvase al tribunal de origen. &nbsp;<\/p>\n<p>&nbsp;&nbsp; &nbsp;<\/p>\n<p>JORGE SANTOS BALLESTEROS &nbsp;<\/p>\n<p>NICOLAS BECHARA SIMANCAS &nbsp;<\/p>\n<p>JORGE ANTONIO CASTILLO RUGELES &nbsp;<\/p>\n<p>CARLOS ESTEBAN JARAMILLO SCHLOSS &nbsp;<\/p>\n<p>PEDRO LAFONT PIANETTA &nbsp;<\/p>\n<p>RAFAEL ROMERO SIERRA &nbsp;<\/p>\n<p>JOSE FERNANDO RAMIREZ GOMEZ &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>S-085-98 &nbsp; &nbsp; &nbsp; CORTE SUPREMA DE JUSTICIA &nbsp; SALA DE CASACION CIVIL Y AGRARIA &nbsp; Magistrado ponente:&nbsp; Doctor PEDRO LAFONT PIANETTA &nbsp; Santaf\u00e9 de Bogot\u00e1, D.C., veintinueve (29) de septiembre de mil novecientos noventa y ocho (1998) &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Referencia: Expediente No. 5191 &nbsp; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79],"tags":[],"class_list":["post-81593","post","type-post","status-publish","format-standard","hentry","category-79"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/81593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=81593"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/81593\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=81593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=81593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=81593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}